{"id":26,"count":3,"description":"","link":"https:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/tag\/windjet\/","name":"WindJet","slug":"windjet","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WindJet Archives - Volare in Piemonte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/tag\/windjet\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WindJet Archives - Volare in Piemonte\" \/>\n<meta property=\"og:url\" content=\"http:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/tag\/windjet\/\" \/>\n<meta property=\"og:site_name\" content=\"Volare in Piemonte\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/volareinpiemonte\\\/tag\\\/windjet\\\/\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/volareinpiemonte\\\/tag\\\/windjet\\\/\",\"name\":\"WindJet Archives - Volare in Piemonte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/volareinpiemonte\\\/#website\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/volareinpiemonte\\\/tag\\\/windjet\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/volareinpiemonte\\\/tag\\\/windjet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/volareinpiemonte\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WindJet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/volareinpiemonte\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/volareinpiemonte\\\/\",\"name\":\"Volare in Piemonte\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/volareinpiemonte\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WindJet Archives - Volare in Piemonte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/tag\/windjet\/","og_locale":"it_IT","og_type":"article","og_title":"WindJet Archives - Volare in Piemonte","og_url":"http:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/tag\/windjet\/","og_site_name":"Volare in Piemonte","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"http:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/tag\/windjet\/","url":"http:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/tag\/windjet\/","name":"WindJet Archives - Volare in Piemonte","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/#website"},"breadcrumb":{"@id":"http:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/tag\/windjet\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"http:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/tag\/windjet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/"},{"@type":"ListItem","position":2,"name":"WindJet"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/#website","url":"https:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/","name":"Volare in Piemonte","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/wp-json\/wp\/v2\/tags\/26","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/wp-json\/wp\/v2\/posts?tags=26"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}