{"id":30,"date":"2012-04-09T08:28:25","date_gmt":"2012-04-09T08:28:25","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/volareinpiemonte\/?p=30"},"modified":"2012-04-09T08:28:25","modified_gmt":"2012-04-09T08:28:25","slug":"dal-28-maggio-il-torino-istanbul-diventa-quotidiano","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/dal-28-maggio-il-torino-istanbul-diventa-quotidiano\/","title":{"rendered":"Dal 28 maggio il Torino &#8211; Istanbul diventa quotidiano"},"content":{"rendered":"<p>Dal 28 maggio, infatti, la Turkish Airlines incrementer\u00e0 i collegamenti tra lo scalo di Torino Caselle ed Istanbul dagli attuali tre voli settimanali ad un \u00a0collegamento giornaliero.\u00a0&#8220;Questo nuovo aumento delle frequenze sulla tratta per Istanbul segna un grande passo avanti per la nostra compagnia, e per la nostra destinazione,&#8221; ha dichiarato Cem Sahir Islam, General Manager Turkish Airlines Torino, &#8220;il nostro obiettivo \u00e8 quello di riuscire a creare una vera e propria connessione tra l&#8217;Italia e il resto del mondo, favorendo i viaggi business ma anche i viaggi lesure&#8221;.\u00a0Per questa occasione, Turkish Airlines ha effettuato il collegamento odierno con un Boeing 737-800 con livrea speciale. Si tratta di una livrea unica, realizzata con le immagini di tutti i 17.000 dipendenti della compagnia turca. \u00c8 questa la prima occasione ufficiale in cui l\u2019aereo atterra su uno scalo italiano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dal 28 maggio, infatti, la Turkish Airlines incrementer\u00e0 i collegamenti tra lo scalo di Torino Caselle ed Istanbul dagli attuali tre voli settimanali ad un \u00a0collegamento giornaliero.\u00a0&#8220;Questo nuovo aumento delle frequenze sulla tratta per Istanbul segna un grande passo avanti per la nostra compagnia, e per la nostra destinazione,&#8221; ha dichiarato Cem Sahir Islam, General &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/dal-28-maggio-il-torino-istanbul-diventa-quotidiano\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Dal 28 maggio il Torino &#8211; Istanbul diventa quotidiano&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[3,15],"class_list":["post-30","post","type-post","status-publish","format-standard","hentry","category-volare-in-piemonte","tag-caselle","tag-turchia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dal 28 maggio il Torino - Istanbul diventa quotidiano - Volare in Piemonte<\/title>\n<meta name=\"description\" content=\"Dal 28 maggio, infatti, la Turkish Airlines incrementer\u00e0 i collegamenti tra lo scalo di Torino Caselle ed Istanbul dagli attuali tre voli settimanali ad\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/dal-28-maggio-il-torino-istanbul-diventa-quotidiano\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dal 28 maggio il Torino - Istanbul diventa quotidiano - Volare in Piemonte\" \/>\n<meta property=\"og:description\" content=\"Dal 28 maggio, infatti, la Turkish Airlines incrementer\u00e0 i collegamenti tra lo scalo di Torino Caselle ed Istanbul dagli attuali tre voli settimanali ad\" \/>\n<meta property=\"og:url\" content=\"http:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/dal-28-maggio-il-torino-istanbul-diventa-quotidiano\/\" \/>\n<meta property=\"og:site_name\" content=\"Volare in Piemonte\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese\" \/>\n<meta property=\"article:published_time\" content=\"2012-04-09T08:28:25+00:00\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/volareinpiemonte\\\/dal-28-maggio-il-torino-istanbul-diventa-quotidiano\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/volareinpiemonte\\\/dal-28-maggio-il-torino-istanbul-diventa-quotidiano\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/volareinpiemonte\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"headline\":\"Dal 28 maggio il Torino &#8211; Istanbul diventa quotidiano\",\"datePublished\":\"2012-04-09T08:28:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/volareinpiemonte\\\/dal-28-maggio-il-torino-istanbul-diventa-quotidiano\\\/\"},\"wordCount\":145,\"commentCount\":0,\"keywords\":[\"caselle\",\"turchia\"],\"articleSection\":[\"Volare in Piemonte\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/volareinpiemonte\\\/dal-28-maggio-il-torino-istanbul-diventa-quotidiano\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/volareinpiemonte\\\/dal-28-maggio-il-torino-istanbul-diventa-quotidiano\\\/\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/volareinpiemonte\\\/dal-28-maggio-il-torino-istanbul-diventa-quotidiano\\\/\",\"name\":\"Dal 28 maggio il Torino - Istanbul diventa quotidiano - Volare in Piemonte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/volareinpiemonte\\\/#website\"},\"datePublished\":\"2012-04-09T08:28:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/volareinpiemonte\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"description\":\"Dal 28 maggio, infatti, la Turkish Airlines incrementer\u00e0 i collegamenti tra lo scalo di Torino Caselle ed Istanbul dagli attuali tre voli settimanali ad\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/volareinpiemonte\\\/dal-28-maggio-il-torino-istanbul-diventa-quotidiano\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/volareinpiemonte\\\/dal-28-maggio-il-torino-istanbul-diventa-quotidiano\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/volareinpiemonte\\\/dal-28-maggio-il-torino-istanbul-diventa-quotidiano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/volareinpiemonte\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dal 28 maggio il Torino &#8211; Istanbul diventa quotidiano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/volareinpiemonte\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/volareinpiemonte\\\/\",\"name\":\"Volare in Piemonte\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/volareinpiemonte\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/volareinpiemonte\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte\",\"sameAs\":[\"http:\\\/\\\/www.quotidianopiemontese.it\\\/\",\"https:\\\/\\\/www.facebook.com\\\/quotidianopiemontese\",\"https:\\\/\\\/x.com\\\/quotidianopiem\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/volareinpiemonte\\\/author\\\/administrator\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dal 28 maggio il Torino - Istanbul diventa quotidiano - Volare in Piemonte","description":"Dal 28 maggio, infatti, la Turkish Airlines incrementer\u00e0 i collegamenti tra lo scalo di Torino Caselle ed Istanbul dagli attuali tre voli settimanali ad","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/dal-28-maggio-il-torino-istanbul-diventa-quotidiano\/","og_locale":"it_IT","og_type":"article","og_title":"Dal 28 maggio il Torino - Istanbul diventa quotidiano - Volare in Piemonte","og_description":"Dal 28 maggio, infatti, la Turkish Airlines incrementer\u00e0 i collegamenti tra lo scalo di Torino Caselle ed Istanbul dagli attuali tre voli settimanali ad","og_url":"http:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/dal-28-maggio-il-torino-istanbul-diventa-quotidiano\/","og_site_name":"Volare in Piemonte","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"https:\/\/www.facebook.com\/quotidianopiemontese","article_published_time":"2012-04-09T08:28:25+00:00","author":"Redazione","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/dal-28-maggio-il-torino-istanbul-diventa-quotidiano\/#article","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/dal-28-maggio-il-torino-istanbul-diventa-quotidiano\/"},"author":{"name":"Redazione","@id":"https:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"headline":"Dal 28 maggio il Torino &#8211; Istanbul diventa quotidiano","datePublished":"2012-04-09T08:28:25+00:00","mainEntityOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/dal-28-maggio-il-torino-istanbul-diventa-quotidiano\/"},"wordCount":145,"commentCount":0,"keywords":["caselle","turchia"],"articleSection":["Volare in Piemonte"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/dal-28-maggio-il-torino-istanbul-diventa-quotidiano\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/dal-28-maggio-il-torino-istanbul-diventa-quotidiano\/","url":"http:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/dal-28-maggio-il-torino-istanbul-diventa-quotidiano\/","name":"Dal 28 maggio il Torino - Istanbul diventa quotidiano - Volare in Piemonte","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/#website"},"datePublished":"2012-04-09T08:28:25+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"description":"Dal 28 maggio, infatti, la Turkish Airlines incrementer\u00e0 i collegamenti tra lo scalo di Torino Caselle ed Istanbul dagli attuali tre voli settimanali ad","breadcrumb":{"@id":"http:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/dal-28-maggio-il-torino-istanbul-diventa-quotidiano\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/dal-28-maggio-il-torino-istanbul-diventa-quotidiano\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/dal-28-maggio-il-torino-istanbul-diventa-quotidiano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/"},{"@type":"ListItem","position":2,"name":"Dal 28 maggio il Torino &#8211; Istanbul diventa quotidiano"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/#website","url":"https:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/","name":"Volare in Piemonte","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","caption":"Redazione"},"description":"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte","sameAs":["http:\/\/www.quotidianopiemontese.it\/","https:\/\/www.facebook.com\/quotidianopiemontese","https:\/\/x.com\/quotidianopiem"],"url":"https:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/author\/administrator\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/wp-json\/wp\/v2\/posts\/30","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/wp-json\/wp\/v2\/comments?post=30"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/wp-json\/wp\/v2\/posts\/30\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/wp-json\/wp\/v2\/media?parent=30"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/wp-json\/wp\/v2\/categories?post=30"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/volareinpiemonte\/wp-json\/wp\/v2\/tags?post=30"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}