{"id":41,"date":"2013-06-08T10:48:31","date_gmt":"2013-06-08T08:48:31","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/?p=41"},"modified":"2013-06-08T10:48:31","modified_gmt":"2013-06-08T08:48:31","slug":"riprende-un-temporale-e-viene-sfiorata-da-un-fulmine","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/riprende-un-temporale-e-viene-sfiorata-da-un-fulmine\/","title":{"rendered":"Riprende un temporale e viene sfiorata da un fulmine"},"content":{"rendered":"<p><iframe loading=\"lazy\" src=\"http:\/\/www.youtube.com\/embed\/AbSsVwurkFA\" height=\"253\" width=\"450\" allowfullscreen=\"\" frameborder=\"0\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[44],"class_list":["post-41","post","type-post","status-publish","format-standard","hentry","category-eventi-naturali","tag-eventi-naturali"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Riprende un temporale e viene sfiorata da un fulmine - Video incredibili dai quattro angoli del mondo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/riprende-un-temporale-e-viene-sfiorata-da-un-fulmine\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Riprende un temporale e viene sfiorata da un fulmine - Video incredibili dai quattro angoli del mondo\" \/>\n<meta property=\"og:url\" content=\"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/riprende-un-temporale-e-viene-sfiorata-da-un-fulmine\/\" \/>\n<meta property=\"og:site_name\" content=\"Video incredibili dai quattro angoli del mondo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"gabriele.farina\" \/>\n<meta property=\"article:published_time\" content=\"2013-06-08T08:48:31+00:00\" \/>\n<meta name=\"author\" content=\"Gabriele Farina\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Farina\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/riprende-un-temporale-e-viene-sfiorata-da-un-fulmine\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/riprende-un-temporale-e-viene-sfiorata-da-un-fulmine\\\/\"},\"author\":{\"name\":\"Gabriele Farina\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"headline\":\"Riprende un temporale e viene sfiorata da un fulmine\",\"datePublished\":\"2013-06-08T08:48:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/riprende-un-temporale-e-viene-sfiorata-da-un-fulmine\\\/\"},\"wordCount\":9,\"commentCount\":0,\"keywords\":[\"eventi naturali\"],\"articleSection\":[\"eventi naturali\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/riprende-un-temporale-e-viene-sfiorata-da-un-fulmine\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/riprende-un-temporale-e-viene-sfiorata-da-un-fulmine\\\/\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/riprende-un-temporale-e-viene-sfiorata-da-un-fulmine\\\/\",\"name\":\"Riprende un temporale e viene sfiorata da un fulmine - Video incredibili dai quattro angoli del mondo\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/#website\"},\"datePublished\":\"2013-06-08T08:48:31+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/riprende-un-temporale-e-viene-sfiorata-da-un-fulmine\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/riprende-un-temporale-e-viene-sfiorata-da-un-fulmine\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/riprende-un-temporale-e-viene-sfiorata-da-un-fulmine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Riprende un temporale e viene sfiorata da un fulmine\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/#website\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/\",\"name\":\"Video incredibili dai quattro angoli del mondo\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\",\"name\":\"Gabriele Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"caption\":\"Gabriele Farina\"},\"description\":\"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO\",\"sameAs\":[\"gabriele.farina\",\"https:\\\/\\\/x.com\\\/solops\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/author\\\/gabriele-farina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Riprende un temporale e viene sfiorata da un fulmine - Video incredibili dai quattro angoli del mondo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/riprende-un-temporale-e-viene-sfiorata-da-un-fulmine\/","og_locale":"it_IT","og_type":"article","og_title":"Riprende un temporale e viene sfiorata da un fulmine - Video incredibili dai quattro angoli del mondo","og_url":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/riprende-un-temporale-e-viene-sfiorata-da-un-fulmine\/","og_site_name":"Video incredibili dai quattro angoli del mondo","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"gabriele.farina","article_published_time":"2013-06-08T08:48:31+00:00","author":"Gabriele Farina","twitter_misc":{"Scritto da":"Gabriele Farina"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/riprende-un-temporale-e-viene-sfiorata-da-un-fulmine\/#article","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/riprende-un-temporale-e-viene-sfiorata-da-un-fulmine\/"},"author":{"name":"Gabriele Farina","@id":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"headline":"Riprende un temporale e viene sfiorata da un fulmine","datePublished":"2013-06-08T08:48:31+00:00","mainEntityOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/riprende-un-temporale-e-viene-sfiorata-da-un-fulmine\/"},"wordCount":9,"commentCount":0,"keywords":["eventi naturali"],"articleSection":["eventi naturali"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/riprende-un-temporale-e-viene-sfiorata-da-un-fulmine\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/riprende-un-temporale-e-viene-sfiorata-da-un-fulmine\/","url":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/riprende-un-temporale-e-viene-sfiorata-da-un-fulmine\/","name":"Riprende un temporale e viene sfiorata da un fulmine - Video incredibili dai quattro angoli del mondo","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/#website"},"datePublished":"2013-06-08T08:48:31+00:00","author":{"@id":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"breadcrumb":{"@id":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/riprende-un-temporale-e-viene-sfiorata-da-un-fulmine\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/riprende-un-temporale-e-viene-sfiorata-da-un-fulmine\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/riprende-un-temporale-e-viene-sfiorata-da-un-fulmine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/"},{"@type":"ListItem","position":2,"name":"Riprende un temporale e viene sfiorata da un fulmine"}]},{"@type":"WebSite","@id":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/#website","url":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/","name":"Video incredibili dai quattro angoli del mondo","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32","name":"Gabriele Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","caption":"Gabriele Farina"},"description":"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO","sameAs":["gabriele.farina","https:\/\/x.com\/solops"],"url":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/author\/gabriele-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/wp-json\/wp\/v2\/posts\/41","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/wp-json\/wp\/v2\/comments?post=41"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/wp-json\/wp\/v2\/posts\/41\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/wp-json\/wp\/v2\/media?parent=41"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/wp-json\/wp\/v2\/categories?post=41"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/wp-json\/wp\/v2\/tags?post=41"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}