{"id":17,"date":"2013-06-06T09:44:11","date_gmt":"2013-06-06T07:44:11","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/?p=17"},"modified":"2013-06-06T09:47:41","modified_gmt":"2013-06-06T07:47:41","slug":"bun-litro-di-birra-in-tre-secondi","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/bun-litro-di-birra-in-tre-secondi\/","title":{"rendered":"Beve un litro di birra in tre secondi"},"content":{"rendered":"<p><iframe loading=\"lazy\" src=\"http:\/\/www.youtube.com\/embed\/zCX3D49Hw0Q\" height=\"338\" width=\"450\" allowfullscreen=\"\" frameborder=\"0\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-17","post","type-post","status-publish","format-standard","hentry","category-pazzi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Beve un litro di birra in tre secondi - Video incredibili dai quattro angoli del mondo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/bun-litro-di-birra-in-tre-secondi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Beve un litro di birra in tre secondi - Video incredibili dai quattro angoli del mondo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/bun-litro-di-birra-in-tre-secondi\/\" \/>\n<meta property=\"og:site_name\" content=\"Video incredibili dai quattro angoli del mondo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"gabriele.farina\" \/>\n<meta property=\"article:published_time\" content=\"2013-06-06T07:44:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-06-06T07:47:41+00:00\" \/>\n<meta name=\"author\" content=\"Gabriele Farina\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Farina\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/bun-litro-di-birra-in-tre-secondi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/bun-litro-di-birra-in-tre-secondi\\\/\"},\"author\":{\"name\":\"Gabriele Farina\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"headline\":\"Beve un litro di birra in tre secondi\",\"datePublished\":\"2013-06-06T07:44:11+00:00\",\"dateModified\":\"2013-06-06T07:47:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/bun-litro-di-birra-in-tre-secondi\\\/\"},\"wordCount\":8,\"commentCount\":0,\"articleSection\":[\"pazzi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/bun-litro-di-birra-in-tre-secondi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/bun-litro-di-birra-in-tre-secondi\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/bun-litro-di-birra-in-tre-secondi\\\/\",\"name\":\"Beve un litro di birra in tre secondi - Video incredibili dai quattro angoli del mondo\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/#website\"},\"datePublished\":\"2013-06-06T07:44:11+00:00\",\"dateModified\":\"2013-06-06T07:47:41+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/bun-litro-di-birra-in-tre-secondi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/bun-litro-di-birra-in-tre-secondi\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/bun-litro-di-birra-in-tre-secondi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Beve un litro di birra in tre secondi\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/#website\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/\",\"name\":\"Video incredibili dai quattro angoli del mondo\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\",\"name\":\"Gabriele Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"caption\":\"Gabriele Farina\"},\"description\":\"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO\",\"sameAs\":[\"gabriele.farina\",\"https:\\\/\\\/x.com\\\/solops\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/author\\\/gabriele-farina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Beve un litro di birra in tre secondi - Video incredibili dai quattro angoli del mondo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/bun-litro-di-birra-in-tre-secondi\/","og_locale":"it_IT","og_type":"article","og_title":"Beve un litro di birra in tre secondi - Video incredibili dai quattro angoli del mondo","og_url":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/bun-litro-di-birra-in-tre-secondi\/","og_site_name":"Video incredibili dai quattro angoli del mondo","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"gabriele.farina","article_published_time":"2013-06-06T07:44:11+00:00","article_modified_time":"2013-06-06T07:47:41+00:00","author":"Gabriele Farina","twitter_misc":{"Scritto da":"Gabriele Farina"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/bun-litro-di-birra-in-tre-secondi\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/bun-litro-di-birra-in-tre-secondi\/"},"author":{"name":"Gabriele Farina","@id":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"headline":"Beve un litro di birra in tre secondi","datePublished":"2013-06-06T07:44:11+00:00","dateModified":"2013-06-06T07:47:41+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/bun-litro-di-birra-in-tre-secondi\/"},"wordCount":8,"commentCount":0,"articleSection":["pazzi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/bun-litro-di-birra-in-tre-secondi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/bun-litro-di-birra-in-tre-secondi\/","url":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/bun-litro-di-birra-in-tre-secondi\/","name":"Beve un litro di birra in tre secondi - Video incredibili dai quattro angoli del mondo","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/#website"},"datePublished":"2013-06-06T07:44:11+00:00","dateModified":"2013-06-06T07:47:41+00:00","author":{"@id":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/bun-litro-di-birra-in-tre-secondi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/bun-litro-di-birra-in-tre-secondi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/bun-litro-di-birra-in-tre-secondi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/"},{"@type":"ListItem","position":2,"name":"Beve un litro di birra in tre secondi"}]},{"@type":"WebSite","@id":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/#website","url":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/","name":"Video incredibili dai quattro angoli del mondo","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32","name":"Gabriele Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","caption":"Gabriele Farina"},"description":"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO","sameAs":["gabriele.farina","https:\/\/x.com\/solops"],"url":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/author\/gabriele-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/wp-json\/wp\/v2\/posts\/17","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/wp-json\/wp\/v2\/comments?post=17"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/wp-json\/wp\/v2\/posts\/17\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/wp-json\/wp\/v2\/media?parent=17"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/wp-json\/wp\/v2\/categories?post=17"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/wp-json\/wp\/v2\/tags?post=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}