{"id":155,"date":"2015-01-07T11:13:18","date_gmt":"2015-01-07T10:13:18","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/?p=155"},"modified":"2015-01-07T11:13:18","modified_gmt":"2015-01-07T10:13:18","slug":"la-befana-inaugura-il-carnevale-di-ivrea-riprese-aeree-drone","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/la-befana-inaugura-il-carnevale-di-ivrea-riprese-aeree-drone\/","title":{"rendered":"La befana inaugura il carnevale di Ivrea &#8211; riprese aeree #drone"},"content":{"rendered":"<p>La befana inaugura il carnevale di Ivrea &#8211; riprese aeree col drone<\/p>\n<p><a href=\"http:\/\/www.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/files\/2015\/01\/carnevale-ivrea-riprese-aeree-6-gennaio-2015.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-156\" src=\"http:\/\/www.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/files\/2015\/01\/carnevale-ivrea-riprese-aeree-6-gennaio-2015.jpg\" alt=\"carnevale-ivrea-riprese-aeree-6-gennaio-2015\" width=\"636\" height=\"313\" srcset=\"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/files\/2015\/01\/carnevale-ivrea-riprese-aeree-6-gennaio-2015.jpg 636w, https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/files\/2015\/01\/carnevale-ivrea-riprese-aeree-6-gennaio-2015-300x147.jpg 300w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><\/a><!--more--><\/p>\n<p>https:\/\/www.youtube.com\/watch?v=t9HIHBOf-j8<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La befana inaugura il carnevale di Ivrea &#8211; riprese aeree col drone<\/p>\n","protected":false},"author":34,"featured_media":156,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[34,33,32],"class_list":["post-155","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-social","tag-befana","tag-carnevale","tag-ivrea"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La befana inaugura il carnevale di Ivrea - riprese aeree #drone - Video incredibili dai quattro angoli del mondo<\/title>\n<meta name=\"description\" content=\"La befana inaugura il carnevale di Ivrea - riprese aeree col drone    https:\/\/www.youtube.com\/watch?v=t9HIHBOf-j8\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/la-befana-inaugura-il-carnevale-di-ivrea-riprese-aeree-drone\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La befana inaugura il carnevale di Ivrea - riprese aeree #drone - Video incredibili dai quattro angoli del mondo\" \/>\n<meta property=\"og:description\" content=\"La befana inaugura il carnevale di Ivrea - riprese aeree col drone    https:\/\/www.youtube.com\/watch?v=t9HIHBOf-j8\" \/>\n<meta property=\"og:url\" content=\"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/la-befana-inaugura-il-carnevale-di-ivrea-riprese-aeree-drone\/\" \/>\n<meta property=\"og:site_name\" content=\"Video incredibili dai quattro angoli del mondo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"gabriele.farina\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-07T10:13:18+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/files\/2015\/01\/carnevale-ivrea-riprese-aeree-6-gennaio-2015.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"636\" \/>\n\t<meta property=\"og:image:height\" content=\"313\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriele Farina\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Farina\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/la-befana-inaugura-il-carnevale-di-ivrea-riprese-aeree-drone\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/la-befana-inaugura-il-carnevale-di-ivrea-riprese-aeree-drone\\\/\"},\"author\":{\"name\":\"Gabriele Farina\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"headline\":\"La befana inaugura il carnevale di Ivrea &#8211; riprese aeree #drone\",\"datePublished\":\"2015-01-07T10:13:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/la-befana-inaugura-il-carnevale-di-ivrea-riprese-aeree-drone\\\/\"},\"wordCount\":31,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/la-befana-inaugura-il-carnevale-di-ivrea-riprese-aeree-drone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/files\\\/2015\\\/01\\\/carnevale-ivrea-riprese-aeree-6-gennaio-2015.jpg\",\"keywords\":[\"befana\",\"carnevale\",\"ivrea\"],\"articleSection\":[\"Social\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/la-befana-inaugura-il-carnevale-di-ivrea-riprese-aeree-drone\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/la-befana-inaugura-il-carnevale-di-ivrea-riprese-aeree-drone\\\/\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/la-befana-inaugura-il-carnevale-di-ivrea-riprese-aeree-drone\\\/\",\"name\":\"La befana inaugura il carnevale di Ivrea - riprese aeree #drone - Video incredibili dai quattro angoli del mondo\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/la-befana-inaugura-il-carnevale-di-ivrea-riprese-aeree-drone\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/la-befana-inaugura-il-carnevale-di-ivrea-riprese-aeree-drone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/files\\\/2015\\\/01\\\/carnevale-ivrea-riprese-aeree-6-gennaio-2015.jpg\",\"datePublished\":\"2015-01-07T10:13:18+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"description\":\"La befana inaugura il carnevale di Ivrea - riprese aeree col drone https:\\\/\\\/www.youtube.com\\\/watch?v=t9HIHBOf-j8\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/la-befana-inaugura-il-carnevale-di-ivrea-riprese-aeree-drone\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/la-befana-inaugura-il-carnevale-di-ivrea-riprese-aeree-drone\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/la-befana-inaugura-il-carnevale-di-ivrea-riprese-aeree-drone\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/files\\\/2015\\\/01\\\/carnevale-ivrea-riprese-aeree-6-gennaio-2015.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/files\\\/2015\\\/01\\\/carnevale-ivrea-riprese-aeree-6-gennaio-2015.jpg\",\"width\":636,\"height\":313},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/la-befana-inaugura-il-carnevale-di-ivrea-riprese-aeree-drone\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La befana inaugura il carnevale di Ivrea &#8211; riprese aeree #drone\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/#website\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/\",\"name\":\"Video incredibili dai quattro angoli del mondo\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\",\"name\":\"Gabriele Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"caption\":\"Gabriele Farina\"},\"description\":\"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO\",\"sameAs\":[\"gabriele.farina\",\"https:\\\/\\\/x.com\\\/solops\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/author\\\/gabriele-farina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La befana inaugura il carnevale di Ivrea - riprese aeree #drone - Video incredibili dai quattro angoli del mondo","description":"La befana inaugura il carnevale di Ivrea - riprese aeree col drone    https:\/\/www.youtube.com\/watch?v=t9HIHBOf-j8","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/la-befana-inaugura-il-carnevale-di-ivrea-riprese-aeree-drone\/","og_locale":"it_IT","og_type":"article","og_title":"La befana inaugura il carnevale di Ivrea - riprese aeree #drone - Video incredibili dai quattro angoli del mondo","og_description":"La befana inaugura il carnevale di Ivrea - riprese aeree col drone    https:\/\/www.youtube.com\/watch?v=t9HIHBOf-j8","og_url":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/la-befana-inaugura-il-carnevale-di-ivrea-riprese-aeree-drone\/","og_site_name":"Video incredibili dai quattro angoli del mondo","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"gabriele.farina","article_published_time":"2015-01-07T10:13:18+00:00","og_image":[{"width":636,"height":313,"url":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/files\/2015\/01\/carnevale-ivrea-riprese-aeree-6-gennaio-2015.jpg","type":"image\/jpeg"}],"author":"Gabriele Farina","twitter_misc":{"Scritto da":"Gabriele Farina"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/la-befana-inaugura-il-carnevale-di-ivrea-riprese-aeree-drone\/#article","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/la-befana-inaugura-il-carnevale-di-ivrea-riprese-aeree-drone\/"},"author":{"name":"Gabriele Farina","@id":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"headline":"La befana inaugura il carnevale di Ivrea &#8211; riprese aeree #drone","datePublished":"2015-01-07T10:13:18+00:00","mainEntityOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/la-befana-inaugura-il-carnevale-di-ivrea-riprese-aeree-drone\/"},"wordCount":31,"commentCount":0,"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/la-befana-inaugura-il-carnevale-di-ivrea-riprese-aeree-drone\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/files\/2015\/01\/carnevale-ivrea-riprese-aeree-6-gennaio-2015.jpg","keywords":["befana","carnevale","ivrea"],"articleSection":["Social"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/la-befana-inaugura-il-carnevale-di-ivrea-riprese-aeree-drone\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/la-befana-inaugura-il-carnevale-di-ivrea-riprese-aeree-drone\/","url":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/la-befana-inaugura-il-carnevale-di-ivrea-riprese-aeree-drone\/","name":"La befana inaugura il carnevale di Ivrea - riprese aeree #drone - Video incredibili dai quattro angoli del mondo","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/#website"},"primaryImageOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/la-befana-inaugura-il-carnevale-di-ivrea-riprese-aeree-drone\/#primaryimage"},"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/la-befana-inaugura-il-carnevale-di-ivrea-riprese-aeree-drone\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/files\/2015\/01\/carnevale-ivrea-riprese-aeree-6-gennaio-2015.jpg","datePublished":"2015-01-07T10:13:18+00:00","author":{"@id":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"description":"La befana inaugura il carnevale di Ivrea - riprese aeree col drone https:\/\/www.youtube.com\/watch?v=t9HIHBOf-j8","breadcrumb":{"@id":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/la-befana-inaugura-il-carnevale-di-ivrea-riprese-aeree-drone\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/la-befana-inaugura-il-carnevale-di-ivrea-riprese-aeree-drone\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/la-befana-inaugura-il-carnevale-di-ivrea-riprese-aeree-drone\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/files\/2015\/01\/carnevale-ivrea-riprese-aeree-6-gennaio-2015.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/files\/2015\/01\/carnevale-ivrea-riprese-aeree-6-gennaio-2015.jpg","width":636,"height":313},{"@type":"BreadcrumbList","@id":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/la-befana-inaugura-il-carnevale-di-ivrea-riprese-aeree-drone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/"},{"@type":"ListItem","position":2,"name":"La befana inaugura il carnevale di Ivrea &#8211; riprese aeree #drone"}]},{"@type":"WebSite","@id":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/#website","url":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/","name":"Video incredibili dai quattro angoli del mondo","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32","name":"Gabriele Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","caption":"Gabriele Farina"},"description":"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO","sameAs":["gabriele.farina","https:\/\/x.com\/solops"],"url":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/author\/gabriele-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/wp-json\/wp\/v2\/posts\/155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/wp-json\/wp\/v2\/comments?post=155"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/wp-json\/wp\/v2\/posts\/155\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/wp-json\/wp\/v2\/media\/156"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/wp-json\/wp\/v2\/media?parent=155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/wp-json\/wp\/v2\/categories?post=155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/wp-json\/wp\/v2\/tags?post=155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}