{"id":120,"date":"2014-03-12T11:11:51","date_gmt":"2014-03-12T10:11:51","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/?p=120"},"modified":"2014-03-28T13:20:55","modified_gmt":"2014-03-28T12:20:55","slug":"quanto-e-bello-baciare-uno-sconosciuto","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/quanto-e-bello-baciare-uno-sconosciuto\/","title":{"rendered":"Quanto \u00e8 bello baciare uno sconosciuto"},"content":{"rendered":"<p style=\"text-align: justify;\">Un&#8217;idea talmente semplice da diventare meravigliosa: prendere 40 sconosciuti e, a coppie, chiedere loro di baciarsi per la prima volta.<br \/>\nNe viene fuori una serie di approcci balbettanti, esitazioni dettate dall&#8217;imbarazzo e genuina vergogna. C&#8217;\u00e8 chi deve concentrarsi e non si ricorda il nome del partner improvvisato, chi ha bisogno di tenere le mani della persona che ha di fronte pur non conoscendola e chi bacia con il sorriso.<br \/>\nMa i baci che infine le venti coppie si scambiano sono veri, sinceri e sorprendentemente appassionati. E, al termine dell&#8217;esperimento, qualcuno sembra voler approfondire la conoscenza&#8230;<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/IpbDHxCV29A\" height=\"276\" width=\"490\" allowfullscreen=\"\" frameborder=\"0\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un&#8217;idea talmente semplice da diventare meravigliosa: prendere 40 sconosciuti e, a coppie, chiedere loro di baciarsi per la prima volta. Ne viene fuori una serie di approcci balbettanti, esitazioni dettate dall&#8217;imbarazzo e genuina vergogna. C&#8217;\u00e8 chi deve concentrarsi e non si ricorda il nome del partner improvvisato, chi ha bisogno di tenere le mani della &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/quanto-e-bello-baciare-uno-sconosciuto\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Quanto \u00e8 bello baciare uno sconosciuto&#8221;<\/span><\/a><\/p>\n","protected":false},"author":945,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[15,16,18],"class_list":["post-120","post","type-post","status-publish","format-standard","hentry","category-romantici","tag-bacio","tag-first-kiss","tag-sconosciuti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quanto \u00e8 bello baciare uno sconosciuto - Video incredibili dai quattro angoli del mondo<\/title>\n<meta name=\"description\" content=\"Un&#039;idea talmente semplice da diventare meravigliosa: prendere 40 sconosciuti e, a coppie, chiedere loro di baciarsi per la prima volta. Ne viene fuori una\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/quanto-e-bello-baciare-uno-sconosciuto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quanto \u00e8 bello baciare uno sconosciuto - Video incredibili dai quattro angoli del mondo\" \/>\n<meta property=\"og:description\" content=\"Un&#039;idea talmente semplice da diventare meravigliosa: prendere 40 sconosciuti e, a coppie, chiedere loro di baciarsi per la prima volta. Ne viene fuori una\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/quanto-e-bello-baciare-uno-sconosciuto\/\" \/>\n<meta property=\"og:site_name\" content=\"Video incredibili dai quattro angoli del mondo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2014-03-12T10:11:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-03-28T12:20:55+00:00\" \/>\n<meta name=\"author\" content=\"Marco Parella\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marco Parella\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/quanto-e-bello-baciare-uno-sconosciuto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/quanto-e-bello-baciare-uno-sconosciuto\\\/\"},\"author\":{\"name\":\"Marco Parella\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/#\\\/schema\\\/person\\\/f921a67b9c10c27a15dcb36a625eb047\"},\"headline\":\"Quanto \u00e8 bello baciare uno sconosciuto\",\"datePublished\":\"2014-03-12T10:11:51+00:00\",\"dateModified\":\"2014-03-28T12:20:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/quanto-e-bello-baciare-uno-sconosciuto\\\/\"},\"wordCount\":102,\"commentCount\":0,\"keywords\":[\"bacio\",\"first kiss\",\"sconosciuti\"],\"articleSection\":[\"romantici\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/quanto-e-bello-baciare-uno-sconosciuto\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/quanto-e-bello-baciare-uno-sconosciuto\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/quanto-e-bello-baciare-uno-sconosciuto\\\/\",\"name\":\"Quanto \u00e8 bello baciare uno sconosciuto - Video incredibili dai quattro angoli del mondo\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/#website\"},\"datePublished\":\"2014-03-12T10:11:51+00:00\",\"dateModified\":\"2014-03-28T12:20:55+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/#\\\/schema\\\/person\\\/f921a67b9c10c27a15dcb36a625eb047\"},\"description\":\"Un'idea talmente semplice da diventare meravigliosa: prendere 40 sconosciuti e, a coppie, chiedere loro di baciarsi per la prima volta. Ne viene fuori una\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/quanto-e-bello-baciare-uno-sconosciuto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/quanto-e-bello-baciare-uno-sconosciuto\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/quanto-e-bello-baciare-uno-sconosciuto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quanto \u00e8 bello baciare uno sconosciuto\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/#website\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/\",\"name\":\"Video incredibili dai quattro angoli del mondo\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/#\\\/schema\\\/person\\\/f921a67b9c10c27a15dcb36a625eb047\",\"name\":\"Marco Parella\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/da9594f08a0387d5c059e65cd1f43d2d3502faed5d770e37ed8dcd6bf2911969?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/da9594f08a0387d5c059e65cd1f43d2d3502faed5d770e37ed8dcd6bf2911969?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/da9594f08a0387d5c059e65cd1f43d2d3502faed5d770e37ed8dcd6bf2911969?s=96&d=mm&r=g\",\"caption\":\"Marco Parella\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/MarcoParella\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/video-incredibili-dai-quattro-angoli-del-mondo\\\/author\\\/marco-parella\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quanto \u00e8 bello baciare uno sconosciuto - Video incredibili dai quattro angoli del mondo","description":"Un'idea talmente semplice da diventare meravigliosa: prendere 40 sconosciuti e, a coppie, chiedere loro di baciarsi per la prima volta. Ne viene fuori una","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/quanto-e-bello-baciare-uno-sconosciuto\/","og_locale":"it_IT","og_type":"article","og_title":"Quanto \u00e8 bello baciare uno sconosciuto - Video incredibili dai quattro angoli del mondo","og_description":"Un'idea talmente semplice da diventare meravigliosa: prendere 40 sconosciuti e, a coppie, chiedere loro di baciarsi per la prima volta. Ne viene fuori una","og_url":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/quanto-e-bello-baciare-uno-sconosciuto\/","og_site_name":"Video incredibili dai quattro angoli del mondo","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2014-03-12T10:11:51+00:00","article_modified_time":"2014-03-28T12:20:55+00:00","author":"Marco Parella","twitter_misc":{"Scritto da":"Marco Parella"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/quanto-e-bello-baciare-uno-sconosciuto\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/quanto-e-bello-baciare-uno-sconosciuto\/"},"author":{"name":"Marco Parella","@id":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/#\/schema\/person\/f921a67b9c10c27a15dcb36a625eb047"},"headline":"Quanto \u00e8 bello baciare uno sconosciuto","datePublished":"2014-03-12T10:11:51+00:00","dateModified":"2014-03-28T12:20:55+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/quanto-e-bello-baciare-uno-sconosciuto\/"},"wordCount":102,"commentCount":0,"keywords":["bacio","first kiss","sconosciuti"],"articleSection":["romantici"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/quanto-e-bello-baciare-uno-sconosciuto\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/quanto-e-bello-baciare-uno-sconosciuto\/","url":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/quanto-e-bello-baciare-uno-sconosciuto\/","name":"Quanto \u00e8 bello baciare uno sconosciuto - Video incredibili dai quattro angoli del mondo","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/#website"},"datePublished":"2014-03-12T10:11:51+00:00","dateModified":"2014-03-28T12:20:55+00:00","author":{"@id":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/#\/schema\/person\/f921a67b9c10c27a15dcb36a625eb047"},"description":"Un'idea talmente semplice da diventare meravigliosa: prendere 40 sconosciuti e, a coppie, chiedere loro di baciarsi per la prima volta. Ne viene fuori una","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/quanto-e-bello-baciare-uno-sconosciuto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/quanto-e-bello-baciare-uno-sconosciuto\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/quanto-e-bello-baciare-uno-sconosciuto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/"},{"@type":"ListItem","position":2,"name":"Quanto \u00e8 bello baciare uno sconosciuto"}]},{"@type":"WebSite","@id":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/#website","url":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/","name":"Video incredibili dai quattro angoli del mondo","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"http:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/#\/schema\/person\/f921a67b9c10c27a15dcb36a625eb047","name":"Marco Parella","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/da9594f08a0387d5c059e65cd1f43d2d3502faed5d770e37ed8dcd6bf2911969?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/da9594f08a0387d5c059e65cd1f43d2d3502faed5d770e37ed8dcd6bf2911969?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/da9594f08a0387d5c059e65cd1f43d2d3502faed5d770e37ed8dcd6bf2911969?s=96&d=mm&r=g","caption":"Marco Parella"},"sameAs":["https:\/\/x.com\/MarcoParella"],"url":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/author\/marco-parella\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/wp-json\/wp\/v2\/posts\/120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/wp-json\/wp\/v2\/users\/945"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/wp-json\/wp\/v2\/comments?post=120"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/wp-json\/wp\/v2\/posts\/120\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/wp-json\/wp\/v2\/media?parent=120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/wp-json\/wp\/v2\/categories?post=120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/video-incredibili-dai-quattro-angoli-del-mondo\/wp-json\/wp\/v2\/tags?post=120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}