{"id":770,"date":"2014-10-30T13:23:44","date_gmt":"2014-10-30T12:23:44","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/torinopuofarcela\/?p=770"},"modified":"2014-10-30T13:23:44","modified_gmt":"2014-10-30T12:23:44","slug":"belgio-negli-anni-delleuro","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/belgio-negli-anni-delleuro\/","title":{"rendered":"Il Belgio negli anni dell&#8217;euro"},"content":{"rendered":"<figure id=\"attachment_771\" aria-describedby=\"caption-attachment-771\" style=\"width: 911px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.quotidianopiemontese.it\/torinopuofarcela\/files\/2014\/10\/141030-bdp-del-belgio.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-771\" src=\"http:\/\/www.quotidianopiemontese.it\/torinopuofarcela\/files\/2014\/10\/141030-bdp-del-belgio.jpg\" alt=\"Anche per il Belgio gli anni dell'euro sono stati anni di progressivo peggioramento delle partite correnti della sua bilancia dei pagamenti\" width=\"911\" height=\"623\" srcset=\"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/files\/2014\/10\/141030-bdp-del-belgio.jpg 911w, https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/files\/2014\/10\/141030-bdp-del-belgio-300x205.jpg 300w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/a><figcaption id=\"caption-attachment-771\" class=\"wp-caption-text\">Anche per il Belgio gli anni dell&#8217;euro sono stati anni di progressivo peggioramento delle partite correnti della sua bilancia dei pagamenti<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":24,"featured_media":771,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,4],"tags":[133,134,121],"class_list":["post-770","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia-e-finanza","category-unione-europea","tag-belgio","tag-bilancia-dei-pagamenti","tag-euro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il Belgio negli anni dell&#039;euro - Torino puo&#039; farcela<\/title>\n<meta name=\"description\" content=\"Per il Belgio gli anni dell&#039;euro hanno significato un progressivo peggioramento dei conti con l&#039;estero.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/belgio-negli-anni-delleuro\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il Belgio negli anni dell&#039;euro - Torino puo&#039; farcela\" \/>\n<meta property=\"og:description\" content=\"Per il Belgio gli anni dell&#039;euro hanno significato un progressivo peggioramento dei conti con l&#039;estero.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/belgio-negli-anni-delleuro\/\" \/>\n<meta property=\"og:site_name\" content=\"Torino puo&#039; farcela\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2014-10-30T12:23:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/files\/2014\/10\/141030-bdp-del-belgio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"911\" \/>\n\t<meta property=\"og:image:height\" content=\"623\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gustavo Rinaldi\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gustavo Rinaldi\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/belgio-negli-anni-delleuro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/belgio-negli-anni-delleuro\\\/\"},\"author\":{\"name\":\"Gustavo Rinaldi\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#\\\/schema\\\/person\\\/8b80d88227572133798036d6f1fb2057\"},\"headline\":\"Il Belgio negli anni dell&#8217;euro\",\"datePublished\":\"2014-10-30T12:23:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/belgio-negli-anni-delleuro\\\/\"},\"wordCount\":35,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/belgio-negli-anni-delleuro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/files\\\/2014\\\/10\\\/141030-bdp-del-belgio.jpg\",\"keywords\":[\"Belgio\",\"Bilancia dei pagamenti\",\"Euro\"],\"articleSection\":[\"Economia e finanza\",\"Unione Europea\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/belgio-negli-anni-delleuro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/belgio-negli-anni-delleuro\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/belgio-negli-anni-delleuro\\\/\",\"name\":\"Il Belgio negli anni dell'euro - Torino puo&#039; farcela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/belgio-negli-anni-delleuro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/belgio-negli-anni-delleuro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/files\\\/2014\\\/10\\\/141030-bdp-del-belgio.jpg\",\"datePublished\":\"2014-10-30T12:23:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#\\\/schema\\\/person\\\/8b80d88227572133798036d6f1fb2057\"},\"description\":\"Per il Belgio gli anni dell'euro hanno significato un progressivo peggioramento dei conti con l'estero.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/belgio-negli-anni-delleuro\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/belgio-negli-anni-delleuro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/belgio-negli-anni-delleuro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/files\\\/2014\\\/10\\\/141030-bdp-del-belgio.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/files\\\/2014\\\/10\\\/141030-bdp-del-belgio.jpg\",\"width\":911,\"height\":623,\"caption\":\"Anche per il Belgio gli anni dell'euro sono stati anni di progressivo peggioramento delle partite correnti della sua bilancia dei pagamenti\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/belgio-negli-anni-delleuro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il Belgio negli anni dell&#8217;euro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/\",\"name\":\"Torino puo&#039; farcela\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#\\\/schema\\\/person\\\/8b80d88227572133798036d6f1fb2057\",\"name\":\"Gustavo Rinaldi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g\",\"caption\":\"Gustavo Rinaldi\"},\"description\":\"Nato a Torino nel 1967, la sua prima maestra e` stata una vittima delle repressioni bolsceviche, Maria Bruch. Ha frequentato sia la scuola pubblica che quella dei Gesuiti. Come volontario ha promosso prima una raccolta carta e poi la riorganizzazione del gentro di formazione agricola di Andriamboasary in Madagascar. Ha fondato l'associazione Enthusiasmus che per piu' di dieci anni si e` occupata di formazione politico-sociale dei giovani, permettendo a molti giovani di conoscere il mondo esterno ed a qualcuno\\\/a di trovare moglie o marito. Nel 1991 e` stato testimone oculare dei moti di piazza che a Leningrado si opponevano al tentato golpe anti-riformatore. Nel 1994 si e` laureato in economia con Sergio Ricossa ed ha prestato servizio presso l'Istituto Penale Minorile \\\"Ferrante Aporti\\\", occupandosi dei denari e delle spese dei detenuti. Dal 1995 ha iniziato a lavorare per diversi progetti di valutazione e formazione promossi dall'Unione Europea e da altri enti nell'ex Unione Sovietica. Nel 2000-2001 e` stato consigliere economico del governo della Georgia. Nel 2006 ha conseguito il Ph.D. in economics all'Imperial College dell'University of London. Ha lavorato come economista per l'Institute of Alcohol Studies di Londra. Dal 2008 lavora per l'universita' di Torino dove oggi insegna public economics; insegna inoltre fundamentals in mathematics ed economics for managers ad ESCP-Europe.\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/author\\\/gustavo-rinaldi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il Belgio negli anni dell'euro - Torino puo&#039; farcela","description":"Per il Belgio gli anni dell'euro hanno significato un progressivo peggioramento dei conti con l'estero.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/belgio-negli-anni-delleuro\/","og_locale":"it_IT","og_type":"article","og_title":"Il Belgio negli anni dell'euro - Torino puo&#039; farcela","og_description":"Per il Belgio gli anni dell'euro hanno significato un progressivo peggioramento dei conti con l'estero.","og_url":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/belgio-negli-anni-delleuro\/","og_site_name":"Torino puo&#039; farcela","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2014-10-30T12:23:44+00:00","og_image":[{"width":911,"height":623,"url":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/files\/2014\/10\/141030-bdp-del-belgio.jpg","type":"image\/jpeg"}],"author":"Gustavo Rinaldi","twitter_misc":{"Scritto da":"Gustavo Rinaldi"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/belgio-negli-anni-delleuro\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/belgio-negli-anni-delleuro\/"},"author":{"name":"Gustavo Rinaldi","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#\/schema\/person\/8b80d88227572133798036d6f1fb2057"},"headline":"Il Belgio negli anni dell&#8217;euro","datePublished":"2014-10-30T12:23:44+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/belgio-negli-anni-delleuro\/"},"wordCount":35,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/belgio-negli-anni-delleuro\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/files\/2014\/10\/141030-bdp-del-belgio.jpg","keywords":["Belgio","Bilancia dei pagamenti","Euro"],"articleSection":["Economia e finanza","Unione Europea"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/belgio-negli-anni-delleuro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/belgio-negli-anni-delleuro\/","url":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/belgio-negli-anni-delleuro\/","name":"Il Belgio negli anni dell'euro - Torino puo&#039; farcela","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/belgio-negli-anni-delleuro\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/belgio-negli-anni-delleuro\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/files\/2014\/10\/141030-bdp-del-belgio.jpg","datePublished":"2014-10-30T12:23:44+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#\/schema\/person\/8b80d88227572133798036d6f1fb2057"},"description":"Per il Belgio gli anni dell'euro hanno significato un progressivo peggioramento dei conti con l'estero.","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/belgio-negli-anni-delleuro\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/belgio-negli-anni-delleuro\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/belgio-negli-anni-delleuro\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/files\/2014\/10\/141030-bdp-del-belgio.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/files\/2014\/10\/141030-bdp-del-belgio.jpg","width":911,"height":623,"caption":"Anche per il Belgio gli anni dell'euro sono stati anni di progressivo peggioramento delle partite correnti della sua bilancia dei pagamenti"},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/belgio-negli-anni-delleuro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/"},{"@type":"ListItem","position":2,"name":"Il Belgio negli anni dell&#8217;euro"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#website","url":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/","name":"Torino puo&#039; farcela","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#\/schema\/person\/8b80d88227572133798036d6f1fb2057","name":"Gustavo Rinaldi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g","caption":"Gustavo Rinaldi"},"description":"Nato a Torino nel 1967, la sua prima maestra e` stata una vittima delle repressioni bolsceviche, Maria Bruch. Ha frequentato sia la scuola pubblica che quella dei Gesuiti. Come volontario ha promosso prima una raccolta carta e poi la riorganizzazione del gentro di formazione agricola di Andriamboasary in Madagascar. Ha fondato l'associazione Enthusiasmus che per piu' di dieci anni si e` occupata di formazione politico-sociale dei giovani, permettendo a molti giovani di conoscere il mondo esterno ed a qualcuno\/a di trovare moglie o marito. Nel 1991 e` stato testimone oculare dei moti di piazza che a Leningrado si opponevano al tentato golpe anti-riformatore. Nel 1994 si e` laureato in economia con Sergio Ricossa ed ha prestato servizio presso l'Istituto Penale Minorile \"Ferrante Aporti\", occupandosi dei denari e delle spese dei detenuti. Dal 1995 ha iniziato a lavorare per diversi progetti di valutazione e formazione promossi dall'Unione Europea e da altri enti nell'ex Unione Sovietica. Nel 2000-2001 e` stato consigliere economico del governo della Georgia. Nel 2006 ha conseguito il Ph.D. in economics all'Imperial College dell'University of London. Ha lavorato come economista per l'Institute of Alcohol Studies di Londra. Dal 2008 lavora per l'universita' di Torino dove oggi insegna public economics; insegna inoltre fundamentals in mathematics ed economics for managers ad ESCP-Europe.","url":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/author\/gustavo-rinaldi\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/posts\/770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/comments?post=770"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/posts\/770\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/media\/771"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/media?parent=770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/categories?post=770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/tags?post=770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}