{"id":463,"date":"2011-11-14T22:40:02","date_gmt":"2011-11-14T21:40:02","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/torinopuofarcela\/?p=463"},"modified":"2011-11-14T22:40:02","modified_gmt":"2011-11-14T21:40:02","slug":"milena-gabanelli-contro-il-contante","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/milena-gabanelli-contro-il-contante\/","title":{"rendered":"Milena Gabanelli contro il contante"},"content":{"rendered":"<p>Giorni fa in un articolo intitolato &#8220;<a href=\"http:\/\/www.quotidianopiemontese.it\/torinopuofarcela\/2011\/10\/27\/per-crescere\/\">Per Crescere<\/a>&#8221; suggerivo (al punto \u00a09) la progressiva abolizione del contante.<\/p>\n<p>Oggi e` bello scoprire che anche una donna intelligente e coraggiosa come Milena Gabanelli sostiene la stessa idea sul <a href=\"http:\/\/www.corriere.it\/inchieste\/reportime\/economia\/11_novembre_12\/fine-del-sommerso_099fe7d6-0d3f-11e1-a42a-1562b6741916.shtml\">Corriere della Sera<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Giorni fa in un articolo intitolato &#8220;Per Crescere&#8221; suggerivo (al punto \u00a09) la progressiva abolizione del contante. Oggi e` bello scoprire che anche una donna intelligente e coraggiosa come Milena Gabanelli sostiene la stessa idea sul Corriere della Sera.<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-463","post","type-post","status-publish","format-standard","hentry","category-forino-puo-farcela"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Milena Gabanelli contro il contante - Torino puo&#039; farcela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/milena-gabanelli-contro-il-contante\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Milena Gabanelli contro il contante - Torino puo&#039; farcela\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/milena-gabanelli-contro-il-contante\/\" \/>\n<meta property=\"og:site_name\" content=\"Torino puo&#039; farcela\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2011-11-14T21:40:02+00:00\" \/>\n<meta name=\"author\" content=\"Gustavo Rinaldi\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gustavo Rinaldi\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/milena-gabanelli-contro-il-contante\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/milena-gabanelli-contro-il-contante\\\/\"},\"author\":{\"name\":\"Gustavo Rinaldi\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#\\\/schema\\\/person\\\/8b80d88227572133798036d6f1fb2057\"},\"headline\":\"Milena Gabanelli contro il contante\",\"datePublished\":\"2011-11-14T21:40:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/milena-gabanelli-contro-il-contante\\\/\"},\"wordCount\":43,\"commentCount\":0,\"articleSection\":[\"Torino pu\u00f2 farcela\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/milena-gabanelli-contro-il-contante\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/milena-gabanelli-contro-il-contante\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/milena-gabanelli-contro-il-contante\\\/\",\"name\":\"Milena Gabanelli contro il contante - Torino puo&#039; farcela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#website\"},\"datePublished\":\"2011-11-14T21:40:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#\\\/schema\\\/person\\\/8b80d88227572133798036d6f1fb2057\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/milena-gabanelli-contro-il-contante\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/milena-gabanelli-contro-il-contante\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/milena-gabanelli-contro-il-contante\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Milena Gabanelli contro il contante\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/\",\"name\":\"Torino puo&#039; farcela\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#\\\/schema\\\/person\\\/8b80d88227572133798036d6f1fb2057\",\"name\":\"Gustavo Rinaldi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g\",\"caption\":\"Gustavo Rinaldi\"},\"description\":\"Nato a Torino nel 1967, la sua prima maestra e` stata una vittima delle repressioni bolsceviche, Maria Bruch. Ha frequentato sia la scuola pubblica che quella dei Gesuiti. Come volontario ha promosso prima una raccolta carta e poi la riorganizzazione del gentro di formazione agricola di Andriamboasary in Madagascar. Ha fondato l'associazione Enthusiasmus che per piu' di dieci anni si e` occupata di formazione politico-sociale dei giovani, permettendo a molti giovani di conoscere il mondo esterno ed a qualcuno\\\/a di trovare moglie o marito. Nel 1991 e` stato testimone oculare dei moti di piazza che a Leningrado si opponevano al tentato golpe anti-riformatore. Nel 1994 si e` laureato in economia con Sergio Ricossa ed ha prestato servizio presso l'Istituto Penale Minorile \\\"Ferrante Aporti\\\", occupandosi dei denari e delle spese dei detenuti. Dal 1995 ha iniziato a lavorare per diversi progetti di valutazione e formazione promossi dall'Unione Europea e da altri enti nell'ex Unione Sovietica. Nel 2000-2001 e` stato consigliere economico del governo della Georgia. Nel 2006 ha conseguito il Ph.D. in economics all'Imperial College dell'University of London. Ha lavorato come economista per l'Institute of Alcohol Studies di Londra. Dal 2008 lavora per l'universita' di Torino dove oggi insegna public economics; insegna inoltre fundamentals in mathematics ed economics for managers ad ESCP-Europe.\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/author\\\/gustavo-rinaldi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Milena Gabanelli contro il contante - Torino puo&#039; farcela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/milena-gabanelli-contro-il-contante\/","og_locale":"it_IT","og_type":"article","og_title":"Milena Gabanelli contro il contante - Torino puo&#039; farcela","og_url":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/milena-gabanelli-contro-il-contante\/","og_site_name":"Torino puo&#039; farcela","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2011-11-14T21:40:02+00:00","author":"Gustavo Rinaldi","twitter_misc":{"Scritto da":"Gustavo Rinaldi"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/milena-gabanelli-contro-il-contante\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/milena-gabanelli-contro-il-contante\/"},"author":{"name":"Gustavo Rinaldi","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#\/schema\/person\/8b80d88227572133798036d6f1fb2057"},"headline":"Milena Gabanelli contro il contante","datePublished":"2011-11-14T21:40:02+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/milena-gabanelli-contro-il-contante\/"},"wordCount":43,"commentCount":0,"articleSection":["Torino pu\u00f2 farcela"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/milena-gabanelli-contro-il-contante\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/milena-gabanelli-contro-il-contante\/","url":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/milena-gabanelli-contro-il-contante\/","name":"Milena Gabanelli contro il contante - Torino puo&#039; farcela","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#website"},"datePublished":"2011-11-14T21:40:02+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#\/schema\/person\/8b80d88227572133798036d6f1fb2057"},"breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/milena-gabanelli-contro-il-contante\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/milena-gabanelli-contro-il-contante\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/milena-gabanelli-contro-il-contante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/"},{"@type":"ListItem","position":2,"name":"Milena Gabanelli contro il contante"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#website","url":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/","name":"Torino puo&#039; farcela","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#\/schema\/person\/8b80d88227572133798036d6f1fb2057","name":"Gustavo Rinaldi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g","caption":"Gustavo Rinaldi"},"description":"Nato a Torino nel 1967, la sua prima maestra e` stata una vittima delle repressioni bolsceviche, Maria Bruch. Ha frequentato sia la scuola pubblica che quella dei Gesuiti. Come volontario ha promosso prima una raccolta carta e poi la riorganizzazione del gentro di formazione agricola di Andriamboasary in Madagascar. Ha fondato l'associazione Enthusiasmus che per piu' di dieci anni si e` occupata di formazione politico-sociale dei giovani, permettendo a molti giovani di conoscere il mondo esterno ed a qualcuno\/a di trovare moglie o marito. Nel 1991 e` stato testimone oculare dei moti di piazza che a Leningrado si opponevano al tentato golpe anti-riformatore. Nel 1994 si e` laureato in economia con Sergio Ricossa ed ha prestato servizio presso l'Istituto Penale Minorile \"Ferrante Aporti\", occupandosi dei denari e delle spese dei detenuti. Dal 1995 ha iniziato a lavorare per diversi progetti di valutazione e formazione promossi dall'Unione Europea e da altri enti nell'ex Unione Sovietica. Nel 2000-2001 e` stato consigliere economico del governo della Georgia. Nel 2006 ha conseguito il Ph.D. in economics all'Imperial College dell'University of London. Ha lavorato come economista per l'Institute of Alcohol Studies di Londra. Dal 2008 lavora per l'universita' di Torino dove oggi insegna public economics; insegna inoltre fundamentals in mathematics ed economics for managers ad ESCP-Europe.","url":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/author\/gustavo-rinaldi\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/posts\/463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/comments?post=463"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/posts\/463\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/media?parent=463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/categories?post=463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/tags?post=463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}