{"id":39,"date":"2008-06-29T21:09:22","date_gmt":"2008-06-29T21:09:22","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/torinopuofarcela\/2008\/06\/29\/a-torino-ce-pos\/"},"modified":"2008-06-29T21:09:22","modified_gmt":"2008-06-29T21:09:22","slug":"a-torino-ce-pos","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/a-torino-ce-pos\/","title":{"rendered":"A Torino c`e` posto per l&#8217;Hockey?"},"content":{"rendered":"<p>Riceviamo e volentieri pubblichiamo:<\/p>\n<p>Le scrivo per esprimere la mia amarezza e la mia proccupazione. Sono un <br \/>tifoso di Hockey in particolare dell&#8217;Hcvalpellice squadra di A2. <br \/>L&#8217;ultima stagione si era creato una nuova positiva realt\u00e0 il &quot;derby&quot; con <br \/>l&#8217;allstar piemonte squadra torinese sita al Palatazzoli. I derby erano <br \/>seguiti da 2000 persone allo stadio pi\u00f9 altre alla radio Rbe di Torre <br \/>pellice in streaming in tutta l&#8217;Italia hockeistica. Arrivo al punto, <br \/>quest&#8217;anno l&#8217;AllStar non avr\u00e0 una squadra di A2 perch\u00e8 in una citt\u00e0 come <br \/>Torino non hanno trovato appoggi e sponsor. La fine delle attivit\u00e0 di La <br \/>Presse e la mancata iscrizione dell&#8217;All Star mi fa pensare a come fa <br \/>Torino ad avere solo due squadre di calcio, per il resto deserto. Gli <br \/>altri sport sono sostenuti da privati cittadini guidati da passione e <br \/>istituzioni come la Regione.<br \/>A mio avviso \u00e8 un grave problema culturale, si parla di costruire <br \/>grattacieli e non si sponsorizza lo Sport a Torino perch\u00e8 non ha <br \/>visibilit\u00e0. Le aziende che operano in Torino hanno come tutte le aziende <br \/>il dovere di essere di aiuto alla societ\u00e0 in cui operano. Una sociaet\u00e0 <br \/>senza sport manca di un grande momento di educazione per i propri <br \/>giovani dei valori dello sport quali il gioco di squadra, il ripetto di <br \/>regole, l&#8217;amicizia etc. Non ci si pu\u00f2 lamentare che i ragazzi vadano a <br \/>distruggere edifici pubblici alle porte di Torino o si arrampicano sui <br \/>treni rimanendo folgorati, per rompere la noia, se non c&#8217;\u00e8 alternativa. <br \/>Ripeto che a Torino non ci siano squadre di Hockey, pallavolo, basket, <br \/>nuoto di discreto livello come in TUTTE le citt\u00e0 europee e preoccupante. <br \/>Quanti ragazzi si appassionerebbero ad uno sport passando i pomeriggi a <br \/>copiare le gesta dei propri beniamini evitando di rovinarsi la vita <br \/>facendo stupidaggini se ci fosse variet\u00e0 di offerte sportive nella citt\u00e0?<br \/>Buon lavoro<\/p>\n<p> Simone Bertalot.<\/p>\n<p>_____________________________________________<br \/>Certamente&nbsp; &nbsp;l&#8217;assenza dell&#8217;hockey e` un segno di poverta`. Siamo sovraccarichi di palazzetti dello sport e non riusciamo a mantenere una squadra di hockey.&nbsp; Si e` pensato tanto agli edifici (spesso brutti ed inefficienti) e poco agli uomini.<br \/>I torinesi con le olimpiadi si sono presi una gran sborgna ed ora stanno arrivando i problemi del giorno dopo. La citta` e` carica di debiti&nbsp; e non sta a guardare tanto cio&#8217; che serve o cio&#8217; che non serve. Risparmia dove puo&#8217;. Dove non ci sono gruppi organizzati in grado di protestare troppo.<br \/>Molta colpa e` dell&#8217;amministrazione comunale, nel sostanziale silenzio connivente dell&#8217;opposizione.<br \/>La colpa piu&#8217; grande e` pero&#8217; quella dei Torinesi che han preso la droga olimpica (soldi, soldi, soldi) senza stare a pensarci troppo su&#8217;, semplicemente ubriacati dalla pioggia di denaro che si riversava sulla citta&#8217;.<br \/>C`e` un grande cambiamento che dobbiamo fare tutti per diventare piu&#8217; coscienti e responsabili ed e` un cammino tutto in salita. Anche io e lei probabilmente dobbiamo cambiare.<\/p>\n<p>Cordiali saluti<br \/>Gustavo Rinaldi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo: Le scrivo per esprimere la mia amarezza e la mia proccupazione. Sono un tifoso di Hockey in particolare dell&#8217;Hcvalpellice squadra di A2. L&#8217;ultima stagione si era creato una nuova positiva realt\u00e0 il &quot;derby&quot; con l&#8217;allstar piemonte squadra torinese sita al Palatazzoli. I derby erano seguiti da 2000 persone allo stadio pi\u00f9 &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/a-torino-ce-pos\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;A Torino c`e` posto per l&#8217;Hockey?&#8221;<\/span><\/a><\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30],"tags":[],"class_list":["post-39","post","type-post","status-publish","format-standard","hentry","category-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A Torino c`e` posto per l&#039;Hockey? - Torino puo&#039; farcela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/a-torino-ce-pos\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Torino c`e` posto per l&#039;Hockey? - Torino puo&#039; farcela\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/a-torino-ce-pos\/\" \/>\n<meta property=\"og:site_name\" content=\"Torino puo&#039; farcela\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2008-06-29T21:09:22+00:00\" \/>\n<meta name=\"author\" content=\"Gustavo Rinaldi\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gustavo Rinaldi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/a-torino-ce-pos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/a-torino-ce-pos\\\/\"},\"author\":{\"name\":\"Gustavo Rinaldi\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#\\\/schema\\\/person\\\/8b80d88227572133798036d6f1fb2057\"},\"headline\":\"A Torino c`e` posto per l&#8217;Hockey?\",\"datePublished\":\"2008-06-29T21:09:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/a-torino-ce-pos\\\/\"},\"wordCount\":500,\"commentCount\":0,\"articleSection\":[\"Sport\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/a-torino-ce-pos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/a-torino-ce-pos\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/a-torino-ce-pos\\\/\",\"name\":\"A Torino c`e` posto per l'Hockey? - Torino puo&#039; farcela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#website\"},\"datePublished\":\"2008-06-29T21:09:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#\\\/schema\\\/person\\\/8b80d88227572133798036d6f1fb2057\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/a-torino-ce-pos\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/a-torino-ce-pos\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/a-torino-ce-pos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Torino c`e` posto per l&#8217;Hockey?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/\",\"name\":\"Torino puo&#039; farcela\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#\\\/schema\\\/person\\\/8b80d88227572133798036d6f1fb2057\",\"name\":\"Gustavo Rinaldi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g\",\"caption\":\"Gustavo Rinaldi\"},\"description\":\"Nato a Torino nel 1967, la sua prima maestra e` stata una vittima delle repressioni bolsceviche, Maria Bruch. Ha frequentato sia la scuola pubblica che quella dei Gesuiti. Come volontario ha promosso prima una raccolta carta e poi la riorganizzazione del gentro di formazione agricola di Andriamboasary in Madagascar. Ha fondato l'associazione Enthusiasmus che per piu' di dieci anni si e` occupata di formazione politico-sociale dei giovani, permettendo a molti giovani di conoscere il mondo esterno ed a qualcuno\\\/a di trovare moglie o marito. Nel 1991 e` stato testimone oculare dei moti di piazza che a Leningrado si opponevano al tentato golpe anti-riformatore. Nel 1994 si e` laureato in economia con Sergio Ricossa ed ha prestato servizio presso l'Istituto Penale Minorile \\\"Ferrante Aporti\\\", occupandosi dei denari e delle spese dei detenuti. Dal 1995 ha iniziato a lavorare per diversi progetti di valutazione e formazione promossi dall'Unione Europea e da altri enti nell'ex Unione Sovietica. Nel 2000-2001 e` stato consigliere economico del governo della Georgia. Nel 2006 ha conseguito il Ph.D. in economics all'Imperial College dell'University of London. Ha lavorato come economista per l'Institute of Alcohol Studies di Londra. Dal 2008 lavora per l'universita' di Torino dove oggi insegna public economics; insegna inoltre fundamentals in mathematics ed economics for managers ad ESCP-Europe.\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/author\\\/gustavo-rinaldi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Torino c`e` posto per l'Hockey? - Torino puo&#039; farcela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/a-torino-ce-pos\/","og_locale":"it_IT","og_type":"article","og_title":"A Torino c`e` posto per l'Hockey? - Torino puo&#039; farcela","og_url":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/a-torino-ce-pos\/","og_site_name":"Torino puo&#039; farcela","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2008-06-29T21:09:22+00:00","author":"Gustavo Rinaldi","twitter_misc":{"Scritto da":"Gustavo Rinaldi","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/a-torino-ce-pos\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/a-torino-ce-pos\/"},"author":{"name":"Gustavo Rinaldi","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#\/schema\/person\/8b80d88227572133798036d6f1fb2057"},"headline":"A Torino c`e` posto per l&#8217;Hockey?","datePublished":"2008-06-29T21:09:22+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/a-torino-ce-pos\/"},"wordCount":500,"commentCount":0,"articleSection":["Sport"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/a-torino-ce-pos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/a-torino-ce-pos\/","url":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/a-torino-ce-pos\/","name":"A Torino c`e` posto per l'Hockey? - Torino puo&#039; farcela","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#website"},"datePublished":"2008-06-29T21:09:22+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#\/schema\/person\/8b80d88227572133798036d6f1fb2057"},"breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/a-torino-ce-pos\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/a-torino-ce-pos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/a-torino-ce-pos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/"},{"@type":"ListItem","position":2,"name":"A Torino c`e` posto per l&#8217;Hockey?"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#website","url":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/","name":"Torino puo&#039; farcela","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#\/schema\/person\/8b80d88227572133798036d6f1fb2057","name":"Gustavo Rinaldi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g","caption":"Gustavo Rinaldi"},"description":"Nato a Torino nel 1967, la sua prima maestra e` stata una vittima delle repressioni bolsceviche, Maria Bruch. Ha frequentato sia la scuola pubblica che quella dei Gesuiti. Come volontario ha promosso prima una raccolta carta e poi la riorganizzazione del gentro di formazione agricola di Andriamboasary in Madagascar. Ha fondato l'associazione Enthusiasmus che per piu' di dieci anni si e` occupata di formazione politico-sociale dei giovani, permettendo a molti giovani di conoscere il mondo esterno ed a qualcuno\/a di trovare moglie o marito. Nel 1991 e` stato testimone oculare dei moti di piazza che a Leningrado si opponevano al tentato golpe anti-riformatore. Nel 1994 si e` laureato in economia con Sergio Ricossa ed ha prestato servizio presso l'Istituto Penale Minorile \"Ferrante Aporti\", occupandosi dei denari e delle spese dei detenuti. Dal 1995 ha iniziato a lavorare per diversi progetti di valutazione e formazione promossi dall'Unione Europea e da altri enti nell'ex Unione Sovietica. Nel 2000-2001 e` stato consigliere economico del governo della Georgia. Nel 2006 ha conseguito il Ph.D. in economics all'Imperial College dell'University of London. Ha lavorato come economista per l'Institute of Alcohol Studies di Londra. Dal 2008 lavora per l'universita' di Torino dove oggi insegna public economics; insegna inoltre fundamentals in mathematics ed economics for managers ad ESCP-Europe.","url":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/author\/gustavo-rinaldi\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/posts\/39","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/comments?post=39"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/posts\/39\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/media?parent=39"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/categories?post=39"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/tags?post=39"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}