{"id":228,"date":"2005-12-15T10:04:19","date_gmt":"2005-12-15T10:04:19","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/torinopuofarcela\/2005\/12\/15\/ricerca_occhio_\/"},"modified":"2005-12-15T10:04:19","modified_gmt":"2005-12-15T10:04:19","slug":"ricerca_occhio_","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/ricerca_occhio_\/","title":{"rendered":"Ricerca: occhio alla scuola."},"content":{"rendered":"<p class=\"MsoNormal\"><span lang=\"IT\">La ricerca scientifica<br \/>\ne` una specie di catena di attivita`<br \/>\ncollegate, dove la prima e` necessaria perche` ci possa essere la seconda e<br \/>\ncosi via. Tecnicamente questo si chiama \u201cfiliera\u201d. Un esempio di filiera e`<br \/>\nquella del pane : agricoltore \u2013 commerciante di grano \u2013 mulino \u2013 commerciante<br \/>\ndi farina \u2013 panificatore \u2013 rivendita pane. La ricerca e` qualcosa di simile.<br \/>\nAlla base della filiera della ricerca probabilmente c`e` la scuola, elementare<br \/>\ne materna. E` li\u2019 dove puo\u2019 nascere un<br \/>\ninteresse per la scienza ed e` li dove deve nascere la famigliarita` con i<br \/>\nnumeri. E` per questo che dovremo prestare particolare attenzione perche` i<br \/>\nnumeri e l`aritmetica siano insegnati bene. Possiamo pensare a forme di aiuto<br \/>\ned incentivo per insegnanti ed alunni. Gli insegnanti potrebbero essere aiutati<br \/>\ncon delle formazioni specifiche o dei sussidi didattici. Una cosa buona<br \/>\npotrebbe anche essere organizzare gare a premi di aritmetica. I premi potrebero<br \/>\nessere oggetti, es. computer, ma anche viaggi premio o corsi speciali. Per gli<br \/>\nstudenti delle superiori questo dovrebbe anche incoraggiare e finanziare&nbsp; la partecipazione alle Olimpiadi della<br \/>\nMatematica (vedi&nbsp; <a href=\"http:\/\/imo.math.ca\/\">http:\/\/imo.math.ca\/<\/a> <a href=\"http:\/\/olimpiadi.ing.unipi.it\/\">http:\/\/olimpiadi.ing.unipi.it\/<\/a> ). <\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"IT\">Dovremo in<br \/>\nparticolare curare ed aiutare la formazione di insegnanti di materie<br \/>\nscientifiche, anche prevedendo che ogni studente delle superiori studi almeno<br \/>\nuna materia scientifica un po` in profondita` (con almeno cinque ore alla<br \/>\nsettimana di lezione). Gli insegnanti dovrebbero avere la preparazione per far capire che cio` che insegnano e\u2019<br \/>\nmolto utile e` puo` risolvere molti problemi pratici. Allo stesso tempo<br \/>\ndovrebbero avere la capacita` di far capire quanto attraente sia l`argomento<br \/>\ndal punto di vista teorico. Se dovessimo accorgerci che c`e` scarsita` di insegnanti di certe materie, si<br \/>\ndovrebbe poter pagare gli insegnanti in modo differenziato. Paghiamo di piu` gli<br \/>\ninsegnanti di quelle materie che scarseggiano. Paghiamo di piu` gli insegnanti<br \/>\nche insegnano nelle scuole dove nessuno vuole insegnare. Paghiamo di meno gli<br \/>\ninsegnanti che insegnano in quelle scuole dove tutti gli insegnanti vogliono<br \/>\ninsegnare. <\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"IT\">Si trattera`<br \/>\nanche di premiare quegli insegnanti che non cessano di studiare ed approfondire<br \/>\nla loro materia, seguendo corsi di formazione, prendendo dottorati e<br \/>\npubblicando su riviste scientifiche. Tutto cio` va premiato.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"IT\">Verifichiamo che<br \/>\ni laboratori scientifici delle scuole siano ben attrezzati, aggiornati e dotati<br \/>\ndi personale di laboratorio.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"IT\">Le fondazioni<br \/>\nbancarie forse dovrebbero considerare di spendere piu` soldi nell`incentivare<br \/>\nlo studio delle scienze nelle scuole. Ovviamente questo dovrebbe valere a<br \/>\nmaggior ragione per tutti i livelli di potere pubblico (stato, regione ed enti<br \/>\nlocali).&nbsp; Troppo spesso si pensa piu` ai<br \/>\nmuri che alla qualita` delle persone.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"IT\">Troppo spesso<br \/>\nquando si pensa alla scuola se ne parla o come un posto dove effettuare nuovi<br \/>\ntagli al bilancio o dove dare un lavoro ad insegnanti in certi casi molto<br \/>\npreparati e diligenti e ad in&nbsp; altri casi no. Oppure se ne parla in termini<br \/>\ndi conflitto chiesa \u2013 stato, molto attuale, ai tempi di Cavour. Troppe volte<br \/>\npassa in secondo piano il fatto che la scuola e` per molti ragazzi l`unica<br \/>\nopportunita` che offriamo loro. Cio` e` particolarmente vero per i piu` poveri,<br \/>\nquelli piu` privi di \u201ccontatti\u201d.&nbsp; La<br \/>\nscuola e` lo strumento che essi dovrebbero avere per costruirsi una loro vita autonoma e libera.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"IT\">Una scuola non<br \/>\nadeguata per i ricchi e` una cattiva notizia, per i poveri e` un disastro.<\/span><\/p>\n<p><span lang=\"IT\">Oggi la concorrenza internazionale si basa sulla conoscenza e&nbsp; la scuola dovrebbe servire a trasmettere ed<br \/>\nacquisire questa risorsa strategica. Mettiamo questo al centro dei nostri<br \/>\nprogetti.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ricerca scientifica e` una specie di catena di attivita` collegate, dove la prima e` necessaria perche` ci possa essere la seconda e cosi via. Tecnicamente questo si chiama \u201cfiliera\u201d. Un esempio di filiera e` quella del pane : agricoltore \u2013 commerciante di grano \u2013 mulino \u2013 commerciante di farina \u2013 panificatore \u2013 rivendita pane. &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/ricerca_occhio_\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Ricerca: occhio alla scuola.&#8221;<\/span><\/a><\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48,46],"tags":[],"class_list":["post-228","post","type-post","status-publish","format-standard","hentry","category-ricerca","category-scuola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ricerca: occhio alla scuola. - Torino puo&#039; farcela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/ricerca_occhio_\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ricerca: occhio alla scuola. - Torino puo&#039; farcela\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/ricerca_occhio_\/\" \/>\n<meta property=\"og:site_name\" content=\"Torino puo&#039; farcela\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2005-12-15T10:04:19+00:00\" \/>\n<meta name=\"author\" content=\"Gustavo Rinaldi\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gustavo Rinaldi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/ricerca_occhio_\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/ricerca_occhio_\\\/\"},\"author\":{\"name\":\"Gustavo Rinaldi\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#\\\/schema\\\/person\\\/8b80d88227572133798036d6f1fb2057\"},\"headline\":\"Ricerca: occhio alla scuola.\",\"datePublished\":\"2005-12-15T10:04:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/ricerca_occhio_\\\/\"},\"wordCount\":583,\"commentCount\":0,\"articleSection\":[\"Ricerca\",\"Scuola\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/ricerca_occhio_\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/ricerca_occhio_\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/ricerca_occhio_\\\/\",\"name\":\"Ricerca: occhio alla scuola. - Torino puo&#039; farcela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#website\"},\"datePublished\":\"2005-12-15T10:04:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#\\\/schema\\\/person\\\/8b80d88227572133798036d6f1fb2057\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/ricerca_occhio_\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/ricerca_occhio_\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/ricerca_occhio_\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ricerca: occhio alla scuola.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/\",\"name\":\"Torino puo&#039; farcela\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#\\\/schema\\\/person\\\/8b80d88227572133798036d6f1fb2057\",\"name\":\"Gustavo Rinaldi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g\",\"caption\":\"Gustavo Rinaldi\"},\"description\":\"Nato a Torino nel 1967, la sua prima maestra e` stata una vittima delle repressioni bolsceviche, Maria Bruch. Ha frequentato sia la scuola pubblica che quella dei Gesuiti. Come volontario ha promosso prima una raccolta carta e poi la riorganizzazione del gentro di formazione agricola di Andriamboasary in Madagascar. Ha fondato l'associazione Enthusiasmus che per piu' di dieci anni si e` occupata di formazione politico-sociale dei giovani, permettendo a molti giovani di conoscere il mondo esterno ed a qualcuno\\\/a di trovare moglie o marito. Nel 1991 e` stato testimone oculare dei moti di piazza che a Leningrado si opponevano al tentato golpe anti-riformatore. Nel 1994 si e` laureato in economia con Sergio Ricossa ed ha prestato servizio presso l'Istituto Penale Minorile \\\"Ferrante Aporti\\\", occupandosi dei denari e delle spese dei detenuti. Dal 1995 ha iniziato a lavorare per diversi progetti di valutazione e formazione promossi dall'Unione Europea e da altri enti nell'ex Unione Sovietica. Nel 2000-2001 e` stato consigliere economico del governo della Georgia. Nel 2006 ha conseguito il Ph.D. in economics all'Imperial College dell'University of London. Ha lavorato come economista per l'Institute of Alcohol Studies di Londra. Dal 2008 lavora per l'universita' di Torino dove oggi insegna public economics; insegna inoltre fundamentals in mathematics ed economics for managers ad ESCP-Europe.\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/author\\\/gustavo-rinaldi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ricerca: occhio alla scuola. - Torino puo&#039; farcela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/ricerca_occhio_\/","og_locale":"it_IT","og_type":"article","og_title":"Ricerca: occhio alla scuola. - Torino puo&#039; farcela","og_url":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/ricerca_occhio_\/","og_site_name":"Torino puo&#039; farcela","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2005-12-15T10:04:19+00:00","author":"Gustavo Rinaldi","twitter_misc":{"Scritto da":"Gustavo Rinaldi","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/ricerca_occhio_\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/ricerca_occhio_\/"},"author":{"name":"Gustavo Rinaldi","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#\/schema\/person\/8b80d88227572133798036d6f1fb2057"},"headline":"Ricerca: occhio alla scuola.","datePublished":"2005-12-15T10:04:19+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/ricerca_occhio_\/"},"wordCount":583,"commentCount":0,"articleSection":["Ricerca","Scuola"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/ricerca_occhio_\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/ricerca_occhio_\/","url":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/ricerca_occhio_\/","name":"Ricerca: occhio alla scuola. - Torino puo&#039; farcela","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#website"},"datePublished":"2005-12-15T10:04:19+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#\/schema\/person\/8b80d88227572133798036d6f1fb2057"},"breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/ricerca_occhio_\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/ricerca_occhio_\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/ricerca_occhio_\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/"},{"@type":"ListItem","position":2,"name":"Ricerca: occhio alla scuola."}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#website","url":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/","name":"Torino puo&#039; farcela","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#\/schema\/person\/8b80d88227572133798036d6f1fb2057","name":"Gustavo Rinaldi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g","caption":"Gustavo Rinaldi"},"description":"Nato a Torino nel 1967, la sua prima maestra e` stata una vittima delle repressioni bolsceviche, Maria Bruch. Ha frequentato sia la scuola pubblica che quella dei Gesuiti. Come volontario ha promosso prima una raccolta carta e poi la riorganizzazione del gentro di formazione agricola di Andriamboasary in Madagascar. Ha fondato l'associazione Enthusiasmus che per piu' di dieci anni si e` occupata di formazione politico-sociale dei giovani, permettendo a molti giovani di conoscere il mondo esterno ed a qualcuno\/a di trovare moglie o marito. Nel 1991 e` stato testimone oculare dei moti di piazza che a Leningrado si opponevano al tentato golpe anti-riformatore. Nel 1994 si e` laureato in economia con Sergio Ricossa ed ha prestato servizio presso l'Istituto Penale Minorile \"Ferrante Aporti\", occupandosi dei denari e delle spese dei detenuti. Dal 1995 ha iniziato a lavorare per diversi progetti di valutazione e formazione promossi dall'Unione Europea e da altri enti nell'ex Unione Sovietica. Nel 2000-2001 e` stato consigliere economico del governo della Georgia. Nel 2006 ha conseguito il Ph.D. in economics all'Imperial College dell'University of London. Ha lavorato come economista per l'Institute of Alcohol Studies di Londra. Dal 2008 lavora per l'universita' di Torino dove oggi insegna public economics; insegna inoltre fundamentals in mathematics ed economics for managers ad ESCP-Europe.","url":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/author\/gustavo-rinaldi\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/posts\/228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/comments?post=228"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/posts\/228\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/media?parent=228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/categories?post=228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/tags?post=228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}