{"id":223,"date":"2005-12-20T10:28:15","date_gmt":"2005-12-20T10:28:15","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/torinopuofarcela\/2005\/12\/20\/energie_alterna\/"},"modified":"2005-12-20T10:28:15","modified_gmt":"2005-12-20T10:28:15","slug":"energie_alterna","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/energie_alterna\/","title":{"rendered":"Energie alternative: un problema di cultura e di regole"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"margin-left: 18pt\"><span lang=\"IT\">Perche` l`Italia e` indietro rispetto a molti paesi europei nell`uso di<br \/>\nenergie alternative? Noi siamo di gran lunga superati non solo dalla piccola<br \/>\nDanimarca, ma anche dalla Germania, dalla non troppo ecologista Gran Bretagna e<br \/>\nperfino dalla latina Spagna. Qual e` il problema in Italia?<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-left: 18pt\"><span lang=\"IT\">Sono vari. Uno di essi dipende dal fatto che ogni tecnologia implica certi modelli di organizzazione del lavoro e certe culture aziendali. Ad esempio gli impianti nucleari, quelli termoelettrici (a gas o&nbsp; a derivati del petrolio) e&nbsp; quelli<br \/>\nidroeletrici, spesso richiedono pochi impianti di dimensioni molto grandi. Percio` le<br \/>\naziende che si sono specializzate a produrre energia da quelle fonti hanno<br \/>\nsviluppato una cultura di grande impresa. Le tecnologie rinnovabili&nbsp; spesso si adattano bene a&nbsp; piccoli impianti, presenti in tanti luoghi. <\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-left: 18pt\"><span lang=\"IT\">Vi sono ovviamente le eccezioni. Ad esempio gli impianti eolici in mare<br \/>\naperto possono richiedere organizzazioni alquanto complesse, normalmente<br \/>\ndisponibili solo in grandi imprese. Non a caso giganti&nbsp; dell`energia come BP o Shell sono entrati<br \/>\nabbastanza massicciamente in questo tipo di attivita`, anche utilizzando parte<br \/>\ndelle esperienze e delle capacita` da loro acquisite nella gestione di piattaforme petrolifere in<br \/>\nmare aperto. <br \/>In Italia gli impianti eolici in mare aperto forse presentano qualche problema in piu`<br \/>\nperche\u2019 non disponiamo di tanti&nbsp; luoghi<br \/>\nabbastanza lontani da riva che siano allo stesso tempo battuti dal vento e dotati di fondali poco<br \/>\nprofondi. Cio` e` molto piu` comune in alcuni paesi del nord Europa, ad esempio<br \/>\nil Regno Unito.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-left: 18pt\"><span lang=\"IT\">Da noi , finora i principali attori in campo energetico sono stati ENEL ed<br \/>\nENI. Entrambi hanno comprensibilmente sviluppato delle culture aziendali proprie delle grandi<br \/>\norganizzazioni con una specifica attitudine a trattare relativamente pochi grandi<br \/>\nimpianti, con grossi costi fissi e grandi volumi. <\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-left: 18pt\"><span lang=\"IT\">Una delle tecnologie che in Italia potrebbe offrire interessanti<br \/>\nprospettive e\u2019 il solare, ma il solare non e` una tecnologia particolarmente<br \/>\nadatta ad essere sfruttata in impianti grandi. Piuttosto il solare si presta<br \/>\nbene come risorsa diffusa, sfruttata un po` dappertutto. Non grandi centrali, ma pannelli piu` o meno<br \/>\nsopra ogni costruzione, abitazione o capannone. Ecco che, per quanto riguarda<br \/>\nil solare, il ruolo delle aziende, che fino ad oggi ci hanno garantito energia,<br \/>\nsarebbe abbastanza modesto. E` cosi\u2019 ingiusto aspettarsi da loro un grande<br \/>\nimpegno per il suo sviluppo. Il problema invece e\u2019 negli usi e nelle norme che<br \/>\nregolano l`edilizia. In Italia l`edilizia e` largamente fuori controllo a causa<br \/>\ndi frequenti condoni che rendono sostanzialmente inutile il rispetto delle<br \/>\nleggi. Inoltre mentre chi compera un\u2019auto oltre a cercare una bella macchina,<br \/>\nspaziosa o compatta, veloce o tranquilla, chiede anche quanto essa consumi per litro di<br \/>\nbenzina, chi compera un\u2019appartamento riceve risposte piu\u2019 confuse. Quando si<br \/>\npensa al costo, spesso ci si chiede di piu\u2019 quanto sara` la rata del mutuo,<br \/>\npiuttosto di chiedersi l\u2019ammontare delle bollette di riscaldamento, luce, gas<br \/>\ned acqua. Quelle verranno quasi come una fatalita`. <\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-left: 18pt\"><span lang=\"IT\">In queste condizioni e` difficile che case un po\u2019 piu\u2019 costose, ma con<br \/>\nconsumi mensili molto piu\u2019 bassi possano avere molto successo. La legislazione<br \/>\nedilizia e quella sui contratti concernenti immobili potrebbero dare una bella<br \/>\nmano. L\u2019una imponendo che il contratto di vendita sia nullo in assenza di una perizia<br \/>\ntecnica sui consumi energetici dell\u2019immobile. Semplicemente l\u2019acquirente non sa<br \/>\ncio\u2019 che compra, se non sa quanto la casa consuma. La legislazione edilizia<br \/>\ndovrebbe imporre che tutte le nuove case ed i nuovi capannoni non consumino<br \/>\npiu\u2019 di un certo ammontare di energia. Queste limitazioni gia` esistono per le<br \/>\nautomobili, non si vede perche` non debbano esistere per le case. Infine ci<br \/>\nvorrebbe una riforma costituzionale che preveda che i condoni possano essere<br \/>\nsolo introdotti con maggioranze molto ampie, almeno dei 2\/3. In tal modo, forse<br \/>\nverrebbero usati piu` parsimoniosamente.<\/span><br \/>Infine sarebbe bene responsabilizzare le regioni. Da un lato bisognerebbe far funzionare un vero e proprio protocollo di Kyoto nazionale; ogni regione dovrebbe concordare con le altre e con lo stato, la sua quota di riduzione di emissioni inquinanti, con sanzioni per chi non rispetta gli accordi; inoltre ogni regione dovrebbe almeno in parte essere responsabile per il proprio approvigionamento energetico.&nbsp; Le regioni potranno poi trasferire parte delle responsabilita`&nbsp; a provincie e comuni. Chi non si da fare per risparmiare e produrre energia&nbsp; dovra` subirne le conseguenze.<br \/><span lang=\"IT\"><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-left: 18pt\"><span lang=\"IT\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-left: 18pt\"><span lang=\"IT\">&nbsp;<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Perche` l`Italia e` indietro rispetto a molti paesi europei nell`uso di energie alternative? Noi siamo di gran lunga superati non solo dalla piccola Danimarca, ma anche dalla Germania, dalla non troppo ecologista Gran Bretagna e perfino dalla latina Spagna. Qual e` il problema in Italia? Sono vari. Uno di essi dipende dal fatto che ogni &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/energie_alterna\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Energie alternative: un problema di cultura e di regole&#8221;<\/span><\/a><\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23,26,3,38],"tags":[],"class_list":["post-223","post","type-post","status-publish","format-standard","hentry","category-ambiente","category-diritto","category-economia-e-finanza","category-tecnologie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Energie alternative: un problema di cultura e di regole - Torino puo&#039; farcela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/energie_alterna\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Energie alternative: un problema di cultura e di regole - Torino puo&#039; farcela\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/energie_alterna\/\" \/>\n<meta property=\"og:site_name\" content=\"Torino puo&#039; farcela\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2005-12-20T10:28:15+00:00\" \/>\n<meta name=\"author\" content=\"Gustavo Rinaldi\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gustavo Rinaldi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/energie_alterna\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/energie_alterna\\\/\"},\"author\":{\"name\":\"Gustavo Rinaldi\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#\\\/schema\\\/person\\\/8b80d88227572133798036d6f1fb2057\"},\"headline\":\"Energie alternative: un problema di cultura e di regole\",\"datePublished\":\"2005-12-20T10:28:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/energie_alterna\\\/\"},\"wordCount\":729,\"commentCount\":2,\"articleSection\":[\"Ambiente\",\"Diritto\",\"Economia e finanza\",\"Tecnologie\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/energie_alterna\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/energie_alterna\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/energie_alterna\\\/\",\"name\":\"Energie alternative: un problema di cultura e di regole - Torino puo&#039; farcela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#website\"},\"datePublished\":\"2005-12-20T10:28:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#\\\/schema\\\/person\\\/8b80d88227572133798036d6f1fb2057\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/energie_alterna\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/energie_alterna\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/energie_alterna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Energie alternative: un problema di cultura e di regole\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/\",\"name\":\"Torino puo&#039; farcela\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#\\\/schema\\\/person\\\/8b80d88227572133798036d6f1fb2057\",\"name\":\"Gustavo Rinaldi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g\",\"caption\":\"Gustavo Rinaldi\"},\"description\":\"Nato a Torino nel 1967, la sua prima maestra e` stata una vittima delle repressioni bolsceviche, Maria Bruch. Ha frequentato sia la scuola pubblica che quella dei Gesuiti. Come volontario ha promosso prima una raccolta carta e poi la riorganizzazione del gentro di formazione agricola di Andriamboasary in Madagascar. Ha fondato l'associazione Enthusiasmus che per piu' di dieci anni si e` occupata di formazione politico-sociale dei giovani, permettendo a molti giovani di conoscere il mondo esterno ed a qualcuno\\\/a di trovare moglie o marito. Nel 1991 e` stato testimone oculare dei moti di piazza che a Leningrado si opponevano al tentato golpe anti-riformatore. Nel 1994 si e` laureato in economia con Sergio Ricossa ed ha prestato servizio presso l'Istituto Penale Minorile \\\"Ferrante Aporti\\\", occupandosi dei denari e delle spese dei detenuti. Dal 1995 ha iniziato a lavorare per diversi progetti di valutazione e formazione promossi dall'Unione Europea e da altri enti nell'ex Unione Sovietica. Nel 2000-2001 e` stato consigliere economico del governo della Georgia. Nel 2006 ha conseguito il Ph.D. in economics all'Imperial College dell'University of London. Ha lavorato come economista per l'Institute of Alcohol Studies di Londra. Dal 2008 lavora per l'universita' di Torino dove oggi insegna public economics; insegna inoltre fundamentals in mathematics ed economics for managers ad ESCP-Europe.\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/author\\\/gustavo-rinaldi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Energie alternative: un problema di cultura e di regole - Torino puo&#039; farcela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/energie_alterna\/","og_locale":"it_IT","og_type":"article","og_title":"Energie alternative: un problema di cultura e di regole - Torino puo&#039; farcela","og_url":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/energie_alterna\/","og_site_name":"Torino puo&#039; farcela","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2005-12-20T10:28:15+00:00","author":"Gustavo Rinaldi","twitter_misc":{"Scritto da":"Gustavo Rinaldi","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/energie_alterna\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/energie_alterna\/"},"author":{"name":"Gustavo Rinaldi","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#\/schema\/person\/8b80d88227572133798036d6f1fb2057"},"headline":"Energie alternative: un problema di cultura e di regole","datePublished":"2005-12-20T10:28:15+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/energie_alterna\/"},"wordCount":729,"commentCount":2,"articleSection":["Ambiente","Diritto","Economia e finanza","Tecnologie"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/energie_alterna\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/energie_alterna\/","url":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/energie_alterna\/","name":"Energie alternative: un problema di cultura e di regole - Torino puo&#039; farcela","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#website"},"datePublished":"2005-12-20T10:28:15+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#\/schema\/person\/8b80d88227572133798036d6f1fb2057"},"breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/energie_alterna\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/energie_alterna\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/energie_alterna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/"},{"@type":"ListItem","position":2,"name":"Energie alternative: un problema di cultura e di regole"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#website","url":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/","name":"Torino puo&#039; farcela","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#\/schema\/person\/8b80d88227572133798036d6f1fb2057","name":"Gustavo Rinaldi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g","caption":"Gustavo Rinaldi"},"description":"Nato a Torino nel 1967, la sua prima maestra e` stata una vittima delle repressioni bolsceviche, Maria Bruch. Ha frequentato sia la scuola pubblica che quella dei Gesuiti. Come volontario ha promosso prima una raccolta carta e poi la riorganizzazione del gentro di formazione agricola di Andriamboasary in Madagascar. Ha fondato l'associazione Enthusiasmus che per piu' di dieci anni si e` occupata di formazione politico-sociale dei giovani, permettendo a molti giovani di conoscere il mondo esterno ed a qualcuno\/a di trovare moglie o marito. Nel 1991 e` stato testimone oculare dei moti di piazza che a Leningrado si opponevano al tentato golpe anti-riformatore. Nel 1994 si e` laureato in economia con Sergio Ricossa ed ha prestato servizio presso l'Istituto Penale Minorile \"Ferrante Aporti\", occupandosi dei denari e delle spese dei detenuti. Dal 1995 ha iniziato a lavorare per diversi progetti di valutazione e formazione promossi dall'Unione Europea e da altri enti nell'ex Unione Sovietica. Nel 2000-2001 e` stato consigliere economico del governo della Georgia. Nel 2006 ha conseguito il Ph.D. in economics all'Imperial College dell'University of London. Ha lavorato come economista per l'Institute of Alcohol Studies di Londra. Dal 2008 lavora per l'universita' di Torino dove oggi insegna public economics; insegna inoltre fundamentals in mathematics ed economics for managers ad ESCP-Europe.","url":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/author\/gustavo-rinaldi\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/posts\/223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/comments?post=223"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/posts\/223\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/media?parent=223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/categories?post=223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/tags?post=223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}