{"id":190,"date":"2006-01-26T10:57:00","date_gmt":"2006-01-26T10:57:00","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/torinopuofarcela\/2006\/01\/26\/le_piazze_sono_\/"},"modified":"2006-01-26T10:57:00","modified_gmt":"2006-01-26T10:57:00","slug":"le_piazze_sono_","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/le_piazze_sono_\/","title":{"rendered":"Le piazze sono preziose"},"content":{"rendered":"<p><a href=\"http:\/\/gustavorinaldi.blog.lastampa.it\/.shared\/image.html?\/photos\/uncategorized\/dscn0284.JPG\"><br \/><\/a>\n<\/p>\n<\/p>\n<p>Le piazze sono una delle caratteristiche forti dell&#8217; Italia. Addirittura in Inghilterra le persone&nbsp; piu&#8217; istruite conoscono&nbsp; la&nbsp; parola&nbsp; &quot;piazza&quot;&nbsp; e considerano le nostre piazze qualcosa di speciale, un segno distintivo dell&#8217; Italia.<\/p>\n<p><a href=\"http:\/\/gustavorinaldi.blog.lastampa.it\/.shared\/image.html?\/photos\/uncategorized\/dscn0284_2.JPG\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" border=\"0\" src=\"http:\/\/gustavorinaldi.blog.lastampa.it\/il_mio_weblog\/images\/dscn0284_2.JPG\" alt=\"Dscn0284_2\" style=\"margin: 0px 5px 5px 0px;float: left\" \/><\/a>\n<\/p>\n<\/p>\n<\/p>\n<p>Dobbiamo difenderle,&nbsp; cosi&#8217; come dobbiamo difendere gli spazi aperti ancora esistenti nelle citta&#8217;.<br \/>Lo spazio e&#8217; un valore, non a caso le persone piu&#8217; ricche spesso finiscono col comprarsi case con giardino ed ampie terrazze. I poveri normalmente devono accontentarsi di piccoli spazi.<br \/>Purtroppo a volte le piazze vengono attaccate, in certe amministrazioni sembra che ci sia una specie di aristotelico o medievale &quot;horror vacui&quot;. Ogni spazio, secondo loro, va riempito, con un edificio, con un gazebo, un tendone, un cioccolatino, una baita, un palcoscenico o qualcos&#8217;altro ancora. <br \/>Se qualche turista verra&#8217; per le olimpiadi, non potra&#8217; vedere Piazza Solferino, Piazza Castello, Piazza Vittorio&#8230; Che idea si potra&#8217; fare di Torino?<br \/>Io credo che le piazze siano un valore. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le piazze sono una delle caratteristiche forti dell&#8217; Italia. Addirittura in Inghilterra le persone&nbsp; piu&#8217; istruite conoscono&nbsp; la&nbsp; parola&nbsp; &quot;piazza&quot;&nbsp; e considerano le nostre piazze qualcosa di speciale, un segno distintivo dell&#8217; Italia. Dobbiamo difenderle,&nbsp; cosi&#8217; come dobbiamo difendere gli spazi aperti ancora esistenti nelle citta&#8217;.Lo spazio e&#8217; un valore, non a caso le persone &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/le_piazze_sono_\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Le piazze sono preziose&#8221;<\/span><\/a><\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23,27,18],"tags":[],"class_list":["post-190","post","type-post","status-publish","format-standard","hentry","category-ambiente","category-attualita","category-torino-da-vivere"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le piazze sono preziose - Torino puo&#039; farcela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/le_piazze_sono_\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le piazze sono preziose - Torino puo&#039; farcela\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/le_piazze_sono_\/\" \/>\n<meta property=\"og:site_name\" content=\"Torino puo&#039; farcela\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2006-01-26T10:57:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/gustavorinaldi.blog.lastampa.it\/il_mio_weblog\/images\/dscn0284_2.JPG\" \/>\n<meta name=\"author\" content=\"Gustavo Rinaldi\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gustavo Rinaldi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/le_piazze_sono_\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/le_piazze_sono_\\\/\"},\"author\":{\"name\":\"Gustavo Rinaldi\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#\\\/schema\\\/person\\\/8b80d88227572133798036d6f1fb2057\"},\"headline\":\"Le piazze sono preziose\",\"datePublished\":\"2006-01-26T10:57:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/le_piazze_sono_\\\/\"},\"wordCount\":167,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/le_piazze_sono_\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/gustavorinaldi.blog.lastampa.it\\\/il_mio_weblog\\\/images\\\/dscn0284_2.JPG\",\"articleSection\":[\"Ambiente\",\"Attualit\u00e0\",\"Torino da vivere\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/le_piazze_sono_\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/le_piazze_sono_\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/le_piazze_sono_\\\/\",\"name\":\"Le piazze sono preziose - Torino puo&#039; farcela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/le_piazze_sono_\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/le_piazze_sono_\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/gustavorinaldi.blog.lastampa.it\\\/il_mio_weblog\\\/images\\\/dscn0284_2.JPG\",\"datePublished\":\"2006-01-26T10:57:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#\\\/schema\\\/person\\\/8b80d88227572133798036d6f1fb2057\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/le_piazze_sono_\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/le_piazze_sono_\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/le_piazze_sono_\\\/#primaryimage\",\"url\":\"http:\\\/\\\/gustavorinaldi.blog.lastampa.it\\\/il_mio_weblog\\\/images\\\/dscn0284_2.JPG\",\"contentUrl\":\"http:\\\/\\\/gustavorinaldi.blog.lastampa.it\\\/il_mio_weblog\\\/images\\\/dscn0284_2.JPG\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/le_piazze_sono_\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le piazze sono preziose\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/\",\"name\":\"Torino puo&#039; farcela\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#\\\/schema\\\/person\\\/8b80d88227572133798036d6f1fb2057\",\"name\":\"Gustavo Rinaldi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g\",\"caption\":\"Gustavo Rinaldi\"},\"description\":\"Nato a Torino nel 1967, la sua prima maestra e` stata una vittima delle repressioni bolsceviche, Maria Bruch. Ha frequentato sia la scuola pubblica che quella dei Gesuiti. Come volontario ha promosso prima una raccolta carta e poi la riorganizzazione del gentro di formazione agricola di Andriamboasary in Madagascar. Ha fondato l'associazione Enthusiasmus che per piu' di dieci anni si e` occupata di formazione politico-sociale dei giovani, permettendo a molti giovani di conoscere il mondo esterno ed a qualcuno\\\/a di trovare moglie o marito. Nel 1991 e` stato testimone oculare dei moti di piazza che a Leningrado si opponevano al tentato golpe anti-riformatore. Nel 1994 si e` laureato in economia con Sergio Ricossa ed ha prestato servizio presso l'Istituto Penale Minorile \\\"Ferrante Aporti\\\", occupandosi dei denari e delle spese dei detenuti. Dal 1995 ha iniziato a lavorare per diversi progetti di valutazione e formazione promossi dall'Unione Europea e da altri enti nell'ex Unione Sovietica. Nel 2000-2001 e` stato consigliere economico del governo della Georgia. Nel 2006 ha conseguito il Ph.D. in economics all'Imperial College dell'University of London. Ha lavorato come economista per l'Institute of Alcohol Studies di Londra. Dal 2008 lavora per l'universita' di Torino dove oggi insegna public economics; insegna inoltre fundamentals in mathematics ed economics for managers ad ESCP-Europe.\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/author\\\/gustavo-rinaldi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le piazze sono preziose - Torino puo&#039; farcela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/le_piazze_sono_\/","og_locale":"it_IT","og_type":"article","og_title":"Le piazze sono preziose - Torino puo&#039; farcela","og_url":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/le_piazze_sono_\/","og_site_name":"Torino puo&#039; farcela","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2006-01-26T10:57:00+00:00","og_image":[{"url":"http:\/\/gustavorinaldi.blog.lastampa.it\/il_mio_weblog\/images\/dscn0284_2.JPG","type":"","width":"","height":""}],"author":"Gustavo Rinaldi","twitter_misc":{"Scritto da":"Gustavo Rinaldi","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/le_piazze_sono_\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/le_piazze_sono_\/"},"author":{"name":"Gustavo Rinaldi","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#\/schema\/person\/8b80d88227572133798036d6f1fb2057"},"headline":"Le piazze sono preziose","datePublished":"2006-01-26T10:57:00+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/le_piazze_sono_\/"},"wordCount":167,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/le_piazze_sono_\/#primaryimage"},"thumbnailUrl":"http:\/\/gustavorinaldi.blog.lastampa.it\/il_mio_weblog\/images\/dscn0284_2.JPG","articleSection":["Ambiente","Attualit\u00e0","Torino da vivere"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/le_piazze_sono_\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/le_piazze_sono_\/","url":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/le_piazze_sono_\/","name":"Le piazze sono preziose - Torino puo&#039; farcela","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/le_piazze_sono_\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/le_piazze_sono_\/#primaryimage"},"thumbnailUrl":"http:\/\/gustavorinaldi.blog.lastampa.it\/il_mio_weblog\/images\/dscn0284_2.JPG","datePublished":"2006-01-26T10:57:00+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#\/schema\/person\/8b80d88227572133798036d6f1fb2057"},"breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/le_piazze_sono_\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/le_piazze_sono_\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/le_piazze_sono_\/#primaryimage","url":"http:\/\/gustavorinaldi.blog.lastampa.it\/il_mio_weblog\/images\/dscn0284_2.JPG","contentUrl":"http:\/\/gustavorinaldi.blog.lastampa.it\/il_mio_weblog\/images\/dscn0284_2.JPG"},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/le_piazze_sono_\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/"},{"@type":"ListItem","position":2,"name":"Le piazze sono preziose"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#website","url":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/","name":"Torino puo&#039; farcela","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#\/schema\/person\/8b80d88227572133798036d6f1fb2057","name":"Gustavo Rinaldi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g","caption":"Gustavo Rinaldi"},"description":"Nato a Torino nel 1967, la sua prima maestra e` stata una vittima delle repressioni bolsceviche, Maria Bruch. Ha frequentato sia la scuola pubblica che quella dei Gesuiti. Come volontario ha promosso prima una raccolta carta e poi la riorganizzazione del gentro di formazione agricola di Andriamboasary in Madagascar. Ha fondato l'associazione Enthusiasmus che per piu' di dieci anni si e` occupata di formazione politico-sociale dei giovani, permettendo a molti giovani di conoscere il mondo esterno ed a qualcuno\/a di trovare moglie o marito. Nel 1991 e` stato testimone oculare dei moti di piazza che a Leningrado si opponevano al tentato golpe anti-riformatore. Nel 1994 si e` laureato in economia con Sergio Ricossa ed ha prestato servizio presso l'Istituto Penale Minorile \"Ferrante Aporti\", occupandosi dei denari e delle spese dei detenuti. Dal 1995 ha iniziato a lavorare per diversi progetti di valutazione e formazione promossi dall'Unione Europea e da altri enti nell'ex Unione Sovietica. Nel 2000-2001 e` stato consigliere economico del governo della Georgia. Nel 2006 ha conseguito il Ph.D. in economics all'Imperial College dell'University of London. Ha lavorato come economista per l'Institute of Alcohol Studies di Londra. Dal 2008 lavora per l'universita' di Torino dove oggi insegna public economics; insegna inoltre fundamentals in mathematics ed economics for managers ad ESCP-Europe.","url":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/author\/gustavo-rinaldi\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/posts\/190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/comments?post=190"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/posts\/190\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/media?parent=190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/categories?post=190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/tags?post=190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}