{"id":163,"date":"2006-02-21T10:50:00","date_gmt":"2006-02-21T10:50:00","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/torinopuofarcela\/2006\/02\/21\/dicono_di_noi_s\/"},"modified":"2006-02-21T10:50:00","modified_gmt":"2006-02-21T10:50:00","slug":"dicono_di_noi_s","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/dicono_di_noi_s\/","title":{"rendered":"Dicono di noi: Scuola Tommaseo, notti bianche, pompieri, ecc."},"content":{"rendered":"<p class=\"MsoNormal\"><span lang=\"EN-GB\">Ottima iniziativa della scuola Tommaseo<br \/>\nche, a<br \/>quanto dice il californiano Times Herald,<br \/>\nha<br \/>stabilito un contatto con una scuola di<br \/>\nVallejo in<\/span><br \/><span lang=\"EN-GB\">California.<br \/>Si<br \/>\nscambiano e-mail e fanno conoscenza,<br \/>parlando delle olimpiadi.<\/span><\/p>\n<p><span lang=\"EN-GB\"><\/span>La notte bianca ha avuto ampia eco da a Los<br \/>Angeles alla Cina. Ha fatto abbastanza<br \/>\ncolpo.<br \/> Ilcorrispondente americano si aspettava<br \/>un`allegria piu\u2019 bagnata dall\u2019alcol cosi`<br \/>\ncome il<br \/>corrispondente del <\/p>\n<p>Financial Times si aspettava piu\u2019 sventolio di bandiere.<\/p>\n<p class=\"MsoNormal\"><span lang=\"EN-GB\">Bisogna accettare che su certe cose siamo<br \/>diversi e nel caso dell\u2019alcol e` un<br \/>\nvantaggio.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"EN-GB\">Il corrispondente&nbsp; del<br \/>\nTampa Tribune ( Florida)<br \/>s`e` chiuso fuori dalla porta<br \/>\ndell`appartamento<br \/>che ha affittato. E` rimasto molto contento<br \/>perche` un usciere gli ha dato il suo<br \/>\ncappotto,<br \/>quando lui era in camicia al freddo, e poi<br \/>\nha<br \/>chiamato i pompieri; questi sono giunti presto e, in poco tempo,<br \/>hanno aperto la porta&nbsp; del suo appartamento. Han<br \/>rifiutato una piccola mancia. Era commosso.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"EN-GB\">Il corrispondente&nbsp; del&nbsp; Seattle Times sta&nbsp; a<br \/>\nSan<br \/>Sicario e si lamenta che la\u2019 i ristoranti chiudono<br \/>molto presto la sera; per fortuna nel suo<br \/>\nhotel (il<br \/>Majestic) il personale e` molto gentile ed<br \/>\napre il<br \/>ristorante anche a mezzanotte.<br \/> L`Indianapolis Star apprezza il massaggio<br \/>shiatsu&nbsp; gratuito disponibile presso la sala stampa.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"EN-GB\">&nbsp;L`indiano Zee News nota che le vendite di<br \/>oggetti \u201colimpici\u201d vanno molto bene.<br \/>E la cinese Xinhua dice che anche le<br \/>\nvendite di<br \/>biglietti vanno bene. Speriamo.<\/span><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ottima iniziativa della scuola Tommaseo che, aquanto dice il californiano Times Herald, hastabilito un contatto con una scuola di Vallejo inCalifornia.Si scambiano e-mail e fanno conoscenza,parlando delle olimpiadi. La notte bianca ha avuto ampia eco da a LosAngeles alla Cina. Ha fatto abbastanza colpo. Ilcorrispondente americano si aspettavaun`allegria piu\u2019 bagnata dall\u2019alcol cosi` come ilcorrispondente del &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/dicono_di_noi_s\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Dicono di noi: Scuola Tommaseo, notti bianche, pompieri, ecc.&#8221;<\/span><\/a><\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"class_list":["post-163","post","type-post","status-publish","format-standard","hentry","category-attualita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dicono di noi: Scuola Tommaseo, notti bianche, pompieri, ecc. - Torino puo&#039; farcela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/dicono_di_noi_s\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dicono di noi: Scuola Tommaseo, notti bianche, pompieri, ecc. - Torino puo&#039; farcela\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/dicono_di_noi_s\/\" \/>\n<meta property=\"og:site_name\" content=\"Torino puo&#039; farcela\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2006-02-21T10:50:00+00:00\" \/>\n<meta name=\"author\" content=\"Gustavo Rinaldi\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gustavo Rinaldi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/dicono_di_noi_s\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/dicono_di_noi_s\\\/\"},\"author\":{\"name\":\"Gustavo Rinaldi\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#\\\/schema\\\/person\\\/8b80d88227572133798036d6f1fb2057\"},\"headline\":\"Dicono di noi: Scuola Tommaseo, notti bianche, pompieri, ecc.\",\"datePublished\":\"2006-02-21T10:50:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/dicono_di_noi_s\\\/\"},\"wordCount\":234,\"commentCount\":0,\"articleSection\":[\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/dicono_di_noi_s\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/dicono_di_noi_s\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/dicono_di_noi_s\\\/\",\"name\":\"Dicono di noi: Scuola Tommaseo, notti bianche, pompieri, ecc. - Torino puo&#039; farcela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#website\"},\"datePublished\":\"2006-02-21T10:50:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#\\\/schema\\\/person\\\/8b80d88227572133798036d6f1fb2057\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/dicono_di_noi_s\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/dicono_di_noi_s\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/dicono_di_noi_s\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dicono di noi: Scuola Tommaseo, notti bianche, pompieri, ecc.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/\",\"name\":\"Torino puo&#039; farcela\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#\\\/schema\\\/person\\\/8b80d88227572133798036d6f1fb2057\",\"name\":\"Gustavo Rinaldi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g\",\"caption\":\"Gustavo Rinaldi\"},\"description\":\"Nato a Torino nel 1967, la sua prima maestra e` stata una vittima delle repressioni bolsceviche, Maria Bruch. Ha frequentato sia la scuola pubblica che quella dei Gesuiti. Come volontario ha promosso prima una raccolta carta e poi la riorganizzazione del gentro di formazione agricola di Andriamboasary in Madagascar. Ha fondato l'associazione Enthusiasmus che per piu' di dieci anni si e` occupata di formazione politico-sociale dei giovani, permettendo a molti giovani di conoscere il mondo esterno ed a qualcuno\\\/a di trovare moglie o marito. Nel 1991 e` stato testimone oculare dei moti di piazza che a Leningrado si opponevano al tentato golpe anti-riformatore. Nel 1994 si e` laureato in economia con Sergio Ricossa ed ha prestato servizio presso l'Istituto Penale Minorile \\\"Ferrante Aporti\\\", occupandosi dei denari e delle spese dei detenuti. Dal 1995 ha iniziato a lavorare per diversi progetti di valutazione e formazione promossi dall'Unione Europea e da altri enti nell'ex Unione Sovietica. Nel 2000-2001 e` stato consigliere economico del governo della Georgia. Nel 2006 ha conseguito il Ph.D. in economics all'Imperial College dell'University of London. Ha lavorato come economista per l'Institute of Alcohol Studies di Londra. Dal 2008 lavora per l'universita' di Torino dove oggi insegna public economics; insegna inoltre fundamentals in mathematics ed economics for managers ad ESCP-Europe.\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/author\\\/gustavo-rinaldi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dicono di noi: Scuola Tommaseo, notti bianche, pompieri, ecc. - Torino puo&#039; farcela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/dicono_di_noi_s\/","og_locale":"it_IT","og_type":"article","og_title":"Dicono di noi: Scuola Tommaseo, notti bianche, pompieri, ecc. - Torino puo&#039; farcela","og_url":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/dicono_di_noi_s\/","og_site_name":"Torino puo&#039; farcela","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2006-02-21T10:50:00+00:00","author":"Gustavo Rinaldi","twitter_misc":{"Scritto da":"Gustavo Rinaldi","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/dicono_di_noi_s\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/dicono_di_noi_s\/"},"author":{"name":"Gustavo Rinaldi","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#\/schema\/person\/8b80d88227572133798036d6f1fb2057"},"headline":"Dicono di noi: Scuola Tommaseo, notti bianche, pompieri, ecc.","datePublished":"2006-02-21T10:50:00+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/dicono_di_noi_s\/"},"wordCount":234,"commentCount":0,"articleSection":["Attualit\u00e0"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/dicono_di_noi_s\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/dicono_di_noi_s\/","url":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/dicono_di_noi_s\/","name":"Dicono di noi: Scuola Tommaseo, notti bianche, pompieri, ecc. - Torino puo&#039; farcela","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#website"},"datePublished":"2006-02-21T10:50:00+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#\/schema\/person\/8b80d88227572133798036d6f1fb2057"},"breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/dicono_di_noi_s\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/dicono_di_noi_s\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/dicono_di_noi_s\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/"},{"@type":"ListItem","position":2,"name":"Dicono di noi: Scuola Tommaseo, notti bianche, pompieri, ecc."}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#website","url":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/","name":"Torino puo&#039; farcela","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#\/schema\/person\/8b80d88227572133798036d6f1fb2057","name":"Gustavo Rinaldi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g","caption":"Gustavo Rinaldi"},"description":"Nato a Torino nel 1967, la sua prima maestra e` stata una vittima delle repressioni bolsceviche, Maria Bruch. Ha frequentato sia la scuola pubblica che quella dei Gesuiti. Come volontario ha promosso prima una raccolta carta e poi la riorganizzazione del gentro di formazione agricola di Andriamboasary in Madagascar. Ha fondato l'associazione Enthusiasmus che per piu' di dieci anni si e` occupata di formazione politico-sociale dei giovani, permettendo a molti giovani di conoscere il mondo esterno ed a qualcuno\/a di trovare moglie o marito. Nel 1991 e` stato testimone oculare dei moti di piazza che a Leningrado si opponevano al tentato golpe anti-riformatore. Nel 1994 si e` laureato in economia con Sergio Ricossa ed ha prestato servizio presso l'Istituto Penale Minorile \"Ferrante Aporti\", occupandosi dei denari e delle spese dei detenuti. Dal 1995 ha iniziato a lavorare per diversi progetti di valutazione e formazione promossi dall'Unione Europea e da altri enti nell'ex Unione Sovietica. Nel 2000-2001 e` stato consigliere economico del governo della Georgia. Nel 2006 ha conseguito il Ph.D. in economics all'Imperial College dell'University of London. Ha lavorato come economista per l'Institute of Alcohol Studies di Londra. Dal 2008 lavora per l'universita' di Torino dove oggi insegna public economics; insegna inoltre fundamentals in mathematics ed economics for managers ad ESCP-Europe.","url":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/author\/gustavo-rinaldi\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/posts\/163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/comments?post=163"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/posts\/163\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/media?parent=163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/categories?post=163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/tags?post=163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}