{"id":138,"date":"2006-03-19T14:06:00","date_gmt":"2006-03-19T14:06:00","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/torinopuofarcela\/2006\/03\/19\/autostrade_del_\/"},"modified":"2006-03-19T14:06:00","modified_gmt":"2006-03-19T14:06:00","slug":"autostrade_del_","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/autostrade_del_\/","title":{"rendered":"Autostrade del mare e balene"},"content":{"rendered":"<p>Poiche` il trasporto via mare e` uno&nbsp; di quelli che inquina&nbsp; poco e costa meno bisognera` cercare di incoraggiarlo. A cio&#8217; si aggiunga che in un viaggio Palermo-Genova un TIR puo&#8217; essere solo difficilmente piu&#8217; veloce di una nave. Il primo deve percorrere 1428 chilometri agli 80 al&#8217;ora, se rispetta le leggi vigenti. Se potesse mantenere quella velocita` sempre, ci metterebbe quasi 18 ore; a cio&#8217; si aggiunga qualche fermata, qualche coda e qualche incidente per la strada e facilmente si raggiungono le&nbsp; 20 ore di viaggio. Questo e&#8217; quanto necessario ad una nave per fare Palermo Genova. Sono relativamente pochi i tipi di merce&nbsp; per i quali poche ore di differenza contano molto. Certo organizzare dei trasporti navali efficienti e veloci non e` una cosa semplicissima, perche&#8217;&nbsp; occorrono non solo porti moderni e ben attrezzati e navi veloci e capaci di caricare e scaricare in fretta e bene, ma anche una capacita` di organizzare il lavoro dentro e fuori i porti in maniera efficiente e competitiva. I porti non possono essere&nbsp; isole e, se non sono ben collegati con una efficiente rete ferroviaria, divengono molto meno utili. Ancora una volta` l&#8217;accento va posto piu&#8217; sull&#8217;organizzazione degli uomini che sulle strutture di ferro e cemento. Sono le relazioni tra esseri umani che ci vedono piu&#8217; spesso deboli e perdenti.<br \/>Migliorare i nostri porti ed i loro annessi non solo favorira` i trasporti tra nord e sud dell`Italia, ma anche favorira` una partecipazione italiana nel mercato internazionale dei servizi portuali e di logistica, dove il potenziale di crescita e&#8217; notevole.&nbsp; &nbsp;foto:Stefan Jacobs<\/p>\n<p><a href=\"http:\/\/gustavorinaldi.blog.lastampa.it\/.shared\/image.html?\/photos\/uncategorized\/060319_balena_nediterraneo.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"280\" border=\"0\" alt=\"060319_balena_nediterraneo\" src=\"http:\/\/gustavorinaldi.blog.lastampa.it\/il_mio_weblog\/images\/060319_balena_nediterraneo.jpg\" style=\"margin: 0px 5px 5px 0px;float: left\" \/><\/a>\n<\/p>\n<p>Il mare e` anche abitato da altri mammiferi, le balene. Esse gia` oggi sono spesso vittime di incidenti nautici dove riportano ferite o muoiono.<br \/>Probabilmente esiste qualche modo intelligente per&nbsp; risolvere il problema di questi incidenti. Intanto si puo&#8217; stabilire che le navi seguano il piu&#8217; possibile rotte precise, evitando&nbsp; cosi&#8217; i posti piu&#8217; frequentemente abitati dai cetacei.&nbsp; Inoltre gli zoologi marini forse potranno identificare e&nbsp; suggerire qualche <br \/>modo per poter avvertire le balene dell&#8217;arrivo delle navi, tenendole&nbsp; a debita distanza; una specie di clacson per balene.&nbsp; Non dico di conoscere la soluzione, dico che e` possibile cercarla&nbsp; e forse anche trovarla.<br \/>Il nostro mare ci puo&#8217; aiutare a collegare&nbsp; il nord ed il sud del paese, ma non per questo dobbiamo rinunciare all&#8217;onore e privilegio di ospitare alcune delle piu&#8217; belle comunita` di balene del mondo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Poiche` il trasporto via mare e` uno&nbsp; di quelli che inquina&nbsp; poco e costa meno bisognera` cercare di incoraggiarlo. A cio&#8217; si aggiunga che in un viaggio Palermo-Genova un TIR puo&#8217; essere solo difficilmente piu&#8217; veloce di una nave. Il primo deve percorrere 1428 chilometri agli 80 al&#8217;ora, se rispetta le leggi vigenti. Se potesse &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/autostrade_del_\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Autostrade del mare e balene&#8221;<\/span><\/a><\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23,43,27,41,38,25],"tags":[],"class_list":["post-138","post","type-post","status-publish","format-standard","hentry","category-ambiente","category-animali","category-attualita","category-scienza","category-tecnologie","category-trasporti-e-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Autostrade del mare e balene - Torino puo&#039; farcela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/autostrade_del_\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Autostrade del mare e balene - Torino puo&#039; farcela\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/autostrade_del_\/\" \/>\n<meta property=\"og:site_name\" content=\"Torino puo&#039; farcela\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2006-03-19T14:06:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/gustavorinaldi.blog.lastampa.it\/il_mio_weblog\/images\/060319_balena_nediterraneo.jpg\" \/>\n<meta name=\"author\" content=\"Gustavo Rinaldi\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gustavo Rinaldi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/autostrade_del_\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/autostrade_del_\\\/\"},\"author\":{\"name\":\"Gustavo Rinaldi\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#\\\/schema\\\/person\\\/8b80d88227572133798036d6f1fb2057\"},\"headline\":\"Autostrade del mare e balene\",\"datePublished\":\"2006-03-19T14:06:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/autostrade_del_\\\/\"},\"wordCount\":422,\"commentCount\":1,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/autostrade_del_\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/gustavorinaldi.blog.lastampa.it\\\/il_mio_weblog\\\/images\\\/060319_balena_nediterraneo.jpg\",\"articleSection\":[\"Ambiente\",\"Animali\",\"Attualit\u00e0\",\"Scienza\",\"Tecnologie\",\"Trasporti e mobilita`\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/autostrade_del_\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/autostrade_del_\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/autostrade_del_\\\/\",\"name\":\"Autostrade del mare e balene - Torino puo&#039; farcela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/autostrade_del_\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/autostrade_del_\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/gustavorinaldi.blog.lastampa.it\\\/il_mio_weblog\\\/images\\\/060319_balena_nediterraneo.jpg\",\"datePublished\":\"2006-03-19T14:06:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#\\\/schema\\\/person\\\/8b80d88227572133798036d6f1fb2057\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/autostrade_del_\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/autostrade_del_\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/autostrade_del_\\\/#primaryimage\",\"url\":\"http:\\\/\\\/gustavorinaldi.blog.lastampa.it\\\/il_mio_weblog\\\/images\\\/060319_balena_nediterraneo.jpg\",\"contentUrl\":\"http:\\\/\\\/gustavorinaldi.blog.lastampa.it\\\/il_mio_weblog\\\/images\\\/060319_balena_nediterraneo.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/autostrade_del_\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Autostrade del mare e balene\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/\",\"name\":\"Torino puo&#039; farcela\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#\\\/schema\\\/person\\\/8b80d88227572133798036d6f1fb2057\",\"name\":\"Gustavo Rinaldi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g\",\"caption\":\"Gustavo Rinaldi\"},\"description\":\"Nato a Torino nel 1967, la sua prima maestra e` stata una vittima delle repressioni bolsceviche, Maria Bruch. Ha frequentato sia la scuola pubblica che quella dei Gesuiti. Come volontario ha promosso prima una raccolta carta e poi la riorganizzazione del gentro di formazione agricola di Andriamboasary in Madagascar. Ha fondato l'associazione Enthusiasmus che per piu' di dieci anni si e` occupata di formazione politico-sociale dei giovani, permettendo a molti giovani di conoscere il mondo esterno ed a qualcuno\\\/a di trovare moglie o marito. Nel 1991 e` stato testimone oculare dei moti di piazza che a Leningrado si opponevano al tentato golpe anti-riformatore. Nel 1994 si e` laureato in economia con Sergio Ricossa ed ha prestato servizio presso l'Istituto Penale Minorile \\\"Ferrante Aporti\\\", occupandosi dei denari e delle spese dei detenuti. Dal 1995 ha iniziato a lavorare per diversi progetti di valutazione e formazione promossi dall'Unione Europea e da altri enti nell'ex Unione Sovietica. Nel 2000-2001 e` stato consigliere economico del governo della Georgia. Nel 2006 ha conseguito il Ph.D. in economics all'Imperial College dell'University of London. Ha lavorato come economista per l'Institute of Alcohol Studies di Londra. Dal 2008 lavora per l'universita' di Torino dove oggi insegna public economics; insegna inoltre fundamentals in mathematics ed economics for managers ad ESCP-Europe.\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/author\\\/gustavo-rinaldi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Autostrade del mare e balene - Torino puo&#039; farcela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/autostrade_del_\/","og_locale":"it_IT","og_type":"article","og_title":"Autostrade del mare e balene - Torino puo&#039; farcela","og_url":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/autostrade_del_\/","og_site_name":"Torino puo&#039; farcela","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2006-03-19T14:06:00+00:00","og_image":[{"url":"http:\/\/gustavorinaldi.blog.lastampa.it\/il_mio_weblog\/images\/060319_balena_nediterraneo.jpg","type":"","width":"","height":""}],"author":"Gustavo Rinaldi","twitter_misc":{"Scritto da":"Gustavo Rinaldi","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/autostrade_del_\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/autostrade_del_\/"},"author":{"name":"Gustavo Rinaldi","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#\/schema\/person\/8b80d88227572133798036d6f1fb2057"},"headline":"Autostrade del mare e balene","datePublished":"2006-03-19T14:06:00+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/autostrade_del_\/"},"wordCount":422,"commentCount":1,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/autostrade_del_\/#primaryimage"},"thumbnailUrl":"http:\/\/gustavorinaldi.blog.lastampa.it\/il_mio_weblog\/images\/060319_balena_nediterraneo.jpg","articleSection":["Ambiente","Animali","Attualit\u00e0","Scienza","Tecnologie","Trasporti e mobilita`"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/autostrade_del_\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/autostrade_del_\/","url":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/autostrade_del_\/","name":"Autostrade del mare e balene - Torino puo&#039; farcela","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/autostrade_del_\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/autostrade_del_\/#primaryimage"},"thumbnailUrl":"http:\/\/gustavorinaldi.blog.lastampa.it\/il_mio_weblog\/images\/060319_balena_nediterraneo.jpg","datePublished":"2006-03-19T14:06:00+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#\/schema\/person\/8b80d88227572133798036d6f1fb2057"},"breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/autostrade_del_\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/autostrade_del_\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/autostrade_del_\/#primaryimage","url":"http:\/\/gustavorinaldi.blog.lastampa.it\/il_mio_weblog\/images\/060319_balena_nediterraneo.jpg","contentUrl":"http:\/\/gustavorinaldi.blog.lastampa.it\/il_mio_weblog\/images\/060319_balena_nediterraneo.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/autostrade_del_\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/"},{"@type":"ListItem","position":2,"name":"Autostrade del mare e balene"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#website","url":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/","name":"Torino puo&#039; farcela","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#\/schema\/person\/8b80d88227572133798036d6f1fb2057","name":"Gustavo Rinaldi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g","caption":"Gustavo Rinaldi"},"description":"Nato a Torino nel 1967, la sua prima maestra e` stata una vittima delle repressioni bolsceviche, Maria Bruch. Ha frequentato sia la scuola pubblica che quella dei Gesuiti. Come volontario ha promosso prima una raccolta carta e poi la riorganizzazione del gentro di formazione agricola di Andriamboasary in Madagascar. Ha fondato l'associazione Enthusiasmus che per piu' di dieci anni si e` occupata di formazione politico-sociale dei giovani, permettendo a molti giovani di conoscere il mondo esterno ed a qualcuno\/a di trovare moglie o marito. Nel 1991 e` stato testimone oculare dei moti di piazza che a Leningrado si opponevano al tentato golpe anti-riformatore. Nel 1994 si e` laureato in economia con Sergio Ricossa ed ha prestato servizio presso l'Istituto Penale Minorile \"Ferrante Aporti\", occupandosi dei denari e delle spese dei detenuti. Dal 1995 ha iniziato a lavorare per diversi progetti di valutazione e formazione promossi dall'Unione Europea e da altri enti nell'ex Unione Sovietica. Nel 2000-2001 e` stato consigliere economico del governo della Georgia. Nel 2006 ha conseguito il Ph.D. in economics all'Imperial College dell'University of London. Ha lavorato come economista per l'Institute of Alcohol Studies di Londra. Dal 2008 lavora per l'universita' di Torino dove oggi insegna public economics; insegna inoltre fundamentals in mathematics ed economics for managers ad ESCP-Europe.","url":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/author\/gustavo-rinaldi\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/posts\/138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/comments?post=138"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/posts\/138\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/media?parent=138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/categories?post=138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/tags?post=138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}