{"id":128,"date":"2006-04-07T11:01:18","date_gmt":"2006-04-07T11:01:18","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/torinopuofarcela\/2006\/04\/07\/i_benefici_dell\/"},"modified":"2006-04-07T11:01:18","modified_gmt":"2006-04-07T11:01:18","slug":"i_benefici_dell","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/i_benefici_dell\/","title":{"rendered":"I benefici dell&#8217;immigrazione vanno redistribuiti"},"content":{"rendered":"<p><a href=\"http:\/\/gustavorinaldi.blog.lastampa.it\/il_mio_weblog\/2006\/03\/gli_immigrati_r.html\">&nbsp;<\/a><\/p>\n<p class=\"MsoNormal\"><span lang=\"EN-GB\">Abbiamo scritto che il lavoro degli<br \/>\nimmigrati non e` in concorrenza con quello degli italiani:<\/span><\/p>\n<p><span style=\"font-size: 0.6em\"><a href=\"http:\/\/gustavorinaldi.blog.lastampa.it\/il_mio_weblog\/2006\/03\/gli_immigrati_r.html\">http:\/\/gustavorinaldi.blog.lastampa.it\/il_mio_weblog\/2006\/03\/gli_immigrati_r.html<\/a><\/span> <\/p>\n<p>Nuovi studi ci dicono che e` il caso di correggere in parte quanto scritto. Martin Wolf del Financial Times di mercoledi&#8217; 5 aprile riferisce di due recenti studi sull&#8217;immigrazione. Da essi risulta che e` vero che gli immigrati favoriscono la crescita economica nei paesi ricchi, ma e` anche vero che esiste una concorrenza tra i lavoratori immigrati e certi lavoratori nazionali con un profilo professionale piu` simile a quello degli immigrati: i poveri ed i meno istruiti. Anche se spesso gli immigrati sono istruiti, di fatto, inizialmente e` con gli italiani meno istruiti che essi sono in diretta concorrenza. In certi casi e` vero che, se lavora l&#8217;immigrato, non lavora l&#8217;italiano.&nbsp; Allora che fare? Bloccare l&#8217;immigrazione? Non&nbsp; necessariamente. L&#8217;immigrazione porta comunque molti benefici al paese. Questi benefici vanno sopratutto alle classi piu&#8217; ricche ed istruite e alla classe media e medio bassa. Non vanno alla classe piu&#8217; bassa. Bisogna ricordarsi di cio&#8217; e dare dei benefici specifici a quei cittadini italiani che sono in diretta concorrenza con gli immigrati: i meno istruiti e qualificati. Loro non hanno torto ad essere contro l&#8217;immigrazione, quando sono lasciati soli a pagarne il costo. Le tasse, il sistema formativo, i servizi sociali, le case popolari ed altri sussidi pubblici dovranno tenere conto di questa realta`.<br \/>Gustavo Rinaldi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Abbiamo scritto che il lavoro degli immigrati non e` in concorrenza con quello degli italiani: http:\/\/gustavorinaldi.blog.lastampa.it\/il_mio_weblog\/2006\/03\/gli_immigrati_r.html Nuovi studi ci dicono che e` il caso di correggere in parte quanto scritto. Martin Wolf del Financial Times di mercoledi&#8217; 5 aprile riferisce di due recenti studi sull&#8217;immigrazione. Da essi risulta che e` vero che gli immigrati &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/i_benefici_dell\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;I benefici dell&#8217;immigrazione vanno redistribuiti&#8221;<\/span><\/a><\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,40],"tags":[],"class_list":["post-128","post","type-post","status-publish","format-standard","hentry","category-attualita","category-lavoro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I benefici dell&#039;immigrazione vanno redistribuiti - Torino puo&#039; farcela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/i_benefici_dell\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I benefici dell&#039;immigrazione vanno redistribuiti - Torino puo&#039; farcela\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/i_benefici_dell\/\" \/>\n<meta property=\"og:site_name\" content=\"Torino puo&#039; farcela\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2006-04-07T11:01:18+00:00\" \/>\n<meta name=\"author\" content=\"Gustavo Rinaldi\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gustavo Rinaldi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/i_benefici_dell\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/i_benefici_dell\\\/\"},\"author\":{\"name\":\"Gustavo Rinaldi\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#\\\/schema\\\/person\\\/8b80d88227572133798036d6f1fb2057\"},\"headline\":\"I benefici dell&#8217;immigrazione vanno redistribuiti\",\"datePublished\":\"2006-04-07T11:01:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/i_benefici_dell\\\/\"},\"wordCount\":254,\"commentCount\":1,\"articleSection\":[\"Attualit\u00e0\",\"Lavoro\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/i_benefici_dell\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/i_benefici_dell\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/i_benefici_dell\\\/\",\"name\":\"I benefici dell'immigrazione vanno redistribuiti - Torino puo&#039; farcela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#website\"},\"datePublished\":\"2006-04-07T11:01:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#\\\/schema\\\/person\\\/8b80d88227572133798036d6f1fb2057\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/i_benefici_dell\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/i_benefici_dell\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/i_benefici_dell\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I benefici dell&#8217;immigrazione vanno redistribuiti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/\",\"name\":\"Torino puo&#039; farcela\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/#\\\/schema\\\/person\\\/8b80d88227572133798036d6f1fb2057\",\"name\":\"Gustavo Rinaldi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g\",\"caption\":\"Gustavo Rinaldi\"},\"description\":\"Nato a Torino nel 1967, la sua prima maestra e` stata una vittima delle repressioni bolsceviche, Maria Bruch. Ha frequentato sia la scuola pubblica che quella dei Gesuiti. Come volontario ha promosso prima una raccolta carta e poi la riorganizzazione del gentro di formazione agricola di Andriamboasary in Madagascar. Ha fondato l'associazione Enthusiasmus che per piu' di dieci anni si e` occupata di formazione politico-sociale dei giovani, permettendo a molti giovani di conoscere il mondo esterno ed a qualcuno\\\/a di trovare moglie o marito. Nel 1991 e` stato testimone oculare dei moti di piazza che a Leningrado si opponevano al tentato golpe anti-riformatore. Nel 1994 si e` laureato in economia con Sergio Ricossa ed ha prestato servizio presso l'Istituto Penale Minorile \\\"Ferrante Aporti\\\", occupandosi dei denari e delle spese dei detenuti. Dal 1995 ha iniziato a lavorare per diversi progetti di valutazione e formazione promossi dall'Unione Europea e da altri enti nell'ex Unione Sovietica. Nel 2000-2001 e` stato consigliere economico del governo della Georgia. Nel 2006 ha conseguito il Ph.D. in economics all'Imperial College dell'University of London. Ha lavorato come economista per l'Institute of Alcohol Studies di Londra. Dal 2008 lavora per l'universita' di Torino dove oggi insegna public economics; insegna inoltre fundamentals in mathematics ed economics for managers ad ESCP-Europe.\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/torinopuofarcela\\\/author\\\/gustavo-rinaldi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I benefici dell'immigrazione vanno redistribuiti - Torino puo&#039; farcela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/i_benefici_dell\/","og_locale":"it_IT","og_type":"article","og_title":"I benefici dell'immigrazione vanno redistribuiti - Torino puo&#039; farcela","og_url":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/i_benefici_dell\/","og_site_name":"Torino puo&#039; farcela","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2006-04-07T11:01:18+00:00","author":"Gustavo Rinaldi","twitter_misc":{"Scritto da":"Gustavo Rinaldi","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/i_benefici_dell\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/i_benefici_dell\/"},"author":{"name":"Gustavo Rinaldi","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#\/schema\/person\/8b80d88227572133798036d6f1fb2057"},"headline":"I benefici dell&#8217;immigrazione vanno redistribuiti","datePublished":"2006-04-07T11:01:18+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/i_benefici_dell\/"},"wordCount":254,"commentCount":1,"articleSection":["Attualit\u00e0","Lavoro"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/i_benefici_dell\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/i_benefici_dell\/","url":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/i_benefici_dell\/","name":"I benefici dell'immigrazione vanno redistribuiti - Torino puo&#039; farcela","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#website"},"datePublished":"2006-04-07T11:01:18+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#\/schema\/person\/8b80d88227572133798036d6f1fb2057"},"breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/i_benefici_dell\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/i_benefici_dell\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/i_benefici_dell\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/"},{"@type":"ListItem","position":2,"name":"I benefici dell&#8217;immigrazione vanno redistribuiti"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#website","url":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/","name":"Torino puo&#039; farcela","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/#\/schema\/person\/8b80d88227572133798036d6f1fb2057","name":"Gustavo Rinaldi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e99a9f82a322e96ef791b7258f31e60fc11045aeb727a5f8f547e81aa58f4b8c?s=96&d=mm&r=g","caption":"Gustavo Rinaldi"},"description":"Nato a Torino nel 1967, la sua prima maestra e` stata una vittima delle repressioni bolsceviche, Maria Bruch. Ha frequentato sia la scuola pubblica che quella dei Gesuiti. Come volontario ha promosso prima una raccolta carta e poi la riorganizzazione del gentro di formazione agricola di Andriamboasary in Madagascar. Ha fondato l'associazione Enthusiasmus che per piu' di dieci anni si e` occupata di formazione politico-sociale dei giovani, permettendo a molti giovani di conoscere il mondo esterno ed a qualcuno\/a di trovare moglie o marito. Nel 1991 e` stato testimone oculare dei moti di piazza che a Leningrado si opponevano al tentato golpe anti-riformatore. Nel 1994 si e` laureato in economia con Sergio Ricossa ed ha prestato servizio presso l'Istituto Penale Minorile \"Ferrante Aporti\", occupandosi dei denari e delle spese dei detenuti. Dal 1995 ha iniziato a lavorare per diversi progetti di valutazione e formazione promossi dall'Unione Europea e da altri enti nell'ex Unione Sovietica. Nel 2000-2001 e` stato consigliere economico del governo della Georgia. Nel 2006 ha conseguito il Ph.D. in economics all'Imperial College dell'University of London. Ha lavorato come economista per l'Institute of Alcohol Studies di Londra. Dal 2008 lavora per l'universita' di Torino dove oggi insegna public economics; insegna inoltre fundamentals in mathematics ed economics for managers ad ESCP-Europe.","url":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/author\/gustavo-rinaldi\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/posts\/128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/comments?post=128"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/posts\/128\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/media?parent=128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/categories?post=128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/torinopuofarcela\/wp-json\/wp\/v2\/tags?post=128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}