{"id":1,"date":"2011-06-17T08:30:03","date_gmt":"2011-06-17T06:30:03","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/storiedipiemonte\/?p=1"},"modified":"2011-06-17T10:34:32","modified_gmt":"2011-06-17T08:34:32","slug":"esodo-clandestino-degli-ebrei-stranieri-dall-italia-alla-francia","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/esodo-clandestino-degli-ebrei-stranieri-dall-italia-alla-francia\/","title":{"rendered":"Esodo clandestino degli Ebrei stranieri dall\u2019Italia alla Francia"},"content":{"rendered":"<p><a href=\"http:\/\/www.quotidianopiemontese.it\/storiedipiemonte\/files\/Esodo-clandestino-degli-ebrei-stranieri-dall\u2019Italia-verso-la-Francia.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-7\" title=\"Esodo clandestino degli ebrei stranieri dall\u2019Italia verso la Francia\" src=\"http:\/\/www.quotidianopiemontese.it\/storiedipiemonte\/files\/Esodo-clandestino-degli-ebrei-stranieri-dall\u2019Italia-verso-la-Francia.jpg\" alt=\"\" width=\"150\" height=\"213\" \/><\/a><\/p>\n<p><strong>Di Elena Dresti <\/strong><\/p>\n<p><strong><a href=\"http:\/\/www.quotidianopiemontese.it\/wp-content\/uploads\/downloads\/2011\/06\/Esodo-clandestino-degli-ebrei-stranieri-dall%E2%80%99Italia-verso-la-Francia.pdf\" target=\"_blank\">Qui per scaricare l&#8217;ebook completo della storia<\/a><\/strong><\/p>\n<p>Dopo mesi contraddistinti da una crescente e virulenta campagna diffamatoria, il Governo fascista stabiliva, con il Decreto legge n. 1381 del 7 settembre 1938 (entrato in vigore il 12 settembre) che entro il 12 marzo 1939, tutti gli ebrei stranieri, circa cinquemila, salvo poche eccezioni, avrebbero dovuto lasciare l\u2019Italia.<br \/>\nMeno conosciute, anche agli ebrei stessi, erano invece le modalit\u00e0 di attuazione.<br \/>\nIl Governo lasciava libert\u00e0 ai singoli individui di scegliere la soluzione di trasferimento ritenuta pi\u00f9 adatta, ma per tutti, l\u2019incognita principale era rappresentata dalla scelta del nuovo paese da raggiungere.<br \/>\nTra l\u2019estate del 1938 ed i primi del 1939, di fronte all\u2019espulsione dalle scuole, alla cacciata degli ebrei stranieri, alla proibizione dei matrimoni misti, alla schedatura, alla perdita del lavoro negli uffici pubblici, all\u2019allontanamento dall\u2019esercito, la prima reazione degli israeliti della provincia di Cuneo fu di smarrimento e di incredulit\u00e0.  <!--more--><br \/>\nLa pressione psicologica esercitata dal Governo produsse i suoi effetti e, circa la met\u00e0 degli ebrei stranieri residenti, lasciarono il paese prima della scadenza fissata. Allo scopo di facilitare l\u2019esodo il Ministero dell\u2019interno, nel gennaio e nell\u2019aprile \u201839, aveva impartito lo opportune istruzioni ai prefetti. I problemi incontrati dagli ebrei erano notevoli, legati soprattutto alla difficolt\u00e0 di ottenere i visti d\u2019ingresso inoltre, le richieste di proroga al provvedimento di espulsione passavano attraverso numerosi ministeri e richiedevano mesi prima di essere evase.<br \/>\nPertanto il regime, allo scopo di superare le difficolt\u00e0, nel gennaio 1939, aveva prospettato agli ebrei stranieri due soluzioni. La prima era il rimpatrio nei loro paesi di provenienza, soluzione sgradita non solo agli ebrei stessi ma anche ai nazisti. La seconda consisteva nell\u2019allontanamento verso la Francia, soluzione che risultava pi\u00f9 gradita e praticabile. Infatti per gli ebrei la Francia era considerata la nazione della rivoluzione francese e dell\u2019emancipazione, la patria dei diritti di eguaglianza, di libert\u00e0, di fraternit\u00e0 e considerata una \u201cTerra Promessa\u201d da chi non si rassegnava all\u2019idea che, nel 1939, terre promesse non ne esistessero pi\u00f9 per nessuno.<br \/>\nAgli ebrei gli affari non andavano bene a causa delle ostilit\u00e0 di molti e delle richieste di denaro da parte di delinquenti che adesso potevano agire impunemente su persone non pi\u00f9 protette dalla legge. La situazione per loro andava via via peggiorando. Il clima era di forte ostilit\u00e0. Ora sempre pi\u00f9 spesso sui giornali comparivano articoli che mettevano in cattiva luce gli ebrei, descrivendoli come essere avidi, ripugnanti, ricchi, traditori e dove venivano indicati con il nome dispregiativo di \u201cgiudei\u201d. Gli altri li guardavano o li consideravano come degli appestati o dei criminali. Le autorit\u00e0 che scoprivano la presenza di ebrei in zona di guerra decretavano che dovevano andarsene e alla svelta. Infatti i giorni per l\u2019evacuazione erano pochi. Gli ebrei avevano paura e non uscivano quasi pi\u00f9 di casa. Per molte famiglie il problema era la sopravvivenza e quindi si presentava ancora pi\u00f9 di prima l\u2019urgenza di fuggire.<br \/>\nIl prefetto e le forze di polizia dovevano gestire gli allontanamenti: l\u2019obbiettivo da raggiungere giustificava i metodi che sarebbero stati impiegati. Furono queste le vere motivazioni  di un esodo che nella sua  evoluzione si sarebbe  sviluppato, nell\u2019arco di due anni, per vie terrestri e marittime, dalla Riviera Ligure verso la Costa Azzurra.<br \/>\nRisulta che, nel febbraio 1939, un mese prima del previsto esodo di massa, 500 ebrei avevano gi\u00e0 raggiunto la citt\u00e0 francese. Le autorit\u00e0 francesi erano molto preoccupate dell\u2019esodo in corso. Il 21 febbraio 1939, il Ministero dell\u2019interno inviava un telegramma al prefetto di Nizza nel quale ordinava alle gendarmerie di Breil e di Mentone di esercitare una vigilanza particolare e di fare controlli molto stretti. Inoltre le stesse dovevano respingere immediatamente e impietosamente i clandestini, sorpresi senza passaporto o sprovvisti di visto consolare francese.<br \/>\nGli ebrei erano ovviamente tenuti all\u2019oscuro del fatto che i sentieri, che si apprestavano a percorrere, erano strettamente sorvegliati dal lato francese, ragion per cui era inevitabile cadere nella rete della polizia. In alcuni casi iniziava per loro una tragica odissea, poich\u00e9 la polizia francese, dopo averli identificati e in qualche caso rifocillati, li rispediva in Italia. Quindi l\u2019espulsione era di conseguenza la regola quasi assoluta ma gli ebrei, nonostante tutto, tentavano di introdursi nuovamente nel paese francese, lungo la frontiera. Giunti ancora ai posti di confine italiani, l\u2019accoglienza non era la stessa che avevano ricevuto in precedenza. Infatti la milizia maltrattava e picchiava gli ebrei respinti rispedendoli, per lo stesso sentiero o per un altro alternativo, nuovamente verso la frontiera francese.<br \/>\nQuesti estenuanti rimbalzi da una parte all\u2019altra del confine, attraverso diversi percorsi, potevano ripetersi in alcuni casi quattro o cinque volte. Agli ebrei percossi, smarriti ed esausti, capitava di restare in quella \u201cterra di nessuno\u201d, tra i due posti fissi, anche per giorni, bevendo a qualche rara fonte incontrata lungo il percorso nutrendosi di bacche o altri frutti, riposando e dormendo in qualche casolare abbandonato, nell\u2019attesa del momento opportuno per tentare nuovamente la sorte. In qualche caso le guardie francesi impietosite dalla condizione in cui versavano o, impossibilitate a respingere nuovamente i clandestini a causa della strettissima sorveglianza delle guardie confinarie italiane, li conducevano a Nizza mettendoli a disposizione dell\u2019autorit\u00e0 giudiziaria. Qualcuno in preda a un profondo sconforto riusc\u00ec a farsi arrestare minacciando di lanciarsi nel vuoto.<br \/>\nA partire dal luglio 1939 le vie terrestri persero il ruolo fondamentale che avevano fino ad allora ricoperto e diverse furono le condizioni che ne provocarono il declino. Fino a quella data, non erano ancora operative le \u201cagenzie marittime\u201d che avrebbero gestito i trasporti via mare e trasportato un numero molto elevato di clandestini. L\u2019arrivo in massa degli ebrei, a partire dal luglio, port\u00f2 un cambiamento nella composizione dei gruppi di profughi. Se prima di quella data i singoli erano la maggioranza, si assiste in seguito all\u2019arrivo sempre pi\u00f9 frequente di interi nuclei familiari, in qualche caso con bambini e spesso con persone anziane. Per loro la scelta pi\u00f9 ovvia, perch\u00e9 meno faticosa, era quella via mare.<br \/>\nMa quantificare il numero di coloro che scelsero di emigrare in Francia, risulta assai arduo. Per quanto riguarda le vie terrestri usate, nonostante fossero infinite, alcune forse mai scoperte, si pu\u00f2 affermare che la stima di 1500 persone \u00e8 da considerarsi realistica. Invece l\u2019esodo via mare, di persone trasportate nella clandestinit\u00e0 pi\u00f9 assoluta, potrebbe essere pari, se non superiore, a quelli che hanno lasciato traccia del loro passaggio e di conseguenza si pu\u00f2 ipotizzare che si tratti di almeno 2000 persone. Naturalmente non manc\u00f2, per entrambe le vie, il guazzabuglio di spregiudicati imprenditori, che si attrezzarono e crearono un efficiente servizio di passaggi transfrontalieri, lucrandoci sopra con la benedizione del prefetto e delle autorit\u00e0 della capitale.<br \/>\nPer tutti gli ebrei stranieri, che avevano raggiunto alla fine degli anni \u201830      clandestinamente  Nizza,  era  stato  creato  il  Comit\u00e9  d\u2019Assistances  aux   Refugies (CAR), fondato con l\u2019obiettivo di  aiutarli  a  regolare  la  loro  posizione  nei  confronti dell\u2019autorit\u00e0 francese. Questo organismo era finanziato dal Comit\u00e9 d\u2019Assistances di Parigi e da contribuzioni volontarie da parte delle famiglie ebree benestanti della citt\u00e0.<br \/>\nSubito dopo la creazione del CAR, era stata aperta in Rue Beaumont una mensa che serviva regolarmente, due volte al giorno, pasti frugali. Si calcola che nel 1939 questa struttura doveva fornire 1000 pasti al giorno. Naturalmente all\u2019interno della mensa si vivevano drammi umani e di disperazione. In quell\u2019umile e decoroso luogo, si ritrovavano seduti allo stesso tavolo, nella miseria pi\u00f9 completa, contadini e operai cecoslovacchi, artisti e celebrit\u00e0 berlinesi che negli anni precedenti erano stati applauditi e osannati in patria.<br \/>\nLa  situazione per una parte degli esuli giunti dalla Riviera ligure, nel periodo che si colloca tra il loro arrivo in Francia e l\u2019inizio degli arresti e delle deportazioni nell\u2019estate 1942, sotto il regime collaborazionista di Vichy, fu addirittura peggiore. Infatti allo scoppio della guerra con la Germania, il 4 settembre 1939, tutti i cittadini di nazionalit\u00e0 tedesca, considerati appartenenti a nazioni nemiche, ebrei e non, di sesso maschile e di et\u00e0 compresa tra 17 e 50 anni, furono internati, per quanto riguarda il Dipartimento della Alpi Marittime, nel Fort Carr\u00e8 di Antibes, assieme ai cittadini ex austriaci e cecoslovacchi. La gran parte degli internati di Antibes fu trasferita, nell\u2019autunno e nell\u2019inverno 1939, al camp des Milles in Provenza, dove le condizioni di vita erano primitive e i servizi igienici assolutamente insufficienti e inoltre vi regnava il pi\u00f9 grande disordine amministrativo.<br \/>\nAl campo di Vernet, nel dipartimento dell\u2019Ariege, classificato come repressivo, furono internati tutti gli esuli tedeschi potenzialmente pericolosi per la sicurezza nazionale. I tedeschi e gli austriaci, classificati come meno sospetti, furono avviati verso i campi di internamento della regione: questi erano spesso installati in fattorie abbandonate, fabbriche dismesse, qualche volta in tende da circo requisite per l\u2019occasione. Le condizioni igieniche erano ovunque insufficienti, la vita era pericolosa e i rifornimenti ai prigionieri, cos\u00ec come il denaro e pacchi dall\u2019esterno, erano difficili da far pervenire.<br \/>\nA partire dal 1941, un certo numero di ebrei fu destinato alle cosiddette residences assign\u00e8 ovvero erano obbligati a risiedere in modo coatto, in alcuni piccoli villaggi, situati nei dintorni di Nizza, quali Levens, Sospel (dove esisteva un piccolo campo di internamento), Puget &#8211; Theniers, Guilliaumes e Villars su Var.<br \/>\nSempre sotto il regime di Vichy, nel 1942, numerosi ebrei furono trasferiti per mezzo convogli ferroviari, al campo di Gurs nei Pirenei, definito come semirepressivo. Nello stesso periodo, vi furono quattro convogli che raggiunsero il campo di Rivesaltes, nel sud della Francia.<br \/>\nInoltre molti ebrei, tra i quali numerosi erano i clandestini giunti dall\u2019Italia, residenti ancora a Nizza o nei dintorni, furono interessati dalla retata organizzata dal Governo di Vichy e condotta dalla polizia francese. Gli ebrei arrestati durante la retata sarebbero stati concentrati nella caserma Auvare a Nizza.<br \/>\nQuesto periodo burrascoso ebbe termine l\u201911 novembre 1942, quando le truppe italiane occuparono la Costa Azzurra e altri sei dipartimenti, situati a ovest del fiume Rodano. In questa occasione i militari italiani garantirono agli ebrei la loro protezione, ostacolando con ogni espediente i tentativi tedeschi di impadronirsi di quanti ancora soggiornavano nella zona.<br \/>\nDopo alcune settimane, le autorit\u00e0 italiane, con il pretesto di un maggior controllo e di una improbabile promessa di deportazione ai tedeschi, avevano provveduto ad avviare verso le r\u00e9sidences forc\u00e9e di Megeve, Saint-Gervais e St. Martin V\u00e9subie, circa 2500 ebrei, giunti da poco nella Costa Azzurra e che si trovavano in una posizione irregolare, e altri 1000 furono inviati in localit\u00e0 quali Vence, Barcelonnette, ecc.. Questa felice parentesi termin\u00f2 l\u20198 settembre 1943 quando, dopo l\u2019annuncio dell\u2019armistizio, le truppe italiane si ritirarono in modo disordinato.<br \/>\nPurtroppo per gli ebrei presto gli avvenimenti cominceranno a precipitare sia sul piano politico sia su quello militare. Ha termine, con questa data, la fase burocratica dell\u2019antisemitismo italiano, che cede il passo all\u2019antisemitismo nazista, mirato non gi\u00e0 alla separazione ma all\u2019eliminazione degli ebrei.<br \/>\nQuindi gli spostamenti si fecero sempre pi\u00f9 clandestini, nel tentativo di sfuggire all\u2019inasprimento delle persecuzioni ed alla cattura, giacch\u00e9 ora non erano pi\u00f9 soltanto in gioco lo studio, il lavoro o la propriet\u00e0 ma la libert\u00e0 personale e la vita.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Di Elena Dresti Qui per scaricare l&#8217;ebook completo della storia Dopo mesi contraddistinti da una crescente e virulenta campagna diffamatoria, il Governo fascista stabiliva, con il Decreto legge n. 1381 del 7 settembre 1938 (entrato in vigore il 12 settembre) che entro il 12 marzo 1939, tutti gli ebrei stranieri, circa cinquemila, salvo poche eccezioni, &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/esodo-clandestino-degli-ebrei-stranieri-dall-italia-alla-francia\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Esodo clandestino degli Ebrei stranieri dall\u2019Italia alla Francia&#8221;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":7,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,1],"tags":[8,3,5,4,7],"class_list":["post-1","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ebook","category-storie","tag-ebook-2","tag-ebrei","tag-francia","tag-italia","tag-piemonte"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Esodo clandestino degli Ebrei stranieri dall\u2019Italia alla Francia - Storie di Piemonte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/esodo-clandestino-degli-ebrei-stranieri-dall-italia-alla-francia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Esodo clandestino degli Ebrei stranieri dall\u2019Italia alla Francia - Storie di Piemonte\" \/>\n<meta property=\"og:description\" content=\"Di Elena Dresti Qui per scaricare l&#8217;ebook completo della storia Dopo mesi contraddistinti da una crescente e virulenta campagna diffamatoria, il Governo fascista stabiliva, con il Decreto legge n. 1381 del 7 settembre 1938 (entrato in vigore il 12 settembre) che entro il 12 marzo 1939, tutti gli ebrei stranieri, circa cinquemila, salvo poche eccezioni, &hellip; Leggi tutto &quot;Esodo clandestino degli Ebrei stranieri dall\u2019Italia alla Francia&quot;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/esodo-clandestino-degli-ebrei-stranieri-dall-italia-alla-francia\/\" \/>\n<meta property=\"og:site_name\" content=\"Storie di Piemonte\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese\" \/>\n<meta property=\"article:published_time\" content=\"2011-06-17T06:30:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-06-17T08:34:32+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/files\/Esodo-clandestino-degli-ebrei-stranieri-dall\u2019Italia-verso-la-Francia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"150\" \/>\n\t<meta property=\"og:image:height\" content=\"213\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione QP\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione QP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/storiedipiemonte\\\/esodo-clandestino-degli-ebrei-stranieri-dall-italia-alla-francia\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/storiedipiemonte\\\/esodo-clandestino-degli-ebrei-stranieri-dall-italia-alla-francia\\\/\"},\"author\":{\"name\":\"Redazione QP\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/storiedipiemonte\\\/#\\\/schema\\\/person\\\/f035517c4ecaa0991ede4668fb6c93a6\"},\"headline\":\"Esodo clandestino degli Ebrei stranieri dall\u2019Italia alla Francia\",\"datePublished\":\"2011-06-17T06:30:03+00:00\",\"dateModified\":\"2011-06-17T08:34:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/storiedipiemonte\\\/esodo-clandestino-degli-ebrei-stranieri-dall-italia-alla-francia\\\/\"},\"wordCount\":1852,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/storiedipiemonte\\\/esodo-clandestino-degli-ebrei-stranieri-dall-italia-alla-francia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/storiedipiemonte\\\/files\\\/Esodo-clandestino-degli-ebrei-stranieri-dall\u2019Italia-verso-la-Francia.jpg\",\"keywords\":[\"ebook\",\"ebrei\",\"francia\",\"italia\",\"piemonte\"],\"articleSection\":[\"Ebook\",\"Storie\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/storiedipiemonte\\\/esodo-clandestino-degli-ebrei-stranieri-dall-italia-alla-francia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/storiedipiemonte\\\/esodo-clandestino-degli-ebrei-stranieri-dall-italia-alla-francia\\\/\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/storiedipiemonte\\\/esodo-clandestino-degli-ebrei-stranieri-dall-italia-alla-francia\\\/\",\"name\":\"Esodo clandestino degli Ebrei stranieri dall\u2019Italia alla Francia - Storie di Piemonte\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/storiedipiemonte\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/storiedipiemonte\\\/esodo-clandestino-degli-ebrei-stranieri-dall-italia-alla-francia\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/storiedipiemonte\\\/esodo-clandestino-degli-ebrei-stranieri-dall-italia-alla-francia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/storiedipiemonte\\\/files\\\/Esodo-clandestino-degli-ebrei-stranieri-dall\u2019Italia-verso-la-Francia.jpg\",\"datePublished\":\"2011-06-17T06:30:03+00:00\",\"dateModified\":\"2011-06-17T08:34:32+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/storiedipiemonte\\\/#\\\/schema\\\/person\\\/f035517c4ecaa0991ede4668fb6c93a6\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/storiedipiemonte\\\/esodo-clandestino-degli-ebrei-stranieri-dall-italia-alla-francia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/storiedipiemonte\\\/esodo-clandestino-degli-ebrei-stranieri-dall-italia-alla-francia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/storiedipiemonte\\\/files\\\/Esodo-clandestino-degli-ebrei-stranieri-dall\u2019Italia-verso-la-Francia.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/storiedipiemonte\\\/files\\\/Esodo-clandestino-degli-ebrei-stranieri-dall\u2019Italia-verso-la-Francia.jpg\",\"width\":\"150\",\"height\":\"213\"},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/storiedipiemonte\\\/#website\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/storiedipiemonte\\\/\",\"name\":\"Storie di Piemonte\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/storiedipiemonte\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/storiedipiemonte\\\/#\\\/schema\\\/person\\\/f035517c4ecaa0991ede4668fb6c93a6\",\"name\":\"Redazione QP\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e231329e5359ccdceec53863359bdff8064f7c323b766bf34a97c00007a7189d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e231329e5359ccdceec53863359bdff8064f7c323b766bf34a97c00007a7189d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e231329e5359ccdceec53863359bdff8064f7c323b766bf34a97c00007a7189d?s=96&d=mm&r=g\",\"caption\":\"Redazione QP\"},\"description\":\"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte\",\"sameAs\":[\"http:\\\/\\\/www.quotidianopiemontese.it\\\/\",\"https:\\\/\\\/www.facebook.com\\\/quotidianopiemontese\",\"https:\\\/\\\/x.com\\\/quotidianopiem\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/storiedipiemonte\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Esodo clandestino degli Ebrei stranieri dall\u2019Italia alla Francia - Storie di Piemonte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/esodo-clandestino-degli-ebrei-stranieri-dall-italia-alla-francia\/","og_locale":"it_IT","og_type":"article","og_title":"Esodo clandestino degli Ebrei stranieri dall\u2019Italia alla Francia - Storie di Piemonte","og_description":"Di Elena Dresti Qui per scaricare l&#8217;ebook completo della storia Dopo mesi contraddistinti da una crescente e virulenta campagna diffamatoria, il Governo fascista stabiliva, con il Decreto legge n. 1381 del 7 settembre 1938 (entrato in vigore il 12 settembre) che entro il 12 marzo 1939, tutti gli ebrei stranieri, circa cinquemila, salvo poche eccezioni, &hellip; Leggi tutto \"Esodo clandestino degli Ebrei stranieri dall\u2019Italia alla Francia\"","og_url":"http:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/esodo-clandestino-degli-ebrei-stranieri-dall-italia-alla-francia\/","og_site_name":"Storie di Piemonte","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"https:\/\/www.facebook.com\/quotidianopiemontese","article_published_time":"2011-06-17T06:30:03+00:00","article_modified_time":"2011-06-17T08:34:32+00:00","og_image":[{"width":150,"height":213,"url":"http:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/files\/Esodo-clandestino-degli-ebrei-stranieri-dall\u2019Italia-verso-la-Francia.jpg","type":"image\/jpeg"}],"author":"Redazione QP","twitter_misc":{"Scritto da":"Redazione QP","Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/esodo-clandestino-degli-ebrei-stranieri-dall-italia-alla-francia\/#article","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/esodo-clandestino-degli-ebrei-stranieri-dall-italia-alla-francia\/"},"author":{"name":"Redazione QP","@id":"http:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/#\/schema\/person\/f035517c4ecaa0991ede4668fb6c93a6"},"headline":"Esodo clandestino degli Ebrei stranieri dall\u2019Italia alla Francia","datePublished":"2011-06-17T06:30:03+00:00","dateModified":"2011-06-17T08:34:32+00:00","mainEntityOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/esodo-clandestino-degli-ebrei-stranieri-dall-italia-alla-francia\/"},"wordCount":1852,"commentCount":0,"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/esodo-clandestino-degli-ebrei-stranieri-dall-italia-alla-francia\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/files\/Esodo-clandestino-degli-ebrei-stranieri-dall\u2019Italia-verso-la-Francia.jpg","keywords":["ebook","ebrei","francia","italia","piemonte"],"articleSection":["Ebook","Storie"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/esodo-clandestino-degli-ebrei-stranieri-dall-italia-alla-francia\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/esodo-clandestino-degli-ebrei-stranieri-dall-italia-alla-francia\/","url":"http:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/esodo-clandestino-degli-ebrei-stranieri-dall-italia-alla-francia\/","name":"Esodo clandestino degli Ebrei stranieri dall\u2019Italia alla Francia - Storie di Piemonte","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/#website"},"primaryImageOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/esodo-clandestino-degli-ebrei-stranieri-dall-italia-alla-francia\/#primaryimage"},"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/esodo-clandestino-degli-ebrei-stranieri-dall-italia-alla-francia\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/files\/Esodo-clandestino-degli-ebrei-stranieri-dall\u2019Italia-verso-la-Francia.jpg","datePublished":"2011-06-17T06:30:03+00:00","dateModified":"2011-06-17T08:34:32+00:00","author":{"@id":"http:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/#\/schema\/person\/f035517c4ecaa0991ede4668fb6c93a6"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/esodo-clandestino-degli-ebrei-stranieri-dall-italia-alla-francia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/esodo-clandestino-degli-ebrei-stranieri-dall-italia-alla-francia\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/files\/Esodo-clandestino-degli-ebrei-stranieri-dall\u2019Italia-verso-la-Francia.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/files\/Esodo-clandestino-degli-ebrei-stranieri-dall\u2019Italia-verso-la-Francia.jpg","width":"150","height":"213"},{"@type":"WebSite","@id":"http:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/#website","url":"http:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/","name":"Storie di Piemonte","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"http:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/#\/schema\/person\/f035517c4ecaa0991ede4668fb6c93a6","name":"Redazione QP","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/e231329e5359ccdceec53863359bdff8064f7c323b766bf34a97c00007a7189d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e231329e5359ccdceec53863359bdff8064f7c323b766bf34a97c00007a7189d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e231329e5359ccdceec53863359bdff8064f7c323b766bf34a97c00007a7189d?s=96&d=mm&r=g","caption":"Redazione QP"},"description":"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte","sameAs":["http:\/\/www.quotidianopiemontese.it\/","https:\/\/www.facebook.com\/quotidianopiemontese","https:\/\/x.com\/quotidianopiem"],"url":"https:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/wp-json\/wp\/v2\/posts\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/wp-json\/wp\/v2\/comments?post=1"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/wp-json\/wp\/v2\/posts\/1\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/wp-json\/wp\/v2\/media\/7"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/wp-json\/wp\/v2\/media?parent=1"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/wp-json\/wp\/v2\/categories?post=1"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/storiedipiemonte\/wp-json\/wp\/v2\/tags?post=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}