{"id":544,"date":"2013-11-20T07:49:12","date_gmt":"2013-11-20T07:49:12","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/spazioaperto\/?p=544"},"modified":"2013-11-20T08:46:08","modified_gmt":"2013-11-20T08:46:08","slug":"come-donare-fondi-alla-croce-rossa-per-aiutare-lemergenza-sardegna","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/come-donare-fondi-alla-croce-rossa-per-aiutare-lemergenza-sardegna\/","title":{"rendered":"Come donare fondi alla Croce Rossa per aiutare l&#8217;emergenza in Sardegna"},"content":{"rendered":"<p><a href=\"http:\/\/www.quotidianopiemontese.it\/spazioaperto\/files\/2013\/11\/croce-rossa.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-thumbnail wp-image-545\" alt=\"croce-rossa\" src=\"http:\/\/www.quotidianopiemontese.it\/spazioaperto\/files\/2013\/11\/croce-rossa-150x149.jpg\" width=\"150\" height=\"149\" \/><\/a>La<a href=\"http:\/\/cri.it\/flex\/cm\/pages\/ServeBLOB.php\/L\/IT\/IDPagina\/19670\"> Croce Rossa Italiana ha attivato la raccolta fondi<\/a> per l&#8217;emergenza in Sardegna. Le donazioni saranno utilizzate dalla\u00a0<acronym title=\"Croce Rossa Italiana\" lang=\"IT\">CRI<\/acronym>\u00a0per sostenere gli interventi di soccorso e sopperire alle esigenze della popolazione colpita dall&#8217;alluvione.<br \/>\nE&#8217; possibile donare:<br \/>\n<strong>Mediante bonifico su conto corrente bancario<\/strong><br \/>\nCodice\u00a0<acronym title=\"International Bank Address Number (Codice identificativo bancario internazionale)\" lang=\"EN\">IBAN<\/acronym>: IT19 P010 0503 3820 0000 0200 208 ,\u00a0Intestato a: &#8221; Croce Rossa Italiana, Via Toscana 12 &#8211; 00187 Roma&#8221;\u00a0presso Banca Nazionale del Lavoro &#8211; Filiale di Roma Bissolati<br \/>\nTesoreria &#8211; Via San Nicola da Tolentino 67 &#8211; Roma.\u00a0Indicare la causale &#8220;Emergenza Sardegna&#8221;\u00a0(Per donazioni dall&#8217;estero codice BIC\/SWIFT: BNL II TRR)\u00a0<!--more--><br \/>\n<strong>Mediante conto corrente postale n. 300004\u00a0<\/strong><br \/>\nintestato a: &#8221; Croce Rossa Italiana, via Toscana 12 &#8211; 00187 Roma&#8221;,\u00a0Indicare la causale\u00a0 &#8220;Emergenza Sardegna&#8221;<br \/>\n<strong>On-line<\/strong><br \/>\nsul sito\u00a0<a href=\"http:\/\/cri.it\/flex\/cm\/pages\/ServeBLOB.php\/L\/IT\/IDPagina\/1\">www.cri.it<\/a>\u00a0(cliccare sul banner &#8220;<a href=\"http:\/\/cri.it\/flex\/FixedPages\/IT\/Donazioni.php\/L\/IT\">DONA on-line<\/a>&#8220;).\u00a0Selezionare la causale &#8220;Emergenza Sardegna&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Croce Rossa Italiana ha attivato la raccolta fondi per l&#8217;emergenza in Sardegna. Le donazioni saranno utilizzate dalla\u00a0CRI\u00a0per sostenere gli interventi di soccorso e sopperire alle esigenze della popolazione colpita dall&#8217;alluvione. E&#8217; possibile donare: Mediante bonifico su conto corrente bancario Codice\u00a0IBAN: IT19 P010 0503 3820 0000 0200 208 ,\u00a0Intestato a: &#8221; Croce Rossa Italiana, Via &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/come-donare-fondi-alla-croce-rossa-per-aiutare-lemergenza-sardegna\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Come donare fondi alla Croce Rossa per aiutare l&#8217;emergenza in Sardegna&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":545,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[57,17,192],"tags":[],"class_list":["post-544","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente","category-cittadini","category-solidarieta"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Come donare fondi alla Croce Rossa per aiutare l&#039;emergenza in Sardegna - Spazio aperto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/come-donare-fondi-alla-croce-rossa-per-aiutare-lemergenza-sardegna\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come donare fondi alla Croce Rossa per aiutare l&#039;emergenza in Sardegna - Spazio aperto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/come-donare-fondi-alla-croce-rossa-per-aiutare-lemergenza-sardegna\/\" \/>\n<meta property=\"og:site_name\" content=\"Spazio aperto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese\" \/>\n<meta property=\"article:published_time\" content=\"2013-11-20T07:49:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-11-20T08:46:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/files\/2013\/11\/croce-rossa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"162\" \/>\n\t<meta property=\"og:image:height\" content=\"149\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/come-donare-fondi-alla-croce-rossa-per-aiutare-lemergenza-sardegna\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/come-donare-fondi-alla-croce-rossa-per-aiutare-lemergenza-sardegna\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"headline\":\"Come donare fondi alla Croce Rossa per aiutare l&#8217;emergenza in Sardegna\",\"datePublished\":\"2013-11-20T07:49:12+00:00\",\"dateModified\":\"2013-11-20T08:46:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/come-donare-fondi-alla-croce-rossa-per-aiutare-lemergenza-sardegna\\\/\"},\"wordCount\":138,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/come-donare-fondi-alla-croce-rossa-per-aiutare-lemergenza-sardegna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/files\\\/2013\\\/11\\\/croce-rossa.jpg\",\"articleSection\":[\"Ambiente\",\"Cittadini\",\"Solidariet\u00e0\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/come-donare-fondi-alla-croce-rossa-per-aiutare-lemergenza-sardegna\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/come-donare-fondi-alla-croce-rossa-per-aiutare-lemergenza-sardegna\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/come-donare-fondi-alla-croce-rossa-per-aiutare-lemergenza-sardegna\\\/\",\"name\":\"Come donare fondi alla Croce Rossa per aiutare l'emergenza in Sardegna - Spazio aperto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/come-donare-fondi-alla-croce-rossa-per-aiutare-lemergenza-sardegna\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/come-donare-fondi-alla-croce-rossa-per-aiutare-lemergenza-sardegna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/files\\\/2013\\\/11\\\/croce-rossa.jpg\",\"datePublished\":\"2013-11-20T07:49:12+00:00\",\"dateModified\":\"2013-11-20T08:46:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/come-donare-fondi-alla-croce-rossa-per-aiutare-lemergenza-sardegna\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/come-donare-fondi-alla-croce-rossa-per-aiutare-lemergenza-sardegna\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/come-donare-fondi-alla-croce-rossa-per-aiutare-lemergenza-sardegna\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/files\\\/2013\\\/11\\\/croce-rossa.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/files\\\/2013\\\/11\\\/croce-rossa.jpg\",\"width\":162,\"height\":149},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/come-donare-fondi-alla-croce-rossa-per-aiutare-lemergenza-sardegna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Come donare fondi alla Croce Rossa per aiutare l&#8217;emergenza in Sardegna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/\",\"name\":\"Spazio aperto\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte\",\"sameAs\":[\"http:\\\/\\\/www.quotidianopiemontese.it\\\/\",\"https:\\\/\\\/www.facebook.com\\\/quotidianopiemontese\",\"https:\\\/\\\/x.com\\\/quotidianopiem\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/author\\\/administrator\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Come donare fondi alla Croce Rossa per aiutare l'emergenza in Sardegna - Spazio aperto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/come-donare-fondi-alla-croce-rossa-per-aiutare-lemergenza-sardegna\/","og_locale":"it_IT","og_type":"article","og_title":"Come donare fondi alla Croce Rossa per aiutare l'emergenza in Sardegna - Spazio aperto","og_url":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/come-donare-fondi-alla-croce-rossa-per-aiutare-lemergenza-sardegna\/","og_site_name":"Spazio aperto","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"https:\/\/www.facebook.com\/quotidianopiemontese","article_published_time":"2013-11-20T07:49:12+00:00","article_modified_time":"2013-11-20T08:46:08+00:00","og_image":[{"width":162,"height":149,"url":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/files\/2013\/11\/croce-rossa.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/come-donare-fondi-alla-croce-rossa-per-aiutare-lemergenza-sardegna\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/come-donare-fondi-alla-croce-rossa-per-aiutare-lemergenza-sardegna\/"},"author":{"name":"Redazione","@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"headline":"Come donare fondi alla Croce Rossa per aiutare l&#8217;emergenza in Sardegna","datePublished":"2013-11-20T07:49:12+00:00","dateModified":"2013-11-20T08:46:08+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/come-donare-fondi-alla-croce-rossa-per-aiutare-lemergenza-sardegna\/"},"wordCount":138,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/come-donare-fondi-alla-croce-rossa-per-aiutare-lemergenza-sardegna\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/files\/2013\/11\/croce-rossa.jpg","articleSection":["Ambiente","Cittadini","Solidariet\u00e0"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/spazioaperto\/come-donare-fondi-alla-croce-rossa-per-aiutare-lemergenza-sardegna\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/come-donare-fondi-alla-croce-rossa-per-aiutare-lemergenza-sardegna\/","url":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/come-donare-fondi-alla-croce-rossa-per-aiutare-lemergenza-sardegna\/","name":"Come donare fondi alla Croce Rossa per aiutare l'emergenza in Sardegna - Spazio aperto","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/come-donare-fondi-alla-croce-rossa-per-aiutare-lemergenza-sardegna\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/come-donare-fondi-alla-croce-rossa-per-aiutare-lemergenza-sardegna\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/files\/2013\/11\/croce-rossa.jpg","datePublished":"2013-11-20T07:49:12+00:00","dateModified":"2013-11-20T08:46:08+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/come-donare-fondi-alla-croce-rossa-per-aiutare-lemergenza-sardegna\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/spazioaperto\/come-donare-fondi-alla-croce-rossa-per-aiutare-lemergenza-sardegna\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/come-donare-fondi-alla-croce-rossa-per-aiutare-lemergenza-sardegna\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/files\/2013\/11\/croce-rossa.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/files\/2013\/11\/croce-rossa.jpg","width":162,"height":149},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/come-donare-fondi-alla-croce-rossa-per-aiutare-lemergenza-sardegna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/"},{"@type":"ListItem","position":2,"name":"Come donare fondi alla Croce Rossa per aiutare l&#8217;emergenza in Sardegna"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/#website","url":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/","name":"Spazio aperto","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","caption":"Redazione"},"description":"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte","sameAs":["http:\/\/www.quotidianopiemontese.it\/","https:\/\/www.facebook.com\/quotidianopiemontese","https:\/\/x.com\/quotidianopiem"],"url":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/author\/administrator\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/posts\/544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/comments?post=544"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/posts\/544\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/media\/545"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/media?parent=544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/categories?post=544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/tags?post=544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}