{"id":444,"date":"2013-02-10T23:29:23","date_gmt":"2013-02-10T23:29:23","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/spazioaperto\/?p=444"},"modified":"2013-02-10T23:29:23","modified_gmt":"2013-02-10T23:29:23","slug":"la-difficile-situazione-dei-malati-di-sarcoidosi-in-piemonte","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/la-difficile-situazione-dei-malati-di-sarcoidosi-in-piemonte\/","title":{"rendered":"La difficile situazione dei malati di sarcoidosi in Piemonte"},"content":{"rendered":"<p>Riceviamo e pubblichiamo questa lettera<\/p>\n<blockquote><p>Gentile Direttore,\u00a0\u00a0le scrivo per segnalarle la difficile situazione di chi, colpito da sarcoidosi, si trova oggi ad affrontare un sistema sociosanitario normalmente impreparato a gestire le difficolt\u00e0 di questa complessa e misconosciuta patologia.<\/p>\n<p>In Piemonte, regione comunque pi\u00f9 sensibile di altre (ha previsto di accludere la sarcoidosi allo status di malattia rara) esiste una concreta difficolt\u00e0 in merito all&#8217;individuazione di uno o pi\u00f9 centri di riferimento, e spesso le persone vagano tra un nosocomio e l&#8217;altro in cerca di una corretta presa in carico.<\/p>\n<p>L&#8217;associazione, esistente da un &#8216;anno, \u00a0st\u00e0 \u00a0raccogliendo nel nostro paese il disagio, a volte fortissimo, di interi nuclei familiari lasciati a se stessi. In particolare spesso difficilissima risulta la posizione di persone che perdono il lavoro per la malattia, che non li abbandoner\u00e0 pi\u00f9, e debbono ricollocarsi in condizioni consone rispetto ad una persona che soffre di sidrome della stanchezza cronica, febbre, dispnea ed \u00e8 colpito dalle menomazioni di una malattia multiorgano, a prevalente interessamento polmonare.<\/p>\n<p>Per fortuna i numeri in questo momento noti in Italia sono quelli di una malattia rara (circa 80 persone su un milione), ma la mia sensazione \u00e8 che sia fortemente sotto diagnosticata. I suoi concittadini la conoscono per la sua grande sensibilit\u00e0 ed il suo forte spirito di comakership nei confronti del terzo settore. Ci presentiamo a lei proprio per poter sviluppare sul territorio la sensibilit\u00e0 attualmente carente\u00a0 nei confronti di questi concittadini meno fortunati, costruendo occasioni di conoscenza e fund rising.<\/p>\n<p>Alberta Solano<\/p>\n<p>Referente per ACSI ONLUS\u00a0AMICI CONTRO LA SARCOIDOSI ITALIA<\/p>\n<p>Associazione Nazionale per l&#8217;Assistenza integrata\u00a0<em id=\"__mceDel\">e la Ricerca contro la Sarcoidosi<\/em><\/p>\n<p>&nbsp;<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Riceviamo e pubblichiamo questa lettera Gentile Direttore,\u00a0\u00a0le scrivo per segnalarle la difficile situazione di chi, colpito da sarcoidosi, si trova oggi ad affrontare un sistema sociosanitario normalmente impreparato a gestire le difficolt\u00e0 di questa complessa e misconosciuta patologia. In Piemonte, regione comunque pi\u00f9 sensibile di altre (ha previsto di accludere la sarcoidosi allo status di &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/la-difficile-situazione-dei-malati-di-sarcoidosi-in-piemonte\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;La difficile situazione dei malati di sarcoidosi in Piemonte&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[160,159],"class_list":["post-444","post","type-post","status-publish","format-standard","hentry","category-spazio-aperto-per-voi","tag-sanita","tag-sarcoidosi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La difficile situazione dei malati di sarcoidosi in Piemonte - Spazio aperto<\/title>\n<meta name=\"description\" content=\"sanit\u00e0, sarcoidosi\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/la-difficile-situazione-dei-malati-di-sarcoidosi-in-piemonte\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La difficile situazione dei malati di sarcoidosi in Piemonte - Spazio aperto\" \/>\n<meta property=\"og:description\" content=\"sanit\u00e0, sarcoidosi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/la-difficile-situazione-dei-malati-di-sarcoidosi-in-piemonte\/\" \/>\n<meta property=\"og:site_name\" content=\"Spazio aperto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese\" \/>\n<meta property=\"article:published_time\" content=\"2013-02-10T23:29:23+00:00\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/la-difficile-situazione-dei-malati-di-sarcoidosi-in-piemonte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/la-difficile-situazione-dei-malati-di-sarcoidosi-in-piemonte\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"headline\":\"La difficile situazione dei malati di sarcoidosi in Piemonte\",\"datePublished\":\"2013-02-10T23:29:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/la-difficile-situazione-dei-malati-di-sarcoidosi-in-piemonte\\\/\"},\"wordCount\":281,\"commentCount\":0,\"keywords\":[\"sanit\u00e0\",\"sarcoidosi\"],\"articleSection\":[\"Spazio Aperto\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/la-difficile-situazione-dei-malati-di-sarcoidosi-in-piemonte\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/la-difficile-situazione-dei-malati-di-sarcoidosi-in-piemonte\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/la-difficile-situazione-dei-malati-di-sarcoidosi-in-piemonte\\\/\",\"name\":\"La difficile situazione dei malati di sarcoidosi in Piemonte - Spazio aperto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/#website\"},\"datePublished\":\"2013-02-10T23:29:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"description\":\"sanit\u00e0, sarcoidosi\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/la-difficile-situazione-dei-malati-di-sarcoidosi-in-piemonte\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/la-difficile-situazione-dei-malati-di-sarcoidosi-in-piemonte\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/la-difficile-situazione-dei-malati-di-sarcoidosi-in-piemonte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La difficile situazione dei malati di sarcoidosi in Piemonte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/\",\"name\":\"Spazio aperto\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte\",\"sameAs\":[\"http:\\\/\\\/www.quotidianopiemontese.it\\\/\",\"https:\\\/\\\/www.facebook.com\\\/quotidianopiemontese\",\"https:\\\/\\\/x.com\\\/quotidianopiem\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/author\\\/administrator\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La difficile situazione dei malati di sarcoidosi in Piemonte - Spazio aperto","description":"sanit\u00e0, sarcoidosi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/la-difficile-situazione-dei-malati-di-sarcoidosi-in-piemonte\/","og_locale":"it_IT","og_type":"article","og_title":"La difficile situazione dei malati di sarcoidosi in Piemonte - Spazio aperto","og_description":"sanit\u00e0, sarcoidosi","og_url":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/la-difficile-situazione-dei-malati-di-sarcoidosi-in-piemonte\/","og_site_name":"Spazio aperto","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"https:\/\/www.facebook.com\/quotidianopiemontese","article_published_time":"2013-02-10T23:29:23+00:00","author":"Redazione","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/la-difficile-situazione-dei-malati-di-sarcoidosi-in-piemonte\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/la-difficile-situazione-dei-malati-di-sarcoidosi-in-piemonte\/"},"author":{"name":"Redazione","@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"headline":"La difficile situazione dei malati di sarcoidosi in Piemonte","datePublished":"2013-02-10T23:29:23+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/la-difficile-situazione-dei-malati-di-sarcoidosi-in-piemonte\/"},"wordCount":281,"commentCount":0,"keywords":["sanit\u00e0","sarcoidosi"],"articleSection":["Spazio Aperto"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/spazioaperto\/la-difficile-situazione-dei-malati-di-sarcoidosi-in-piemonte\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/la-difficile-situazione-dei-malati-di-sarcoidosi-in-piemonte\/","url":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/la-difficile-situazione-dei-malati-di-sarcoidosi-in-piemonte\/","name":"La difficile situazione dei malati di sarcoidosi in Piemonte - Spazio aperto","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/#website"},"datePublished":"2013-02-10T23:29:23+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"description":"sanit\u00e0, sarcoidosi","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/la-difficile-situazione-dei-malati-di-sarcoidosi-in-piemonte\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/spazioaperto\/la-difficile-situazione-dei-malati-di-sarcoidosi-in-piemonte\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/la-difficile-situazione-dei-malati-di-sarcoidosi-in-piemonte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/"},{"@type":"ListItem","position":2,"name":"La difficile situazione dei malati di sarcoidosi in Piemonte"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/#website","url":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/","name":"Spazio aperto","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","caption":"Redazione"},"description":"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte","sameAs":["http:\/\/www.quotidianopiemontese.it\/","https:\/\/www.facebook.com\/quotidianopiemontese","https:\/\/x.com\/quotidianopiem"],"url":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/author\/administrator\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/posts\/444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/comments?post=444"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/posts\/444\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/media?parent=444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/categories?post=444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/tags?post=444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}