{"id":44,"date":"2011-04-02T07:57:54","date_gmt":"2011-04-02T07:57:54","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/spazioaperto\/?p=44"},"modified":"2011-04-02T07:57:54","modified_gmt":"2011-04-02T07:57:54","slug":"i-consulenti-accompagnati-nellattraversamento","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/i-consulenti-accompagnati-nellattraversamento\/","title":{"rendered":"I consulenti accompagnati nell&#8217;attraversamento"},"content":{"rendered":"<p><a href=\"http:\/\/bertola.eu\/nearatree\/?p=2119\">Dal blog di Vittorio Bertola<br \/>\n<\/a><br \/>\nLuned\u00ec scorso, i dirigenti del centro Intesa Sanpaolo di Moncalieri &#8211; situato nel bel mezzo di uno svincolo della tangenziale &#8211; hanno deciso di vietare l\u2019uso del parcheggio interno alle centinaia di consulenti che esso ospita, costringendoli a parcheggiare l\u2019auto a qualche centinaio di metri e poi a rischiare la vita attraversando un tratto di svincolo a due corsie dove le auto sfrecciano a cento all\u2019ora, senza che vi siano strisce o semafori pedonali. Nonostante il problema sia noto da mesi, sia la banca che il Comune di Moncalieri se ne sono lavati le mani; queste persone ci hanno contattato e noi abbiamo deciso di fare un\u2019altra azione dimostrativa come quella di via San Donato, aiutandoli ad attraversare e soprattutto facendo in modo che i giornali parlassero del loro piccolo grande problema.<\/p>\n<p><object width=\"480\" height=\"300\"><param name=\"movie\" value=\"http:\/\/www.youtube.com\/v\/YsOeizLouZA?fs=1&amp;hl=it_IT&amp;rel=0\" \/><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><embed type=\"application\/x-shockwave-flash\" width=\"480\" height=\"300\" src=\"http:\/\/www.youtube.com\/v\/YsOeizLouZA?fs=1&amp;hl=it_IT&amp;rel=0\" allowfullscreen=\"true\" allowscriptaccess=\"always\"><\/embed><\/object><\/p>\n<p>Dove si trova l&#8217;attraversamento<br \/>\nhttp:\/\/maps.google.it\/maps?f=q&#038;source=s_q&#038;hl=it&#038;q=Corso+Moncalieri,+Torino,+Piemonte&#038;aq=&#038;sll=41.442726,12.392578&#038;sspn=23.809124,39.506836&#038;ie=UTF8&#038;geocode=FbxErwIdQTx1AA&#038;split=0&#038;hq=&#038;hnear=Corso+Moncalieri,+Torino,+Piemonte&#038;ll=44.989418,7.703497&#038;spn=0.010987,0.01929&#038;t=h&#038;z=16<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dal blog di Vittorio Bertola Luned\u00ec scorso, i dirigenti del centro Intesa Sanpaolo di Moncalieri &#8211; situato nel bel mezzo di uno svincolo della tangenziale &#8211; hanno deciso di vietare l\u2019uso del parcheggio interno alle centinaia di consulenti che esso ospita, costringendoli a parcheggiare l\u2019auto a qualche centinaio di metri e poi a rischiare la &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/i-consulenti-accompagnati-nellattraversamento\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;I consulenti accompagnati nell&#8217;attraversamento&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[31,32,18],"class_list":["post-44","post","type-post","status-publish","format-standard","hentry","category-cittadini","tag-moncalieri","tag-san-paolo","tag-torino"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I consulenti accompagnati nell&#039;attraversamento - Spazio aperto<\/title>\n<meta name=\"description\" content=\"Moncalieri, san paolo, torino\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/i-consulenti-accompagnati-nellattraversamento\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I consulenti accompagnati nell&#039;attraversamento - Spazio aperto\" \/>\n<meta property=\"og:description\" content=\"Moncalieri, san paolo, torino\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/i-consulenti-accompagnati-nellattraversamento\/\" \/>\n<meta property=\"og:site_name\" content=\"Spazio aperto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese\" \/>\n<meta property=\"article:published_time\" content=\"2011-04-02T07:57:54+00:00\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/i-consulenti-accompagnati-nellattraversamento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/i-consulenti-accompagnati-nellattraversamento\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"headline\":\"I consulenti accompagnati nell&#8217;attraversamento\",\"datePublished\":\"2011-04-02T07:57:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/i-consulenti-accompagnati-nellattraversamento\\\/\"},\"wordCount\":188,\"commentCount\":0,\"keywords\":[\"Moncalieri\",\"san paolo\",\"torino\"],\"articleSection\":[\"Cittadini\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/i-consulenti-accompagnati-nellattraversamento\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/i-consulenti-accompagnati-nellattraversamento\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/i-consulenti-accompagnati-nellattraversamento\\\/\",\"name\":\"I consulenti accompagnati nell'attraversamento - Spazio aperto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/#website\"},\"datePublished\":\"2011-04-02T07:57:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"description\":\"Moncalieri, san paolo, torino\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/i-consulenti-accompagnati-nellattraversamento\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/i-consulenti-accompagnati-nellattraversamento\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/i-consulenti-accompagnati-nellattraversamento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I consulenti accompagnati nell&#8217;attraversamento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/\",\"name\":\"Spazio aperto\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte\",\"sameAs\":[\"http:\\\/\\\/www.quotidianopiemontese.it\\\/\",\"https:\\\/\\\/www.facebook.com\\\/quotidianopiemontese\",\"https:\\\/\\\/x.com\\\/quotidianopiem\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/author\\\/administrator\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I consulenti accompagnati nell'attraversamento - Spazio aperto","description":"Moncalieri, san paolo, torino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/i-consulenti-accompagnati-nellattraversamento\/","og_locale":"it_IT","og_type":"article","og_title":"I consulenti accompagnati nell'attraversamento - Spazio aperto","og_description":"Moncalieri, san paolo, torino","og_url":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/i-consulenti-accompagnati-nellattraversamento\/","og_site_name":"Spazio aperto","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"https:\/\/www.facebook.com\/quotidianopiemontese","article_published_time":"2011-04-02T07:57:54+00:00","author":"Redazione","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/i-consulenti-accompagnati-nellattraversamento\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/i-consulenti-accompagnati-nellattraversamento\/"},"author":{"name":"Redazione","@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"headline":"I consulenti accompagnati nell&#8217;attraversamento","datePublished":"2011-04-02T07:57:54+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/i-consulenti-accompagnati-nellattraversamento\/"},"wordCount":188,"commentCount":0,"keywords":["Moncalieri","san paolo","torino"],"articleSection":["Cittadini"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/spazioaperto\/i-consulenti-accompagnati-nellattraversamento\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/i-consulenti-accompagnati-nellattraversamento\/","url":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/i-consulenti-accompagnati-nellattraversamento\/","name":"I consulenti accompagnati nell'attraversamento - Spazio aperto","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/#website"},"datePublished":"2011-04-02T07:57:54+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"description":"Moncalieri, san paolo, torino","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/i-consulenti-accompagnati-nellattraversamento\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/spazioaperto\/i-consulenti-accompagnati-nellattraversamento\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/i-consulenti-accompagnati-nellattraversamento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/"},{"@type":"ListItem","position":2,"name":"I consulenti accompagnati nell&#8217;attraversamento"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/#website","url":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/","name":"Spazio aperto","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","caption":"Redazione"},"description":"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte","sameAs":["http:\/\/www.quotidianopiemontese.it\/","https:\/\/www.facebook.com\/quotidianopiemontese","https:\/\/x.com\/quotidianopiem"],"url":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/author\/administrator\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/posts\/44","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/comments?post=44"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/posts\/44\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/media?parent=44"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/categories?post=44"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/tags?post=44"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}