{"id":256,"date":"2012-04-23T07:54:30","date_gmt":"2012-04-23T07:54:30","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/spazioaperto\/?p=256"},"modified":"2012-04-23T08:30:48","modified_gmt":"2012-04-23T08:30:48","slug":"scontri-tra-sudan-e-sud-sudan-una-possibile-emergenza-umanitaria","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/scontri-tra-sudan-e-sud-sudan-una-possibile-emergenza-umanitaria\/","title":{"rendered":"Scontri tra Sudan e Sud Sudan: una possibile emergenza umanitaria"},"content":{"rendered":"<p>Riceviamo e pubblichiamo<\/p>\n<blockquote><p>Il <a href=\"http:\/\/www.ccm-italia.org\/\" target=\"_blank\">Comitato Collaborazione Medica<\/a> esprime preoccupazione per la ripresa del conflitto tra Sudan e Sud Sudan, dove l\u2019ong torinese \u00e8 presente da molti anni con progetti di cooperazione internazionale sanitaria. Il presidente sudanese Omar el-B\u00e9chir ha dichiarato che \u201cil Sudan dar\u00e0 una lezione con la forza al Sud Sudan\u201d, mentre ieri nella capitale sud sudanese Juba c\u2019\u00e8 stata una manifestazione \u201cper la pace\u201d, che tuttavia inneggiava al diritto di mantenere la zona petrolifera di frontiera di Higlig, occupata dal 10 aprile da parte del Sud Sudan, che prosegue il reclutamento di soldati tra la popolazione locale, soprattutto nello stato di Warrap. Gli scontri sarebbero cominciati dal 26 marzo nell\u2019area di Higlig e in altre zone all\u2019interno dello stato di Unity, bombardato da aerei sudanesi dal 31 marzo insieme all\u2019area di Abyej e ad altre zone nello stato di Warrap, con un intensificarsi dei bombardamenti la scorsa settimana.<!--more--><\/p>\n<p>In questa situazione di conflitto, la contea di Twic, dove il CCM sostiene l\u2019ospedale rurale di Turalei, \u00e8 stata identificata come uno dei luoghi chiave per l\u2019assistenza umanitaria agli sfollati interni e ai feriti dovuti alle violenze in corso. Il personale delle ong internazionali presente ad Agok e sul confine con il Sudan \u00e8 in stato di allerta e molte hanno riallocato il loro staff a Turalei, per ragioni di sicurezza, ma la situazione \u00e8 fluida ed in continua evoluzione. Il CCM \u00e8 in stretto contatto con i funzionari ONU e con le altre ong presenti ad Agok, Turalei e Wunrok per il coordinamento dell\u2019assistenza sanitaria e sta lavorando ad un piano di emergenza presso l\u2019ospedale di Turalei, nel caso di peggioramento della situazione ed espansione del conflitto. La struttura sanitaria gestita dal CCM continua intanto le sue attivit\u00e0. Dispone di circa 40 letti per degenze chirurgiche e ricoveri e uno staff che prevede anche un chirurgo, un anestesista, e il personale per le emergenze ostetriche, pronti ad accogliere feriti e sfollati e tra di loro i pi\u00f9 vulnerabili come donne e bambini.<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Riceviamo e pubblichiamo Il Comitato Collaborazione Medica esprime preoccupazione per la ripresa del conflitto tra Sudan e Sud Sudan, dove l\u2019ong torinese \u00e8 presente da molti anni con progetti di cooperazione internazionale sanitaria. Il presidente sudanese Omar el-B\u00e9chir ha dichiarato che \u201cil Sudan dar\u00e0 una lezione con la forza al Sud Sudan\u201d, mentre ieri nella &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/scontri-tra-sudan-e-sud-sudan-una-possibile-emergenza-umanitaria\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Scontri tra Sudan e Sud Sudan: una possibile emergenza umanitaria&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[73,6],"tags":[67,110],"class_list":["post-256","post","type-post","status-publish","format-standard","hentry","category-mondo","category-spazio-aperto-per-voi","tag-africa","tag-appelli"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Scontri tra Sudan e Sud Sudan: una possibile emergenza umanitaria - Spazio aperto<\/title>\n<meta name=\"description\" content=\"africa, appelli\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/scontri-tra-sudan-e-sud-sudan-una-possibile-emergenza-umanitaria\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Scontri tra Sudan e Sud Sudan: una possibile emergenza umanitaria - Spazio aperto\" \/>\n<meta property=\"og:description\" content=\"africa, appelli\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/scontri-tra-sudan-e-sud-sudan-una-possibile-emergenza-umanitaria\/\" \/>\n<meta property=\"og:site_name\" content=\"Spazio aperto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese\" \/>\n<meta property=\"article:published_time\" content=\"2012-04-23T07:54:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-04-23T08:30:48+00:00\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/scontri-tra-sudan-e-sud-sudan-una-possibile-emergenza-umanitaria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/scontri-tra-sudan-e-sud-sudan-una-possibile-emergenza-umanitaria\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"headline\":\"Scontri tra Sudan e Sud Sudan: una possibile emergenza umanitaria\",\"datePublished\":\"2012-04-23T07:54:30+00:00\",\"dateModified\":\"2012-04-23T08:30:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/scontri-tra-sudan-e-sud-sudan-una-possibile-emergenza-umanitaria\\\/\"},\"wordCount\":344,\"commentCount\":0,\"keywords\":[\"africa\",\"appelli\"],\"articleSection\":[\"Mondo\",\"Spazio Aperto\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/scontri-tra-sudan-e-sud-sudan-una-possibile-emergenza-umanitaria\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/scontri-tra-sudan-e-sud-sudan-una-possibile-emergenza-umanitaria\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/scontri-tra-sudan-e-sud-sudan-una-possibile-emergenza-umanitaria\\\/\",\"name\":\"Scontri tra Sudan e Sud Sudan: una possibile emergenza umanitaria - Spazio aperto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/#website\"},\"datePublished\":\"2012-04-23T07:54:30+00:00\",\"dateModified\":\"2012-04-23T08:30:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"description\":\"africa, appelli\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/scontri-tra-sudan-e-sud-sudan-una-possibile-emergenza-umanitaria\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/scontri-tra-sudan-e-sud-sudan-una-possibile-emergenza-umanitaria\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/scontri-tra-sudan-e-sud-sudan-una-possibile-emergenza-umanitaria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Scontri tra Sudan e Sud Sudan: una possibile emergenza umanitaria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/\",\"name\":\"Spazio aperto\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte\",\"sameAs\":[\"http:\\\/\\\/www.quotidianopiemontese.it\\\/\",\"https:\\\/\\\/www.facebook.com\\\/quotidianopiemontese\",\"https:\\\/\\\/x.com\\\/quotidianopiem\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/author\\\/administrator\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Scontri tra Sudan e Sud Sudan: una possibile emergenza umanitaria - Spazio aperto","description":"africa, appelli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/scontri-tra-sudan-e-sud-sudan-una-possibile-emergenza-umanitaria\/","og_locale":"it_IT","og_type":"article","og_title":"Scontri tra Sudan e Sud Sudan: una possibile emergenza umanitaria - Spazio aperto","og_description":"africa, appelli","og_url":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/scontri-tra-sudan-e-sud-sudan-una-possibile-emergenza-umanitaria\/","og_site_name":"Spazio aperto","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"https:\/\/www.facebook.com\/quotidianopiemontese","article_published_time":"2012-04-23T07:54:30+00:00","article_modified_time":"2012-04-23T08:30:48+00:00","author":"Redazione","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/scontri-tra-sudan-e-sud-sudan-una-possibile-emergenza-umanitaria\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/scontri-tra-sudan-e-sud-sudan-una-possibile-emergenza-umanitaria\/"},"author":{"name":"Redazione","@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"headline":"Scontri tra Sudan e Sud Sudan: una possibile emergenza umanitaria","datePublished":"2012-04-23T07:54:30+00:00","dateModified":"2012-04-23T08:30:48+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/scontri-tra-sudan-e-sud-sudan-una-possibile-emergenza-umanitaria\/"},"wordCount":344,"commentCount":0,"keywords":["africa","appelli"],"articleSection":["Mondo","Spazio Aperto"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/spazioaperto\/scontri-tra-sudan-e-sud-sudan-una-possibile-emergenza-umanitaria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/scontri-tra-sudan-e-sud-sudan-una-possibile-emergenza-umanitaria\/","url":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/scontri-tra-sudan-e-sud-sudan-una-possibile-emergenza-umanitaria\/","name":"Scontri tra Sudan e Sud Sudan: una possibile emergenza umanitaria - Spazio aperto","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/#website"},"datePublished":"2012-04-23T07:54:30+00:00","dateModified":"2012-04-23T08:30:48+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"description":"africa, appelli","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/scontri-tra-sudan-e-sud-sudan-una-possibile-emergenza-umanitaria\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/spazioaperto\/scontri-tra-sudan-e-sud-sudan-una-possibile-emergenza-umanitaria\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/scontri-tra-sudan-e-sud-sudan-una-possibile-emergenza-umanitaria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/"},{"@type":"ListItem","position":2,"name":"Scontri tra Sudan e Sud Sudan: una possibile emergenza umanitaria"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/#website","url":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/","name":"Spazio aperto","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","caption":"Redazione"},"description":"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte","sameAs":["http:\/\/www.quotidianopiemontese.it\/","https:\/\/www.facebook.com\/quotidianopiemontese","https:\/\/x.com\/quotidianopiem"],"url":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/author\/administrator\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/posts\/256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/comments?post=256"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/posts\/256\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/media?parent=256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/categories?post=256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/tags?post=256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}