{"id":236,"date":"2012-02-02T08:09:37","date_gmt":"2012-02-02T08:09:37","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/spazioaperto\/?p=236"},"modified":"2012-04-02T23:14:18","modified_gmt":"2012-04-02T23:14:18","slug":"tedesco-in-scena-a-torino-dal-2-al-4-aprile","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/tedesco-in-scena-a-torino-dal-2-al-4-aprile\/","title":{"rendered":"Tedesco in Scena a Torino dal 2 al 4 aprile"},"content":{"rendered":"<p>Anche quest&#8217;anno il Goethe Institut, l&#8217;istituto tedesco che promuove la lingua all&#8217;estero, porta a\u00a0Torino pi\u00f9 di 250 ragazzi provenienti da mezza Europa e li fa salire sul palcoscenico. Studenti di et\u00e0\u00a0compresa tra i 14 e i 19 anni imparano il tedesco fuori dai banchi di scuola.\u00a0Ventiquattro le scuole che hanno chiesto di partecipare al festival \u201c<a href=\"http:\/\/www.goethe.de\/ins\/it\/tur\/lhr\/it9004596v.htm\" target=\"_blank\">Tedesco in Scena<\/a>\u201d a Torino, ma\u00a0solo sedici potranno calcare le scene della Casa del Teatro Ragazzi e Giovani.<!--more--><\/p>\n<p>Come ogni anno si cambia tema e per il 2012 i gruppi teatrali scolastici di Germania, Francia, Italia,\u00a0Portogallo, Spagna, Repubblica Slovacca e Ucraina hanno preparato le loro pi\u00e8ces sul tema\u00a0dell&#8217;amicizia, dell&#8217;amore e della sofferenza. A partire dalle ore 9 di luned\u00ec mattina le presenteranno\u00a0ai loro compagni e ai loro insegnanti.<\/p>\n<p>L&#8217;ultimo giorno del festival sar\u00e0 dedicato a laboratori condotti da attori professionisti, registi e\u00a0pedagoghi teatrali. Gli allievi di tedesco potranno cos\u00ec elaborare una performance, che verr\u00e0\u00a0presentata il giorno mercoled\u00ec 4 aprile alle ore 16, sempre presso il Teatro Ragazzi.\u00a0Il palcoscenico diventa anche un luogo per apprendere la lingua di Goethe, per fare conoscenza e\u00a0scambiare esperienze con gli altri, una cosa unisce tutti questi studenti di paesi diversi.\u00a0I migliori gruppi saranno poi invitati a partecipare al Festival studentesco europeo di teatro\u00a0plurilingue \u201cLingue in scena\u201d dal 6 al 11 maggio 2012 a Torino.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anche quest&#8217;anno il Goethe Institut, l&#8217;istituto tedesco che promuove la lingua all&#8217;estero, porta a\u00a0Torino pi\u00f9 di 250 ragazzi provenienti da mezza Europa e li fa salire sul palcoscenico. Studenti di et\u00e0\u00a0compresa tra i 14 e i 19 anni imparano il tedesco fuori dai banchi di scuola.\u00a0Ventiquattro le scuole che hanno chiesto di partecipare al festival &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/tedesco-in-scena-a-torino-dal-2-al-4-aprile\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Tedesco in Scena a Torino dal 2 al 4 aprile&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,73],"tags":[],"class_list":["post-236","post","type-post","status-publish","format-standard","hentry","category-cittadini","category-mondo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tedesco in Scena a Torino dal 2 al 4 aprile - Spazio aperto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/tedesco-in-scena-a-torino-dal-2-al-4-aprile\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tedesco in Scena a Torino dal 2 al 4 aprile - Spazio aperto\" \/>\n<meta property=\"og:url\" content=\"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/tedesco-in-scena-a-torino-dal-2-al-4-aprile\/\" \/>\n<meta property=\"og:site_name\" content=\"Spazio aperto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese\" \/>\n<meta property=\"article:published_time\" content=\"2012-02-02T08:09:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-04-02T23:14:18+00:00\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/tedesco-in-scena-a-torino-dal-2-al-4-aprile\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/tedesco-in-scena-a-torino-dal-2-al-4-aprile\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"headline\":\"Tedesco in Scena a Torino dal 2 al 4 aprile\",\"datePublished\":\"2012-02-02T08:09:37+00:00\",\"dateModified\":\"2012-04-02T23:14:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/tedesco-in-scena-a-torino-dal-2-al-4-aprile\\\/\"},\"wordCount\":232,\"commentCount\":0,\"articleSection\":[\"Cittadini\",\"Mondo\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/tedesco-in-scena-a-torino-dal-2-al-4-aprile\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/tedesco-in-scena-a-torino-dal-2-al-4-aprile\\\/\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/tedesco-in-scena-a-torino-dal-2-al-4-aprile\\\/\",\"name\":\"Tedesco in Scena a Torino dal 2 al 4 aprile - Spazio aperto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/#website\"},\"datePublished\":\"2012-02-02T08:09:37+00:00\",\"dateModified\":\"2012-04-02T23:14:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/tedesco-in-scena-a-torino-dal-2-al-4-aprile\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/tedesco-in-scena-a-torino-dal-2-al-4-aprile\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/tedesco-in-scena-a-torino-dal-2-al-4-aprile\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tedesco in Scena a Torino dal 2 al 4 aprile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/\",\"name\":\"Spazio aperto\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte\",\"sameAs\":[\"http:\\\/\\\/www.quotidianopiemontese.it\\\/\",\"https:\\\/\\\/www.facebook.com\\\/quotidianopiemontese\",\"https:\\\/\\\/x.com\\\/quotidianopiem\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/author\\\/administrator\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tedesco in Scena a Torino dal 2 al 4 aprile - Spazio aperto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/tedesco-in-scena-a-torino-dal-2-al-4-aprile\/","og_locale":"it_IT","og_type":"article","og_title":"Tedesco in Scena a Torino dal 2 al 4 aprile - Spazio aperto","og_url":"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/tedesco-in-scena-a-torino-dal-2-al-4-aprile\/","og_site_name":"Spazio aperto","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"https:\/\/www.facebook.com\/quotidianopiemontese","article_published_time":"2012-02-02T08:09:37+00:00","article_modified_time":"2012-04-02T23:14:18+00:00","author":"Redazione","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/tedesco-in-scena-a-torino-dal-2-al-4-aprile\/#article","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/tedesco-in-scena-a-torino-dal-2-al-4-aprile\/"},"author":{"name":"Redazione","@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"headline":"Tedesco in Scena a Torino dal 2 al 4 aprile","datePublished":"2012-02-02T08:09:37+00:00","dateModified":"2012-04-02T23:14:18+00:00","mainEntityOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/tedesco-in-scena-a-torino-dal-2-al-4-aprile\/"},"wordCount":232,"commentCount":0,"articleSection":["Cittadini","Mondo"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/web.quotidianopiemontese.it\/spazioaperto\/tedesco-in-scena-a-torino-dal-2-al-4-aprile\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/tedesco-in-scena-a-torino-dal-2-al-4-aprile\/","url":"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/tedesco-in-scena-a-torino-dal-2-al-4-aprile\/","name":"Tedesco in Scena a Torino dal 2 al 4 aprile - Spazio aperto","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/#website"},"datePublished":"2012-02-02T08:09:37+00:00","dateModified":"2012-04-02T23:14:18+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"breadcrumb":{"@id":"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/tedesco-in-scena-a-torino-dal-2-al-4-aprile\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/web.quotidianopiemontese.it\/spazioaperto\/tedesco-in-scena-a-torino-dal-2-al-4-aprile\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/tedesco-in-scena-a-torino-dal-2-al-4-aprile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/"},{"@type":"ListItem","position":2,"name":"Tedesco in Scena a Torino dal 2 al 4 aprile"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/#website","url":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/","name":"Spazio aperto","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","caption":"Redazione"},"description":"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte","sameAs":["http:\/\/www.quotidianopiemontese.it\/","https:\/\/www.facebook.com\/quotidianopiemontese","https:\/\/x.com\/quotidianopiem"],"url":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/author\/administrator\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/posts\/236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/comments?post=236"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/posts\/236\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/media?parent=236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/categories?post=236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/tags?post=236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}