{"id":1311,"date":"2024-10-08T17:24:34","date_gmt":"2024-10-08T17:24:34","guid":{"rendered":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/?p=1311"},"modified":"2024-10-08T17:28:39","modified_gmt":"2024-10-08T17:28:39","slug":"bussoleno-celebra-i-600-anni-del-drapo-la-bandiera-del-piemonte","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/bussoleno-celebra-i-600-anni-del-drapo-la-bandiera-del-piemonte\/","title":{"rendered":"Bussoleno celebra i 600 anni del Drap\u00f2: la bandiera del Piemonte"},"content":{"rendered":"<div class=\"space-y-6 prose lg:prose-lg\">\n<p>Il <a href=\"https:\/\/www.comune.bussoleno.to.it\/it-it\/home\" target=\"_blank\" rel=\"noopener\"><strong>Comune di Bussoleno<\/strong><\/a> si appresta a festeggiare i <strong>600 anni del Drap\u00f2<\/strong>, simbolo del Piemonte, con un evento straordinario fortemente voluto dall&#8217;<strong>Amministrazione Comunale<\/strong> previsto per <strong>sabato 12 ottobre 2024<\/strong>. L&#8217;iniziativa, sostenuta dal Consiglio Regionale del Piemonte, promette di essere un&#8217;occasione importante per la comunit\u00e0 locale e per tutti coloro che sono legati alla storia e alle tradizioni piemontesi.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-23982\" src=\"https:\/\/www.torinofree.it\/wp-content\/uploads\/2024\/10\/drapo-bussoleno.jpg\" alt=\"\" width=\"1005\" height=\"1443\" \/><\/p>\n<p>La giornata inizier\u00e0 alle 10:30 con il ritrovo dei partecipanti in Piazza Cav. di Vittorio Veneto, a cui seguir\u00e0 una parata lungo le vie del centro storico. Questa sfilata sar\u00e0 accompagnata dalla Filarmonica, dalle Associazioni locali e dai cittadini. Alle 11:30, \u00e8 previsto il ritorno nella piazza, dove si terr\u00e0 un discorso istituzionale e la cerimonia dell&#8217;alzabandiera. Durante questo momento solenne, verr\u00e0 eseguito l&#8217;inno ufficiale del Piemonte e il Coro Alpi Cozie Valsusa offrir\u00e0 una performance.<\/p>\n<div class=\"flex max-w-full flex-col flex-grow\">\n<div class=\"min-h-8 text-message flex w-full flex-col items-end gap-2 whitespace-normal break-words [.text-message+&amp;]:mt-5\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"94b5fbc1-b17f-4948-b461-d755055eddef\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[3px]\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<p>Il pomeriggio proseguir\u00e0 alle 14:30 con una mostra di veicoli del club piemontese \u201cMotor Vej d\u2019la Valsusa 22\u201d. A partire dalle 16:00, presso il Teatro Don Bunino in Piazza Cavour, avr\u00e0 luogo una serie di interventi culturali e musicali. Tra i protagonisti dell\u2019evento ci sar\u00e0 il Laboratorio di canto popolare de L\u2019Asola di Govi, che presenter\u00e0 un\u2019esibizione intitolata <em>Il popolo canta<\/em>. Parteciperanno anche artisti locali come Ombretta Mantoan, Nicoletta Ciari e Pino Potenza. Saranno presenti lo storico Alberto Borgatta, che terr\u00e0 una conferenza sui 600 anni del Drap\u00f2, e Michele Bonavero, che offrir\u00e0 un approfondimento sulla lingua e le tradizioni del Piemonte.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>Alle\u00a0<strong>18:00<\/strong>, per concludere la giornata, sar\u00e0 offerta una \u201cMerenda Sinoira\u201d presso il Bar Ferrari, in Piazza Cavalieri di Vittorio Veneto, accompagnata da una band musicale. La prenotazione \u00e8 gradita entro il 9 ottobre.<\/p>\n<p>Questo evento segna un momento importante nella celebrazione della storia piemontese, con particolare attenzione al\u00a0<em>Drap\u00f2<\/em>, il vessillo che ha radici profonde nel passato della regione, risalenti al 1424, quando fu creato sotto la dinastia dei Savoia. Come evidenziato anche dal\u00a0<em>Laboratorio Alte Valli<\/em>, il\u00a0<em>Drap\u00f2<\/em>\u00a0ha accompagnato per secoli il Piemonte, rappresentando simbolicamente la sua autonomia e il suo spirito. L\u2019evento di Bussoleno \u00e8 quindi un\u2019occasione per riscoprire e valorizzare questo importante simbolo, portando avanti una tradizione che unisce storia e comunit\u00e0.<\/p>\n<h3><strong>Cenni Storici sul Drap\u00f2<\/strong><span style=\"font-size: 16px;font-weight: 400\">\u00a0<\/span><\/h3>\n<article class=\"w-full text-token-text-primary focus-visible:outline-2 focus-visible:outline-offset-[-4px]\" dir=\"auto\" data-testid=\"conversation-turn-3\" data-scroll-anchor=\"true\">\n<div class=\"text-base py-[18px] px-3 md:px-4 m-auto w-full md:px-5 lg:px-4 xl:px-5\">\n<div class=\"mx-auto flex flex-1 gap-4 text-base md:gap-5 lg:gap-6 md:max-w-3xl lg:max-w-[40rem] xl:max-w-[48rem]\">\n<div class=\"group\/conversation-turn relative flex w-full min-w-0 flex-col agent-turn\">\n<div class=\"flex-col gap-1 md:gap-3\">\n<div class=\"flex max-w-full flex-col flex-grow\">\n<div class=\"min-h-8 text-message flex w-full flex-col items-end gap-2 whitespace-normal break-words [.text-message+&amp;]:mt-5\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"ec5d1d60-9c64-4f22-8366-ae7a9e2a03c9\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[3px]\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<p>Nel 1424, il duca Amedeo VIII assegn\u00f2 al figlio Amedeo junior il titolo di Principe di Piemonte, rendendolo erede al trono. In quell&#8217;occasione apparve per la prima volta lo stemma di Savoia con il lambello azzurro, che identificava un&#8217;area geografica precisa, comprendente approssimativamente Aosta, Nizza, Torino, Vercelli e Biella. Lo stemma rosso con la croce d\u2019argento, comune nel Medioevo, era utilizzato dalle famiglie alleate con l\u2019Imperatore, come testimonia anche Novara, che esibiva lo stesso simbolo. Il lambello azzurro, una sorta di rastrello a tre denti, era l&#8217;evoluzione grafica dei nastri che pendevano dall\u2019elmo dei primogeniti. L&#8217;azzurro del Drap\u00f2, adottato pi\u00f9 recentemente, si ispira al colore dinastico dei Savoia, legato alla loro devozione alla Vergine Maria, tradizione risalente al XIV secolo.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<div class=\"pt-14 space-y-8\" style=\"text-align: right\"><strong><strong>Claudio Pasqua<br \/>\n<\/strong><\/strong>Giornalista scientifico<br \/>\nDirettore ADI &#8211; Agenza Digitale Italiana<\/p>\n<div class=\"py-8 space-y-6\">\n<div class=\"flex w-full\"><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Il Comune di Bussoleno si appresta a festeggiare i 600 anni del Drap\u00f2, simbolo del Piemonte, con un evento straordinario fortemente voluto dall&#8217;Amministrazione Comunale previsto per sabato 12 ottobre 2024. L&#8217;iniziativa, sostenuta dal Consiglio Regionale del Piemonte, promette di essere un&#8217;occasione importante per la comunit\u00e0 locale e per tutti coloro che sono legati alla storia &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/bussoleno-celebra-i-600-anni-del-drapo-la-bandiera-del-piemonte\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Bussoleno celebra i 600 anni del Drap\u00f2: la bandiera del Piemonte&#8221;<\/span><\/a><\/p>\n","protected":false},"author":33,"featured_media":1317,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[231,121],"tags":[],"class_list":["post-1311","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bussoleno celebra i 600 anni del Drap\u00f2: la bandiera del Piemonte - Spazio aperto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/bussoleno-celebra-i-600-anni-del-drapo-la-bandiera-del-piemonte\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bussoleno celebra i 600 anni del Drap\u00f2: la bandiera del Piemonte - Spazio aperto\" \/>\n<meta property=\"og:url\" content=\"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/bussoleno-celebra-i-600-anni-del-drapo-la-bandiera-del-piemonte\/\" \/>\n<meta property=\"og:site_name\" content=\"Spazio aperto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-08T17:24:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-08T17:28:39+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/files\/2024\/10\/Logo-600-Anni-1024x808-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"808\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione online\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione online\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/bussoleno-celebra-i-600-anni-del-drapo-la-bandiera-del-piemonte\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/bussoleno-celebra-i-600-anni-del-drapo-la-bandiera-del-piemonte\/\"},\"author\":{\"name\":\"Redazione online\",\"@id\":\"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/#\/schema\/person\/74fbe7ffba2c29e0cd6b39f67cc8437c\"},\"headline\":\"Bussoleno celebra i 600 anni del Drap\u00f2: la bandiera del Piemonte\",\"datePublished\":\"2024-10-08T17:24:34+00:00\",\"dateModified\":\"2024-10-08T17:28:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/bussoleno-celebra-i-600-anni-del-drapo-la-bandiera-del-piemonte\/\"},\"wordCount\":500,\"commentCount\":0,\"image\":{\"@id\":\"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/bussoleno-celebra-i-600-anni-del-drapo-la-bandiera-del-piemonte\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/files\/2024\/10\/Logo-600-Anni-1024x808-1.jpg\",\"articleSection\":[\"Cultura\",\"Eventi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/bussoleno-celebra-i-600-anni-del-drapo-la-bandiera-del-piemonte\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/bussoleno-celebra-i-600-anni-del-drapo-la-bandiera-del-piemonte\/\",\"url\":\"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/bussoleno-celebra-i-600-anni-del-drapo-la-bandiera-del-piemonte\/\",\"name\":\"Bussoleno celebra i 600 anni del Drap\u00f2: la bandiera del Piemonte - Spazio aperto\",\"isPartOf\":{\"@id\":\"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/bussoleno-celebra-i-600-anni-del-drapo-la-bandiera-del-piemonte\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/bussoleno-celebra-i-600-anni-del-drapo-la-bandiera-del-piemonte\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/files\/2024\/10\/Logo-600-Anni-1024x808-1.jpg\",\"datePublished\":\"2024-10-08T17:24:34+00:00\",\"dateModified\":\"2024-10-08T17:28:39+00:00\",\"author\":{\"@id\":\"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/#\/schema\/person\/74fbe7ffba2c29e0cd6b39f67cc8437c\"},\"breadcrumb\":{\"@id\":\"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/bussoleno-celebra-i-600-anni-del-drapo-la-bandiera-del-piemonte\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/bussoleno-celebra-i-600-anni-del-drapo-la-bandiera-del-piemonte\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/bussoleno-celebra-i-600-anni-del-drapo-la-bandiera-del-piemonte\/#primaryimage\",\"url\":\"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/files\/2024\/10\/Logo-600-Anni-1024x808-1.jpg\",\"contentUrl\":\"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/files\/2024\/10\/Logo-600-Anni-1024x808-1.jpg\",\"width\":1024,\"height\":808,\"caption\":\"drapo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/bussoleno-celebra-i-600-anni-del-drapo-la-bandiera-del-piemonte\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bussoleno celebra i 600 anni del Drap\u00f2: la bandiera del Piemonte\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/#website\",\"url\":\"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/\",\"name\":\"Spazio aperto\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/#\/schema\/person\/74fbe7ffba2c29e0cd6b39f67cc8437c\",\"name\":\"Redazione online\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4b53a39155f681a1e81390ef615328300b7e77eef03a6eb81fdd89bb5d3a98a6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4b53a39155f681a1e81390ef615328300b7e77eef03a6eb81fdd89bb5d3a98a6?s=96&d=mm&r=g\",\"caption\":\"Redazione online\"},\"url\":\"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/author\/claudio-pasqua\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bussoleno celebra i 600 anni del Drap\u00f2: la bandiera del Piemonte - Spazio aperto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/bussoleno-celebra-i-600-anni-del-drapo-la-bandiera-del-piemonte\/","og_locale":"it_IT","og_type":"article","og_title":"Bussoleno celebra i 600 anni del Drap\u00f2: la bandiera del Piemonte - Spazio aperto","og_url":"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/bussoleno-celebra-i-600-anni-del-drapo-la-bandiera-del-piemonte\/","og_site_name":"Spazio aperto","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2024-10-08T17:24:34+00:00","article_modified_time":"2024-10-08T17:28:39+00:00","og_image":[{"width":1024,"height":808,"url":"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/files\/2024\/10\/Logo-600-Anni-1024x808-1.jpg","type":"image\/jpeg"}],"author":"Redazione online","twitter_misc":{"Scritto da":"Redazione online","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/bussoleno-celebra-i-600-anni-del-drapo-la-bandiera-del-piemonte\/#article","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/bussoleno-celebra-i-600-anni-del-drapo-la-bandiera-del-piemonte\/"},"author":{"name":"Redazione online","@id":"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/#\/schema\/person\/74fbe7ffba2c29e0cd6b39f67cc8437c"},"headline":"Bussoleno celebra i 600 anni del Drap\u00f2: la bandiera del Piemonte","datePublished":"2024-10-08T17:24:34+00:00","dateModified":"2024-10-08T17:28:39+00:00","mainEntityOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/bussoleno-celebra-i-600-anni-del-drapo-la-bandiera-del-piemonte\/"},"wordCount":500,"commentCount":0,"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/bussoleno-celebra-i-600-anni-del-drapo-la-bandiera-del-piemonte\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/files\/2024\/10\/Logo-600-Anni-1024x808-1.jpg","articleSection":["Cultura","Eventi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/web.quotidianopiemontese.it\/spazioaperto\/bussoleno-celebra-i-600-anni-del-drapo-la-bandiera-del-piemonte\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/bussoleno-celebra-i-600-anni-del-drapo-la-bandiera-del-piemonte\/","url":"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/bussoleno-celebra-i-600-anni-del-drapo-la-bandiera-del-piemonte\/","name":"Bussoleno celebra i 600 anni del Drap\u00f2: la bandiera del Piemonte - Spazio aperto","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/#website"},"primaryImageOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/bussoleno-celebra-i-600-anni-del-drapo-la-bandiera-del-piemonte\/#primaryimage"},"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/bussoleno-celebra-i-600-anni-del-drapo-la-bandiera-del-piemonte\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/files\/2024\/10\/Logo-600-Anni-1024x808-1.jpg","datePublished":"2024-10-08T17:24:34+00:00","dateModified":"2024-10-08T17:28:39+00:00","author":{"@id":"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/#\/schema\/person\/74fbe7ffba2c29e0cd6b39f67cc8437c"},"breadcrumb":{"@id":"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/bussoleno-celebra-i-600-anni-del-drapo-la-bandiera-del-piemonte\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/web.quotidianopiemontese.it\/spazioaperto\/bussoleno-celebra-i-600-anni-del-drapo-la-bandiera-del-piemonte\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/bussoleno-celebra-i-600-anni-del-drapo-la-bandiera-del-piemonte\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/files\/2024\/10\/Logo-600-Anni-1024x808-1.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/files\/2024\/10\/Logo-600-Anni-1024x808-1.jpg","width":1024,"height":808,"caption":"drapo"},{"@type":"BreadcrumbList","@id":"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/bussoleno-celebra-i-600-anni-del-drapo-la-bandiera-del-piemonte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/"},{"@type":"ListItem","position":2,"name":"Bussoleno celebra i 600 anni del Drap\u00f2: la bandiera del Piemonte"}]},{"@type":"WebSite","@id":"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/#website","url":"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/","name":"Spazio aperto","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/#\/schema\/person\/74fbe7ffba2c29e0cd6b39f67cc8437c","name":"Redazione online","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/web.quotidianopiemontese.it\/spazioaperto\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4b53a39155f681a1e81390ef615328300b7e77eef03a6eb81fdd89bb5d3a98a6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4b53a39155f681a1e81390ef615328300b7e77eef03a6eb81fdd89bb5d3a98a6?s=96&d=mm&r=g","caption":"Redazione online"},"url":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/author\/claudio-pasqua\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/posts\/1311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/comments?post=1311"}],"version-history":[{"count":5,"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/posts\/1311\/revisions"}],"predecessor-version":[{"id":1316,"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/posts\/1311\/revisions\/1316"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/media\/1317"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/media?parent=1311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/categories?post=1311"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/tags?post=1311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}