{"id":123,"date":"2011-11-18T12:43:42","date_gmt":"2011-11-18T12:43:42","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/spazioaperto\/?p=123"},"modified":"2011-11-18T23:55:28","modified_gmt":"2011-11-18T23:55:28","slug":"facciamo-sorridere-le-madri-africane","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/facciamo-sorridere-le-madri-africane\/","title":{"rendered":"Facciamo sorridere le madri africane"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright\" title=\"mamme africane\" src=\"http:\/\/www.ccm-italia.org\/images\/sorrisi\/ccm_banner_sorrisi%20di%20madri%20africane_200x200.jpg\" alt=\"\" width=\"200\" height=\"200\" \/><a href=\" http:\/\/www.ccm-italia.org\/index.php?option=com_content&amp;view=category&amp;layout=blog&amp;id=89&amp;Itemid=223&amp;lang=it\" target=\"_blank\">Vogliamo che le mamme e i bambini africani tornino a sorridere<\/a>, dichiarano con forza Marilena Bertini, presidente, e Filippo Spagnuolo, direttore del <a href=\"http:\/\/www.ccm-italia.org\/\">Comitato Collaborazione Medica<\/a>. Conosciamo le cause e le soluzioni ai problemi sanitari dei Paesi a basso reddito e il CCM, in oltre 40 anni di attivit\u00e0 e grazie al supporto di molti, ha dimostrato che si pu\u00f2 salvare o migliorare la vita della popolazione locale con progetti a sostegno dei sistemi sanitari territoriali.<\/p>\n<p>Ma si deve fare di pi\u00f9 per garantire a tutti uno dei diritti fondamentali, quello alla salute, specialmente alle donne e ai bambini, che rappresentano il futuro delle comunit\u00e0 africane\u201d. Questo \u00e8 il messaggio che lancia oggi il Comitato Collaborazione Medica, con la presentazione alla stampa della campagna Sorrisi di madri africane.<\/p>\n<p>L\u2019appello \u00e8 rivolto a tutte le persone e alle aggregazioni che sono espressione delle nostre comunit\u00e0 in Italia, perch\u00e9 sostengano azioni concrete per assicurare il diritto alla salute a donne e bambini, i soggetti pi\u00f9 vulnerabili nei Paesi a basso reddito, dove il CCM opera con progetti di cooperazione internazionale che mirano a garantire l\u2019accesso ai servizi sanitari primari.<\/p>\n<p><a href=\"http:\/\/www.ccm-italia.org\/index.php?option=com_content&amp;view=article&amp;id=10&amp;Itemid=37&amp;lang=it\" target=\"_blank\">La campagna Sorrisi di madri africane<\/a> vuole coinvolgere quanti pi\u00f9 cittadini ed organizzazioni possibili per realizzare alcune azioni concrete entro il 2015, anno di scadenza degli Obiettivi di sviluppo del Millennio sanciti dall\u2019Onu nel 2000, traguardi ancora molto lontani in alcuni paesi e che per essere raggiunti richiedono dunque uno sforzo straordinario da parte di tutti.<\/p>\n<p>Il CCM \u00e8 convinto che insieme possiamo restituire un sorriso alle madri e ai bambini in Burundi, Etiopia, Mali, Kenya, Somalia, Sud Sudan, i paesi africani dove opera attualmente. Vogliamo garantire, nei prossimi 4 anni, una gravidanza ed un parto sicuri a 200.000 donne; assicurare una nascita senza complicazioni, vaccinazioni e cure durante l\u2019infanzia a 500.000 bambini; sensibilizzare quante pi\u00f9 persone, istituzioni, scuole, organizzazioni economiche, sociali e culturali sul tema della salute materno infantile.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vogliamo che le mamme e i bambini africani tornino a sorridere, dichiarano con forza Marilena Bertini, presidente, e Filippo Spagnuolo, direttore del Comitato Collaborazione Medica. Conosciamo le cause e le soluzioni ai problemi sanitari dei Paesi a basso reddito e il CCM, in oltre 40 anni di attivit\u00e0 e grazie al supporto di molti, ha &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/facciamo-sorridere-le-madri-africane\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Facciamo sorridere le madri africane&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[67,68],"class_list":["post-123","post","type-post","status-publish","format-standard","hentry","category-spazio-aperto-per-voi","tag-africa","tag-medici"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Facciamo sorridere le madri africane - Spazio aperto<\/title>\n<meta name=\"description\" content=\"africa, medici\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/facciamo-sorridere-le-madri-africane\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Facciamo sorridere le madri africane - Spazio aperto\" \/>\n<meta property=\"og:description\" content=\"africa, medici\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/facciamo-sorridere-le-madri-africane\/\" \/>\n<meta property=\"og:site_name\" content=\"Spazio aperto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese\" \/>\n<meta property=\"article:published_time\" content=\"2011-11-18T12:43:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-11-18T23:55:28+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.ccm-italia.org\/images\/sorrisi\/ccm_banner_sorrisi%20di%20madri%20africane_200x200.jpg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/facciamo-sorridere-le-madri-africane\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/facciamo-sorridere-le-madri-africane\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"headline\":\"Facciamo sorridere le madri africane\",\"datePublished\":\"2011-11-18T12:43:42+00:00\",\"dateModified\":\"2011-11-18T23:55:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/facciamo-sorridere-le-madri-africane\\\/\"},\"wordCount\":316,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/facciamo-sorridere-le-madri-africane\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.ccm-italia.org\\\/images\\\/sorrisi\\\/ccm_banner_sorrisi%20di%20madri%20africane_200x200.jpg\",\"keywords\":[\"africa\",\"medici\"],\"articleSection\":[\"Spazio Aperto\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/facciamo-sorridere-le-madri-africane\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/facciamo-sorridere-le-madri-africane\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/facciamo-sorridere-le-madri-africane\\\/\",\"name\":\"Facciamo sorridere le madri africane - Spazio aperto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/facciamo-sorridere-le-madri-africane\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/facciamo-sorridere-le-madri-africane\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.ccm-italia.org\\\/images\\\/sorrisi\\\/ccm_banner_sorrisi%20di%20madri%20africane_200x200.jpg\",\"datePublished\":\"2011-11-18T12:43:42+00:00\",\"dateModified\":\"2011-11-18T23:55:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"description\":\"africa, medici\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/facciamo-sorridere-le-madri-africane\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/facciamo-sorridere-le-madri-africane\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/facciamo-sorridere-le-madri-africane\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.ccm-italia.org\\\/images\\\/sorrisi\\\/ccm_banner_sorrisi%20di%20madri%20africane_200x200.jpg\",\"contentUrl\":\"http:\\\/\\\/www.ccm-italia.org\\\/images\\\/sorrisi\\\/ccm_banner_sorrisi%20di%20madri%20africane_200x200.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/facciamo-sorridere-le-madri-africane\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Facciamo sorridere le madri africane\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/\",\"name\":\"Spazio aperto\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte\",\"sameAs\":[\"http:\\\/\\\/www.quotidianopiemontese.it\\\/\",\"https:\\\/\\\/www.facebook.com\\\/quotidianopiemontese\",\"https:\\\/\\\/x.com\\\/quotidianopiem\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/spazioaperto\\\/author\\\/administrator\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Facciamo sorridere le madri africane - Spazio aperto","description":"africa, medici","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/facciamo-sorridere-le-madri-africane\/","og_locale":"it_IT","og_type":"article","og_title":"Facciamo sorridere le madri africane - Spazio aperto","og_description":"africa, medici","og_url":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/facciamo-sorridere-le-madri-africane\/","og_site_name":"Spazio aperto","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"https:\/\/www.facebook.com\/quotidianopiemontese","article_published_time":"2011-11-18T12:43:42+00:00","article_modified_time":"2011-11-18T23:55:28+00:00","og_image":[{"url":"http:\/\/www.ccm-italia.org\/images\/sorrisi\/ccm_banner_sorrisi%20di%20madri%20africane_200x200.jpg","type":"","width":"","height":""}],"author":"Redazione","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/facciamo-sorridere-le-madri-africane\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/facciamo-sorridere-le-madri-africane\/"},"author":{"name":"Redazione","@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"headline":"Facciamo sorridere le madri africane","datePublished":"2011-11-18T12:43:42+00:00","dateModified":"2011-11-18T23:55:28+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/facciamo-sorridere-le-madri-africane\/"},"wordCount":316,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/facciamo-sorridere-le-madri-africane\/#primaryimage"},"thumbnailUrl":"http:\/\/www.ccm-italia.org\/images\/sorrisi\/ccm_banner_sorrisi%20di%20madri%20africane_200x200.jpg","keywords":["africa","medici"],"articleSection":["Spazio Aperto"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/spazioaperto\/facciamo-sorridere-le-madri-africane\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/facciamo-sorridere-le-madri-africane\/","url":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/facciamo-sorridere-le-madri-africane\/","name":"Facciamo sorridere le madri africane - Spazio aperto","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/facciamo-sorridere-le-madri-africane\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/facciamo-sorridere-le-madri-africane\/#primaryimage"},"thumbnailUrl":"http:\/\/www.ccm-italia.org\/images\/sorrisi\/ccm_banner_sorrisi%20di%20madri%20africane_200x200.jpg","datePublished":"2011-11-18T12:43:42+00:00","dateModified":"2011-11-18T23:55:28+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"description":"africa, medici","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/facciamo-sorridere-le-madri-africane\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/spazioaperto\/facciamo-sorridere-le-madri-africane\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/facciamo-sorridere-le-madri-africane\/#primaryimage","url":"http:\/\/www.ccm-italia.org\/images\/sorrisi\/ccm_banner_sorrisi%20di%20madri%20africane_200x200.jpg","contentUrl":"http:\/\/www.ccm-italia.org\/images\/sorrisi\/ccm_banner_sorrisi%20di%20madri%20africane_200x200.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/facciamo-sorridere-le-madri-africane\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/"},{"@type":"ListItem","position":2,"name":"Facciamo sorridere le madri africane"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/#website","url":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/","name":"Spazio aperto","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","caption":"Redazione"},"description":"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte","sameAs":["http:\/\/www.quotidianopiemontese.it\/","https:\/\/www.facebook.com\/quotidianopiemontese","https:\/\/x.com\/quotidianopiem"],"url":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/author\/administrator\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/posts\/123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/comments?post=123"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/posts\/123\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/media?parent=123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/categories?post=123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/spazioaperto\/wp-json\/wp\/v2\/tags?post=123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}