{"id":978,"date":"2013-04-20T06:03:51","date_gmt":"2013-04-20T05:03:51","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/?p=978"},"modified":"2013-04-11T09:26:59","modified_gmt":"2013-04-11T08:26:59","slug":"a-tutto-yoga-con-il-proprio-cane","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/a-tutto-yoga-con-il-proprio-cane\/","title":{"rendered":"A tutto yoga con il proprio cane"},"content":{"rendered":"<p><a href=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/04\/cane-yoga-foto-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-979\" alt=\"cane-yoga-foto-3\" src=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/04\/cane-yoga-foto-3-300x161.jpg\" width=\"300\" height=\"161\" srcset=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/04\/cane-yoga-foto-3-300x161.jpg 300w, https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/04\/cane-yoga-foto-3.jpg 400w\" sizes=\"auto, (max-width: 300px) 85vw, 300px\" \/><\/a>Ebbene si, questa ci mancava proprio, anche se forse avremmo potuto farne a meno ancora per un po&#8217;! ma gi\u00e0 che ci siamo&#8230; parliamone. Molti bipedi, un po&#8217; per convinzione individuale, un po&#8217; per tendenza, si dedicano alla pratica dello yoga, antichissima disciplina che educa corpo e mente al sano rapporto con le forze universali e quelle interiori, attraverso la meditazione e alcune posizioni particolari chiamate \u00e2sana. Sono numerose le persone che ritengono di sentirsi meglio grazie allo yoga e, a quanto pare lo sostengono anche i cani. Certo, a modo loro. Che l&#8217;attivit\u00e0 fisica sia utile e benefica al nostro amico a quattro zampe (e anche a noi) \u00e8 fuori d&#8217;ogni dubbio. Riduce il rischio di malattie, di obesit\u00e0, di aggressivit\u00e0, di stress dell&#8217;animale, e non solo. Altrettanto utile \u00e8 il rapporto con il proprio umano. <!--more--><a href=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/04\/doga-yoga-cavalier-warrior.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-980\" alt=\"doga-yoga-cavalier-warrior\" src=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/04\/doga-yoga-cavalier-warrior-300x200.jpg\" width=\"300\" height=\"200\" srcset=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/04\/doga-yoga-cavalier-warrior-300x200.jpg 300w, https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/04\/doga-yoga-cavalier-warrior.jpg 600w\" sizes=\"auto, (max-width: 300px) 85vw, 300px\" \/><\/a>Rapporto &#8220;open air&#8221;, all&#8217;aria, magari durante una passeggiata al parco. Fare sport con Fido, insomma aiuta lui e pure il suo padrone. Vale anche per lo yoga. A Fido non serve il tappetino di gommapiuma su cui sdraiarsi, ma \u00e8 capace di imitare molte posizioni umane. Non tutte, ovviamente e non bisogna forzarlo. Le posizioni sedute pare che servano a rilassare la mente, a liberarla dai pensieri e conciliano un buon riposo, mantengono ottimale la pressione sanguigna. Quelle in piedi sono tonificanti e agiscono sugli organi interni, favoriscono il metabolismo, mentre le posizioni supine<strong><\/strong> consentono di recuperare energie. Le posizioni capovolte, invece migliorano la circolazione sanguigna e favoriscono l\u2019afflusso di ossigeno al cervello. Le torsioni sono tonificanti per le terminazioni nervose, placano mal di schiena, emicranie, tensioni a collo e spalle. Alcune posizioni che gli uomini assumono durante la pratica yoga si rifanno proprio a quelle degli animali e per i cani sono naturali e spontanee, quindi non hanno difficolt\u00e0 ad imitare il padrone&#8230; piuttosto potrebbe chiedersi perch\u00e8 vuol copiarlo!<\/p>\n<p>In altri casi, poi si pu\u00f2 provare la pratica Doga, ovvero lo yoga per cani, tendenza firmata Usa. Nata a New York, tale attivit\u00e0 propone di dedicarsi allo yoga con un compagno peloso<strong>. <\/strong>Dog + yoga: doga! La tecnica \u00e8 iniziata in una palestra newyorkese sette anni fa e, poi si \u00e8 diffusa a macchia d&#8217;olio. In tal caso, alcune posizioni, non solo si assumono insieme al proprio cane, ma tenendolo in braccio e il \u201cmantra yoga\u201d, ovvero\u00a0 una sorta di yoga del suono che prevede la ripetizione vocale di alcune frasi o suoni \u00e8 modificata in modo da non infastidire i cani che potrebbero latrare. Insomma, che dire&#8230; chi pi\u00f9 ne ha&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ebbene si, questa ci mancava proprio, anche se forse avremmo potuto farne a meno ancora per un po&#8217;! ma gi\u00e0 che ci siamo&#8230; parliamone. Molti bipedi, un po&#8217; per convinzione individuale, un po&#8217; per tendenza, si dedicano alla pratica dello yoga, antichissima disciplina che educa corpo e mente al sano rapporto con le forze universali &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/a-tutto-yoga-con-il-proprio-cane\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;A tutto yoga con il proprio cane&#8221;<\/span><\/a><\/p>\n","protected":false},"author":46,"featured_media":980,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[764,765,762,761,755,763,758,760,757,759,756],"class_list":["post-978","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-quattro-zampe","tag-animali-stress","tag-animali-yoga","tag-asana","tag-asana-cane","tag-doga","tag-doga-new-york","tag-mantra","tag-new-york","tag-yoga","tag-yoga-nidra","tag-yoga-per-cani"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A tutto yoga con il proprio cane - Quattro zampe e dintorni<\/title>\n<meta name=\"description\" content=\"Ebbene si, questa ci mancava proprio, anche se forse avremmo potuto farne a meno ancora per un po&#039;! ma gi\u00e0 che ci siamo... parliamone. Molti bipedi, un\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/a-tutto-yoga-con-il-proprio-cane\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A tutto yoga con il proprio cane - Quattro zampe e dintorni\" \/>\n<meta property=\"og:description\" content=\"Ebbene si, questa ci mancava proprio, anche se forse avremmo potuto farne a meno ancora per un po&#039;! ma gi\u00e0 che ci siamo... parliamone. Molti bipedi, un\" \/>\n<meta property=\"og:url\" content=\"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/a-tutto-yoga-con-il-proprio-cane\/\" \/>\n<meta property=\"og:site_name\" content=\"Quattro zampe e dintorni\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2013-04-20T05:03:51+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/04\/doga-yoga-cavalier-warrior.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Monica Genovese\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Monica Genovese\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/a-tutto-yoga-con-il-proprio-cane\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/a-tutto-yoga-con-il-proprio-cane\\\/\"},\"author\":{\"name\":\"Monica Genovese\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\"},\"headline\":\"A tutto yoga con il proprio cane\",\"datePublished\":\"2013-04-20T05:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/a-tutto-yoga-con-il-proprio-cane\\\/\"},\"wordCount\":426,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/a-tutto-yoga-con-il-proprio-cane\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2013\\\/04\\\/doga-yoga-cavalier-warrior.jpg\",\"keywords\":[\"animali stress\",\"animali yoga\",\"asana\",\"asana cane\",\"doga\",\"doga New York\",\"mantra\",\"New York\",\"yoga\",\"yoga nidra\",\"yoga per cani\"],\"articleSection\":[\"Quattro zampe\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/a-tutto-yoga-con-il-proprio-cane\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/a-tutto-yoga-con-il-proprio-cane\\\/\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/a-tutto-yoga-con-il-proprio-cane\\\/\",\"name\":\"A tutto yoga con il proprio cane - Quattro zampe e dintorni\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/a-tutto-yoga-con-il-proprio-cane\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/a-tutto-yoga-con-il-proprio-cane\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2013\\\/04\\\/doga-yoga-cavalier-warrior.jpg\",\"datePublished\":\"2013-04-20T05:03:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\"},\"description\":\"Ebbene si, questa ci mancava proprio, anche se forse avremmo potuto farne a meno ancora per un po'! ma gi\u00e0 che ci siamo... parliamone. Molti bipedi, un\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/a-tutto-yoga-con-il-proprio-cane\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/a-tutto-yoga-con-il-proprio-cane\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/a-tutto-yoga-con-il-proprio-cane\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2013\\\/04\\\/doga-yoga-cavalier-warrior.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2013\\\/04\\\/doga-yoga-cavalier-warrior.jpg\",\"width\":600,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/a-tutto-yoga-con-il-proprio-cane\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A tutto yoga con il proprio cane\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\",\"name\":\"Quattro zampe e dintorni\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\",\"name\":\"Monica Genovese\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"caption\":\"Monica Genovese\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Monica_Genovese\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/author\\\/monica-genovese\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A tutto yoga con il proprio cane - Quattro zampe e dintorni","description":"Ebbene si, questa ci mancava proprio, anche se forse avremmo potuto farne a meno ancora per un po'! ma gi\u00e0 che ci siamo... parliamone. Molti bipedi, un","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/a-tutto-yoga-con-il-proprio-cane\/","og_locale":"it_IT","og_type":"article","og_title":"A tutto yoga con il proprio cane - Quattro zampe e dintorni","og_description":"Ebbene si, questa ci mancava proprio, anche se forse avremmo potuto farne a meno ancora per un po'! ma gi\u00e0 che ci siamo... parliamone. Molti bipedi, un","og_url":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/a-tutto-yoga-con-il-proprio-cane\/","og_site_name":"Quattro zampe e dintorni","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2013-04-20T05:03:51+00:00","og_image":[{"width":600,"height":400,"url":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/04\/doga-yoga-cavalier-warrior.jpg","type":"image\/jpeg"}],"author":"Monica Genovese","twitter_misc":{"Scritto da":"Monica Genovese","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/a-tutto-yoga-con-il-proprio-cane\/#article","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/a-tutto-yoga-con-il-proprio-cane\/"},"author":{"name":"Monica Genovese","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce"},"headline":"A tutto yoga con il proprio cane","datePublished":"2013-04-20T05:03:51+00:00","mainEntityOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/a-tutto-yoga-con-il-proprio-cane\/"},"wordCount":426,"commentCount":0,"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/a-tutto-yoga-con-il-proprio-cane\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/04\/doga-yoga-cavalier-warrior.jpg","keywords":["animali stress","animali yoga","asana","asana cane","doga","doga New York","mantra","New York","yoga","yoga nidra","yoga per cani"],"articleSection":["Quattro zampe"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/a-tutto-yoga-con-il-proprio-cane\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/a-tutto-yoga-con-il-proprio-cane\/","url":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/a-tutto-yoga-con-il-proprio-cane\/","name":"A tutto yoga con il proprio cane - Quattro zampe e dintorni","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website"},"primaryImageOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/a-tutto-yoga-con-il-proprio-cane\/#primaryimage"},"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/a-tutto-yoga-con-il-proprio-cane\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/04\/doga-yoga-cavalier-warrior.jpg","datePublished":"2013-04-20T05:03:51+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce"},"description":"Ebbene si, questa ci mancava proprio, anche se forse avremmo potuto farne a meno ancora per un po'! ma gi\u00e0 che ci siamo... parliamone. Molti bipedi, un","breadcrumb":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/a-tutto-yoga-con-il-proprio-cane\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/a-tutto-yoga-con-il-proprio-cane\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/a-tutto-yoga-con-il-proprio-cane\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/04\/doga-yoga-cavalier-warrior.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/04\/doga-yoga-cavalier-warrior.jpg","width":600,"height":400},{"@type":"BreadcrumbList","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/a-tutto-yoga-con-il-proprio-cane\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/"},{"@type":"ListItem","position":2,"name":"A tutto yoga con il proprio cane"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/","name":"Quattro zampe e dintorni","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce","name":"Monica Genovese","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","caption":"Monica Genovese"},"sameAs":["https:\/\/x.com\/Monica_Genovese"],"url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/author\/monica-genovese\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/comments?post=978"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/978\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media\/980"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media?parent=978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/categories?post=978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/tags?post=978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}