{"id":849,"date":"2013-02-20T05:42:58","date_gmt":"2013-02-20T04:42:58","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/?p=849"},"modified":"2013-02-20T10:23:58","modified_gmt":"2013-02-20T09:23:58","slug":"salvato-il-gattino-che-viveva-nel-tombino","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/salvato-il-gattino-che-viveva-nel-tombino\/","title":{"rendered":"Salvato il gattino che &#8220;viveva&#8221; nel tombino!"},"content":{"rendered":"<p><a href=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/02\/Desktop28-cucciolo-gatto-norvegese.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-thumbnail wp-image-850\" alt=\"Desktop28-cucciolo-gatto-norvegese\" src=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/02\/Desktop28-cucciolo-gatto-norvegese-150x150.jpg\" width=\"150\" height=\"150\" srcset=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/02\/Desktop28-cucciolo-gatto-norvegese-150x150.jpg 150w, https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/02\/Desktop28-cucciolo-gatto-norvegese-120x120.jpg 120w\" sizes=\"auto, (max-width: 150px) 85vw, 150px\" \/><\/a>A volte l&#8217;asfalto \u00e8 rovente, altro volte disastrato dai mezzi pesanti, altre ancora l&#8217;asflato&#8230; miagola. E miagola davvero, un miagolio vero e proprio, di quelli che attirano l&#8217;attenzione e ti inteneriscono anche se, al posto del cuore hai un vuoto come l&#8217;uomo di latta di Alice nel paese delle meraviglie! In questo caso, la strada dai mattoni rossi non porta a casa di Dorothy\u00a0ma a San Raffaele Cimena, piccola localit\u00e0 in provincia di Torino dove, poche sere fa, un anziano signore, intento a passeggiare lungo via San Rocco, ha sentito ripetuti e sottili miagolii. <!--more-->Nonostante le sue ricerche, sugli alberi, dietro cassonetti dei rifiuti, sotto le auto, tra le piante, non ha trovato niente, ma il miagolio era sempre l\u00ec, nelle sue orecchie a reclamare attenzione e pi\u00f9 l&#8217;uomo camminava, pi\u00f9 il miagolio lo seguiva con insistenza. Ad un certo punto, come in tutte le favole a lieto fine, il signore, accantonando l&#8217;idea di essere impazzito o di udire la voce di qualche fantasma, ha scorto dei tombini per lo smaltimento di acque reflue, in pratica le fogne e, spinto da curiosit\u00e0, ha acceso la torcia che aveva con se! Perch\u00e9 poi una persona che esca per una passeggiata debba portarsi la torcia, non \u00e8 dato sapere. In ogni caso, \u00e8 tornata utile visto che, proprio nel tombino si trovava la fonte del mistero.<\/p>\n<p>Il miagolio giungeva dal sottosuolo. Un cucciolo di gatto, tigrato, rosso, dal musetto spaventato e tutto infreddolito era l\u00ec che, con lo sguardo verso le grate del tombino, guardava il suo salvatore, ovvero l&#8217;uomo con la torcia. Il malcapitato micino si era infilato nella condotta sotto il manto stradale restando incastrato. Allertati i volontari della locale protezione civile, il felino bagnato e sporco, \u00e8 stato salvato nel giro qualche minuto. Poche martellate al tombino e il gatto ha ritrovato l&#8217;agognata libert\u00e0. E speriamo che non ci riprovi!<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A volte l&#8217;asfalto \u00e8 rovente, altro volte disastrato dai mezzi pesanti, altre ancora l&#8217;asflato&#8230; miagola. E miagola davvero, un miagolio vero e proprio, di quelli che attirano l&#8217;attenzione e ti inteneriscono anche se, al posto del cuore hai un vuoto come l&#8217;uomo di latta di Alice nel paese delle meraviglie! In questo caso, la strada &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/salvato-il-gattino-che-viveva-nel-tombino\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Salvato il gattino che &#8220;viveva&#8221; nel tombino!&#8221;<\/span><\/a><\/p>\n","protected":false},"author":46,"featured_media":850,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[656,653,655,4,652,3,654,132,657],"class_list":["post-849","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-quattro-zampe","tag-alice-nel-paese-meraviglie","tag-cucciolo-tombino","tag-doroty","tag-felino","tag-gattino","tag-gatto","tag-san-raffaele-cinmena","tag-torino","tag-uomo-di-latta"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Salvato il gattino che &quot;viveva&quot; nel tombino! - Quattro zampe e dintorni<\/title>\n<meta name=\"description\" content=\"A volte l&#039;asfalto \u00e8 rovente, altro volte disastrato dai mezzi pesanti, altre ancora l&#039;asflato... miagola. E miagola davvero, un miagolio vero e proprio,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/salvato-il-gattino-che-viveva-nel-tombino\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salvato il gattino che &quot;viveva&quot; nel tombino! - Quattro zampe e dintorni\" \/>\n<meta property=\"og:description\" content=\"A volte l&#039;asfalto \u00e8 rovente, altro volte disastrato dai mezzi pesanti, altre ancora l&#039;asflato... miagola. E miagola davvero, un miagolio vero e proprio,\" \/>\n<meta property=\"og:url\" content=\"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/salvato-il-gattino-che-viveva-nel-tombino\/\" \/>\n<meta property=\"og:site_name\" content=\"Quattro zampe e dintorni\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2013-02-20T04:42:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-02-20T09:23:58+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/02\/Desktop28-cucciolo-gatto-norvegese.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"777\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Monica Genovese\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Monica Genovese\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/salvato-il-gattino-che-viveva-nel-tombino\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/salvato-il-gattino-che-viveva-nel-tombino\\\/\"},\"author\":{\"name\":\"Monica Genovese\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\"},\"headline\":\"Salvato il gattino che &#8220;viveva&#8221; nel tombino!\",\"datePublished\":\"2013-02-20T04:42:58+00:00\",\"dateModified\":\"2013-02-20T09:23:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/salvato-il-gattino-che-viveva-nel-tombino\\\/\"},\"wordCount\":324,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/salvato-il-gattino-che-viveva-nel-tombino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2013\\\/02\\\/Desktop28-cucciolo-gatto-norvegese.jpg\",\"keywords\":[\"alice nel paese meraviglie\",\"cucciolo tombino\",\"doroty\",\"felino\",\"gattino\",\"Gatto\",\"san raffaele cinmena\",\"Torino\",\"uomo di latta\"],\"articleSection\":[\"Quattro zampe\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/salvato-il-gattino-che-viveva-nel-tombino\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/salvato-il-gattino-che-viveva-nel-tombino\\\/\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/salvato-il-gattino-che-viveva-nel-tombino\\\/\",\"name\":\"Salvato il gattino che \\\"viveva\\\" nel tombino! - Quattro zampe e dintorni\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/salvato-il-gattino-che-viveva-nel-tombino\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/salvato-il-gattino-che-viveva-nel-tombino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2013\\\/02\\\/Desktop28-cucciolo-gatto-norvegese.jpg\",\"datePublished\":\"2013-02-20T04:42:58+00:00\",\"dateModified\":\"2013-02-20T09:23:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\"},\"description\":\"A volte l'asfalto \u00e8 rovente, altro volte disastrato dai mezzi pesanti, altre ancora l'asflato... miagola. E miagola davvero, un miagolio vero e proprio,\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/salvato-il-gattino-che-viveva-nel-tombino\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/salvato-il-gattino-che-viveva-nel-tombino\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/salvato-il-gattino-che-viveva-nel-tombino\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2013\\\/02\\\/Desktop28-cucciolo-gatto-norvegese.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2013\\\/02\\\/Desktop28-cucciolo-gatto-norvegese.jpg\",\"width\":1024,\"height\":777},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/salvato-il-gattino-che-viveva-nel-tombino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Salvato il gattino che &#8220;viveva&#8221; nel tombino!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\",\"name\":\"Quattro zampe e dintorni\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\",\"name\":\"Monica Genovese\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"caption\":\"Monica Genovese\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Monica_Genovese\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/author\\\/monica-genovese\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salvato il gattino che \"viveva\" nel tombino! - Quattro zampe e dintorni","description":"A volte l'asfalto \u00e8 rovente, altro volte disastrato dai mezzi pesanti, altre ancora l'asflato... miagola. E miagola davvero, un miagolio vero e proprio,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/salvato-il-gattino-che-viveva-nel-tombino\/","og_locale":"it_IT","og_type":"article","og_title":"Salvato il gattino che \"viveva\" nel tombino! - Quattro zampe e dintorni","og_description":"A volte l'asfalto \u00e8 rovente, altro volte disastrato dai mezzi pesanti, altre ancora l'asflato... miagola. E miagola davvero, un miagolio vero e proprio,","og_url":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/salvato-il-gattino-che-viveva-nel-tombino\/","og_site_name":"Quattro zampe e dintorni","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2013-02-20T04:42:58+00:00","article_modified_time":"2013-02-20T09:23:58+00:00","og_image":[{"width":1024,"height":777,"url":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/02\/Desktop28-cucciolo-gatto-norvegese.jpg","type":"image\/jpeg"}],"author":"Monica Genovese","twitter_misc":{"Scritto da":"Monica Genovese","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/salvato-il-gattino-che-viveva-nel-tombino\/#article","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/salvato-il-gattino-che-viveva-nel-tombino\/"},"author":{"name":"Monica Genovese","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce"},"headline":"Salvato il gattino che &#8220;viveva&#8221; nel tombino!","datePublished":"2013-02-20T04:42:58+00:00","dateModified":"2013-02-20T09:23:58+00:00","mainEntityOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/salvato-il-gattino-che-viveva-nel-tombino\/"},"wordCount":324,"commentCount":0,"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/salvato-il-gattino-che-viveva-nel-tombino\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/02\/Desktop28-cucciolo-gatto-norvegese.jpg","keywords":["alice nel paese meraviglie","cucciolo tombino","doroty","felino","gattino","Gatto","san raffaele cinmena","Torino","uomo di latta"],"articleSection":["Quattro zampe"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/salvato-il-gattino-che-viveva-nel-tombino\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/salvato-il-gattino-che-viveva-nel-tombino\/","url":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/salvato-il-gattino-che-viveva-nel-tombino\/","name":"Salvato il gattino che \"viveva\" nel tombino! - Quattro zampe e dintorni","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website"},"primaryImageOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/salvato-il-gattino-che-viveva-nel-tombino\/#primaryimage"},"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/salvato-il-gattino-che-viveva-nel-tombino\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/02\/Desktop28-cucciolo-gatto-norvegese.jpg","datePublished":"2013-02-20T04:42:58+00:00","dateModified":"2013-02-20T09:23:58+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce"},"description":"A volte l'asfalto \u00e8 rovente, altro volte disastrato dai mezzi pesanti, altre ancora l'asflato... miagola. E miagola davvero, un miagolio vero e proprio,","breadcrumb":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/salvato-il-gattino-che-viveva-nel-tombino\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/salvato-il-gattino-che-viveva-nel-tombino\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/salvato-il-gattino-che-viveva-nel-tombino\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/02\/Desktop28-cucciolo-gatto-norvegese.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/02\/Desktop28-cucciolo-gatto-norvegese.jpg","width":1024,"height":777},{"@type":"BreadcrumbList","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/salvato-il-gattino-che-viveva-nel-tombino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/"},{"@type":"ListItem","position":2,"name":"Salvato il gattino che &#8220;viveva&#8221; nel tombino!"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/","name":"Quattro zampe e dintorni","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce","name":"Monica Genovese","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","caption":"Monica Genovese"},"sameAs":["https:\/\/x.com\/Monica_Genovese"],"url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/author\/monica-genovese\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/comments?post=849"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/849\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media\/850"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media?parent=849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/categories?post=849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/tags?post=849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}