{"id":818,"date":"2013-02-10T05:50:16","date_gmt":"2013-02-10T04:50:16","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/?p=818"},"modified":"2013-02-10T14:32:32","modified_gmt":"2013-02-10T13:32:32","slug":"paolo-e-droopi-il-primo-uno-scrittore-il-secondo-la-sua-ispirazione","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/paolo-e-droopi-il-primo-uno-scrittore-il-secondo-la-sua-ispirazione\/","title":{"rendered":"Paolo e Droopi: il primo, uno scrittore. Il secondo la sua ispirazione felina"},"content":{"rendered":"<figure id=\"attachment_819\" aria-describedby=\"caption-attachment-819\" style=\"width: 150px\" class=\"wp-caption alignright\"><a href=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/2013\/02\/10\/paolo-e-droopi-il-primo-uno-scrittore-il-secondo-la-sua-ispirazione\/paolo-e-droopi\/\" rel=\"attachment wp-att-819\"><img loading=\"lazy\" decoding=\"async\" class=\"size-thumbnail wp-image-819\" alt=\"Paolo e Droopi\" src=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/01\/Paolo-e-Droopi-150x150.jpg\" width=\"150\" height=\"150\" srcset=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/01\/Paolo-e-Droopi-150x150.jpg 150w, https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/01\/Paolo-e-Droopi-120x120.jpg 120w\" sizes=\"auto, (max-width: 150px) 85vw, 150px\" \/><\/a><figcaption id=\"caption-attachment-819\" class=\"wp-caption-text\">Paolo e Droopi<\/figcaption><\/figure>\n<p>Tra le tante mail che arrivano alla redazione di Quotidiano Piemontese, alcune si riferiscono al nostro blog &#8220;Quattro Zampe e dintorni&#8221;. Molti lettori ci segnalano abusi su animali, denunce, situazioni critiche di canili, ma anche belle vicende, storie a lieto fine che mostrano come, giorno per giorno, i nostri &#8220;familiari pelosi&#8221; facciano parte della vita, della casa, del cuore. Ecco uno di questi bei racconti, scritto da un personaggio noto nell&#8217;astigiano, e non solo. Si tratta dello scrittore Paolo Ferrero&#8230; e del suo gatto, ispirazione della storia, Droopie. Un incontro del destino sulla strada di Paolo.<!--more-->Io e Droopie c\u2019incontriamo domenica 25 settembre 2011 a Bra, mentre quasi lo schiaccio con la mia Multipla andando a presentare il libro a Savigliano: quando mi accorgo che \u00e8 vivo, fermo il poco traffico delle 13 e &#8211; dopo averne ricevuti i primi, robusti graffi &#8211; lo sistemo sul sedile accanto a me. Gli apro una delle buste di cibo che avevo acquistato un\u2019ora prima per gli altri miei quattro gatti. Io e Droopie andiamo al bar a Savigliano: nel senso che quando racconto l\u2019accaduto alla barista, quella parte assieme a me e una ciotola di latte a vedere la bestiola, ma lui , snob e spaurito, scompare sotto il sedile.<\/p>\n<p>Io e Droopie alle 15 ci becchiamo un temporale che fa slittare la presentazione alle 18: io sto un po\u2019 con lui e poi me ne vado in giro con l\u2019addetto stampa, che \u00e8 un gran tronco di femmina, tanto di accarezzare lui manco a parlarne\u2026 Io e Droopie torniamo a casa che \u00e8 dopo le nove di sera e passo mezz\u2019ora a cristonare nel sudore, ch\u00e9 lui si \u00e8 ficcato sotto la pedaliera e, dopo tutti le brugole e i cacciavite che ho tirato fuori per smontare la macchina, lui non ti scappa sotto il cruscotto dove la mia mano a prenderlo proprio non c\u2019arriva?<\/p>\n<p>Io e Droopie la mattina dopo abbiamo fatto colazione presto: lui si \u00e8 sbafato l\u2019altro cibo che gli avevo messo sull\u2019auto (a proposito: ha cacato e pisciato, ma i sedili in pelle \u2013 dicono \u2013 non patiscono), mentre io finisco il caff\u00e8 aspettando la giornalista che devo portare a fotografare la vendemmia. Io e Droopie \u00e8 di nuovo sera, che quando porto Michela a vedere la cosa, fuori \u00e8 gi\u00e0 di nuovo scuro e lui \u00e8 l\u00ec che mangia e gli punto la torcia negli occhietti e riesco a prenderlo! Io e Droopie dormiamo nel mio letto, stanchi di due fatiche ben diverse\u2026<\/p>\n<p>Io e Droopie il mattino dopo, facciamo le foto con Michela, che non si era fermata solo a cena. Michela ha una trentina d\u2019anni, i capelli neri e gli occhi azzurri come questo cielo di settembre che le viene in mente \u201cSereno \u00e8\u201d di Drupi, ma, quando lo porto al vaccino e il veterinario mi chiede come si chiama, dico Droopie con due \u201co\u201d perch\u00e9 \u00a0lui \u00e8 un vero figo e Clooney mica lo scrivi con la \u201cu\u201d!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tra le tante mail che arrivano alla redazione di Quotidiano Piemontese, alcune si riferiscono al nostro blog &#8220;Quattro Zampe e dintorni&#8221;. Molti lettori ci segnalano abusi su animali, denunce, situazioni critiche di canili, ma anche belle vicende, storie a lieto fine che mostrano come, giorno per giorno, i nostri &#8220;familiari pelosi&#8221; facciano parte della vita, &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/paolo-e-droopi-il-primo-uno-scrittore-il-secondo-la-sua-ispirazione\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Paolo e Droopi: il primo, uno scrittore. Il secondo la sua ispirazione felina&#8221;<\/span><\/a><\/p>\n","protected":false},"author":46,"featured_media":819,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[3,630,628,631,629],"class_list":["post-818","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-quattro-zampe","tag-gatto","tag-multipla","tag-paolo-ferrero","tag-salvata-gatto","tag-scrittore-asti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Paolo e Droopi: il primo, uno scrittore. Il secondo la sua ispirazione felina - Quattro zampe e dintorni<\/title>\n<meta name=\"description\" content=\"Tra le tante mail che arrivano alla redazione di Quotidiano Piemontese, alcune si riferiscono al nostro blog &quot;Quattro Zampe e dintorni&quot;. Molti lettori ci\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/paolo-e-droopi-il-primo-uno-scrittore-il-secondo-la-sua-ispirazione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paolo e Droopi: il primo, uno scrittore. Il secondo la sua ispirazione felina - Quattro zampe e dintorni\" \/>\n<meta property=\"og:description\" content=\"Tra le tante mail che arrivano alla redazione di Quotidiano Piemontese, alcune si riferiscono al nostro blog &quot;Quattro Zampe e dintorni&quot;. Molti lettori ci\" \/>\n<meta property=\"og:url\" content=\"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/paolo-e-droopi-il-primo-uno-scrittore-il-secondo-la-sua-ispirazione\/\" \/>\n<meta property=\"og:site_name\" content=\"Quattro zampe e dintorni\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2013-02-10T04:50:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-02-10T13:32:32+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/01\/Paolo-e-Droopi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"320\" \/>\n\t<meta property=\"og:image:height\" content=\"213\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Monica Genovese\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Monica Genovese\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/paolo-e-droopi-il-primo-uno-scrittore-il-secondo-la-sua-ispirazione\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/paolo-e-droopi-il-primo-uno-scrittore-il-secondo-la-sua-ispirazione\\\/\"},\"author\":{\"name\":\"Monica Genovese\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\"},\"headline\":\"Paolo e Droopi: il primo, uno scrittore. Il secondo la sua ispirazione felina\",\"datePublished\":\"2013-02-10T04:50:16+00:00\",\"dateModified\":\"2013-02-10T13:32:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/paolo-e-droopi-il-primo-uno-scrittore-il-secondo-la-sua-ispirazione\\\/\"},\"wordCount\":510,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/paolo-e-droopi-il-primo-uno-scrittore-il-secondo-la-sua-ispirazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2013\\\/01\\\/Paolo-e-Droopi.jpg\",\"keywords\":[\"Gatto\",\"multipla\",\"paolo ferrero\",\"salvata gatto\",\"scrittore asti\"],\"articleSection\":[\"Quattro zampe\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/paolo-e-droopi-il-primo-uno-scrittore-il-secondo-la-sua-ispirazione\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/paolo-e-droopi-il-primo-uno-scrittore-il-secondo-la-sua-ispirazione\\\/\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/paolo-e-droopi-il-primo-uno-scrittore-il-secondo-la-sua-ispirazione\\\/\",\"name\":\"Paolo e Droopi: il primo, uno scrittore. Il secondo la sua ispirazione felina - Quattro zampe e dintorni\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/paolo-e-droopi-il-primo-uno-scrittore-il-secondo-la-sua-ispirazione\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/paolo-e-droopi-il-primo-uno-scrittore-il-secondo-la-sua-ispirazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2013\\\/01\\\/Paolo-e-Droopi.jpg\",\"datePublished\":\"2013-02-10T04:50:16+00:00\",\"dateModified\":\"2013-02-10T13:32:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\"},\"description\":\"Tra le tante mail che arrivano alla redazione di Quotidiano Piemontese, alcune si riferiscono al nostro blog \\\"Quattro Zampe e dintorni\\\". Molti lettori ci\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/paolo-e-droopi-il-primo-uno-scrittore-il-secondo-la-sua-ispirazione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/paolo-e-droopi-il-primo-uno-scrittore-il-secondo-la-sua-ispirazione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/paolo-e-droopi-il-primo-uno-scrittore-il-secondo-la-sua-ispirazione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2013\\\/01\\\/Paolo-e-Droopi.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2013\\\/01\\\/Paolo-e-Droopi.jpg\",\"width\":320,\"height\":213,\"caption\":\"Paolo e Droopi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/paolo-e-droopi-il-primo-uno-scrittore-il-secondo-la-sua-ispirazione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paolo e Droopi: il primo, uno scrittore. Il secondo la sua ispirazione felina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\",\"name\":\"Quattro zampe e dintorni\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\",\"name\":\"Monica Genovese\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"caption\":\"Monica Genovese\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Monica_Genovese\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/author\\\/monica-genovese\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paolo e Droopi: il primo, uno scrittore. Il secondo la sua ispirazione felina - Quattro zampe e dintorni","description":"Tra le tante mail che arrivano alla redazione di Quotidiano Piemontese, alcune si riferiscono al nostro blog \"Quattro Zampe e dintorni\". Molti lettori ci","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/paolo-e-droopi-il-primo-uno-scrittore-il-secondo-la-sua-ispirazione\/","og_locale":"it_IT","og_type":"article","og_title":"Paolo e Droopi: il primo, uno scrittore. Il secondo la sua ispirazione felina - Quattro zampe e dintorni","og_description":"Tra le tante mail che arrivano alla redazione di Quotidiano Piemontese, alcune si riferiscono al nostro blog \"Quattro Zampe e dintorni\". Molti lettori ci","og_url":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/paolo-e-droopi-il-primo-uno-scrittore-il-secondo-la-sua-ispirazione\/","og_site_name":"Quattro zampe e dintorni","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2013-02-10T04:50:16+00:00","article_modified_time":"2013-02-10T13:32:32+00:00","og_image":[{"width":320,"height":213,"url":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/01\/Paolo-e-Droopi.jpg","type":"image\/jpeg"}],"author":"Monica Genovese","twitter_misc":{"Scritto da":"Monica Genovese","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/paolo-e-droopi-il-primo-uno-scrittore-il-secondo-la-sua-ispirazione\/#article","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/paolo-e-droopi-il-primo-uno-scrittore-il-secondo-la-sua-ispirazione\/"},"author":{"name":"Monica Genovese","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce"},"headline":"Paolo e Droopi: il primo, uno scrittore. Il secondo la sua ispirazione felina","datePublished":"2013-02-10T04:50:16+00:00","dateModified":"2013-02-10T13:32:32+00:00","mainEntityOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/paolo-e-droopi-il-primo-uno-scrittore-il-secondo-la-sua-ispirazione\/"},"wordCount":510,"commentCount":0,"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/paolo-e-droopi-il-primo-uno-scrittore-il-secondo-la-sua-ispirazione\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/01\/Paolo-e-Droopi.jpg","keywords":["Gatto","multipla","paolo ferrero","salvata gatto","scrittore asti"],"articleSection":["Quattro zampe"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/paolo-e-droopi-il-primo-uno-scrittore-il-secondo-la-sua-ispirazione\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/paolo-e-droopi-il-primo-uno-scrittore-il-secondo-la-sua-ispirazione\/","url":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/paolo-e-droopi-il-primo-uno-scrittore-il-secondo-la-sua-ispirazione\/","name":"Paolo e Droopi: il primo, uno scrittore. Il secondo la sua ispirazione felina - Quattro zampe e dintorni","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website"},"primaryImageOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/paolo-e-droopi-il-primo-uno-scrittore-il-secondo-la-sua-ispirazione\/#primaryimage"},"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/paolo-e-droopi-il-primo-uno-scrittore-il-secondo-la-sua-ispirazione\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/01\/Paolo-e-Droopi.jpg","datePublished":"2013-02-10T04:50:16+00:00","dateModified":"2013-02-10T13:32:32+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce"},"description":"Tra le tante mail che arrivano alla redazione di Quotidiano Piemontese, alcune si riferiscono al nostro blog \"Quattro Zampe e dintorni\". Molti lettori ci","breadcrumb":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/paolo-e-droopi-il-primo-uno-scrittore-il-secondo-la-sua-ispirazione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/paolo-e-droopi-il-primo-uno-scrittore-il-secondo-la-sua-ispirazione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/paolo-e-droopi-il-primo-uno-scrittore-il-secondo-la-sua-ispirazione\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/01\/Paolo-e-Droopi.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/01\/Paolo-e-Droopi.jpg","width":320,"height":213,"caption":"Paolo e Droopi"},{"@type":"BreadcrumbList","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/paolo-e-droopi-il-primo-uno-scrittore-il-secondo-la-sua-ispirazione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/"},{"@type":"ListItem","position":2,"name":"Paolo e Droopi: il primo, uno scrittore. Il secondo la sua ispirazione felina"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/","name":"Quattro zampe e dintorni","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce","name":"Monica Genovese","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","caption":"Monica Genovese"},"sameAs":["https:\/\/x.com\/Monica_Genovese"],"url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/author\/monica-genovese\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/comments?post=818"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/818\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media\/819"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media?parent=818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/categories?post=818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/tags?post=818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}