{"id":711,"date":"2013-01-03T06:27:18","date_gmt":"2013-01-03T05:27:18","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/?p=711"},"modified":"2013-01-05T19:12:24","modified_gmt":"2013-01-05T18:12:24","slug":"baffuti-come-gli-animali-dalle-vibrisse-feline-ai-baffi-sulle-auto","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/baffuti-come-gli-animali-dalle-vibrisse-feline-ai-baffi-sulle-auto\/","title":{"rendered":"Baffuti come gli animali. Dalle vibrisse feline ai baffi sulle auto"},"content":{"rendered":"<p><a href=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/12\/LEGANERD_044937.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-thumbnail wp-image-712\" alt=\"\" src=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/12\/LEGANERD_044937-150x150.jpg\" width=\"150\" height=\"150\" \/><\/a>Baffoni non si nasce, ma si diventa e quando i baffi prendono il sopravvento, allora significa che siete diventati &#8220;Mustache&#8221;, ovvero appassionati di peli (superflui?) sul viso, a mo&#8217; di certi animali. La moda di farsi crescere baffi dalla forme bizzarre, arricciandoli, lisciandoli, curandoli e decorandoli, si festeggia, pi\u00f9 che in un giorno particolare, in un mese intero, quello scorso, il &#8220;Mustache Day&#8221;, tendenza nata in Australia dove, anni fa, per sostenere la ricerca sul cancro alla prostata, si diede il via a questo insolito ritrovo di baffuti. <!--more-->Il baffo tira anche in Italia, tanto che ne \u00e8 nata una pagina facebook sempre a scopo benefico, ma ci\u00f2 che spinge i baffoni a distinguersi, in fatto di peli, dagli altri sbarbatelli, non \u00e8 soltanto solidariet\u00e0, ma voglia di apparire e, in alcuni casi, somigliare a questo o quell&#8217;animale.<\/p>\n<p>lcuni, infatti optano per baffetti sottili che irrigidiscono con gel per creare l&#8217;effetto vibrisse feline, piuttosto appuntite. Altri optano per un pelo pi\u00f9 folto in stile cagnone. Quello che \u00e8 certo \u00e8 che, nel mondo animale le vibrisse, i baffi, hanno un&#8217;importanza notevole in termine di equilibrio e di visibilit\u00e0 dell&#8217;animale stesso. E non parliamo solo di cani e gatti. Il tamarino imperatore \u00e8 una piccola scimmia baffuta di 25 centimetri il cui nome rammenta quello di Guglielmo II, sovrano tedesco il quale aveva lunghi baffi bianchi.<\/p>\n<p>E che dire di quelle auto americane che vogliono somigliare ad animali? sto parlando delle auto con i baffi. Che gli americani siano stravaganti \u00e8 sicuro, al punto da modificare le loro vetture dotandole di baffi realizzati con materiali vari e applicati sulla presa d\u2019aria anteriore. Paese che vai&#8230;<br \/>\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Baffoni non si nasce, ma si diventa e quando i baffi prendono il sopravvento, allora significa che siete diventati &#8220;Mustache&#8221;, ovvero appassionati di peli (superflui?) sul viso, a mo&#8217; di certi animali. La moda di farsi crescere baffi dalla forme bizzarre, arricciandoli, lisciandoli, curandoli e decorandoli, si festeggia, pi\u00f9 che in un giorno particolare, in &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/baffuti-come-gli-animali-dalle-vibrisse-feline-ai-baffi-sulle-auto\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Baffuti come gli animali. Dalle vibrisse feline ai baffi sulle auto&#8221;<\/span><\/a><\/p>\n","protected":false},"author":46,"featured_media":712,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[558,560,21,22,557,559],"class_list":["post-711","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-quattro-zampe","tag-baffi","tag-baffuti","tag-cani","tag-gatti","tag-mustache","tag-vibrisse"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Baffuti come gli animali. Dalle vibrisse feline ai baffi sulle auto - Quattro zampe e dintorni<\/title>\n<meta name=\"description\" content=\"Baffoni non si nasce, ma si diventa e quando i baffi prendono il sopravvento, allora significa che siete diventati &quot;Mustache&quot;, ovvero appassionati di peli\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/baffuti-come-gli-animali-dalle-vibrisse-feline-ai-baffi-sulle-auto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Baffuti come gli animali. Dalle vibrisse feline ai baffi sulle auto - Quattro zampe e dintorni\" \/>\n<meta property=\"og:description\" content=\"Baffoni non si nasce, ma si diventa e quando i baffi prendono il sopravvento, allora significa che siete diventati &quot;Mustache&quot;, ovvero appassionati di peli\" \/>\n<meta property=\"og:url\" content=\"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/baffuti-come-gli-animali-dalle-vibrisse-feline-ai-baffi-sulle-auto\/\" \/>\n<meta property=\"og:site_name\" content=\"Quattro zampe e dintorni\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2013-01-03T05:27:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-01-05T18:12:24+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/12\/LEGANERD_044937.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"269\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Monica Genovese\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Monica Genovese\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/baffuti-come-gli-animali-dalle-vibrisse-feline-ai-baffi-sulle-auto\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/baffuti-come-gli-animali-dalle-vibrisse-feline-ai-baffi-sulle-auto\\\/\"},\"author\":{\"name\":\"Monica Genovese\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\"},\"headline\":\"Baffuti come gli animali. Dalle vibrisse feline ai baffi sulle auto\",\"datePublished\":\"2013-01-03T05:27:18+00:00\",\"dateModified\":\"2013-01-05T18:12:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/baffuti-come-gli-animali-dalle-vibrisse-feline-ai-baffi-sulle-auto\\\/\"},\"wordCount\":284,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/baffuti-come-gli-animali-dalle-vibrisse-feline-ai-baffi-sulle-auto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2012\\\/12\\\/LEGANERD_044937.jpg\",\"keywords\":[\"baffi\",\"baffuti\",\"cani\",\"gatti\",\"Mustache\",\"vibrisse\"],\"articleSection\":[\"Quattro zampe\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/baffuti-come-gli-animali-dalle-vibrisse-feline-ai-baffi-sulle-auto\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/baffuti-come-gli-animali-dalle-vibrisse-feline-ai-baffi-sulle-auto\\\/\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/baffuti-come-gli-animali-dalle-vibrisse-feline-ai-baffi-sulle-auto\\\/\",\"name\":\"Baffuti come gli animali. Dalle vibrisse feline ai baffi sulle auto - Quattro zampe e dintorni\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/baffuti-come-gli-animali-dalle-vibrisse-feline-ai-baffi-sulle-auto\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/baffuti-come-gli-animali-dalle-vibrisse-feline-ai-baffi-sulle-auto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2012\\\/12\\\/LEGANERD_044937.jpg\",\"datePublished\":\"2013-01-03T05:27:18+00:00\",\"dateModified\":\"2013-01-05T18:12:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\"},\"description\":\"Baffoni non si nasce, ma si diventa e quando i baffi prendono il sopravvento, allora significa che siete diventati \\\"Mustache\\\", ovvero appassionati di peli\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/baffuti-come-gli-animali-dalle-vibrisse-feline-ai-baffi-sulle-auto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/baffuti-come-gli-animali-dalle-vibrisse-feline-ai-baffi-sulle-auto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/baffuti-come-gli-animali-dalle-vibrisse-feline-ai-baffi-sulle-auto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2012\\\/12\\\/LEGANERD_044937.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2012\\\/12\\\/LEGANERD_044937.jpg\",\"width\":\"500\",\"height\":\"269\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/baffuti-come-gli-animali-dalle-vibrisse-feline-ai-baffi-sulle-auto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Baffuti come gli animali. Dalle vibrisse feline ai baffi sulle auto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\",\"name\":\"Quattro zampe e dintorni\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\",\"name\":\"Monica Genovese\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"caption\":\"Monica Genovese\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Monica_Genovese\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/author\\\/monica-genovese\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Baffuti come gli animali. Dalle vibrisse feline ai baffi sulle auto - Quattro zampe e dintorni","description":"Baffoni non si nasce, ma si diventa e quando i baffi prendono il sopravvento, allora significa che siete diventati \"Mustache\", ovvero appassionati di peli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/baffuti-come-gli-animali-dalle-vibrisse-feline-ai-baffi-sulle-auto\/","og_locale":"it_IT","og_type":"article","og_title":"Baffuti come gli animali. Dalle vibrisse feline ai baffi sulle auto - Quattro zampe e dintorni","og_description":"Baffoni non si nasce, ma si diventa e quando i baffi prendono il sopravvento, allora significa che siete diventati \"Mustache\", ovvero appassionati di peli","og_url":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/baffuti-come-gli-animali-dalle-vibrisse-feline-ai-baffi-sulle-auto\/","og_site_name":"Quattro zampe e dintorni","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2013-01-03T05:27:18+00:00","article_modified_time":"2013-01-05T18:12:24+00:00","og_image":[{"width":500,"height":269,"url":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/12\/LEGANERD_044937.jpg","type":"image\/jpeg"}],"author":"Monica Genovese","twitter_misc":{"Scritto da":"Monica Genovese","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/baffuti-come-gli-animali-dalle-vibrisse-feline-ai-baffi-sulle-auto\/#article","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/baffuti-come-gli-animali-dalle-vibrisse-feline-ai-baffi-sulle-auto\/"},"author":{"name":"Monica Genovese","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce"},"headline":"Baffuti come gli animali. Dalle vibrisse feline ai baffi sulle auto","datePublished":"2013-01-03T05:27:18+00:00","dateModified":"2013-01-05T18:12:24+00:00","mainEntityOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/baffuti-come-gli-animali-dalle-vibrisse-feline-ai-baffi-sulle-auto\/"},"wordCount":284,"commentCount":0,"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/baffuti-come-gli-animali-dalle-vibrisse-feline-ai-baffi-sulle-auto\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/12\/LEGANERD_044937.jpg","keywords":["baffi","baffuti","cani","gatti","Mustache","vibrisse"],"articleSection":["Quattro zampe"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/baffuti-come-gli-animali-dalle-vibrisse-feline-ai-baffi-sulle-auto\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/baffuti-come-gli-animali-dalle-vibrisse-feline-ai-baffi-sulle-auto\/","url":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/baffuti-come-gli-animali-dalle-vibrisse-feline-ai-baffi-sulle-auto\/","name":"Baffuti come gli animali. Dalle vibrisse feline ai baffi sulle auto - Quattro zampe e dintorni","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website"},"primaryImageOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/baffuti-come-gli-animali-dalle-vibrisse-feline-ai-baffi-sulle-auto\/#primaryimage"},"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/baffuti-come-gli-animali-dalle-vibrisse-feline-ai-baffi-sulle-auto\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/12\/LEGANERD_044937.jpg","datePublished":"2013-01-03T05:27:18+00:00","dateModified":"2013-01-05T18:12:24+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce"},"description":"Baffoni non si nasce, ma si diventa e quando i baffi prendono il sopravvento, allora significa che siete diventati \"Mustache\", ovvero appassionati di peli","breadcrumb":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/baffuti-come-gli-animali-dalle-vibrisse-feline-ai-baffi-sulle-auto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/baffuti-come-gli-animali-dalle-vibrisse-feline-ai-baffi-sulle-auto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/baffuti-come-gli-animali-dalle-vibrisse-feline-ai-baffi-sulle-auto\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/12\/LEGANERD_044937.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/12\/LEGANERD_044937.jpg","width":"500","height":"269"},{"@type":"BreadcrumbList","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/baffuti-come-gli-animali-dalle-vibrisse-feline-ai-baffi-sulle-auto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/"},{"@type":"ListItem","position":2,"name":"Baffuti come gli animali. Dalle vibrisse feline ai baffi sulle auto"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/","name":"Quattro zampe e dintorni","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce","name":"Monica Genovese","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","caption":"Monica Genovese"},"sameAs":["https:\/\/x.com\/Monica_Genovese"],"url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/author\/monica-genovese\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/comments?post=711"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/711\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media\/712"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media?parent=711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/categories?post=711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/tags?post=711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}