{"id":508,"date":"2012-09-13T10:08:45","date_gmt":"2012-09-13T10:08:45","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/?p=508"},"modified":"2012-09-13T16:12:09","modified_gmt":"2012-09-13T16:12:09","slug":"scoperta-nuova-specie-di-scimmia-docile-e-dallo-sguardo-umano","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/scoperta-nuova-specie-di-scimmia-docile-e-dallo-sguardo-umano\/","title":{"rendered":"Scoperta nuova specie di scimmia. Docile e dallo sguardo umano!"},"content":{"rendered":"<figure id=\"attachment_509\" aria-describedby=\"caption-attachment-509\" style=\"width: 150px\" class=\"wp-caption alignright\"><a href=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/09\/images.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-thumbnail wp-image-509\" title=\"images\" src=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/09\/images-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><figcaption id=\"caption-attachment-509\" class=\"wp-caption-text\">Lesula<\/figcaption><\/figure>\n<p>Figura slanciata, volto singolare, occhi molto espressivi, carattere dolce. No, non \u00e8 la tipica ragazza della porta accanto che pu\u00f2 far girare la testa, ma una scimmia. Si, proprio una scimmia con una particolarit\u00e0 che la rende unica al mondo. E&#8217; una nuova specie e, in un mondo in cui molti animali rischiano l&#8217;estinzione e altri, purtroppo sono gi\u00e0 estinti, \u00e8 un evento eccezionale. Si chiama Lesula, nome comune con cui \u00e8 conosciuta dai popoli del Paese di origine. <!--more-->Scientificamente si tratta di un Cercopithecus lomamiensis, rinvenuto nella foresta del bacino africano di Lonami, in Congo. La scoperta, o meglio l&#8217;individuazione, \u00e8 opera di due ricercatori americani, John e Terese Hart che, nel 2007 notarono un esemplare di Lesula in cattivit\u00e0 e ora, a 28 anni di distanza ne hanno notato un altro. Fortunati o attenti osservatori? In ogni caso \u00e8 un primate di cui prima non si conosceva l&#8217;esistenza. Questa novit\u00e0 rappresenta un passo importante, secondo gli scienziati, per la comprensione dell&#8217;evoluzione animale e umana.<\/p>\n<p>I maschi adulti di questa specie sono piuttosto lunghi, 47 &#8211; 65 cm e pesano 4,0 &#8211; 7,1 kg.\u00a0Le \u00a0femmine subadulte sono lunghe 40 &#8211; 42 cm e pesano 3,5 &#8211; 4,0 kg. Secondo studi effettuati, pare che Lesula sia tipica di un terrritorio a 17 mila km2, circa di foreste del bacino centro-orientale della Repubblica del Congo, nelle province di Maniema e Orientale, ad ovest del corso superiore del fiume Tshuapa e nel distretto di Sankuru, nel Kasai Orientale. La scimmia vive tra i 400 e i 715 metri di altitudine. Le zone africane in questione sono rimaste, a lungo tempo, inesplorate e sconosciute ai pi\u00f9, pertanto \u00e8 possibile che altre specie animali non ancora note vivano l\u00ec indisturbate. La curiosit\u00e0 \u00e8 d&#8217;obbligo e comprensibile, ma speriamo anche il rispetto per un ambiente ancora incontaminato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Figura slanciata, volto singolare, occhi molto espressivi, carattere dolce. No, non \u00e8 la tipica ragazza della porta accanto che pu\u00f2 far girare la testa, ma una scimmia. Si, proprio una scimmia con una particolarit\u00e0 che la rende unica al mondo. E&#8217; una nuova specie e, in un mondo in cui molti animali rischiano l&#8217;estinzione e &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/scoperta-nuova-specie-di-scimmia-docile-e-dallo-sguardo-umano\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Scoperta nuova specie di scimmia. Docile e dallo sguardo umano!&#8221;<\/span><\/a><\/p>\n","protected":false},"author":46,"featured_media":509,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[347,18,372,374,377,378,376,373,379,375],"class_list":["post-508","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-quattro-zampe","tag-africa","tag-animali","tag-cercopithecus-lomamiensis","tag-congo","tag-kasai-orientale","tag-lesula","tag-repubblica-del-congo","tag-scimmia","tag-terese-hart","tag-tshuapa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Scoperta nuova specie di scimmia. Docile e dallo sguardo umano! - Quattro zampe e dintorni<\/title>\n<meta name=\"description\" content=\"Figura slanciata, volto singolare, occhi molto espressivi, carattere dolce. No, non \u00e8 la tipica ragazza della porta accanto che pu\u00f2 far girare la testa,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/scoperta-nuova-specie-di-scimmia-docile-e-dallo-sguardo-umano\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Scoperta nuova specie di scimmia. Docile e dallo sguardo umano! - Quattro zampe e dintorni\" \/>\n<meta property=\"og:description\" content=\"Figura slanciata, volto singolare, occhi molto espressivi, carattere dolce. No, non \u00e8 la tipica ragazza della porta accanto che pu\u00f2 far girare la testa,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/scoperta-nuova-specie-di-scimmia-docile-e-dallo-sguardo-umano\/\" \/>\n<meta property=\"og:site_name\" content=\"Quattro zampe e dintorni\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2012-09-13T10:08:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-09-13T16:12:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/09\/images.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"219\" \/>\n\t<meta property=\"og:image:height\" content=\"230\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Monica Genovese\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Monica Genovese\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/scoperta-nuova-specie-di-scimmia-docile-e-dallo-sguardo-umano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/scoperta-nuova-specie-di-scimmia-docile-e-dallo-sguardo-umano\\\/\"},\"author\":{\"name\":\"Monica Genovese\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\"},\"headline\":\"Scoperta nuova specie di scimmia. Docile e dallo sguardo umano!\",\"datePublished\":\"2012-09-13T10:08:45+00:00\",\"dateModified\":\"2012-09-13T16:12:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/scoperta-nuova-specie-di-scimmia-docile-e-dallo-sguardo-umano\\\/\"},\"wordCount\":306,\"commentCount\":2,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/scoperta-nuova-specie-di-scimmia-docile-e-dallo-sguardo-umano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2012\\\/09\\\/images.jpg\",\"keywords\":[\"africa\",\"animali\",\"Cercopithecus lomamiensis\",\"Congo\",\"Kasai Orientale\",\"Lesula\",\"Repubblica del Congo\",\"scimmia\",\"Terese Hart\",\"Tshuapa\"],\"articleSection\":[\"Quattro zampe\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/scoperta-nuova-specie-di-scimmia-docile-e-dallo-sguardo-umano\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/scoperta-nuova-specie-di-scimmia-docile-e-dallo-sguardo-umano\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/scoperta-nuova-specie-di-scimmia-docile-e-dallo-sguardo-umano\\\/\",\"name\":\"Scoperta nuova specie di scimmia. Docile e dallo sguardo umano! - Quattro zampe e dintorni\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/scoperta-nuova-specie-di-scimmia-docile-e-dallo-sguardo-umano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/scoperta-nuova-specie-di-scimmia-docile-e-dallo-sguardo-umano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2012\\\/09\\\/images.jpg\",\"datePublished\":\"2012-09-13T10:08:45+00:00\",\"dateModified\":\"2012-09-13T16:12:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\"},\"description\":\"Figura slanciata, volto singolare, occhi molto espressivi, carattere dolce. No, non \u00e8 la tipica ragazza della porta accanto che pu\u00f2 far girare la testa,\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/scoperta-nuova-specie-di-scimmia-docile-e-dallo-sguardo-umano\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/scoperta-nuova-specie-di-scimmia-docile-e-dallo-sguardo-umano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/scoperta-nuova-specie-di-scimmia-docile-e-dallo-sguardo-umano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2012\\\/09\\\/images.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2012\\\/09\\\/images.jpg\",\"width\":\"219\",\"height\":\"230\",\"caption\":\"Lesula\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/scoperta-nuova-specie-di-scimmia-docile-e-dallo-sguardo-umano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Scoperta nuova specie di scimmia. Docile e dallo sguardo umano!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\",\"name\":\"Quattro zampe e dintorni\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\",\"name\":\"Monica Genovese\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"caption\":\"Monica Genovese\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Monica_Genovese\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/author\\\/monica-genovese\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Scoperta nuova specie di scimmia. Docile e dallo sguardo umano! - Quattro zampe e dintorni","description":"Figura slanciata, volto singolare, occhi molto espressivi, carattere dolce. No, non \u00e8 la tipica ragazza della porta accanto che pu\u00f2 far girare la testa,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/scoperta-nuova-specie-di-scimmia-docile-e-dallo-sguardo-umano\/","og_locale":"it_IT","og_type":"article","og_title":"Scoperta nuova specie di scimmia. Docile e dallo sguardo umano! - Quattro zampe e dintorni","og_description":"Figura slanciata, volto singolare, occhi molto espressivi, carattere dolce. No, non \u00e8 la tipica ragazza della porta accanto che pu\u00f2 far girare la testa,","og_url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/scoperta-nuova-specie-di-scimmia-docile-e-dallo-sguardo-umano\/","og_site_name":"Quattro zampe e dintorni","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2012-09-13T10:08:45+00:00","article_modified_time":"2012-09-13T16:12:09+00:00","og_image":[{"width":219,"height":230,"url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/09\/images.jpg","type":"image\/jpeg"}],"author":"Monica Genovese","twitter_misc":{"Scritto da":"Monica Genovese","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/scoperta-nuova-specie-di-scimmia-docile-e-dallo-sguardo-umano\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/scoperta-nuova-specie-di-scimmia-docile-e-dallo-sguardo-umano\/"},"author":{"name":"Monica Genovese","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce"},"headline":"Scoperta nuova specie di scimmia. Docile e dallo sguardo umano!","datePublished":"2012-09-13T10:08:45+00:00","dateModified":"2012-09-13T16:12:09+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/scoperta-nuova-specie-di-scimmia-docile-e-dallo-sguardo-umano\/"},"wordCount":306,"commentCount":2,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/scoperta-nuova-specie-di-scimmia-docile-e-dallo-sguardo-umano\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/09\/images.jpg","keywords":["africa","animali","Cercopithecus lomamiensis","Congo","Kasai Orientale","Lesula","Repubblica del Congo","scimmia","Terese Hart","Tshuapa"],"articleSection":["Quattro zampe"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/scoperta-nuova-specie-di-scimmia-docile-e-dallo-sguardo-umano\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/scoperta-nuova-specie-di-scimmia-docile-e-dallo-sguardo-umano\/","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/scoperta-nuova-specie-di-scimmia-docile-e-dallo-sguardo-umano\/","name":"Scoperta nuova specie di scimmia. Docile e dallo sguardo umano! - Quattro zampe e dintorni","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/scoperta-nuova-specie-di-scimmia-docile-e-dallo-sguardo-umano\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/scoperta-nuova-specie-di-scimmia-docile-e-dallo-sguardo-umano\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/09\/images.jpg","datePublished":"2012-09-13T10:08:45+00:00","dateModified":"2012-09-13T16:12:09+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce"},"description":"Figura slanciata, volto singolare, occhi molto espressivi, carattere dolce. No, non \u00e8 la tipica ragazza della porta accanto che pu\u00f2 far girare la testa,","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/scoperta-nuova-specie-di-scimmia-docile-e-dallo-sguardo-umano\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/scoperta-nuova-specie-di-scimmia-docile-e-dallo-sguardo-umano\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/scoperta-nuova-specie-di-scimmia-docile-e-dallo-sguardo-umano\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/09\/images.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/09\/images.jpg","width":"219","height":"230","caption":"Lesula"},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/scoperta-nuova-specie-di-scimmia-docile-e-dallo-sguardo-umano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/"},{"@type":"ListItem","position":2,"name":"Scoperta nuova specie di scimmia. Docile e dallo sguardo umano!"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/","name":"Quattro zampe e dintorni","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce","name":"Monica Genovese","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","caption":"Monica Genovese"},"sameAs":["https:\/\/x.com\/Monica_Genovese"],"url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/author\/monica-genovese\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/comments?post=508"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/508\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media\/509"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media?parent=508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/categories?post=508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/tags?post=508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}