{"id":494,"date":"2012-08-07T06:06:13","date_gmt":"2012-08-07T06:06:13","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/?p=494"},"modified":"2012-08-03T09:10:33","modified_gmt":"2012-08-03T09:10:33","slug":"animali-in-vacanza-dove-e-come-portarli-con-tutta-la-famiglia","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/animali-in-vacanza-dove-e-come-portarli-con-tutta-la-famiglia\/","title":{"rendered":"Animali in vacanza. Dove e come portarli con tutta la famiglia"},"content":{"rendered":"<p><a href=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/08\/Vacanze-Cani-18_352-288.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-thumbnail wp-image-496\" title=\"Dog Beachcredits actiondog.it\" src=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/08\/Vacanze-Cani-18_352-288-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>Pronti per le vacanze? E Fido, dove lo lasciate? Se siete tra i fortunati che viaggiano con i propri animali al seguito e desiderate una vacanza comoda per tutta la famiglia, membri pelosi compresi, allora vi pu\u00f2 essere utile scoprire, a priori, quali strutture ricettive italiane ospitino anche i 4 zampe. Il portale di \u201cAnimali in vacanza\u201d (<a href=\"http:\/\/www.animali-in-vacanza.com\/index.asp\">http:\/\/www.animali-in-vacanza.com\/index.asp<\/a>) fa al caso vostro. Si tratta di un sito internet turistico, tradotto in pi\u00f9 lingue, dedicato alle sole location, b&amp;b, alberghi, dimore storiche, affittacamere, appartamenti, ville, campeggi, agriturismi che annoverano tra i propri frequentatori anche gli animali.<!--more-->C\u2019\u00e8 una sezione dedicata a contenuti a protezione, prevenzione e difesa degli animali, ma anche un utile form tramite il quale, inserendo regione, provincia o citt\u00e0 nella quale desiderate trascorrere il vostro tempo, potete valutare gli alberghi a portata di zampa. Un network che offre visibilit\u00e0, sia a canili, oasi, rifugi, sia all\u2019ospitalit\u00e0 vacanziera anche con offerte last minute, suggerimenti di itinerari, eventi e offerte speciali.<\/p>\n<p>Utili suggerimenti anche per i viaggiatori inesperti, magari alla prima vacanza con il loro cane. Nella pagina \u201cPianificare la vacanza\u201d, infatti si possono trovare consigli pratici per una perfetta organizzazione in considerazione delle esigenze di tutti, sia che il cane sia adulto, sia cucciolo. Non resta che partire e godersi il sospirato mese di agosto!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pronti per le vacanze? E Fido, dove lo lasciate? Se siete tra i fortunati che viaggiano con i propri animali al seguito e desiderate una vacanza comoda per tutta la famiglia, membri pelosi compresi, allora vi pu\u00f2 essere utile scoprire, a priori, quali strutture ricettive italiane ospitino anche i 4 zampe. Il portale di \u201cAnimali &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/animali-in-vacanza-dove-e-come-portarli-con-tutta-la-famiglia\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Animali in vacanza. Dove e come portarli con tutta la famiglia&#8221;<\/span><\/a><\/p>\n","protected":false},"author":46,"featured_media":496,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[368,366,364,21,369,168,26,22,365,367],"class_list":["post-494","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-quattro-zampe","tag-agosto","tag-animal-free","tag-animali-in-vacanza","tag-cani","tag-cucciolo","tag-estate","tag-fido","tag-gatti","tag-sito","tag-vacanze"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Animali in vacanza. Dove e come portarli con tutta la famiglia - Quattro zampe e dintorni<\/title>\n<meta name=\"description\" content=\"Pronti per le vacanze? E Fido, dove lo lasciate? Se siete tra i fortunati che viaggiano con i propri animali al seguito e desiderate una vacanza comoda\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/animali-in-vacanza-dove-e-come-portarli-con-tutta-la-famiglia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Animali in vacanza. Dove e come portarli con tutta la famiglia - Quattro zampe e dintorni\" \/>\n<meta property=\"og:description\" content=\"Pronti per le vacanze? E Fido, dove lo lasciate? Se siete tra i fortunati che viaggiano con i propri animali al seguito e desiderate una vacanza comoda\" \/>\n<meta property=\"og:url\" content=\"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/animali-in-vacanza-dove-e-come-portarli-con-tutta-la-famiglia\/\" \/>\n<meta property=\"og:site_name\" content=\"Quattro zampe e dintorni\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2012-08-07T06:06:13+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/08\/Vacanze-Cani-18_352-288.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"352\" \/>\n\t<meta property=\"og:image:height\" content=\"288\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Monica Genovese\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Monica Genovese\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/animali-in-vacanza-dove-e-come-portarli-con-tutta-la-famiglia\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/animali-in-vacanza-dove-e-come-portarli-con-tutta-la-famiglia\\\/\"},\"author\":{\"name\":\"Monica Genovese\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\"},\"headline\":\"Animali in vacanza. Dove e come portarli con tutta la famiglia\",\"datePublished\":\"2012-08-07T06:06:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/animali-in-vacanza-dove-e-come-portarli-con-tutta-la-famiglia\\\/\"},\"wordCount\":234,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/animali-in-vacanza-dove-e-come-portarli-con-tutta-la-famiglia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2012\\\/08\\\/Vacanze-Cani-18_352-288.jpg\",\"keywords\":[\"agosto\",\"animal free\",\"Animali in vacanza\",\"cani\",\"cucciolo\",\"estate\",\"fido\",\"gatti\",\"sito\",\"vacanze\"],\"articleSection\":[\"Quattro zampe\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/animali-in-vacanza-dove-e-come-portarli-con-tutta-la-famiglia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/animali-in-vacanza-dove-e-come-portarli-con-tutta-la-famiglia\\\/\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/animali-in-vacanza-dove-e-come-portarli-con-tutta-la-famiglia\\\/\",\"name\":\"Animali in vacanza. Dove e come portarli con tutta la famiglia - Quattro zampe e dintorni\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/animali-in-vacanza-dove-e-come-portarli-con-tutta-la-famiglia\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/animali-in-vacanza-dove-e-come-portarli-con-tutta-la-famiglia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2012\\\/08\\\/Vacanze-Cani-18_352-288.jpg\",\"datePublished\":\"2012-08-07T06:06:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\"},\"description\":\"Pronti per le vacanze? E Fido, dove lo lasciate? Se siete tra i fortunati che viaggiano con i propri animali al seguito e desiderate una vacanza comoda\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/animali-in-vacanza-dove-e-come-portarli-con-tutta-la-famiglia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/animali-in-vacanza-dove-e-come-portarli-con-tutta-la-famiglia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/animali-in-vacanza-dove-e-come-portarli-con-tutta-la-famiglia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2012\\\/08\\\/Vacanze-Cani-18_352-288.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2012\\\/08\\\/Vacanze-Cani-18_352-288.jpg\",\"width\":\"352\",\"height\":\"288\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/animali-in-vacanza-dove-e-come-portarli-con-tutta-la-famiglia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Animali in vacanza. Dove e come portarli con tutta la famiglia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\",\"name\":\"Quattro zampe e dintorni\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\",\"name\":\"Monica Genovese\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"caption\":\"Monica Genovese\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Monica_Genovese\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/author\\\/monica-genovese\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Animali in vacanza. Dove e come portarli con tutta la famiglia - Quattro zampe e dintorni","description":"Pronti per le vacanze? E Fido, dove lo lasciate? Se siete tra i fortunati che viaggiano con i propri animali al seguito e desiderate una vacanza comoda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/animali-in-vacanza-dove-e-come-portarli-con-tutta-la-famiglia\/","og_locale":"it_IT","og_type":"article","og_title":"Animali in vacanza. Dove e come portarli con tutta la famiglia - Quattro zampe e dintorni","og_description":"Pronti per le vacanze? E Fido, dove lo lasciate? Se siete tra i fortunati che viaggiano con i propri animali al seguito e desiderate una vacanza comoda","og_url":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/animali-in-vacanza-dove-e-come-portarli-con-tutta-la-famiglia\/","og_site_name":"Quattro zampe e dintorni","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2012-08-07T06:06:13+00:00","og_image":[{"width":352,"height":288,"url":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/08\/Vacanze-Cani-18_352-288.jpg","type":"image\/jpeg"}],"author":"Monica Genovese","twitter_misc":{"Scritto da":"Monica Genovese","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/animali-in-vacanza-dove-e-come-portarli-con-tutta-la-famiglia\/#article","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/animali-in-vacanza-dove-e-come-portarli-con-tutta-la-famiglia\/"},"author":{"name":"Monica Genovese","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce"},"headline":"Animali in vacanza. Dove e come portarli con tutta la famiglia","datePublished":"2012-08-07T06:06:13+00:00","mainEntityOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/animali-in-vacanza-dove-e-come-portarli-con-tutta-la-famiglia\/"},"wordCount":234,"commentCount":0,"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/animali-in-vacanza-dove-e-come-portarli-con-tutta-la-famiglia\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/08\/Vacanze-Cani-18_352-288.jpg","keywords":["agosto","animal free","Animali in vacanza","cani","cucciolo","estate","fido","gatti","sito","vacanze"],"articleSection":["Quattro zampe"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/animali-in-vacanza-dove-e-come-portarli-con-tutta-la-famiglia\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/animali-in-vacanza-dove-e-come-portarli-con-tutta-la-famiglia\/","url":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/animali-in-vacanza-dove-e-come-portarli-con-tutta-la-famiglia\/","name":"Animali in vacanza. Dove e come portarli con tutta la famiglia - Quattro zampe e dintorni","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website"},"primaryImageOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/animali-in-vacanza-dove-e-come-portarli-con-tutta-la-famiglia\/#primaryimage"},"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/animali-in-vacanza-dove-e-come-portarli-con-tutta-la-famiglia\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/08\/Vacanze-Cani-18_352-288.jpg","datePublished":"2012-08-07T06:06:13+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce"},"description":"Pronti per le vacanze? E Fido, dove lo lasciate? Se siete tra i fortunati che viaggiano con i propri animali al seguito e desiderate una vacanza comoda","breadcrumb":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/animali-in-vacanza-dove-e-come-portarli-con-tutta-la-famiglia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/animali-in-vacanza-dove-e-come-portarli-con-tutta-la-famiglia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/animali-in-vacanza-dove-e-come-portarli-con-tutta-la-famiglia\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/08\/Vacanze-Cani-18_352-288.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/08\/Vacanze-Cani-18_352-288.jpg","width":"352","height":"288"},{"@type":"BreadcrumbList","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/animali-in-vacanza-dove-e-come-portarli-con-tutta-la-famiglia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/"},{"@type":"ListItem","position":2,"name":"Animali in vacanza. Dove e come portarli con tutta la famiglia"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/","name":"Quattro zampe e dintorni","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce","name":"Monica Genovese","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","caption":"Monica Genovese"},"sameAs":["https:\/\/x.com\/Monica_Genovese"],"url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/author\/monica-genovese\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/comments?post=494"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/494\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media\/496"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media?parent=494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/categories?post=494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/tags?post=494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}