{"id":487,"date":"2012-09-09T06:00:56","date_gmt":"2012-09-09T06:00:56","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/?p=487"},"modified":"2012-07-25T08:53:39","modified_gmt":"2012-07-25T08:53:39","slug":"spopola-la-cow-poop-ovvero-la-mucca-da-cacca","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/spopola-la-cow-poop-ovvero-la-mucca-da-cacca\/","title":{"rendered":"Spopola la &#8220;Cow poop&#8221;, ovvero la mucca da cacca!"},"content":{"rendered":"<figure id=\"attachment_488\" aria-describedby=\"caption-attachment-488\" style=\"width: 300px\" class=\"wp-caption alignright\"><a href=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/07\/mucca_cagona.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-488\" title=\"mucca_cagona\" src=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/07\/mucca_cagona-300x213.jpg\" alt=\"\" width=\"300\" height=\"213\" srcset=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/07\/mucca_cagona-300x213.jpg 300w, https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/07\/mucca_cagona-1024x727.jpg 1024w, https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/07\/mucca_cagona.jpg 1533w\" sizes=\"auto, (max-width: 300px) 85vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-488\" class=\"wp-caption-text\">Cow poop della Farm Serenity Cow<\/figcaption><\/figure>\n<p>Si chiama &#8220;Cow poop&#8221; ed \u00e8 il primo allevamento in Piemonte, a Cavour, nella zona di Torino, di mucche da cacca! Proprio cos\u00ec. L&#8217;iniziativa, lodevole sotto molti aspetti, \u00e8 di una giovane coppia desiderosa di una vita pi\u00f9 sana e a stretto contatto con la natura, rispettosa di questa, dei suoi ritmi e in pieno accordo con la vita altrui, quella animale. In che modo realizzare tale progetto? Con la creazione di una nuova realt\u00e0 agricola che consenta di allevare gli \u201canimali da fattoria\u201d traendo risorse dalla loro vita anzich\u00e9 dalla loro morte e reinvestendo quanto ottenuto nelle attivit\u00e0 di coltivazione del terreno, insomma invece di macellare le mucche, usarle per il loro letame con cui concimare le coltivazioni. <!--more-->Un rapporto di collaborazione professionale uomo-animale. Paritario! Ed ecco che nasce la Farm Serenity \u201cCaud\u201d dove mucche e cavalli, che nel corso degli anni i due agricoltori hanno salvato dal macello, garantiscono la disponibilit\u00e0 del letame che viene utilizzato una volta \u201cmaturo\u201d per arricchire i terreni adibiti alla coltivazione di ortaggi e frutta prodotti come natura vuole. Un percorso non facile, ma che alla lunga rende, sia in termini economici, sia in termini salutistici.<\/p>\n<p>La cow-poop \u00e8 una mucca da cacca, ovvero un animale allevato unicamente per la produzione del letame che non \u00e8 sottoposto a fecondazione e quindi non partorisce vitelli o produce latte. Il suo lavoro \u00e8&#8230; defecare e, a quanto pare ci riesce anche bene! La mucca di razza piemontese, nota per le sue carni gustose, \u00e8 un animale docile le cui origini sono molto antiche. Si stima che risalgano a 25mila anni fa quando alcuni esemplari di Aurochs (bovini di epoca giurassica) si incrociarono con Zeb\u00f9 di provenienza eurasiatica.<\/p>\n<p>Nei secoli, questo nobile animale ha servito i contadini del Piemonte lavorando accanto a loro finendo, poi nel piatto come fonte di cibo, ma sebbenea piccoli passi, la rivoluzione antispecista \u00e8 gi\u00e0 in atto. La mucca continua a lavorare, come molti altri animali, per l&#8217;uomo, ma in cambio ottiene una vita serena e un ciaciglio comodo. In breve, un dare e avere.<\/p>\n<p>Il &#8220;cinguettio sociale&#8221; attorno alla Cow poop viaggia on line, sui forum, sui social network e sempre pi\u00f9 persone apprezzano questo stile di vita, desiderando condividerlo o, almeno avvicinarsi e pre farlo imetodo sono semplici. Basta anche solo &#8220;noleggiare&#8221; a tempo determinato un animale della fattoria, ad esempio la maialina Lady. Gli usi sono molteplici e la compagnia garantita.<\/p>\n<p>Info: 333 5241264; <a href=\"mailto:shadow.horse@hotmail.it\">shadow.horse@hotmail.it<\/a>; http:\/\/farmserenitycow.blogspot.it\/<\/p>\n<div><\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si chiama &#8220;Cow poop&#8221; ed \u00e8 il primo allevamento in Piemonte, a Cavour, nella zona di Torino, di mucche da cacca! Proprio cos\u00ec. L&#8217;iniziativa, lodevole sotto molti aspetti, \u00e8 di una giovane coppia desiderosa di una vita pi\u00f9 sana e a stretto contatto con la natura, rispettosa di questa, dei suoi ritmi e in pieno &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/spopola-la-cow-poop-ovvero-la-mucca-da-cacca\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Spopola la &#8220;Cow poop&#8221;, ovvero la mucca da cacca!&#8221;<\/span><\/a><\/p>\n","protected":false},"author":46,"featured_media":488,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[18,360,361,363,362,69,132],"class_list":["post-487","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-quattro-zampe","tag-animali","tag-cow-poop","tag-farm-serenity-cow","tag-fattoria","tag-letame","tag-mucca","tag-torino"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Spopola la &quot;Cow poop&quot;, ovvero la mucca da cacca! - Quattro zampe e dintorni<\/title>\n<meta name=\"description\" content=\"Si chiama &quot;Cow poop&quot; ed \u00e8 il primo allevamento in Piemonte, a Cavour, nella zona di Torino, di mucche da cacca! Proprio cos\u00ec. L&#039;iniziativa, lodevole sotto\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/spopola-la-cow-poop-ovvero-la-mucca-da-cacca\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spopola la &quot;Cow poop&quot;, ovvero la mucca da cacca! - Quattro zampe e dintorni\" \/>\n<meta property=\"og:description\" content=\"Si chiama &quot;Cow poop&quot; ed \u00e8 il primo allevamento in Piemonte, a Cavour, nella zona di Torino, di mucche da cacca! Proprio cos\u00ec. L&#039;iniziativa, lodevole sotto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/spopola-la-cow-poop-ovvero-la-mucca-da-cacca\/\" \/>\n<meta property=\"og:site_name\" content=\"Quattro zampe e dintorni\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2012-09-09T06:00:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/07\/mucca_cagona.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1533\" \/>\n\t<meta property=\"og:image:height\" content=\"1089\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Monica Genovese\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Monica Genovese\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/spopola-la-cow-poop-ovvero-la-mucca-da-cacca\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/spopola-la-cow-poop-ovvero-la-mucca-da-cacca\\\/\"},\"author\":{\"name\":\"Monica Genovese\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\"},\"headline\":\"Spopola la &#8220;Cow poop&#8221;, ovvero la mucca da cacca!\",\"datePublished\":\"2012-09-09T06:00:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/spopola-la-cow-poop-ovvero-la-mucca-da-cacca\\\/\"},\"wordCount\":430,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/spopola-la-cow-poop-ovvero-la-mucca-da-cacca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2012\\\/07\\\/mucca_cagona.jpg\",\"keywords\":[\"animali\",\"cow poop\",\"farm serenity cow\",\"fattoria\",\"letame\",\"mucca\",\"Torino\"],\"articleSection\":[\"Quattro zampe\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/spopola-la-cow-poop-ovvero-la-mucca-da-cacca\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/spopola-la-cow-poop-ovvero-la-mucca-da-cacca\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/spopola-la-cow-poop-ovvero-la-mucca-da-cacca\\\/\",\"name\":\"Spopola la \\\"Cow poop\\\", ovvero la mucca da cacca! - Quattro zampe e dintorni\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/spopola-la-cow-poop-ovvero-la-mucca-da-cacca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/spopola-la-cow-poop-ovvero-la-mucca-da-cacca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2012\\\/07\\\/mucca_cagona.jpg\",\"datePublished\":\"2012-09-09T06:00:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\"},\"description\":\"Si chiama \\\"Cow poop\\\" ed \u00e8 il primo allevamento in Piemonte, a Cavour, nella zona di Torino, di mucche da cacca! Proprio cos\u00ec. L'iniziativa, lodevole sotto\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/spopola-la-cow-poop-ovvero-la-mucca-da-cacca\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/spopola-la-cow-poop-ovvero-la-mucca-da-cacca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/spopola-la-cow-poop-ovvero-la-mucca-da-cacca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2012\\\/07\\\/mucca_cagona.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2012\\\/07\\\/mucca_cagona.jpg\",\"width\":\"1533\",\"height\":\"1089\",\"caption\":\"Cow poop della Farm Serenity Cow\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/spopola-la-cow-poop-ovvero-la-mucca-da-cacca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Spopola la &#8220;Cow poop&#8221;, ovvero la mucca da cacca!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\",\"name\":\"Quattro zampe e dintorni\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\",\"name\":\"Monica Genovese\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"caption\":\"Monica Genovese\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Monica_Genovese\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/author\\\/monica-genovese\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Spopola la \"Cow poop\", ovvero la mucca da cacca! - Quattro zampe e dintorni","description":"Si chiama \"Cow poop\" ed \u00e8 il primo allevamento in Piemonte, a Cavour, nella zona di Torino, di mucche da cacca! Proprio cos\u00ec. L'iniziativa, lodevole sotto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/spopola-la-cow-poop-ovvero-la-mucca-da-cacca\/","og_locale":"it_IT","og_type":"article","og_title":"Spopola la \"Cow poop\", ovvero la mucca da cacca! - Quattro zampe e dintorni","og_description":"Si chiama \"Cow poop\" ed \u00e8 il primo allevamento in Piemonte, a Cavour, nella zona di Torino, di mucche da cacca! Proprio cos\u00ec. L'iniziativa, lodevole sotto","og_url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/spopola-la-cow-poop-ovvero-la-mucca-da-cacca\/","og_site_name":"Quattro zampe e dintorni","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2012-09-09T06:00:56+00:00","og_image":[{"width":1533,"height":1089,"url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/07\/mucca_cagona.jpg","type":"image\/jpeg"}],"author":"Monica Genovese","twitter_misc":{"Scritto da":"Monica Genovese","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/spopola-la-cow-poop-ovvero-la-mucca-da-cacca\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/spopola-la-cow-poop-ovvero-la-mucca-da-cacca\/"},"author":{"name":"Monica Genovese","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce"},"headline":"Spopola la &#8220;Cow poop&#8221;, ovvero la mucca da cacca!","datePublished":"2012-09-09T06:00:56+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/spopola-la-cow-poop-ovvero-la-mucca-da-cacca\/"},"wordCount":430,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/spopola-la-cow-poop-ovvero-la-mucca-da-cacca\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/07\/mucca_cagona.jpg","keywords":["animali","cow poop","farm serenity cow","fattoria","letame","mucca","Torino"],"articleSection":["Quattro zampe"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/spopola-la-cow-poop-ovvero-la-mucca-da-cacca\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/spopola-la-cow-poop-ovvero-la-mucca-da-cacca\/","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/spopola-la-cow-poop-ovvero-la-mucca-da-cacca\/","name":"Spopola la \"Cow poop\", ovvero la mucca da cacca! - Quattro zampe e dintorni","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/spopola-la-cow-poop-ovvero-la-mucca-da-cacca\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/spopola-la-cow-poop-ovvero-la-mucca-da-cacca\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/07\/mucca_cagona.jpg","datePublished":"2012-09-09T06:00:56+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce"},"description":"Si chiama \"Cow poop\" ed \u00e8 il primo allevamento in Piemonte, a Cavour, nella zona di Torino, di mucche da cacca! Proprio cos\u00ec. L'iniziativa, lodevole sotto","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/spopola-la-cow-poop-ovvero-la-mucca-da-cacca\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/spopola-la-cow-poop-ovvero-la-mucca-da-cacca\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/spopola-la-cow-poop-ovvero-la-mucca-da-cacca\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/07\/mucca_cagona.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/07\/mucca_cagona.jpg","width":"1533","height":"1089","caption":"Cow poop della Farm Serenity Cow"},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/spopola-la-cow-poop-ovvero-la-mucca-da-cacca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/"},{"@type":"ListItem","position":2,"name":"Spopola la &#8220;Cow poop&#8221;, ovvero la mucca da cacca!"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/","name":"Quattro zampe e dintorni","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce","name":"Monica Genovese","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","caption":"Monica Genovese"},"sameAs":["https:\/\/x.com\/Monica_Genovese"],"url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/author\/monica-genovese\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/comments?post=487"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/487\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media\/488"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media?parent=487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/categories?post=487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/tags?post=487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}