{"id":286,"date":"2012-04-24T14:00:28","date_gmt":"2012-04-24T14:00:28","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/?p=286"},"modified":"2012-04-24T14:00:28","modified_gmt":"2012-04-24T14:00:28","slug":"tra-fido-e-felix-chi-vince-in-intelligenza-e-addestramento","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/tra-fido-e-felix-chi-vince-in-intelligenza-e-addestramento\/","title":{"rendered":"Tra Fido e Felix chi vince in intelligenza e addestramento?"},"content":{"rendered":"<p><a href=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/04\/baffi-gatti.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-thumbnail wp-image-287\" src=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/04\/baffi-gatti-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>E\u2019 finita. Pare sia propria giunta ad una soluzione l\u2019ancestrale diatriba tra cane e gatto su chi ce l\u2019ha pi\u00f9 alto. Il quoziente intellettivo! Non so se avremmo potuto ancora vivere senza questa novit\u00e0, ma visto che la scienza ci fornisce la risposta, allora parliamone. Ad esser pi\u00f9 intelligente di quanto si pensava fino ad oggi \u00e8 il nostro amico felino.<\/p>\n<p>Felix 1 e Fido 0. Loro due, credo proprio, che non siamo interessati alla discussione, ma i bipedi, divisi tra \u201cgattari\u201d e cinofili forse lo sono. Una recente ricerca ha stabilito che il cervello dei gatti \u00e8 simile, in quanto a struttura e funzione, a quello umano e che il gatto supera il cane in capacit\u00e0 di dialogo con il padrone e addestrabilit\u00e0.<\/p>\n<p>Insomma, se Felix fa i capricci, \u00e8 disobbediente e poco educato, non \u00e8 colpa sua, ma nostra che non siamo in grado di educarlo.<!--more--><\/p>\n<p>Il settimanale scientifico inglese New Scientist ha fatto i cosiddetti conti della serva, tirando le somme delle pi\u00f9 disparate ricerche ed esperimenti condotti negli anni su cani e gatti. Questi hanno entrambi un cervello complesso e ben sviluppato, capace di pensieri, ragionamenti, aspettative, desideri anche se non li possono esprimere verbalmente. E\u2019 vero che il cervello felino \u00e8 pi\u00f9 piccolo rispetto a quello canino, ma presenta il doppio dei neuroni, ovvero maggior capacit\u00e0 di processare le informazioni.<\/p>\n<p>E\u2019 proprio il caso di dire che le dimensioni non sono tutto! Anche in materia di olfatto, il gatto ha molto da insegnare, o meglio da annusare, infatti pare che i 200 milioni di recettori olfattivi presenti in media nei felini, a seconda della razza, siano in numero pi\u00f9 elevato dei ricettori dell\u2019amico Fido.<\/p>\n<p>Inoltre, pare che il classico \u201cron ron\u201d dei gatti, le fusa, cio\u00e8 quelle sottili vibrazioni che emette, per quanto ancora in parte misteriose per noi, abbiano un potere curativo, calmante per gli uomini e il loro umore quando si accarezza il piccolo peloso.<\/p>\n<p>Il fatto che la scienza dimostri, ogni giorno di pi\u00f9, quanto siano simili tra loro uomini e animali (almeno alcuni) dovrebbe sensibilizzare la civile (?) razza umana a rispettare ambiente, natura e mondo animale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>E\u2019 finita. Pare sia propria giunta ad una soluzione l\u2019ancestrale diatriba tra cane e gatto su chi ce l\u2019ha pi\u00f9 alto. Il quoziente intellettivo! Non so se avremmo potuto ancora vivere senza questa novit\u00e0, ma visto che la scienza ci fornisce la risposta, allora parliamone. Ad esser pi\u00f9 intelligente di quanto si pensava fino ad &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/tra-fido-e-felix-chi-vince-in-intelligenza-e-addestramento\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Tra Fido e Felix chi vince in intelligenza e addestramento?&#8221;<\/span><\/a><\/p>\n","protected":false},"author":46,"featured_media":287,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[21,27,26,22,190,189,192,191],"class_list":["post-286","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-quattro-zampe","tag-cani","tag-felix","tag-fido","tag-gatti","tag-intelligenza","tag-new-scientis","tag-ricerca-scientifica","tag-uomini"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tra Fido e Felix chi vince in intelligenza e addestramento? - Quattro zampe e dintorni<\/title>\n<meta name=\"description\" content=\"E\u2019 finita. Pare sia propria giunta ad una soluzione l\u2019ancestrale diatriba tra cane e gatto su chi ce l\u2019ha pi\u00f9 alto. Il quoziente intellettivo! Non so se\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/tra-fido-e-felix-chi-vince-in-intelligenza-e-addestramento\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tra Fido e Felix chi vince in intelligenza e addestramento? - Quattro zampe e dintorni\" \/>\n<meta property=\"og:description\" content=\"E\u2019 finita. Pare sia propria giunta ad una soluzione l\u2019ancestrale diatriba tra cane e gatto su chi ce l\u2019ha pi\u00f9 alto. Il quoziente intellettivo! Non so se\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/tra-fido-e-felix-chi-vince-in-intelligenza-e-addestramento\/\" \/>\n<meta property=\"og:site_name\" content=\"Quattro zampe e dintorni\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2012-04-24T14:00:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/04\/baffi-gatti.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1152\" \/>\n\t<meta property=\"og:image:height\" content=\"864\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Monica Genovese\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Monica Genovese\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/tra-fido-e-felix-chi-vince-in-intelligenza-e-addestramento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/tra-fido-e-felix-chi-vince-in-intelligenza-e-addestramento\\\/\"},\"author\":{\"name\":\"Monica Genovese\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\"},\"headline\":\"Tra Fido e Felix chi vince in intelligenza e addestramento?\",\"datePublished\":\"2012-04-24T14:00:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/tra-fido-e-felix-chi-vince-in-intelligenza-e-addestramento\\\/\"},\"wordCount\":360,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/tra-fido-e-felix-chi-vince-in-intelligenza-e-addestramento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2012\\\/04\\\/baffi-gatti.jpg\",\"keywords\":[\"cani\",\"felix\",\"fido\",\"gatti\",\"intelligenza\",\"New Scientis\",\"ricerca scientifica\",\"uomini\"],\"articleSection\":[\"Quattro zampe\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/tra-fido-e-felix-chi-vince-in-intelligenza-e-addestramento\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/tra-fido-e-felix-chi-vince-in-intelligenza-e-addestramento\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/tra-fido-e-felix-chi-vince-in-intelligenza-e-addestramento\\\/\",\"name\":\"Tra Fido e Felix chi vince in intelligenza e addestramento? - Quattro zampe e dintorni\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/tra-fido-e-felix-chi-vince-in-intelligenza-e-addestramento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/tra-fido-e-felix-chi-vince-in-intelligenza-e-addestramento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2012\\\/04\\\/baffi-gatti.jpg\",\"datePublished\":\"2012-04-24T14:00:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\"},\"description\":\"E\u2019 finita. Pare sia propria giunta ad una soluzione l\u2019ancestrale diatriba tra cane e gatto su chi ce l\u2019ha pi\u00f9 alto. Il quoziente intellettivo! Non so se\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/tra-fido-e-felix-chi-vince-in-intelligenza-e-addestramento\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/tra-fido-e-felix-chi-vince-in-intelligenza-e-addestramento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/tra-fido-e-felix-chi-vince-in-intelligenza-e-addestramento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2012\\\/04\\\/baffi-gatti.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2012\\\/04\\\/baffi-gatti.jpg\",\"width\":\"1152\",\"height\":\"864\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/tra-fido-e-felix-chi-vince-in-intelligenza-e-addestramento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tra Fido e Felix chi vince in intelligenza e addestramento?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\",\"name\":\"Quattro zampe e dintorni\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\",\"name\":\"Monica Genovese\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"caption\":\"Monica Genovese\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Monica_Genovese\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/author\\\/monica-genovese\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tra Fido e Felix chi vince in intelligenza e addestramento? - Quattro zampe e dintorni","description":"E\u2019 finita. Pare sia propria giunta ad una soluzione l\u2019ancestrale diatriba tra cane e gatto su chi ce l\u2019ha pi\u00f9 alto. Il quoziente intellettivo! Non so se","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/tra-fido-e-felix-chi-vince-in-intelligenza-e-addestramento\/","og_locale":"it_IT","og_type":"article","og_title":"Tra Fido e Felix chi vince in intelligenza e addestramento? - Quattro zampe e dintorni","og_description":"E\u2019 finita. Pare sia propria giunta ad una soluzione l\u2019ancestrale diatriba tra cane e gatto su chi ce l\u2019ha pi\u00f9 alto. Il quoziente intellettivo! Non so se","og_url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/tra-fido-e-felix-chi-vince-in-intelligenza-e-addestramento\/","og_site_name":"Quattro zampe e dintorni","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2012-04-24T14:00:28+00:00","og_image":[{"width":1152,"height":864,"url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/04\/baffi-gatti.jpg","type":"image\/jpeg"}],"author":"Monica Genovese","twitter_misc":{"Scritto da":"Monica Genovese","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/tra-fido-e-felix-chi-vince-in-intelligenza-e-addestramento\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/tra-fido-e-felix-chi-vince-in-intelligenza-e-addestramento\/"},"author":{"name":"Monica Genovese","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce"},"headline":"Tra Fido e Felix chi vince in intelligenza e addestramento?","datePublished":"2012-04-24T14:00:28+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/tra-fido-e-felix-chi-vince-in-intelligenza-e-addestramento\/"},"wordCount":360,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/tra-fido-e-felix-chi-vince-in-intelligenza-e-addestramento\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/04\/baffi-gatti.jpg","keywords":["cani","felix","fido","gatti","intelligenza","New Scientis","ricerca scientifica","uomini"],"articleSection":["Quattro zampe"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/tra-fido-e-felix-chi-vince-in-intelligenza-e-addestramento\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/tra-fido-e-felix-chi-vince-in-intelligenza-e-addestramento\/","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/tra-fido-e-felix-chi-vince-in-intelligenza-e-addestramento\/","name":"Tra Fido e Felix chi vince in intelligenza e addestramento? - Quattro zampe e dintorni","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/tra-fido-e-felix-chi-vince-in-intelligenza-e-addestramento\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/tra-fido-e-felix-chi-vince-in-intelligenza-e-addestramento\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/04\/baffi-gatti.jpg","datePublished":"2012-04-24T14:00:28+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce"},"description":"E\u2019 finita. Pare sia propria giunta ad una soluzione l\u2019ancestrale diatriba tra cane e gatto su chi ce l\u2019ha pi\u00f9 alto. Il quoziente intellettivo! Non so se","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/tra-fido-e-felix-chi-vince-in-intelligenza-e-addestramento\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/tra-fido-e-felix-chi-vince-in-intelligenza-e-addestramento\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/tra-fido-e-felix-chi-vince-in-intelligenza-e-addestramento\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/04\/baffi-gatti.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/04\/baffi-gatti.jpg","width":"1152","height":"864"},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/tra-fido-e-felix-chi-vince-in-intelligenza-e-addestramento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/"},{"@type":"ListItem","position":2,"name":"Tra Fido e Felix chi vince in intelligenza e addestramento?"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/","name":"Quattro zampe e dintorni","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce","name":"Monica Genovese","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","caption":"Monica Genovese"},"sameAs":["https:\/\/x.com\/Monica_Genovese"],"url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/author\/monica-genovese\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/comments?post=286"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/286\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media\/287"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media?parent=286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/categories?post=286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/tags?post=286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}