{"id":272,"date":"2012-04-19T10:19:03","date_gmt":"2012-04-19T10:19:03","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/?p=272"},"modified":"2012-04-23T11:39:44","modified_gmt":"2012-04-23T11:39:44","slug":"sindaci-ditalia-proprietari-dei-cani-abbandonati-nei-loro-comuni","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/sindaci-ditalia-proprietari-dei-cani-abbandonati-nei-loro-comuni\/","title":{"rendered":"Sindaci d&#8217;Italia proprietari dei cani abbandonati nei loro Comuni"},"content":{"rendered":"<p><a href=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/04\/1272014926_cane_randagio_occhi_tristi.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-thumbnail wp-image-278\" src=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/04\/1272014926_cane_randagio_occhi_tristi-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>Un cane abbandonato e randagio in un determinato Comune \u00e8 di propriet\u00e0 del sindaco di quel Comune. La <strong>legge 281\/91<\/strong> per la tutela e il benessere animale, contenuta nella L.R. 16\/2006 e nel successivo Regolamento di attuazione, stabilisce che il sindaco \u00e8 tenuto a garantire il benessere dell&#8217;animale accalappiato nel suo Comune. Il primo cittadino, quindi DEVE tutelare il cane in qualche modo, anche affidandolo ad una struttura di accoglienza, ad un canile convenzionato accertandosi delle condizioni in cui versi il canile stesso.<\/p>\n<p>Pena, nel caso non lo faccia, la possibile imputazione penale per omissione di atti d&#8217;ufficio e maltrattamento. Detto questo, <strong>Chiliamacisegua<\/strong>, neo associazione di volontari animalisti, suportata da avvocati civilisti e penalisti, ha recentemente chiesto ai sindaci del Bel Paese l&#8217;applicazione di tale legge a cui nessun primo cittadino deve sfuggire.<!--more-->Che sia necessaria una legge del genere per obbligare le persone a prendersi cura degli animali \u00e8 gi\u00e0 vergognoso, soprattutto in una Italia che si definisce civile e di buon senso, ma visto che la situazione sta cos\u00ec e che, a quanto pare, siamo un popolo poco evoluto da questo punto di vista, che legge sia, ma soprattutto che applicazione della legge sia!<\/p>\n<p>Di canili lager la bella penisola \u00e8 tristemente piena, ragion per cui \u00e8 ora (ma non lo \u00e8 solo a adesso, gi\u00e0 da sempre) di dire basta a gran voce e Chiliamacisegua scrive, nella propria richiesta, la pretesa dell&#8217;applicazione di tale legge. Anche perch\u00e9 che senso ha elaborare leggi senza applicarle nel quotidiano?<\/p>\n<p>Purtroppo il giro d&#8217;affari che ruota attorno al randagismo, ai canili privati e pubblici, che ricevono sovvenzioni statali per il mantenimento dei cani \u00e8 molto elevato e complesso. Chiliamacisegua stima in 500milioni di euro tale giro.<\/p>\n<p>L&#8217;onorevole veronese <strong>Francesca Martini<\/strong>, assessore alle Politiche Sanitarie della regione Veneto, nonch\u00e9 curatrice, insieme a <strong>Michela Brambilla<\/strong>, ex ministro del Turismo e presidente Leida, lega italiana per la difesa degli animali, dell&#8217;ordinanza sugli standard di benessere degli animali nei canili sta convocando i vari sindaci per fare il punto della situazione Comune per Comune.<\/p>\n<p>Quale fotografia dell&#8217;Italia a 4 zampe verr\u00e0 scattata da questa indagine, \u00e8 ancora da vedere, ma i primi risultati non fanno sperare in termini di civilt\u00e0, umanit\u00e0 e compassione.<\/p>\n<p>Gli uomini, di qualsiasi et\u00e0 ed epoca, purtroppo chiudono gli occhi spesso per non vedere e dimenticano ancor pi\u00f9 spesso. Invece di evolvere verso una societ\u00e0 pi\u00f9 consapevole e rispettosa dei diritti di tutti (indipendetemente dalla specie di appartenenza) si involve a grandi passi e le lezioni che noi dovremmo imparare, viste le esperienze passate, le tragedie, le guerre, le violenze di ieri e di oggi, non insegnano perch\u00e9 non c&#8217;\u00e8 peggior sordo di chi non vuol udire e peggior allievo di chi non vuole imparare!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un cane abbandonato e randagio in un determinato Comune \u00e8 di propriet\u00e0 del sindaco di quel Comune. La legge 281\/91 per la tutela e il benessere animale, contenuta nella L.R. 16\/2006 e nel successivo Regolamento di attuazione, stabilisce che il sindaco \u00e8 tenuto a garantire il benessere dell&#8217;animale accalappiato nel suo Comune. Il primo cittadino, &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/sindaci-ditalia-proprietari-dei-cani-abbandonati-nei-loro-comuni\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Sindaci d&#8217;Italia proprietari dei cani abbandonati nei loro Comuni&#8221;<\/span><\/a><\/p>\n","protected":false},"author":46,"featured_media":280,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[185,18,21,182,180,181,187,186,160,184,183,188],"class_list":["post-272","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-quattro-zampe","tag-accalappiacani","tag-animali","tag-cani","tag-canili","tag-chiliamacisegua","tag-francesca-martini","tag-italia","tag-legge","tag-michela-brambilla","tag-randagi","tag-sindaci","tag-veneto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sindaci d&#039;Italia proprietari dei cani abbandonati nei loro Comuni - Quattro zampe e dintorni<\/title>\n<meta name=\"description\" content=\"Un cane abbandonato e randagio in un determinato Comune \u00e8 di propriet\u00e0 del sindaco di quel Comune. La legge 281\/91 per la tutela e il benessere animale,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/sindaci-ditalia-proprietari-dei-cani-abbandonati-nei-loro-comuni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sindaci d&#039;Italia proprietari dei cani abbandonati nei loro Comuni - Quattro zampe e dintorni\" \/>\n<meta property=\"og:description\" content=\"Un cane abbandonato e randagio in un determinato Comune \u00e8 di propriet\u00e0 del sindaco di quel Comune. La legge 281\/91 per la tutela e il benessere animale,\" \/>\n<meta property=\"og:url\" content=\"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/sindaci-ditalia-proprietari-dei-cani-abbandonati-nei-loro-comuni\/\" \/>\n<meta property=\"og:site_name\" content=\"Quattro zampe e dintorni\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2012-04-19T10:19:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-04-23T11:39:44+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/04\/amicicani_469246981_P1010006.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Monica Genovese\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Monica Genovese\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/sindaci-ditalia-proprietari-dei-cani-abbandonati-nei-loro-comuni\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/sindaci-ditalia-proprietari-dei-cani-abbandonati-nei-loro-comuni\\\/\"},\"author\":{\"name\":\"Monica Genovese\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\"},\"headline\":\"Sindaci d&#8217;Italia proprietari dei cani abbandonati nei loro Comuni\",\"datePublished\":\"2012-04-19T10:19:03+00:00\",\"dateModified\":\"2012-04-23T11:39:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/sindaci-ditalia-proprietari-dei-cani-abbandonati-nei-loro-comuni\\\/\"},\"wordCount\":462,\"commentCount\":3,\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/sindaci-ditalia-proprietari-dei-cani-abbandonati-nei-loro-comuni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2012\\\/04\\\/amicicani_469246981_P1010006.jpg\",\"keywords\":[\"accalappiacani\",\"animali\",\"cani\",\"canili\",\"Chiliamacisegua\",\"Francesca Martini\",\"Italia\",\"legge\",\"Michela Brambilla\",\"randagi\",\"sindaci\",\"Veneto\"],\"articleSection\":[\"Quattro zampe\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/sindaci-ditalia-proprietari-dei-cani-abbandonati-nei-loro-comuni\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/sindaci-ditalia-proprietari-dei-cani-abbandonati-nei-loro-comuni\\\/\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/sindaci-ditalia-proprietari-dei-cani-abbandonati-nei-loro-comuni\\\/\",\"name\":\"Sindaci d'Italia proprietari dei cani abbandonati nei loro Comuni - Quattro zampe e dintorni\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/sindaci-ditalia-proprietari-dei-cani-abbandonati-nei-loro-comuni\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/sindaci-ditalia-proprietari-dei-cani-abbandonati-nei-loro-comuni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2012\\\/04\\\/amicicani_469246981_P1010006.jpg\",\"datePublished\":\"2012-04-19T10:19:03+00:00\",\"dateModified\":\"2012-04-23T11:39:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\"},\"description\":\"Un cane abbandonato e randagio in un determinato Comune \u00e8 di propriet\u00e0 del sindaco di quel Comune. La legge 281\\\/91 per la tutela e il benessere animale,\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/sindaci-ditalia-proprietari-dei-cani-abbandonati-nei-loro-comuni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/sindaci-ditalia-proprietari-dei-cani-abbandonati-nei-loro-comuni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/sindaci-ditalia-proprietari-dei-cani-abbandonati-nei-loro-comuni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2012\\\/04\\\/amicicani_469246981_P1010006.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2012\\\/04\\\/amicicani_469246981_P1010006.jpg\",\"width\":\"600\",\"height\":\"450\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/sindaci-ditalia-proprietari-dei-cani-abbandonati-nei-loro-comuni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sindaci d&#8217;Italia proprietari dei cani abbandonati nei loro Comuni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\",\"name\":\"Quattro zampe e dintorni\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\",\"name\":\"Monica Genovese\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"caption\":\"Monica Genovese\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Monica_Genovese\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/author\\\/monica-genovese\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sindaci d'Italia proprietari dei cani abbandonati nei loro Comuni - Quattro zampe e dintorni","description":"Un cane abbandonato e randagio in un determinato Comune \u00e8 di propriet\u00e0 del sindaco di quel Comune. La legge 281\/91 per la tutela e il benessere animale,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/sindaci-ditalia-proprietari-dei-cani-abbandonati-nei-loro-comuni\/","og_locale":"it_IT","og_type":"article","og_title":"Sindaci d'Italia proprietari dei cani abbandonati nei loro Comuni - Quattro zampe e dintorni","og_description":"Un cane abbandonato e randagio in un determinato Comune \u00e8 di propriet\u00e0 del sindaco di quel Comune. La legge 281\/91 per la tutela e il benessere animale,","og_url":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/sindaci-ditalia-proprietari-dei-cani-abbandonati-nei-loro-comuni\/","og_site_name":"Quattro zampe e dintorni","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2012-04-19T10:19:03+00:00","article_modified_time":"2012-04-23T11:39:44+00:00","og_image":[{"width":600,"height":450,"url":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/04\/amicicani_469246981_P1010006.jpg","type":"image\/jpeg"}],"author":"Monica Genovese","twitter_misc":{"Scritto da":"Monica Genovese","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/sindaci-ditalia-proprietari-dei-cani-abbandonati-nei-loro-comuni\/#article","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/sindaci-ditalia-proprietari-dei-cani-abbandonati-nei-loro-comuni\/"},"author":{"name":"Monica Genovese","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce"},"headline":"Sindaci d&#8217;Italia proprietari dei cani abbandonati nei loro Comuni","datePublished":"2012-04-19T10:19:03+00:00","dateModified":"2012-04-23T11:39:44+00:00","mainEntityOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/sindaci-ditalia-proprietari-dei-cani-abbandonati-nei-loro-comuni\/"},"wordCount":462,"commentCount":3,"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/sindaci-ditalia-proprietari-dei-cani-abbandonati-nei-loro-comuni\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/04\/amicicani_469246981_P1010006.jpg","keywords":["accalappiacani","animali","cani","canili","Chiliamacisegua","Francesca Martini","Italia","legge","Michela Brambilla","randagi","sindaci","Veneto"],"articleSection":["Quattro zampe"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/sindaci-ditalia-proprietari-dei-cani-abbandonati-nei-loro-comuni\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/sindaci-ditalia-proprietari-dei-cani-abbandonati-nei-loro-comuni\/","url":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/sindaci-ditalia-proprietari-dei-cani-abbandonati-nei-loro-comuni\/","name":"Sindaci d'Italia proprietari dei cani abbandonati nei loro Comuni - Quattro zampe e dintorni","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website"},"primaryImageOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/sindaci-ditalia-proprietari-dei-cani-abbandonati-nei-loro-comuni\/#primaryimage"},"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/sindaci-ditalia-proprietari-dei-cani-abbandonati-nei-loro-comuni\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/04\/amicicani_469246981_P1010006.jpg","datePublished":"2012-04-19T10:19:03+00:00","dateModified":"2012-04-23T11:39:44+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce"},"description":"Un cane abbandonato e randagio in un determinato Comune \u00e8 di propriet\u00e0 del sindaco di quel Comune. La legge 281\/91 per la tutela e il benessere animale,","breadcrumb":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/sindaci-ditalia-proprietari-dei-cani-abbandonati-nei-loro-comuni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/sindaci-ditalia-proprietari-dei-cani-abbandonati-nei-loro-comuni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/sindaci-ditalia-proprietari-dei-cani-abbandonati-nei-loro-comuni\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/04\/amicicani_469246981_P1010006.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2012\/04\/amicicani_469246981_P1010006.jpg","width":"600","height":"450"},{"@type":"BreadcrumbList","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/sindaci-ditalia-proprietari-dei-cani-abbandonati-nei-loro-comuni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/"},{"@type":"ListItem","position":2,"name":"Sindaci d&#8217;Italia proprietari dei cani abbandonati nei loro Comuni"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/","name":"Quattro zampe e dintorni","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce","name":"Monica Genovese","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","caption":"Monica Genovese"},"sameAs":["https:\/\/x.com\/Monica_Genovese"],"url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/author\/monica-genovese\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/comments?post=272"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/272\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media\/280"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media?parent=272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/categories?post=272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/tags?post=272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}