{"id":1841,"date":"2018-11-30T09:31:39","date_gmt":"2018-11-30T08:31:39","guid":{"rendered":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/?p=1841"},"modified":"2018-11-30T09:31:39","modified_gmt":"2018-11-30T08:31:39","slug":"un-crowdfunding-per-salvare-38-asinelli-di-asti-dal-freddo-dellinverno","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/un-crowdfunding-per-salvare-38-asinelli-di-asti-dal-freddo-dellinverno\/","title":{"rendered":"Un crowdfunding per salvare 38 asinelli di Asti dal freddo dell&#8217;inverno"},"content":{"rendered":"<p>Il freddo sta per arrivare e in provincia di Asti, in un\u2019azienda agricola, ci sono 38 asini ragusani di cui prendersi cura. La responsabilit\u00e0 \u00e8 di Gabriele, titolare dell\u2019azienda che li ha rilevati da un\u2019esperienza di allevamento <!--more-->che non \u00e8 andata a buon fine e che, insieme a Manuela, non vuole che gli animali soffrano per il rigido inverno. Ecco allora il <a href=\"https:\/\/www.eppela.com\/it\/projects\/21116-adotta-gli-asinelli-dell-azienda-asiland\">progetto selezionato per il crowdfunding di Eppela<\/a>, che chiede ai finanziatori amanti degli animali un aiuto per acquistare alimenti sostituivi del fieno e materiali per lettiera alternativi alla paglia. Gli animali, soprattutto quelli pi\u00f9 giovani e i maschi pi\u00f9 anziani, hanno inoltre bisogno di un riparo nelle stalle alternativo all\u2019allevamento all\u2019aperto soprattutto nei mesi pi\u00f9 rigidi.<br \/>\nIl traguardo da raggiungere prevede la raccolta di 1000 euro.<\/p>\n<p><iframe loading=\"lazy\" title=\"Adotta un asinello dell&#039;azienda Asiland! Sostienici su eppela.com\" width=\"840\" height=\"473\" src=\"https:\/\/www.youtube.com\/embed\/18f-mkhoDhc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il freddo sta per arrivare e in provincia di Asti, in un\u2019azienda agricola, ci sono 38 asini ragusani di cui prendersi cura. La responsabilit\u00e0 \u00e8 di Gabriele, titolare dell\u2019azienda che li ha rilevati da un\u2019esperienza di allevamento<\/p>\n","protected":false},"author":34,"featured_media":1842,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[353],"class_list":["post-1841","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-quattro-zampe","tag-asini"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un crowdfunding per salvare 38 asinelli di Asti dal freddo dell&#039;inverno - Quattro zampe e dintorni<\/title>\n<meta name=\"description\" content=\"Il freddo sta per arrivare e in provincia di Asti, in un\u2019azienda agricola, ci sono 38 asini ragusani di cui prendersi cura. La responsabilit\u00e0 \u00e8 di\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/un-crowdfunding-per-salvare-38-asinelli-di-asti-dal-freddo-dellinverno\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un crowdfunding per salvare 38 asinelli di Asti dal freddo dell&#039;inverno - Quattro zampe e dintorni\" \/>\n<meta property=\"og:description\" content=\"Il freddo sta per arrivare e in provincia di Asti, in un\u2019azienda agricola, ci sono 38 asini ragusani di cui prendersi cura. La responsabilit\u00e0 \u00e8 di\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/un-crowdfunding-per-salvare-38-asinelli-di-asti-dal-freddo-dellinverno\/\" \/>\n<meta property=\"og:site_name\" content=\"Quattro zampe e dintorni\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"gabriele.farina\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-30T08:31:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2018\/11\/asiland.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriele Farina\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Farina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/un-crowdfunding-per-salvare-38-asinelli-di-asti-dal-freddo-dellinverno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/un-crowdfunding-per-salvare-38-asinelli-di-asti-dal-freddo-dellinverno\\\/\"},\"author\":{\"name\":\"Gabriele Farina\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"headline\":\"Un crowdfunding per salvare 38 asinelli di Asti dal freddo dell&#8217;inverno\",\"datePublished\":\"2018-11-30T08:31:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/un-crowdfunding-per-salvare-38-asinelli-di-asti-dal-freddo-dellinverno\\\/\"},\"wordCount\":147,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/un-crowdfunding-per-salvare-38-asinelli-di-asti-dal-freddo-dellinverno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2018\\\/11\\\/asiland.jpg\",\"keywords\":[\"asini\"],\"articleSection\":[\"Quattro zampe\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/un-crowdfunding-per-salvare-38-asinelli-di-asti-dal-freddo-dellinverno\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/un-crowdfunding-per-salvare-38-asinelli-di-asti-dal-freddo-dellinverno\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/un-crowdfunding-per-salvare-38-asinelli-di-asti-dal-freddo-dellinverno\\\/\",\"name\":\"Un crowdfunding per salvare 38 asinelli di Asti dal freddo dell'inverno - Quattro zampe e dintorni\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/un-crowdfunding-per-salvare-38-asinelli-di-asti-dal-freddo-dellinverno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/un-crowdfunding-per-salvare-38-asinelli-di-asti-dal-freddo-dellinverno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2018\\\/11\\\/asiland.jpg\",\"datePublished\":\"2018-11-30T08:31:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"description\":\"Il freddo sta per arrivare e in provincia di Asti, in un\u2019azienda agricola, ci sono 38 asini ragusani di cui prendersi cura. La responsabilit\u00e0 \u00e8 di\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/un-crowdfunding-per-salvare-38-asinelli-di-asti-dal-freddo-dellinverno\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/un-crowdfunding-per-salvare-38-asinelli-di-asti-dal-freddo-dellinverno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/un-crowdfunding-per-salvare-38-asinelli-di-asti-dal-freddo-dellinverno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2018\\\/11\\\/asiland.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2018\\\/11\\\/asiland.jpg\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/un-crowdfunding-per-salvare-38-asinelli-di-asti-dal-freddo-dellinverno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un crowdfunding per salvare 38 asinelli di Asti dal freddo dell&#8217;inverno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\",\"name\":\"Quattro zampe e dintorni\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\",\"name\":\"Gabriele Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"caption\":\"Gabriele Farina\"},\"description\":\"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO\",\"sameAs\":[\"gabriele.farina\",\"https:\\\/\\\/x.com\\\/solops\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/author\\\/gabriele-farina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un crowdfunding per salvare 38 asinelli di Asti dal freddo dell'inverno - Quattro zampe e dintorni","description":"Il freddo sta per arrivare e in provincia di Asti, in un\u2019azienda agricola, ci sono 38 asini ragusani di cui prendersi cura. La responsabilit\u00e0 \u00e8 di","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/un-crowdfunding-per-salvare-38-asinelli-di-asti-dal-freddo-dellinverno\/","og_locale":"it_IT","og_type":"article","og_title":"Un crowdfunding per salvare 38 asinelli di Asti dal freddo dell'inverno - Quattro zampe e dintorni","og_description":"Il freddo sta per arrivare e in provincia di Asti, in un\u2019azienda agricola, ci sono 38 asini ragusani di cui prendersi cura. La responsabilit\u00e0 \u00e8 di","og_url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/un-crowdfunding-per-salvare-38-asinelli-di-asti-dal-freddo-dellinverno\/","og_site_name":"Quattro zampe e dintorni","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"gabriele.farina","article_published_time":"2018-11-30T08:31:39+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2018\/11\/asiland.jpg","type":"image\/jpeg"}],"author":"Gabriele Farina","twitter_misc":{"Scritto da":"Gabriele Farina","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/un-crowdfunding-per-salvare-38-asinelli-di-asti-dal-freddo-dellinverno\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/un-crowdfunding-per-salvare-38-asinelli-di-asti-dal-freddo-dellinverno\/"},"author":{"name":"Gabriele Farina","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"headline":"Un crowdfunding per salvare 38 asinelli di Asti dal freddo dell&#8217;inverno","datePublished":"2018-11-30T08:31:39+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/un-crowdfunding-per-salvare-38-asinelli-di-asti-dal-freddo-dellinverno\/"},"wordCount":147,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/un-crowdfunding-per-salvare-38-asinelli-di-asti-dal-freddo-dellinverno\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2018\/11\/asiland.jpg","keywords":["asini"],"articleSection":["Quattro zampe"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/un-crowdfunding-per-salvare-38-asinelli-di-asti-dal-freddo-dellinverno\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/un-crowdfunding-per-salvare-38-asinelli-di-asti-dal-freddo-dellinverno\/","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/un-crowdfunding-per-salvare-38-asinelli-di-asti-dal-freddo-dellinverno\/","name":"Un crowdfunding per salvare 38 asinelli di Asti dal freddo dell'inverno - Quattro zampe e dintorni","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/un-crowdfunding-per-salvare-38-asinelli-di-asti-dal-freddo-dellinverno\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/un-crowdfunding-per-salvare-38-asinelli-di-asti-dal-freddo-dellinverno\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2018\/11\/asiland.jpg","datePublished":"2018-11-30T08:31:39+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"description":"Il freddo sta per arrivare e in provincia di Asti, in un\u2019azienda agricola, ci sono 38 asini ragusani di cui prendersi cura. La responsabilit\u00e0 \u00e8 di","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/un-crowdfunding-per-salvare-38-asinelli-di-asti-dal-freddo-dellinverno\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/un-crowdfunding-per-salvare-38-asinelli-di-asti-dal-freddo-dellinverno\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/un-crowdfunding-per-salvare-38-asinelli-di-asti-dal-freddo-dellinverno\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2018\/11\/asiland.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2018\/11\/asiland.jpg","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/un-crowdfunding-per-salvare-38-asinelli-di-asti-dal-freddo-dellinverno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/"},{"@type":"ListItem","position":2,"name":"Un crowdfunding per salvare 38 asinelli di Asti dal freddo dell&#8217;inverno"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/","name":"Quattro zampe e dintorni","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32","name":"Gabriele Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","caption":"Gabriele Farina"},"description":"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO","sameAs":["gabriele.farina","https:\/\/x.com\/solops"],"url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/author\/gabriele-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/1841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/comments?post=1841"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/1841\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media\/1842"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media?parent=1841"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/categories?post=1841"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/tags?post=1841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}