{"id":1827,"date":"2018-11-12T09:28:41","date_gmt":"2018-11-12T08:28:41","guid":{"rendered":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/?p=1827"},"modified":"2018-11-12T09:28:41","modified_gmt":"2018-11-12T08:28:41","slug":"il-video-dei-vigili-del-fuoco-che-salvano-un-gatto-incastrato-su-un-balcone","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/il-video-dei-vigili-del-fuoco-che-salvano-un-gatto-incastrato-su-un-balcone\/","title":{"rendered":"Il video dei vigili del fuoco che salvano un gatto incastrato su un balcone"},"content":{"rendered":"<p>I Vigili del fuoco sono intervenuti a Lavena Ponte Tresa per soccorrere un gatto incastrato nelle balaustre a vetro di un&#8217;attivit\u00e0 commerciale. Con l\u2019ausilio di alcuni cuscini pneumatici, le squadre intervenute sono<!--more--> riuscite ad allargare i vetri, creando lo spazio per raggiungere l\u2019intercapedine dove era incastrato il felino ed estrarlo sano e salvo.<\/p>\n<p>https:\/\/www.facebook.com\/QuattroZampeDintorni\/videos\/285112405460618\/?__xts__%5B0%5D=68.ARDY3sjR4sg5ioAJ8mKeErYXdTl-vbMKUMpjTmVuHg7Iq6JM8tfJm-4ElccPPD61nwwUuJ_8J0SdoWOhQFaCQIv3un4JLuErDAPkw9jvJmX0ixItrKrqSIJkxW6cbWeKLUJwbnuOuwCDXjZE2pQlKlYip8234xkq7NT-iFTynr6Qz7_3ddfBaCtH8YZsljvOK55a3kxeyREyPgrcwr-G8ZRUieZ0EWrol3fKYIteo9Ap4IkHRGd0ZsnLb9J7IIzGiiWPllhEdKZggmJdXCKBEy9XpHevd6zYBSjYN2Skdt4d28eE4n8Ap0S4WbSSgDm1Qx4sInuh6ctH&#038;__tn__=-R<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I Vigili del fuoco sono intervenuti a Lavena Ponte Tresa per soccorrere un gatto incastrato nelle balaustre a vetro di un&#8217;attivit\u00e0 commerciale. Con l\u2019ausilio di alcuni cuscini pneumatici, le squadre intervenute sono<\/p>\n","protected":false},"author":34,"featured_media":1828,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[3],"class_list":["post-1827","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-quattro-zampe","tag-gatto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il video dei vigili del fuoco che salvano un gatto incastrato su un balcone - Quattro zampe e dintorni<\/title>\n<meta name=\"description\" content=\"I Vigili del fuoco sono intervenuti a Lavena Ponte Tresa per soccorrere un gatto incastrato nelle balaustre a vetro di un&#039;attivit\u00e0 commerciale. Con\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/il-video-dei-vigili-del-fuoco-che-salvano-un-gatto-incastrato-su-un-balcone\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il video dei vigili del fuoco che salvano un gatto incastrato su un balcone - Quattro zampe e dintorni\" \/>\n<meta property=\"og:description\" content=\"I Vigili del fuoco sono intervenuti a Lavena Ponte Tresa per soccorrere un gatto incastrato nelle balaustre a vetro di un&#039;attivit\u00e0 commerciale. Con\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/il-video-dei-vigili-del-fuoco-che-salvano-un-gatto-incastrato-su-un-balcone\/\" \/>\n<meta property=\"og:site_name\" content=\"Quattro zampe e dintorni\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"gabriele.farina\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-12T08:28:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2018\/11\/gatto-incastrato-video.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"575\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriele Farina\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Farina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/il-video-dei-vigili-del-fuoco-che-salvano-un-gatto-incastrato-su-un-balcone\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/il-video-dei-vigili-del-fuoco-che-salvano-un-gatto-incastrato-su-un-balcone\\\/\"},\"author\":{\"name\":\"Gabriele Farina\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"headline\":\"Il video dei vigili del fuoco che salvano un gatto incastrato su un balcone\",\"datePublished\":\"2018-11-12T08:28:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/il-video-dei-vigili-del-fuoco-che-salvano-un-gatto-incastrato-su-un-balcone\\\/\"},\"wordCount\":127,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/il-video-dei-vigili-del-fuoco-che-salvano-un-gatto-incastrato-su-un-balcone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2018\\\/11\\\/gatto-incastrato-video.jpg\",\"keywords\":[\"Gatto\"],\"articleSection\":[\"Quattro zampe\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/il-video-dei-vigili-del-fuoco-che-salvano-un-gatto-incastrato-su-un-balcone\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/il-video-dei-vigili-del-fuoco-che-salvano-un-gatto-incastrato-su-un-balcone\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/il-video-dei-vigili-del-fuoco-che-salvano-un-gatto-incastrato-su-un-balcone\\\/\",\"name\":\"Il video dei vigili del fuoco che salvano un gatto incastrato su un balcone - Quattro zampe e dintorni\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/il-video-dei-vigili-del-fuoco-che-salvano-un-gatto-incastrato-su-un-balcone\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/il-video-dei-vigili-del-fuoco-che-salvano-un-gatto-incastrato-su-un-balcone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2018\\\/11\\\/gatto-incastrato-video.jpg\",\"datePublished\":\"2018-11-12T08:28:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"description\":\"I Vigili del fuoco sono intervenuti a Lavena Ponte Tresa per soccorrere un gatto incastrato nelle balaustre a vetro di un'attivit\u00e0 commerciale. Con\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/il-video-dei-vigili-del-fuoco-che-salvano-un-gatto-incastrato-su-un-balcone\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/il-video-dei-vigili-del-fuoco-che-salvano-un-gatto-incastrato-su-un-balcone\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/il-video-dei-vigili-del-fuoco-che-salvano-un-gatto-incastrato-su-un-balcone\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2018\\\/11\\\/gatto-incastrato-video.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2018\\\/11\\\/gatto-incastrato-video.jpg\",\"width\":1024,\"height\":575},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/il-video-dei-vigili-del-fuoco-che-salvano-un-gatto-incastrato-su-un-balcone\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il video dei vigili del fuoco che salvano un gatto incastrato su un balcone\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\",\"name\":\"Quattro zampe e dintorni\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\",\"name\":\"Gabriele Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"caption\":\"Gabriele Farina\"},\"description\":\"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO\",\"sameAs\":[\"gabriele.farina\",\"https:\\\/\\\/x.com\\\/solops\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/author\\\/gabriele-farina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il video dei vigili del fuoco che salvano un gatto incastrato su un balcone - Quattro zampe e dintorni","description":"I Vigili del fuoco sono intervenuti a Lavena Ponte Tresa per soccorrere un gatto incastrato nelle balaustre a vetro di un'attivit\u00e0 commerciale. Con","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/il-video-dei-vigili-del-fuoco-che-salvano-un-gatto-incastrato-su-un-balcone\/","og_locale":"it_IT","og_type":"article","og_title":"Il video dei vigili del fuoco che salvano un gatto incastrato su un balcone - Quattro zampe e dintorni","og_description":"I Vigili del fuoco sono intervenuti a Lavena Ponte Tresa per soccorrere un gatto incastrato nelle balaustre a vetro di un'attivit\u00e0 commerciale. Con","og_url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/il-video-dei-vigili-del-fuoco-che-salvano-un-gatto-incastrato-su-un-balcone\/","og_site_name":"Quattro zampe e dintorni","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"gabriele.farina","article_published_time":"2018-11-12T08:28:41+00:00","og_image":[{"width":1024,"height":575,"url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2018\/11\/gatto-incastrato-video.jpg","type":"image\/jpeg"}],"author":"Gabriele Farina","twitter_misc":{"Scritto da":"Gabriele Farina","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/il-video-dei-vigili-del-fuoco-che-salvano-un-gatto-incastrato-su-un-balcone\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/il-video-dei-vigili-del-fuoco-che-salvano-un-gatto-incastrato-su-un-balcone\/"},"author":{"name":"Gabriele Farina","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"headline":"Il video dei vigili del fuoco che salvano un gatto incastrato su un balcone","datePublished":"2018-11-12T08:28:41+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/il-video-dei-vigili-del-fuoco-che-salvano-un-gatto-incastrato-su-un-balcone\/"},"wordCount":127,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/il-video-dei-vigili-del-fuoco-che-salvano-un-gatto-incastrato-su-un-balcone\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2018\/11\/gatto-incastrato-video.jpg","keywords":["Gatto"],"articleSection":["Quattro zampe"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/il-video-dei-vigili-del-fuoco-che-salvano-un-gatto-incastrato-su-un-balcone\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/il-video-dei-vigili-del-fuoco-che-salvano-un-gatto-incastrato-su-un-balcone\/","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/il-video-dei-vigili-del-fuoco-che-salvano-un-gatto-incastrato-su-un-balcone\/","name":"Il video dei vigili del fuoco che salvano un gatto incastrato su un balcone - Quattro zampe e dintorni","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/il-video-dei-vigili-del-fuoco-che-salvano-un-gatto-incastrato-su-un-balcone\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/il-video-dei-vigili-del-fuoco-che-salvano-un-gatto-incastrato-su-un-balcone\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2018\/11\/gatto-incastrato-video.jpg","datePublished":"2018-11-12T08:28:41+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"description":"I Vigili del fuoco sono intervenuti a Lavena Ponte Tresa per soccorrere un gatto incastrato nelle balaustre a vetro di un'attivit\u00e0 commerciale. Con","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/il-video-dei-vigili-del-fuoco-che-salvano-un-gatto-incastrato-su-un-balcone\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/il-video-dei-vigili-del-fuoco-che-salvano-un-gatto-incastrato-su-un-balcone\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/il-video-dei-vigili-del-fuoco-che-salvano-un-gatto-incastrato-su-un-balcone\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2018\/11\/gatto-incastrato-video.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2018\/11\/gatto-incastrato-video.jpg","width":1024,"height":575},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/il-video-dei-vigili-del-fuoco-che-salvano-un-gatto-incastrato-su-un-balcone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/"},{"@type":"ListItem","position":2,"name":"Il video dei vigili del fuoco che salvano un gatto incastrato su un balcone"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/","name":"Quattro zampe e dintorni","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32","name":"Gabriele Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","caption":"Gabriele Farina"},"description":"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO","sameAs":["gabriele.farina","https:\/\/x.com\/solops"],"url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/author\/gabriele-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/1827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/comments?post=1827"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/1827\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media\/1828"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media?parent=1827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/categories?post=1827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/tags?post=1827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}