{"id":1688,"date":"2017-10-19T09:14:55","date_gmt":"2017-10-19T08:14:55","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/?p=1688"},"modified":"2017-10-19T09:14:55","modified_gmt":"2017-10-19T08:14:55","slug":"cane-randagio-gli-la-pipi-addosso-lo-adotta","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cane-randagio-gli-la-pipi-addosso-lo-adotta\/","title":{"rendered":"Il cane randagio gli fa la pip\u00ec addosso e lui lo adotta"},"content":{"rendered":"<p>Un&#8217;amicizia nata in maniera del tutto particolare: per colpa di una pip\u00ec. Il video registrato in Brasile da una telecamera di sicurezza mostra un ragazzo seduto sul marciapiede, intento a guardare il suo cellulare. Poco dopo<!--more--> si avvicina un cane randagio, lo annusa e decide che la schiena del giovane \u00e8 il posto adatto per fare la pip\u00ec. Il giovane ovviamente non la prende bene, si alza e cerca di sferrare un calcio al cane. Poi i due si guardano a distanza.<\/p>\n<p>https:\/\/www.youtube.com\/watch?v=6gKykKY_TQw<\/p>\n<p>Quello che il video non mostra \u00e8 che pi\u00f9 tardi il ragazzo \u00e8 tornato sul posto, ha cercato il cane ed ha deciso di portarselo a casa. Ora l&#8217;animale, che \u00e8 stato chiamato Enzo, ha una casa e un nuovo amico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un&#8217;amicizia nata in maniera del tutto particolare: per colpa di una pip\u00ec. Il video registrato in Brasile da una telecamera di sicurezza mostra un ragazzo seduto sul marciapiede, intento a guardare il suo cellulare. Poco dopo<\/p>\n","protected":false},"author":34,"featured_media":1689,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[11],"class_list":["post-1688","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-quattro-zampe","tag-cane"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il cane randagio gli fa la pip\u00ec addosso e lui lo adotta - Quattro zampe e dintorni<\/title>\n<meta name=\"description\" content=\"Un&#039;amicizia nata in maniera del tutto particolare: per colpa di una pip\u00ec. Il video registrato in Brasile da una telecamera di sicurezza mostra un ragazzo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cane-randagio-gli-la-pipi-addosso-lo-adotta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il cane randagio gli fa la pip\u00ec addosso e lui lo adotta - Quattro zampe e dintorni\" \/>\n<meta property=\"og:description\" content=\"Un&#039;amicizia nata in maniera del tutto particolare: per colpa di una pip\u00ec. Il video registrato in Brasile da una telecamera di sicurezza mostra un ragazzo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cane-randagio-gli-la-pipi-addosso-lo-adotta\/\" \/>\n<meta property=\"og:site_name\" content=\"Quattro zampe e dintorni\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"gabriele.farina\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-19T08:14:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2017\/10\/Screenshot-2017-10-19-Il-cane-gli-fa-la-pip\u00ec-addosso-la-reazione-dell\u2019uomo-\u00e8-inaspettata.png\" \/>\n\t<meta property=\"og:image:width\" content=\"613\" \/>\n\t<meta property=\"og:image:height\" content=\"413\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Gabriele Farina\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Farina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cane-randagio-gli-la-pipi-addosso-lo-adotta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cane-randagio-gli-la-pipi-addosso-lo-adotta\\\/\"},\"author\":{\"name\":\"Gabriele Farina\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"headline\":\"Il cane randagio gli fa la pip\u00ec addosso e lui lo adotta\",\"datePublished\":\"2017-10-19T08:14:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cane-randagio-gli-la-pipi-addosso-lo-adotta\\\/\"},\"wordCount\":141,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cane-randagio-gli-la-pipi-addosso-lo-adotta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2017\\\/10\\\/Screenshot-2017-10-19-Il-cane-gli-fa-la-pip\u00ec-addosso-la-reazione-dell\u2019uomo-\u00e8-inaspettata.png\",\"keywords\":[\"cane\"],\"articleSection\":[\"Quattro zampe\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cane-randagio-gli-la-pipi-addosso-lo-adotta\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cane-randagio-gli-la-pipi-addosso-lo-adotta\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cane-randagio-gli-la-pipi-addosso-lo-adotta\\\/\",\"name\":\"Il cane randagio gli fa la pip\u00ec addosso e lui lo adotta - Quattro zampe e dintorni\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cane-randagio-gli-la-pipi-addosso-lo-adotta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cane-randagio-gli-la-pipi-addosso-lo-adotta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2017\\\/10\\\/Screenshot-2017-10-19-Il-cane-gli-fa-la-pip\u00ec-addosso-la-reazione-dell\u2019uomo-\u00e8-inaspettata.png\",\"datePublished\":\"2017-10-19T08:14:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"description\":\"Un'amicizia nata in maniera del tutto particolare: per colpa di una pip\u00ec. Il video registrato in Brasile da una telecamera di sicurezza mostra un ragazzo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cane-randagio-gli-la-pipi-addosso-lo-adotta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cane-randagio-gli-la-pipi-addosso-lo-adotta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cane-randagio-gli-la-pipi-addosso-lo-adotta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2017\\\/10\\\/Screenshot-2017-10-19-Il-cane-gli-fa-la-pip\u00ec-addosso-la-reazione-dell\u2019uomo-\u00e8-inaspettata.png\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2017\\\/10\\\/Screenshot-2017-10-19-Il-cane-gli-fa-la-pip\u00ec-addosso-la-reazione-dell\u2019uomo-\u00e8-inaspettata.png\",\"width\":613,\"height\":413},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cane-randagio-gli-la-pipi-addosso-lo-adotta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il cane randagio gli fa la pip\u00ec addosso e lui lo adotta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\",\"name\":\"Quattro zampe e dintorni\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\",\"name\":\"Gabriele Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"caption\":\"Gabriele Farina\"},\"description\":\"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO\",\"sameAs\":[\"gabriele.farina\",\"https:\\\/\\\/x.com\\\/solops\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/author\\\/gabriele-farina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il cane randagio gli fa la pip\u00ec addosso e lui lo adotta - Quattro zampe e dintorni","description":"Un'amicizia nata in maniera del tutto particolare: per colpa di una pip\u00ec. Il video registrato in Brasile da una telecamera di sicurezza mostra un ragazzo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cane-randagio-gli-la-pipi-addosso-lo-adotta\/","og_locale":"it_IT","og_type":"article","og_title":"Il cane randagio gli fa la pip\u00ec addosso e lui lo adotta - Quattro zampe e dintorni","og_description":"Un'amicizia nata in maniera del tutto particolare: per colpa di una pip\u00ec. Il video registrato in Brasile da una telecamera di sicurezza mostra un ragazzo","og_url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cane-randagio-gli-la-pipi-addosso-lo-adotta\/","og_site_name":"Quattro zampe e dintorni","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"gabriele.farina","article_published_time":"2017-10-19T08:14:55+00:00","og_image":[{"width":613,"height":413,"url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2017\/10\/Screenshot-2017-10-19-Il-cane-gli-fa-la-pip\u00ec-addosso-la-reazione-dell\u2019uomo-\u00e8-inaspettata.png","type":"image\/png"}],"author":"Gabriele Farina","twitter_misc":{"Scritto da":"Gabriele Farina","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cane-randagio-gli-la-pipi-addosso-lo-adotta\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cane-randagio-gli-la-pipi-addosso-lo-adotta\/"},"author":{"name":"Gabriele Farina","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"headline":"Il cane randagio gli fa la pip\u00ec addosso e lui lo adotta","datePublished":"2017-10-19T08:14:55+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cane-randagio-gli-la-pipi-addosso-lo-adotta\/"},"wordCount":141,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cane-randagio-gli-la-pipi-addosso-lo-adotta\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2017\/10\/Screenshot-2017-10-19-Il-cane-gli-fa-la-pip\u00ec-addosso-la-reazione-dell\u2019uomo-\u00e8-inaspettata.png","keywords":["cane"],"articleSection":["Quattro zampe"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cane-randagio-gli-la-pipi-addosso-lo-adotta\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cane-randagio-gli-la-pipi-addosso-lo-adotta\/","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cane-randagio-gli-la-pipi-addosso-lo-adotta\/","name":"Il cane randagio gli fa la pip\u00ec addosso e lui lo adotta - Quattro zampe e dintorni","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cane-randagio-gli-la-pipi-addosso-lo-adotta\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cane-randagio-gli-la-pipi-addosso-lo-adotta\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2017\/10\/Screenshot-2017-10-19-Il-cane-gli-fa-la-pip\u00ec-addosso-la-reazione-dell\u2019uomo-\u00e8-inaspettata.png","datePublished":"2017-10-19T08:14:55+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"description":"Un'amicizia nata in maniera del tutto particolare: per colpa di una pip\u00ec. Il video registrato in Brasile da una telecamera di sicurezza mostra un ragazzo","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cane-randagio-gli-la-pipi-addosso-lo-adotta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cane-randagio-gli-la-pipi-addosso-lo-adotta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cane-randagio-gli-la-pipi-addosso-lo-adotta\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2017\/10\/Screenshot-2017-10-19-Il-cane-gli-fa-la-pip\u00ec-addosso-la-reazione-dell\u2019uomo-\u00e8-inaspettata.png","contentUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2017\/10\/Screenshot-2017-10-19-Il-cane-gli-fa-la-pip\u00ec-addosso-la-reazione-dell\u2019uomo-\u00e8-inaspettata.png","width":613,"height":413},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cane-randagio-gli-la-pipi-addosso-lo-adotta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/"},{"@type":"ListItem","position":2,"name":"Il cane randagio gli fa la pip\u00ec addosso e lui lo adotta"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/","name":"Quattro zampe e dintorni","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32","name":"Gabriele Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","caption":"Gabriele Farina"},"description":"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO","sameAs":["gabriele.farina","https:\/\/x.com\/solops"],"url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/author\/gabriele-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/1688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/comments?post=1688"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/1688\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media\/1689"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media?parent=1688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/categories?post=1688"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/tags?post=1688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}