{"id":1663,"date":"2017-09-14T10:55:54","date_gmt":"2017-09-14T09:55:54","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/?p=1663"},"modified":"2017-09-14T10:55:54","modified_gmt":"2017-09-14T09:55:54","slug":"briciola-scappa-casa-lennesima-volta-la-padrona-viene-multata","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/briciola-scappa-casa-lennesima-volta-la-padrona-viene-multata\/","title":{"rendered":"Briciola scappa di casa per l&#8217;ennesima volta e la padrona viene multata"},"content":{"rendered":"<p>Briciola, uno splendido Border Collie che vive a Gaglianico, ha l&#8217;abitudine di allontanarsi di casa per fare un giro in paese. Nella mattina del 13 settembre il cane \u00e8 stato avvistato nuovamente in Strada Trossi e, dopo un&#8217;ora di <!--more-->inseguimento, \u00e8 stato recuperato\u00a0dal personale del Canile Consortile di Cossato, con il supporto della Polizia Locale di Gaglianico.<\/p>\n<p>Briciola \u00e8 stato riportato dalla sua padrona, una 50enne del paese che era stata diffidata dalla Polizia Locale di Gaglianico per omessa custodia di animali gi\u00e0 in precedenza. Questa volta per lei \u00e8 scattata la multa per omessa custodia e malgoverno di animali, che prevede una sanzione amministrativa da 25 ad 258 euro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Briciola, uno splendido Border Collie che vive a Gaglianico, ha l&#8217;abitudine di allontanarsi di casa per fare un giro in paese. Nella mattina del 13 settembre il cane \u00e8 stato avvistato nuovamente in Strada Trossi e, dopo un&#8217;ora di<\/p>\n","protected":false},"author":34,"featured_media":1664,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[11],"class_list":["post-1663","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-quattro-zampe","tag-cane"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Briciola scappa di casa per l&#039;ennesima volta e la padrona viene multata - Quattro zampe e dintorni<\/title>\n<meta name=\"description\" content=\"Briciola, uno splendido Border Collie che vive a Gaglianico, ha l&#039;abitudine di allontanarsi di casa per fare un giro in paese. Nella mattina del 13\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/briciola-scappa-casa-lennesima-volta-la-padrona-viene-multata\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Briciola scappa di casa per l&#039;ennesima volta e la padrona viene multata - Quattro zampe e dintorni\" \/>\n<meta property=\"og:description\" content=\"Briciola, uno splendido Border Collie che vive a Gaglianico, ha l&#039;abitudine di allontanarsi di casa per fare un giro in paese. Nella mattina del 13\" \/>\n<meta property=\"og:url\" content=\"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/briciola-scappa-casa-lennesima-volta-la-padrona-viene-multata\/\" \/>\n<meta property=\"og:site_name\" content=\"Quattro zampe e dintorni\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"gabriele.farina\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-14T09:55:54+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2017\/09\/Border_Collie_cane-qp.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriele Farina\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Farina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/briciola-scappa-casa-lennesima-volta-la-padrona-viene-multata\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/briciola-scappa-casa-lennesima-volta-la-padrona-viene-multata\\\/\"},\"author\":{\"name\":\"Gabriele Farina\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"headline\":\"Briciola scappa di casa per l&#8217;ennesima volta e la padrona viene multata\",\"datePublished\":\"2017-09-14T09:55:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/briciola-scappa-casa-lennesima-volta-la-padrona-viene-multata\\\/\"},\"wordCount\":119,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/briciola-scappa-casa-lennesima-volta-la-padrona-viene-multata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2017\\\/09\\\/Border_Collie_cane-qp.jpg\",\"keywords\":[\"cane\"],\"articleSection\":[\"Quattro zampe\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/briciola-scappa-casa-lennesima-volta-la-padrona-viene-multata\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/briciola-scappa-casa-lennesima-volta-la-padrona-viene-multata\\\/\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/briciola-scappa-casa-lennesima-volta-la-padrona-viene-multata\\\/\",\"name\":\"Briciola scappa di casa per l'ennesima volta e la padrona viene multata - Quattro zampe e dintorni\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/briciola-scappa-casa-lennesima-volta-la-padrona-viene-multata\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/briciola-scappa-casa-lennesima-volta-la-padrona-viene-multata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2017\\\/09\\\/Border_Collie_cane-qp.jpg\",\"datePublished\":\"2017-09-14T09:55:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"description\":\"Briciola, uno splendido Border Collie che vive a Gaglianico, ha l'abitudine di allontanarsi di casa per fare un giro in paese. Nella mattina del 13\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/briciola-scappa-casa-lennesima-volta-la-padrona-viene-multata\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/briciola-scappa-casa-lennesima-volta-la-padrona-viene-multata\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/briciola-scappa-casa-lennesima-volta-la-padrona-viene-multata\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2017\\\/09\\\/Border_Collie_cane-qp.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2017\\\/09\\\/Border_Collie_cane-qp.jpg\",\"width\":1024,\"height\":683,\"caption\":\"By Tina creates (Own work) [CC BY-SA 3.0 (http:\\\/\\\/creativecommons.org\\\/licenses\\\/by-sa\\\/3.0)], via Wikimedia Commons\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/briciola-scappa-casa-lennesima-volta-la-padrona-viene-multata\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Briciola scappa di casa per l&#8217;ennesima volta e la padrona viene multata\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\",\"name\":\"Quattro zampe e dintorni\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\",\"name\":\"Gabriele Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"caption\":\"Gabriele Farina\"},\"description\":\"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO\",\"sameAs\":[\"gabriele.farina\",\"https:\\\/\\\/x.com\\\/solops\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/author\\\/gabriele-farina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Briciola scappa di casa per l'ennesima volta e la padrona viene multata - Quattro zampe e dintorni","description":"Briciola, uno splendido Border Collie che vive a Gaglianico, ha l'abitudine di allontanarsi di casa per fare un giro in paese. Nella mattina del 13","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/briciola-scappa-casa-lennesima-volta-la-padrona-viene-multata\/","og_locale":"it_IT","og_type":"article","og_title":"Briciola scappa di casa per l'ennesima volta e la padrona viene multata - Quattro zampe e dintorni","og_description":"Briciola, uno splendido Border Collie che vive a Gaglianico, ha l'abitudine di allontanarsi di casa per fare un giro in paese. Nella mattina del 13","og_url":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/briciola-scappa-casa-lennesima-volta-la-padrona-viene-multata\/","og_site_name":"Quattro zampe e dintorni","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"gabriele.farina","article_published_time":"2017-09-14T09:55:54+00:00","og_image":[{"width":1024,"height":683,"url":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2017\/09\/Border_Collie_cane-qp.jpg","type":"image\/jpeg"}],"author":"Gabriele Farina","twitter_misc":{"Scritto da":"Gabriele Farina","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/briciola-scappa-casa-lennesima-volta-la-padrona-viene-multata\/#article","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/briciola-scappa-casa-lennesima-volta-la-padrona-viene-multata\/"},"author":{"name":"Gabriele Farina","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"headline":"Briciola scappa di casa per l&#8217;ennesima volta e la padrona viene multata","datePublished":"2017-09-14T09:55:54+00:00","mainEntityOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/briciola-scappa-casa-lennesima-volta-la-padrona-viene-multata\/"},"wordCount":119,"commentCount":0,"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/briciola-scappa-casa-lennesima-volta-la-padrona-viene-multata\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2017\/09\/Border_Collie_cane-qp.jpg","keywords":["cane"],"articleSection":["Quattro zampe"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/briciola-scappa-casa-lennesima-volta-la-padrona-viene-multata\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/briciola-scappa-casa-lennesima-volta-la-padrona-viene-multata\/","url":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/briciola-scappa-casa-lennesima-volta-la-padrona-viene-multata\/","name":"Briciola scappa di casa per l'ennesima volta e la padrona viene multata - Quattro zampe e dintorni","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website"},"primaryImageOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/briciola-scappa-casa-lennesima-volta-la-padrona-viene-multata\/#primaryimage"},"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/briciola-scappa-casa-lennesima-volta-la-padrona-viene-multata\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2017\/09\/Border_Collie_cane-qp.jpg","datePublished":"2017-09-14T09:55:54+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"description":"Briciola, uno splendido Border Collie che vive a Gaglianico, ha l'abitudine di allontanarsi di casa per fare un giro in paese. Nella mattina del 13","breadcrumb":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/briciola-scappa-casa-lennesima-volta-la-padrona-viene-multata\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/briciola-scappa-casa-lennesima-volta-la-padrona-viene-multata\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/briciola-scappa-casa-lennesima-volta-la-padrona-viene-multata\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2017\/09\/Border_Collie_cane-qp.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2017\/09\/Border_Collie_cane-qp.jpg","width":1024,"height":683,"caption":"By Tina creates (Own work) [CC BY-SA 3.0 (http:\/\/creativecommons.org\/licenses\/by-sa\/3.0)], via Wikimedia Commons"},{"@type":"BreadcrumbList","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/briciola-scappa-casa-lennesima-volta-la-padrona-viene-multata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/"},{"@type":"ListItem","position":2,"name":"Briciola scappa di casa per l&#8217;ennesima volta e la padrona viene multata"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/","name":"Quattro zampe e dintorni","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32","name":"Gabriele Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","caption":"Gabriele Farina"},"description":"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO","sameAs":["gabriele.farina","https:\/\/x.com\/solops"],"url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/author\/gabriele-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/1663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/comments?post=1663"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/1663\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media\/1664"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media?parent=1663"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/categories?post=1663"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/tags?post=1663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}