{"id":1619,"date":"2017-06-27T08:36:30","date_gmt":"2017-06-27T07:36:30","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/?p=1619"},"modified":"2017-06-27T08:36:30","modified_gmt":"2017-06-27T07:36:30","slug":"cane-terrorizzato-dal-piccolo-criceto-video","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cane-terrorizzato-dal-piccolo-criceto-video\/","title":{"rendered":"Il cane \u00e8 terrorizzato dal piccolo criceto &#8211; video"},"content":{"rendered":"<p>Pu\u00f2 un cane grande e grosso essere terrorizzato da un minuscolo criceto, per di pi\u00f9 tenuto in mano dal suo padrone, al punto da non volerlo nemmeno guardare? Evidentemente si!<!--more--><\/p>\n<p><iframe loading=\"lazy\" src=\"http:\/\/www.lastampa.it\/modulo\/slideshow\/jsp\/video_embed.jsp?u=9b8f6662-5a28-11e7-833e-2a6101c81b76&amp;w=700&amp;h=394\" width=\"700\" height=\"394\" frameborder=\"0\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pu\u00f2 un cane grande e grosso essere terrorizzato da un minuscolo criceto, per di pi\u00f9 tenuto in mano dal suo padrone, al punto da non volerlo nemmeno guardare? Evidentemente si!<\/p>\n","protected":false},"author":34,"featured_media":1620,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[11,1082],"class_list":["post-1619","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-quattro-zampe","tag-cane","tag-criceto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il cane \u00e8 terrorizzato dal piccolo criceto - video - Quattro zampe e dintorni<\/title>\n<meta name=\"description\" content=\"Pu\u00f2 un cane grande e grosso essere terrorizzato da un minuscolo criceto, per di pi\u00f9 tenuto in mano dal suo padrone, al punto da non volerlo nemmeno\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cane-terrorizzato-dal-piccolo-criceto-video\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il cane \u00e8 terrorizzato dal piccolo criceto - video - Quattro zampe e dintorni\" \/>\n<meta property=\"og:description\" content=\"Pu\u00f2 un cane grande e grosso essere terrorizzato da un minuscolo criceto, per di pi\u00f9 tenuto in mano dal suo padrone, al punto da non volerlo nemmeno\" \/>\n<meta property=\"og:url\" content=\"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cane-terrorizzato-dal-piccolo-criceto-video\/\" \/>\n<meta property=\"og:site_name\" content=\"Quattro zampe e dintorni\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"gabriele.farina\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-27T07:36:30+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2017\/06\/cane-criceto-video.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"742\" \/>\n\t<meta property=\"og:image:height\" content=\"410\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriele Farina\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Farina\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cane-terrorizzato-dal-piccolo-criceto-video\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cane-terrorizzato-dal-piccolo-criceto-video\\\/\"},\"author\":{\"name\":\"Gabriele Farina\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"headline\":\"Il cane \u00e8 terrorizzato dal piccolo criceto &#8211; video\",\"datePublished\":\"2017-06-27T07:36:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cane-terrorizzato-dal-piccolo-criceto-video\\\/\"},\"wordCount\":38,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cane-terrorizzato-dal-piccolo-criceto-video\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2017\\\/06\\\/cane-criceto-video.jpg\",\"keywords\":[\"cane\",\"criceto\"],\"articleSection\":[\"Quattro zampe\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cane-terrorizzato-dal-piccolo-criceto-video\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cane-terrorizzato-dal-piccolo-criceto-video\\\/\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cane-terrorizzato-dal-piccolo-criceto-video\\\/\",\"name\":\"Il cane \u00e8 terrorizzato dal piccolo criceto - video - Quattro zampe e dintorni\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cane-terrorizzato-dal-piccolo-criceto-video\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cane-terrorizzato-dal-piccolo-criceto-video\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2017\\\/06\\\/cane-criceto-video.jpg\",\"datePublished\":\"2017-06-27T07:36:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\"},\"description\":\"Pu\u00f2 un cane grande e grosso essere terrorizzato da un minuscolo criceto, per di pi\u00f9 tenuto in mano dal suo padrone, al punto da non volerlo nemmeno\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cane-terrorizzato-dal-piccolo-criceto-video\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cane-terrorizzato-dal-piccolo-criceto-video\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cane-terrorizzato-dal-piccolo-criceto-video\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2017\\\/06\\\/cane-criceto-video.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2017\\\/06\\\/cane-criceto-video.jpg\",\"width\":742,\"height\":410},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cane-terrorizzato-dal-piccolo-criceto-video\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il cane \u00e8 terrorizzato dal piccolo criceto &#8211; video\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\",\"name\":\"Quattro zampe e dintorni\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/3d4a46ba85e808ba27b5c97af2f74c32\",\"name\":\"Gabriele Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g\",\"caption\":\"Gabriele Farina\"},\"description\":\"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO\",\"sameAs\":[\"gabriele.farina\",\"https:\\\/\\\/x.com\\\/solops\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/author\\\/gabriele-farina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il cane \u00e8 terrorizzato dal piccolo criceto - video - Quattro zampe e dintorni","description":"Pu\u00f2 un cane grande e grosso essere terrorizzato da un minuscolo criceto, per di pi\u00f9 tenuto in mano dal suo padrone, al punto da non volerlo nemmeno","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cane-terrorizzato-dal-piccolo-criceto-video\/","og_locale":"it_IT","og_type":"article","og_title":"Il cane \u00e8 terrorizzato dal piccolo criceto - video - Quattro zampe e dintorni","og_description":"Pu\u00f2 un cane grande e grosso essere terrorizzato da un minuscolo criceto, per di pi\u00f9 tenuto in mano dal suo padrone, al punto da non volerlo nemmeno","og_url":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cane-terrorizzato-dal-piccolo-criceto-video\/","og_site_name":"Quattro zampe e dintorni","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"gabriele.farina","article_published_time":"2017-06-27T07:36:30+00:00","og_image":[{"width":742,"height":410,"url":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2017\/06\/cane-criceto-video.jpg","type":"image\/jpeg"}],"author":"Gabriele Farina","twitter_misc":{"Scritto da":"Gabriele Farina"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cane-terrorizzato-dal-piccolo-criceto-video\/#article","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cane-terrorizzato-dal-piccolo-criceto-video\/"},"author":{"name":"Gabriele Farina","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"headline":"Il cane \u00e8 terrorizzato dal piccolo criceto &#8211; video","datePublished":"2017-06-27T07:36:30+00:00","mainEntityOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cane-terrorizzato-dal-piccolo-criceto-video\/"},"wordCount":38,"commentCount":0,"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cane-terrorizzato-dal-piccolo-criceto-video\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2017\/06\/cane-criceto-video.jpg","keywords":["cane","criceto"],"articleSection":["Quattro zampe"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cane-terrorizzato-dal-piccolo-criceto-video\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cane-terrorizzato-dal-piccolo-criceto-video\/","url":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cane-terrorizzato-dal-piccolo-criceto-video\/","name":"Il cane \u00e8 terrorizzato dal piccolo criceto - video - Quattro zampe e dintorni","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website"},"primaryImageOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cane-terrorizzato-dal-piccolo-criceto-video\/#primaryimage"},"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cane-terrorizzato-dal-piccolo-criceto-video\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2017\/06\/cane-criceto-video.jpg","datePublished":"2017-06-27T07:36:30+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32"},"description":"Pu\u00f2 un cane grande e grosso essere terrorizzato da un minuscolo criceto, per di pi\u00f9 tenuto in mano dal suo padrone, al punto da non volerlo nemmeno","breadcrumb":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cane-terrorizzato-dal-piccolo-criceto-video\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cane-terrorizzato-dal-piccolo-criceto-video\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cane-terrorizzato-dal-piccolo-criceto-video\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2017\/06\/cane-criceto-video.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2017\/06\/cane-criceto-video.jpg","width":742,"height":410},{"@type":"BreadcrumbList","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cane-terrorizzato-dal-piccolo-criceto-video\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/"},{"@type":"ListItem","position":2,"name":"Il cane \u00e8 terrorizzato dal piccolo criceto &#8211; video"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/","name":"Quattro zampe e dintorni","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/3d4a46ba85e808ba27b5c97af2f74c32","name":"Gabriele Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d631b633e16668ca195d50c5134af46a193f4fdaad431b46e8453b6acfd836?s=96&d=mm&r=g","caption":"Gabriele Farina"},"description":"Blogger, scrittore, regista, poeta, in fondo narratore di storie. Nel 2005 nasce il suo storico blog Vita di un IO","sameAs":["gabriele.farina","https:\/\/x.com\/solops"],"url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/author\/gabriele-farina\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/1619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/comments?post=1619"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/1619\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media\/1620"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media?parent=1619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/categories?post=1619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/tags?post=1619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}