{"id":1552,"date":"2016-02-25T20:12:23","date_gmt":"2016-02-25T19:12:23","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/?p=1552"},"modified":"2016-02-25T20:14:09","modified_gmt":"2016-02-25T19:14:09","slug":"il-futuro-dellidentificazione-delle-cacche-di-cane-passa-dal-dna-dellamico-fido","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/il-futuro-dellidentificazione-delle-cacche-di-cane-passa-dal-dna-dellamico-fido\/","title":{"rendered":"Il futuro dell&#8217;identificazione delle cacche di cane passa dal DNA dell&#8217;amico fido"},"content":{"rendered":"<p>Il Comune di Trieste che si \u00e8 a lungo interrogato su quali contromisure mettere in atto contro le cacche di cane ha detto basta e ha deciso di dichiarare guerra gli incivili. Per risalire agli autori del misfatto si <!--more-->\u00e8 deciso di usare un\u00a0metodo assolutamente scientifico che prevede la raccolta delle feci, che spetter\u00e0 agli agenti della polizia municipale o alla guardia ambientale del Comune a cui seguir\u00e0 l\u2019analisi in laboratorio e il controllo incrociato con un prelievo ematico del cane per un esame del dna . In questo modo sar\u00e0 possibile identificare il proprietario e mandargli la sanzione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Comune di Trieste che si \u00e8 a lungo interrogato su quali contromisure mettere in atto contro le cacche di cane ha detto basta e ha deciso di dichiarare guerra gli incivili. Per risalire agli autori del misfatto si<\/p>\n","protected":false},"author":1,"featured_media":1553,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1552","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-quattro-zampe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il futuro dell&#039;identificazione delle cacche di cane passa dal DNA dell&#039;amico fido - Quattro zampe e dintorni<\/title>\n<meta name=\"description\" content=\"Il Comune di Trieste che si \u00e8 a lungo interrogato su quali contromisure mettere in atto contro le cacche di cane ha detto basta e ha deciso di dichiarare\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/il-futuro-dellidentificazione-delle-cacche-di-cane-passa-dal-dna-dellamico-fido\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il futuro dell&#039;identificazione delle cacche di cane passa dal DNA dell&#039;amico fido - Quattro zampe e dintorni\" \/>\n<meta property=\"og:description\" content=\"Il Comune di Trieste che si \u00e8 a lungo interrogato su quali contromisure mettere in atto contro le cacche di cane ha detto basta e ha deciso di dichiarare\" \/>\n<meta property=\"og:url\" content=\"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/il-futuro-dellidentificazione-delle-cacche-di-cane-passa-dal-dna-dellamico-fido\/\" \/>\n<meta property=\"og:site_name\" content=\"Quattro zampe e dintorni\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-25T19:12:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-02-25T19:14:09+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2016\/02\/cacca-di-cane.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1360\" \/>\n\t<meta property=\"og:image:height\" content=\"1098\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/il-futuro-dellidentificazione-delle-cacche-di-cane-passa-dal-dna-dellamico-fido\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/il-futuro-dellidentificazione-delle-cacche-di-cane-passa-dal-dna-dellamico-fido\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"headline\":\"Il futuro dell&#8217;identificazione delle cacche di cane passa dal DNA dell&#8217;amico fido\",\"datePublished\":\"2016-02-25T19:12:23+00:00\",\"dateModified\":\"2016-02-25T19:14:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/il-futuro-dellidentificazione-delle-cacche-di-cane-passa-dal-dna-dellamico-fido\\\/\"},\"wordCount\":112,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/il-futuro-dellidentificazione-delle-cacche-di-cane-passa-dal-dna-dellamico-fido\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2016\\\/02\\\/cacca-di-cane.jpg\",\"articleSection\":[\"Quattro zampe\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/il-futuro-dellidentificazione-delle-cacche-di-cane-passa-dal-dna-dellamico-fido\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/il-futuro-dellidentificazione-delle-cacche-di-cane-passa-dal-dna-dellamico-fido\\\/\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/il-futuro-dellidentificazione-delle-cacche-di-cane-passa-dal-dna-dellamico-fido\\\/\",\"name\":\"Il futuro dell'identificazione delle cacche di cane passa dal DNA dell'amico fido - Quattro zampe e dintorni\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/il-futuro-dellidentificazione-delle-cacche-di-cane-passa-dal-dna-dellamico-fido\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/il-futuro-dellidentificazione-delle-cacche-di-cane-passa-dal-dna-dellamico-fido\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2016\\\/02\\\/cacca-di-cane.jpg\",\"datePublished\":\"2016-02-25T19:12:23+00:00\",\"dateModified\":\"2016-02-25T19:14:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"description\":\"Il Comune di Trieste che si \u00e8 a lungo interrogato su quali contromisure mettere in atto contro le cacche di cane ha detto basta e ha deciso di dichiarare\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/il-futuro-dellidentificazione-delle-cacche-di-cane-passa-dal-dna-dellamico-fido\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/il-futuro-dellidentificazione-delle-cacche-di-cane-passa-dal-dna-dellamico-fido\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/il-futuro-dellidentificazione-delle-cacche-di-cane-passa-dal-dna-dellamico-fido\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2016\\\/02\\\/cacca-di-cane.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2016\\\/02\\\/cacca-di-cane.jpg\",\"width\":1360,\"height\":1098},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/il-futuro-dellidentificazione-delle-cacche-di-cane-passa-dal-dna-dellamico-fido\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il futuro dell&#8217;identificazione delle cacche di cane passa dal DNA dell&#8217;amico fido\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\",\"name\":\"Quattro zampe e dintorni\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte\",\"sameAs\":[\"http:\\\/\\\/www.quotidianopiemontese.it\\\/\",\"https:\\\/\\\/www.facebook.com\\\/quotidianopiemontese\",\"https:\\\/\\\/x.com\\\/quotidianopiem\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/author\\\/administrator\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il futuro dell'identificazione delle cacche di cane passa dal DNA dell'amico fido - Quattro zampe e dintorni","description":"Il Comune di Trieste che si \u00e8 a lungo interrogato su quali contromisure mettere in atto contro le cacche di cane ha detto basta e ha deciso di dichiarare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/il-futuro-dellidentificazione-delle-cacche-di-cane-passa-dal-dna-dellamico-fido\/","og_locale":"it_IT","og_type":"article","og_title":"Il futuro dell'identificazione delle cacche di cane passa dal DNA dell'amico fido - Quattro zampe e dintorni","og_description":"Il Comune di Trieste che si \u00e8 a lungo interrogato su quali contromisure mettere in atto contro le cacche di cane ha detto basta e ha deciso di dichiarare","og_url":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/il-futuro-dellidentificazione-delle-cacche-di-cane-passa-dal-dna-dellamico-fido\/","og_site_name":"Quattro zampe e dintorni","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"https:\/\/www.facebook.com\/quotidianopiemontese","article_published_time":"2016-02-25T19:12:23+00:00","article_modified_time":"2016-02-25T19:14:09+00:00","og_image":[{"width":1360,"height":1098,"url":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2016\/02\/cacca-di-cane.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_misc":{"Scritto da":"Redazione"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/il-futuro-dellidentificazione-delle-cacche-di-cane-passa-dal-dna-dellamico-fido\/#article","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/il-futuro-dellidentificazione-delle-cacche-di-cane-passa-dal-dna-dellamico-fido\/"},"author":{"name":"Redazione","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"headline":"Il futuro dell&#8217;identificazione delle cacche di cane passa dal DNA dell&#8217;amico fido","datePublished":"2016-02-25T19:12:23+00:00","dateModified":"2016-02-25T19:14:09+00:00","mainEntityOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/il-futuro-dellidentificazione-delle-cacche-di-cane-passa-dal-dna-dellamico-fido\/"},"wordCount":112,"commentCount":0,"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/il-futuro-dellidentificazione-delle-cacche-di-cane-passa-dal-dna-dellamico-fido\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2016\/02\/cacca-di-cane.jpg","articleSection":["Quattro zampe"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/il-futuro-dellidentificazione-delle-cacche-di-cane-passa-dal-dna-dellamico-fido\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/il-futuro-dellidentificazione-delle-cacche-di-cane-passa-dal-dna-dellamico-fido\/","url":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/il-futuro-dellidentificazione-delle-cacche-di-cane-passa-dal-dna-dellamico-fido\/","name":"Il futuro dell'identificazione delle cacche di cane passa dal DNA dell'amico fido - Quattro zampe e dintorni","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website"},"primaryImageOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/il-futuro-dellidentificazione-delle-cacche-di-cane-passa-dal-dna-dellamico-fido\/#primaryimage"},"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/il-futuro-dellidentificazione-delle-cacche-di-cane-passa-dal-dna-dellamico-fido\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2016\/02\/cacca-di-cane.jpg","datePublished":"2016-02-25T19:12:23+00:00","dateModified":"2016-02-25T19:14:09+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"description":"Il Comune di Trieste che si \u00e8 a lungo interrogato su quali contromisure mettere in atto contro le cacche di cane ha detto basta e ha deciso di dichiarare","breadcrumb":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/il-futuro-dellidentificazione-delle-cacche-di-cane-passa-dal-dna-dellamico-fido\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/il-futuro-dellidentificazione-delle-cacche-di-cane-passa-dal-dna-dellamico-fido\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/il-futuro-dellidentificazione-delle-cacche-di-cane-passa-dal-dna-dellamico-fido\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2016\/02\/cacca-di-cane.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2016\/02\/cacca-di-cane.jpg","width":1360,"height":1098},{"@type":"BreadcrumbList","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/il-futuro-dellidentificazione-delle-cacche-di-cane-passa-dal-dna-dellamico-fido\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/"},{"@type":"ListItem","position":2,"name":"Il futuro dell&#8217;identificazione delle cacche di cane passa dal DNA dell&#8217;amico fido"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/","name":"Quattro zampe e dintorni","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","caption":"Redazione"},"description":"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte","sameAs":["http:\/\/www.quotidianopiemontese.it\/","https:\/\/www.facebook.com\/quotidianopiemontese","https:\/\/x.com\/quotidianopiem"],"url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/author\/administrator\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/1552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/comments?post=1552"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/1552\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media\/1553"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media?parent=1552"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/categories?post=1552"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/tags?post=1552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}