{"id":1364,"date":"2014-05-31T08:03:21","date_gmt":"2014-05-31T07:03:21","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/?p=1364"},"modified":"2014-05-30T20:15:59","modified_gmt":"2014-05-30T19:15:59","slug":"decalogo-ministero-salute-per-affrontare-stagione-calda-malesseri-per-fido-felix","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/decalogo-ministero-salute-per-affrontare-stagione-calda-malesseri-per-fido-felix\/","title":{"rendered":"Decalogo del Ministero della Salute per affrontare la stagione calda senza malesseri per Fido e Felix"},"content":{"rendered":"<p><a href=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2014\/05\/cane-caldo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-thumbnail wp-image-1365\" src=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2014\/05\/cane-caldo-150x150.jpg\" alt=\"cane-caldo\" width=\"150\" height=\"150\" \/><\/a>L&#8217;estate \u00e8 alle porte, come ogni anno in questo periodo d&#8217;altronde e per i felici proprietari bipedi\u00a0di cani e gatti, soprattutto i neo proprietari, \u00e8 il momento di valutare alcune piccole, ma importanti regole comportamentali per aiutare gli animali ad affrontare la stagione calda senza disagi. Il <a href=\"http:\/\/www.salute.gov.it\/portale\/news\/p3_2_1_1_1.jsp?lingua=italiano&amp;menu=notizie&amp;p=dalministero&amp;id=1138\">Ministero della Salute<\/a> pubblica sul proprio sito web un decalogo di consigli. Il caldo molto intenso e afoso, specie se con un elevato tasso di umidit\u00e0, pu\u00f2 essere un pericolo per Fido e Felix che possono andare incontro a colpi di calore o di sole. Cani, gatti, uccellini e altri piccoli animali d&#8217;affezione non sudano come noi umani, ma sono dotati di un sistema che raffreddi la temperatura corporea, che in pratica funga da ventilazione tramite frequenti e ritmati atti di respirazione. <!--more-->In tal modo fanno veicolare l&#8217;aria sulle loro superfici del cavo orale e disperdono il calore. E&#8217; meglio fare sempre attenzione a non lasciarli troppo a lungo all&#8217;aperto nelle ore calde, in modo particolare se gli animali sono cuccioli, malati, obesi o anziani. Le razze\u00a0brachicefale\u00a0come\u00a0bulldog\u00a0e\u00a0gatti persiani sono le pi\u00f9 sensibili ai colpi di sole.\u00a0Ecco l&#8217;opuscolo ministeriale, redatto nel 2013\u00a0e\u00a0sempre valido:\u00a0<a href=\"http:\/\/www.salute.gov.it\/imgs\/C_17_opuscoliPoster_189_allegato.pdf\">http:\/\/www.salute.gov.it\/imgs\/C_17_opuscoliPoster_189_allegato.pdf<\/a>\u00a0che spiega, non solo come prevenire alcuni malesseri di cane e gatto, ma anche come affrontare situazioni di improvviso malore dell&#8217;animale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;estate \u00e8 alle porte, come ogni anno in questo periodo d&#8217;altronde e per i felici proprietari bipedi\u00a0di cani e gatti, soprattutto i neo proprietari, \u00e8 il momento di valutare alcune piccole, ma importanti regole comportamentali per aiutare gli animali ad affrontare la stagione calda senza disagi. Il Ministero della Salute pubblica sul proprio sito web &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/decalogo-ministero-salute-per-affrontare-stagione-calda-malesseri-per-fido-felix\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Decalogo del Ministero della Salute per affrontare la stagione calda senza malesseri per Fido e Felix&#8221;<\/span><\/a><\/p>\n","protected":false},"author":46,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[425,11,1066,1064,3,1065,1063],"class_list":["post-1364","post","type-post","status-publish","format-standard","hentry","category-quattro-zampe","tag-bulldog","tag-cane","tag-cane-caldo","tag-colpo-sole","tag-gatto","tag-gatto-persiano","tag-ministero-salute"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Decalogo del Ministero della Salute per affrontare la stagione calda senza malesseri per Fido e Felix - Quattro zampe e dintorni<\/title>\n<meta name=\"description\" content=\"L&#039;estate \u00e8 alle porte, come ogni anno in questo periodo d&#039;altronde e per i felici proprietari bipedi\u00a0di cani e gatti, soprattutto i neo proprietari, \u00e8 il\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/decalogo-ministero-salute-per-affrontare-stagione-calda-malesseri-per-fido-felix\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Decalogo del Ministero della Salute per affrontare la stagione calda senza malesseri per Fido e Felix - Quattro zampe e dintorni\" \/>\n<meta property=\"og:description\" content=\"L&#039;estate \u00e8 alle porte, come ogni anno in questo periodo d&#039;altronde e per i felici proprietari bipedi\u00a0di cani e gatti, soprattutto i neo proprietari, \u00e8 il\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/decalogo-ministero-salute-per-affrontare-stagione-calda-malesseri-per-fido-felix\/\" \/>\n<meta property=\"og:site_name\" content=\"Quattro zampe e dintorni\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2014-05-31T07:03:21+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2014\/05\/cane-caldo-150x150.jpg\" \/>\n<meta name=\"author\" content=\"Monica Genovese\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Monica Genovese\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/decalogo-ministero-salute-per-affrontare-stagione-calda-malesseri-per-fido-felix\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/decalogo-ministero-salute-per-affrontare-stagione-calda-malesseri-per-fido-felix\\\/\"},\"author\":{\"name\":\"Monica Genovese\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\"},\"headline\":\"Decalogo del Ministero della Salute per affrontare la stagione calda senza malesseri per Fido e Felix\",\"datePublished\":\"2014-05-31T07:03:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/decalogo-ministero-salute-per-affrontare-stagione-calda-malesseri-per-fido-felix\\\/\"},\"wordCount\":249,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/decalogo-ministero-salute-per-affrontare-stagione-calda-malesseri-per-fido-felix\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2014\\\/05\\\/cane-caldo-150x150.jpg\",\"keywords\":[\"bulldog\",\"cane\",\"cane caldo\",\"colpo sole\",\"Gatto\",\"gatto persiano\",\"ministero salute\"],\"articleSection\":[\"Quattro zampe\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/decalogo-ministero-salute-per-affrontare-stagione-calda-malesseri-per-fido-felix\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/decalogo-ministero-salute-per-affrontare-stagione-calda-malesseri-per-fido-felix\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/decalogo-ministero-salute-per-affrontare-stagione-calda-malesseri-per-fido-felix\\\/\",\"name\":\"Decalogo del Ministero della Salute per affrontare la stagione calda senza malesseri per Fido e Felix - Quattro zampe e dintorni\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/decalogo-ministero-salute-per-affrontare-stagione-calda-malesseri-per-fido-felix\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/decalogo-ministero-salute-per-affrontare-stagione-calda-malesseri-per-fido-felix\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2014\\\/05\\\/cane-caldo-150x150.jpg\",\"datePublished\":\"2014-05-31T07:03:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\"},\"description\":\"L'estate \u00e8 alle porte, come ogni anno in questo periodo d'altronde e per i felici proprietari bipedi\u00a0di cani e gatti, soprattutto i neo proprietari, \u00e8 il\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/decalogo-ministero-salute-per-affrontare-stagione-calda-malesseri-per-fido-felix\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/decalogo-ministero-salute-per-affrontare-stagione-calda-malesseri-per-fido-felix\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/decalogo-ministero-salute-per-affrontare-stagione-calda-malesseri-per-fido-felix\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2014\\\/05\\\/cane-caldo-150x150.jpg\",\"contentUrl\":\"http:\\\/\\\/www.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2014\\\/05\\\/cane-caldo-150x150.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/decalogo-ministero-salute-per-affrontare-stagione-calda-malesseri-per-fido-felix\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Decalogo del Ministero della Salute per affrontare la stagione calda senza malesseri per Fido e Felix\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\",\"name\":\"Quattro zampe e dintorni\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\",\"name\":\"Monica Genovese\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"caption\":\"Monica Genovese\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Monica_Genovese\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/author\\\/monica-genovese\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Decalogo del Ministero della Salute per affrontare la stagione calda senza malesseri per Fido e Felix - Quattro zampe e dintorni","description":"L'estate \u00e8 alle porte, come ogni anno in questo periodo d'altronde e per i felici proprietari bipedi\u00a0di cani e gatti, soprattutto i neo proprietari, \u00e8 il","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/decalogo-ministero-salute-per-affrontare-stagione-calda-malesseri-per-fido-felix\/","og_locale":"it_IT","og_type":"article","og_title":"Decalogo del Ministero della Salute per affrontare la stagione calda senza malesseri per Fido e Felix - Quattro zampe e dintorni","og_description":"L'estate \u00e8 alle porte, come ogni anno in questo periodo d'altronde e per i felici proprietari bipedi\u00a0di cani e gatti, soprattutto i neo proprietari, \u00e8 il","og_url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/decalogo-ministero-salute-per-affrontare-stagione-calda-malesseri-per-fido-felix\/","og_site_name":"Quattro zampe e dintorni","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2014-05-31T07:03:21+00:00","og_image":[{"url":"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2014\/05\/cane-caldo-150x150.jpg","type":"","width":"","height":""}],"author":"Monica Genovese","twitter_misc":{"Scritto da":"Monica Genovese","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/decalogo-ministero-salute-per-affrontare-stagione-calda-malesseri-per-fido-felix\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/decalogo-ministero-salute-per-affrontare-stagione-calda-malesseri-per-fido-felix\/"},"author":{"name":"Monica Genovese","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce"},"headline":"Decalogo del Ministero della Salute per affrontare la stagione calda senza malesseri per Fido e Felix","datePublished":"2014-05-31T07:03:21+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/decalogo-ministero-salute-per-affrontare-stagione-calda-malesseri-per-fido-felix\/"},"wordCount":249,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/decalogo-ministero-salute-per-affrontare-stagione-calda-malesseri-per-fido-felix\/#primaryimage"},"thumbnailUrl":"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2014\/05\/cane-caldo-150x150.jpg","keywords":["bulldog","cane","cane caldo","colpo sole","Gatto","gatto persiano","ministero salute"],"articleSection":["Quattro zampe"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/decalogo-ministero-salute-per-affrontare-stagione-calda-malesseri-per-fido-felix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/decalogo-ministero-salute-per-affrontare-stagione-calda-malesseri-per-fido-felix\/","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/decalogo-ministero-salute-per-affrontare-stagione-calda-malesseri-per-fido-felix\/","name":"Decalogo del Ministero della Salute per affrontare la stagione calda senza malesseri per Fido e Felix - Quattro zampe e dintorni","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/decalogo-ministero-salute-per-affrontare-stagione-calda-malesseri-per-fido-felix\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/decalogo-ministero-salute-per-affrontare-stagione-calda-malesseri-per-fido-felix\/#primaryimage"},"thumbnailUrl":"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2014\/05\/cane-caldo-150x150.jpg","datePublished":"2014-05-31T07:03:21+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce"},"description":"L'estate \u00e8 alle porte, come ogni anno in questo periodo d'altronde e per i felici proprietari bipedi\u00a0di cani e gatti, soprattutto i neo proprietari, \u00e8 il","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/decalogo-ministero-salute-per-affrontare-stagione-calda-malesseri-per-fido-felix\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/decalogo-ministero-salute-per-affrontare-stagione-calda-malesseri-per-fido-felix\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/decalogo-ministero-salute-per-affrontare-stagione-calda-malesseri-per-fido-felix\/#primaryimage","url":"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2014\/05\/cane-caldo-150x150.jpg","contentUrl":"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2014\/05\/cane-caldo-150x150.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/decalogo-ministero-salute-per-affrontare-stagione-calda-malesseri-per-fido-felix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/"},{"@type":"ListItem","position":2,"name":"Decalogo del Ministero della Salute per affrontare la stagione calda senza malesseri per Fido e Felix"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/","name":"Quattro zampe e dintorni","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce","name":"Monica Genovese","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","caption":"Monica Genovese"},"sameAs":["https:\/\/x.com\/Monica_Genovese"],"url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/author\/monica-genovese\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/1364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/comments?post=1364"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/1364\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media?parent=1364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/categories?post=1364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/tags?post=1364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}