{"id":1285,"date":"2014-03-10T06:33:32","date_gmt":"2014-03-10T05:33:32","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/?p=1285"},"modified":"2014-02-28T18:55:54","modified_gmt":"2014-02-28T17:55:54","slug":"cani-e-gatti-affitto-animali-tempo-determinato-noleggiati-per-moda-o-test","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cani-e-gatti-affitto-animali-tempo-determinato-noleggiati-per-moda-o-test\/","title":{"rendered":"Cani e gatti in affitto. Animali a tempo determinato noleggiati per moda o test"},"content":{"rendered":"<p><a href=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2014\/02\/cucciolo_cane_1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-thumbnail wp-image-1288\" alt=\" \" src=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2014\/02\/cucciolo_cane_1-150x150.jpg\" width=\"150\" height=\"150\" \/><\/a>Cani, e gatti, in affitto per giapponesi, americani e, di recente anche europei. Nuova tendenza e, al tempo stesso, esperimento per verificare se certi bipedi e animali possano andare d&#8217;accordo e condividere un appartamento e la vita. L&#8217;idea, la cui paternit\u00e0, o maternit\u00e0 che dir si voglia, spazia dal Giappone agli Stati Uniti d&#8217;America dove c&#8217;\u00e8 addirittura un&#8217;agenzia di dog rental, la\u00a0FlexPetz che noleggia (o almeno lo ha fatto fino a poco tempo fa visto che, forse sta per chiudere i battenti) quattro zampe a ore, giorni, a chi non pu\u00f2 o non vuole curarli full time e a tempo indefinito. Se l&#8217;affittuario non \u00e8 in grado di permettersi un cane, magari di razza, quindi costoso, o un cucciolo perch\u00e9 vive in una piccola casa o lavora tutto il giorno e non potrebbe occuparsene, ecco che la soluzione \u00e8 a portata di mano. <!--more-->Poche ore di coccole e svago e poi la restituzione. Si va al parco con il cane di tendenza, quello del momento, per essere pi\u00f9 glamour, alla moda e, magari passeggiare con l&#8217;animale pi\u00f9 pregiato e in tinta con i propri capelli! In alcuni casi, le persone, ad esempio genitori che vogliono mettere alla prova i loro pargoli, noleggiano i cani per testare se i figli siano capaci di gestirli, prima di passare in canile (o, ahime&#8217; al negozio a comprarli) per l&#8217;adozione. In tale ultimo caso, l&#8217;affitto pu\u00f2 essere utile, ma siamo sicuri che i cani gradiscano avere, ogni volta, un padrone bipede temporaneo a cui affezionarsi per poi tornare in agenzia per un successivo noleggio?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cani, e gatti, in affitto per giapponesi, americani e, di recente anche europei. Nuova tendenza e, al tempo stesso, esperimento per verificare se certi bipedi e animali possano andare d&#8217;accordo e condividere un appartamento e la vita. L&#8217;idea, la cui paternit\u00e0, o maternit\u00e0 che dir si voglia, spazia dal Giappone agli Stati Uniti d&#8217;America dove &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cani-e-gatti-affitto-animali-tempo-determinato-noleggiati-per-moda-o-test\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Cani e gatti in affitto. Animali a tempo determinato noleggiati per moda o test&#8221;<\/span><\/a><\/p>\n","protected":false},"author":46,"featured_media":1288,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[1021,1019,1020,1022],"class_list":["post-1285","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-quattro-zampe","tag-cani-noleggio","tag-dog-rental","tag-flex-petz","tag-noleggiare-cane"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cani e gatti in affitto. Animali a tempo determinato noleggiati per moda o test - Quattro zampe e dintorni<\/title>\n<meta name=\"description\" content=\"Cani, e gatti, in affitto per giapponesi, americani e, di recente anche europei. Nuova tendenza e, al tempo stesso, esperimento per verificare se certi\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cani-e-gatti-affitto-animali-tempo-determinato-noleggiati-per-moda-o-test\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cani e gatti in affitto. Animali a tempo determinato noleggiati per moda o test - Quattro zampe e dintorni\" \/>\n<meta property=\"og:description\" content=\"Cani, e gatti, in affitto per giapponesi, americani e, di recente anche europei. Nuova tendenza e, al tempo stesso, esperimento per verificare se certi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cani-e-gatti-affitto-animali-tempo-determinato-noleggiati-per-moda-o-test\/\" \/>\n<meta property=\"og:site_name\" content=\"Quattro zampe e dintorni\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2014-03-10T05:33:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2014\/02\/cucciolo_cane_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"301\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Monica Genovese\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Monica Genovese\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cani-e-gatti-affitto-animali-tempo-determinato-noleggiati-per-moda-o-test\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cani-e-gatti-affitto-animali-tempo-determinato-noleggiati-per-moda-o-test\\\/\"},\"author\":{\"name\":\"Monica Genovese\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\"},\"headline\":\"Cani e gatti in affitto. Animali a tempo determinato noleggiati per moda o test\",\"datePublished\":\"2014-03-10T05:33:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cani-e-gatti-affitto-animali-tempo-determinato-noleggiati-per-moda-o-test\\\/\"},\"wordCount\":281,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cani-e-gatti-affitto-animali-tempo-determinato-noleggiati-per-moda-o-test\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2014\\\/02\\\/cucciolo_cane_1.jpg\",\"keywords\":[\"cani noleggio\",\"dog rental\",\"flex petz\",\"noleggiare cane\"],\"articleSection\":[\"Quattro zampe\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cani-e-gatti-affitto-animali-tempo-determinato-noleggiati-per-moda-o-test\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cani-e-gatti-affitto-animali-tempo-determinato-noleggiati-per-moda-o-test\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cani-e-gatti-affitto-animali-tempo-determinato-noleggiati-per-moda-o-test\\\/\",\"name\":\"Cani e gatti in affitto. Animali a tempo determinato noleggiati per moda o test - Quattro zampe e dintorni\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cani-e-gatti-affitto-animali-tempo-determinato-noleggiati-per-moda-o-test\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cani-e-gatti-affitto-animali-tempo-determinato-noleggiati-per-moda-o-test\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2014\\\/02\\\/cucciolo_cane_1.jpg\",\"datePublished\":\"2014-03-10T05:33:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\"},\"description\":\"Cani, e gatti, in affitto per giapponesi, americani e, di recente anche europei. Nuova tendenza e, al tempo stesso, esperimento per verificare se certi\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cani-e-gatti-affitto-animali-tempo-determinato-noleggiati-per-moda-o-test\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cani-e-gatti-affitto-animali-tempo-determinato-noleggiati-per-moda-o-test\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cani-e-gatti-affitto-animali-tempo-determinato-noleggiati-per-moda-o-test\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2014\\\/02\\\/cucciolo_cane_1.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2014\\\/02\\\/cucciolo_cane_1.jpg\",\"width\":480,\"height\":301},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/cani-e-gatti-affitto-animali-tempo-determinato-noleggiati-per-moda-o-test\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cani e gatti in affitto. Animali a tempo determinato noleggiati per moda o test\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\",\"name\":\"Quattro zampe e dintorni\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\",\"name\":\"Monica Genovese\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"caption\":\"Monica Genovese\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Monica_Genovese\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/author\\\/monica-genovese\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cani e gatti in affitto. Animali a tempo determinato noleggiati per moda o test - Quattro zampe e dintorni","description":"Cani, e gatti, in affitto per giapponesi, americani e, di recente anche europei. Nuova tendenza e, al tempo stesso, esperimento per verificare se certi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cani-e-gatti-affitto-animali-tempo-determinato-noleggiati-per-moda-o-test\/","og_locale":"it_IT","og_type":"article","og_title":"Cani e gatti in affitto. Animali a tempo determinato noleggiati per moda o test - Quattro zampe e dintorni","og_description":"Cani, e gatti, in affitto per giapponesi, americani e, di recente anche europei. Nuova tendenza e, al tempo stesso, esperimento per verificare se certi","og_url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cani-e-gatti-affitto-animali-tempo-determinato-noleggiati-per-moda-o-test\/","og_site_name":"Quattro zampe e dintorni","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2014-03-10T05:33:32+00:00","og_image":[{"width":480,"height":301,"url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2014\/02\/cucciolo_cane_1.jpg","type":"image\/jpeg"}],"author":"Monica Genovese","twitter_misc":{"Scritto da":"Monica Genovese","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cani-e-gatti-affitto-animali-tempo-determinato-noleggiati-per-moda-o-test\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cani-e-gatti-affitto-animali-tempo-determinato-noleggiati-per-moda-o-test\/"},"author":{"name":"Monica Genovese","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce"},"headline":"Cani e gatti in affitto. Animali a tempo determinato noleggiati per moda o test","datePublished":"2014-03-10T05:33:32+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cani-e-gatti-affitto-animali-tempo-determinato-noleggiati-per-moda-o-test\/"},"wordCount":281,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cani-e-gatti-affitto-animali-tempo-determinato-noleggiati-per-moda-o-test\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2014\/02\/cucciolo_cane_1.jpg","keywords":["cani noleggio","dog rental","flex petz","noleggiare cane"],"articleSection":["Quattro zampe"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cani-e-gatti-affitto-animali-tempo-determinato-noleggiati-per-moda-o-test\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cani-e-gatti-affitto-animali-tempo-determinato-noleggiati-per-moda-o-test\/","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cani-e-gatti-affitto-animali-tempo-determinato-noleggiati-per-moda-o-test\/","name":"Cani e gatti in affitto. Animali a tempo determinato noleggiati per moda o test - Quattro zampe e dintorni","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cani-e-gatti-affitto-animali-tempo-determinato-noleggiati-per-moda-o-test\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cani-e-gatti-affitto-animali-tempo-determinato-noleggiati-per-moda-o-test\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2014\/02\/cucciolo_cane_1.jpg","datePublished":"2014-03-10T05:33:32+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce"},"description":"Cani, e gatti, in affitto per giapponesi, americani e, di recente anche europei. Nuova tendenza e, al tempo stesso, esperimento per verificare se certi","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cani-e-gatti-affitto-animali-tempo-determinato-noleggiati-per-moda-o-test\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cani-e-gatti-affitto-animali-tempo-determinato-noleggiati-per-moda-o-test\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cani-e-gatti-affitto-animali-tempo-determinato-noleggiati-per-moda-o-test\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2014\/02\/cucciolo_cane_1.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2014\/02\/cucciolo_cane_1.jpg","width":480,"height":301},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/cani-e-gatti-affitto-animali-tempo-determinato-noleggiati-per-moda-o-test\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/"},{"@type":"ListItem","position":2,"name":"Cani e gatti in affitto. Animali a tempo determinato noleggiati per moda o test"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/","name":"Quattro zampe e dintorni","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce","name":"Monica Genovese","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","caption":"Monica Genovese"},"sameAs":["https:\/\/x.com\/Monica_Genovese"],"url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/author\/monica-genovese\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/1285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/comments?post=1285"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/1285\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media\/1288"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media?parent=1285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/categories?post=1285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/tags?post=1285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}