{"id":1274,"date":"2014-03-03T06:54:58","date_gmt":"2014-03-03T05:54:58","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/?p=1274"},"modified":"2014-03-04T15:07:30","modified_gmt":"2014-03-04T14:07:30","slug":"giapponesi-sempre-piu-simili-ai-gatti-indossano-orecchie-controllo-neuronale-per-drizzarle-o-rilassarle-come-felix","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/giapponesi-sempre-piu-simili-ai-gatti-indossano-orecchie-controllo-neuronale-per-drizzarle-o-rilassarle-come-felix\/","title":{"rendered":"Giapponesi sempre pi\u00f9 simili ai gatti. Indossano orecchie a controllo neuronale per drizzarle o rilassarle come Felix"},"content":{"rendered":"<p><a href=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2014\/02\/12_necomimi.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-thumbnail wp-image-1275\" alt=\" \" src=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2014\/02\/12_necomimi-150x150.jpg\" width=\"150\" height=\"150\" \/><\/a>I giapponesi sono amanti dei gatti. Sono dei portafortuna. Li apprezzano, li coccolano e, in alcuni casi, li imitano. Come? Indossando delle belle orecchie, di qualsivoglia colore, come quelle dei felini sopra la propria testa. Si tratta di un cerchietto dotato di orecchie di gatto che funzionano, si animano, vivono di vita propria grazie al controllo wireless dei neuroni. In pratica, chi le indossa, a seconda delle emozioni che prova, pu\u00f2 far drizzare o rilassare le orecchie, proprio come fanno i mici. Una vera mania per somigliare ai loro beniamini a quattro zampe. Forse, un po&#8217; eccessivo! Le originali orecchie di gatto Nekomini sono opera della ditta\u00a0<a href=\"http:\/\/neurowear.com\/news\/index.html\">Neurowear <\/a>che desidera aumentare le abilit\u00e0 umane attraverso sensori di onde cerebrali. Il gatto, tramite onde che invia ai suoi neuroni, evidenzia il proprio stato d&#8217;animo. <!--more-->Ecco che, in una forma simile, anche i giapponesi possono fare la medesima cosa! Ma, una volta non c&#8217;era la parola per esprimere i pensieri senza l&#8217;uso di orecchie fittizie? \u00a0E se le orecchie non bastano, a completare il corredo felino, arriva pure la coda. Si chiama Nekoshippo ed \u00e8 agganciata ad una leggera cintura legata in vita. Si indossa semplicemente, ovunque e, anche in tal caso pu\u00f2 esprimere le proprie emozioni attraverso tre posizioni, a riposo, di allarme e quella da forti sentimenti.<\/p>\n<p>Alcuni ritengono orecchie e coda un gioco, una moda, altri invece credono che, a lungo andare, possano rappresentare un veicolo per consentire ai diversamente abili, agli affetti da autismo, ad esempio di mostrare ci\u00f2 che provano anche se, forse si potrebbero creare supporti un po&#8217; meno animaleschi. In fondo chi ha detto che girare con la coda (e sedersi, soprattutto) sia cos\u00ec comodo!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I giapponesi sono amanti dei gatti. Sono dei portafortuna. Li apprezzano, li coccolano e, in alcuni casi, li imitano. Come? Indossando delle belle orecchie, di qualsivoglia colore, come quelle dei felini sopra la propria testa. Si tratta di un cerchietto dotato di orecchie di gatto che funzionano, si animano, vivono di vita propria grazie al &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/giapponesi-sempre-piu-simili-ai-gatti-indossano-orecchie-controllo-neuronale-per-drizzarle-o-rilassarle-come-felix\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Giapponesi sempre pi\u00f9 simili ai gatti. Indossano orecchie a controllo neuronale per drizzarle o rilassarle come Felix&#8221;<\/span><\/a><\/p>\n","protected":false},"author":46,"featured_media":1275,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[1017,1016,1015,1018],"class_list":["post-1274","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-quattro-zampe","tag-nekomini","tag-nekoshippo","tag-neurowear","tag-orecchie-gatto-giapponesi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Giapponesi sempre pi\u00f9 simili ai gatti. Indossano orecchie a controllo neuronale per drizzarle o rilassarle come Felix - Quattro zampe e dintorni<\/title>\n<meta name=\"description\" content=\"I giapponesi sono amanti dei gatti. Sono dei portafortuna. Li apprezzano, li coccolano e, in alcuni casi, li imitano. Come? Indossando delle belle\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/giapponesi-sempre-piu-simili-ai-gatti-indossano-orecchie-controllo-neuronale-per-drizzarle-o-rilassarle-come-felix\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giapponesi sempre pi\u00f9 simili ai gatti. Indossano orecchie a controllo neuronale per drizzarle o rilassarle come Felix - Quattro zampe e dintorni\" \/>\n<meta property=\"og:description\" content=\"I giapponesi sono amanti dei gatti. Sono dei portafortuna. Li apprezzano, li coccolano e, in alcuni casi, li imitano. Come? Indossando delle belle\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/giapponesi-sempre-piu-simili-ai-gatti-indossano-orecchie-controllo-neuronale-per-drizzarle-o-rilassarle-come-felix\/\" \/>\n<meta property=\"og:site_name\" content=\"Quattro zampe e dintorni\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2014-03-03T05:54:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-03-04T14:07:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2014\/02\/12_necomimi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Monica Genovese\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Monica Genovese\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/giapponesi-sempre-piu-simili-ai-gatti-indossano-orecchie-controllo-neuronale-per-drizzarle-o-rilassarle-come-felix\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/giapponesi-sempre-piu-simili-ai-gatti-indossano-orecchie-controllo-neuronale-per-drizzarle-o-rilassarle-come-felix\\\/\"},\"author\":{\"name\":\"Monica Genovese\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\"},\"headline\":\"Giapponesi sempre pi\u00f9 simili ai gatti. Indossano orecchie a controllo neuronale per drizzarle o rilassarle come Felix\",\"datePublished\":\"2014-03-03T05:54:58+00:00\",\"dateModified\":\"2014-03-04T14:07:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/giapponesi-sempre-piu-simili-ai-gatti-indossano-orecchie-controllo-neuronale-per-drizzarle-o-rilassarle-come-felix\\\/\"},\"wordCount\":299,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/giapponesi-sempre-piu-simili-ai-gatti-indossano-orecchie-controllo-neuronale-per-drizzarle-o-rilassarle-come-felix\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2014\\\/02\\\/12_necomimi.jpg\",\"keywords\":[\"Nekomini\",\"Nekoshippo\",\"Neurowear\",\"orecchie gatto giapponesi\"],\"articleSection\":[\"Quattro zampe\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/giapponesi-sempre-piu-simili-ai-gatti-indossano-orecchie-controllo-neuronale-per-drizzarle-o-rilassarle-come-felix\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/giapponesi-sempre-piu-simili-ai-gatti-indossano-orecchie-controllo-neuronale-per-drizzarle-o-rilassarle-come-felix\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/giapponesi-sempre-piu-simili-ai-gatti-indossano-orecchie-controllo-neuronale-per-drizzarle-o-rilassarle-come-felix\\\/\",\"name\":\"Giapponesi sempre pi\u00f9 simili ai gatti. Indossano orecchie a controllo neuronale per drizzarle o rilassarle come Felix - Quattro zampe e dintorni\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/giapponesi-sempre-piu-simili-ai-gatti-indossano-orecchie-controllo-neuronale-per-drizzarle-o-rilassarle-come-felix\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/giapponesi-sempre-piu-simili-ai-gatti-indossano-orecchie-controllo-neuronale-per-drizzarle-o-rilassarle-come-felix\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2014\\\/02\\\/12_necomimi.jpg\",\"datePublished\":\"2014-03-03T05:54:58+00:00\",\"dateModified\":\"2014-03-04T14:07:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\"},\"description\":\"I giapponesi sono amanti dei gatti. Sono dei portafortuna. Li apprezzano, li coccolano e, in alcuni casi, li imitano. Come? Indossando delle belle\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/giapponesi-sempre-piu-simili-ai-gatti-indossano-orecchie-controllo-neuronale-per-drizzarle-o-rilassarle-come-felix\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/giapponesi-sempre-piu-simili-ai-gatti-indossano-orecchie-controllo-neuronale-per-drizzarle-o-rilassarle-come-felix\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/giapponesi-sempre-piu-simili-ai-gatti-indossano-orecchie-controllo-neuronale-per-drizzarle-o-rilassarle-come-felix\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2014\\\/02\\\/12_necomimi.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2014\\\/02\\\/12_necomimi.jpg\",\"width\":400,\"height\":250},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/giapponesi-sempre-piu-simili-ai-gatti-indossano-orecchie-controllo-neuronale-per-drizzarle-o-rilassarle-come-felix\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Giapponesi sempre pi\u00f9 simili ai gatti. Indossano orecchie a controllo neuronale per drizzarle o rilassarle come Felix\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\",\"name\":\"Quattro zampe e dintorni\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\",\"name\":\"Monica Genovese\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"caption\":\"Monica Genovese\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Monica_Genovese\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/author\\\/monica-genovese\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Giapponesi sempre pi\u00f9 simili ai gatti. Indossano orecchie a controllo neuronale per drizzarle o rilassarle come Felix - Quattro zampe e dintorni","description":"I giapponesi sono amanti dei gatti. Sono dei portafortuna. Li apprezzano, li coccolano e, in alcuni casi, li imitano. Come? Indossando delle belle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/giapponesi-sempre-piu-simili-ai-gatti-indossano-orecchie-controllo-neuronale-per-drizzarle-o-rilassarle-come-felix\/","og_locale":"it_IT","og_type":"article","og_title":"Giapponesi sempre pi\u00f9 simili ai gatti. Indossano orecchie a controllo neuronale per drizzarle o rilassarle come Felix - Quattro zampe e dintorni","og_description":"I giapponesi sono amanti dei gatti. Sono dei portafortuna. Li apprezzano, li coccolano e, in alcuni casi, li imitano. Come? Indossando delle belle","og_url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/giapponesi-sempre-piu-simili-ai-gatti-indossano-orecchie-controllo-neuronale-per-drizzarle-o-rilassarle-come-felix\/","og_site_name":"Quattro zampe e dintorni","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2014-03-03T05:54:58+00:00","article_modified_time":"2014-03-04T14:07:30+00:00","og_image":[{"width":400,"height":250,"url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2014\/02\/12_necomimi.jpg","type":"image\/jpeg"}],"author":"Monica Genovese","twitter_misc":{"Scritto da":"Monica Genovese","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/giapponesi-sempre-piu-simili-ai-gatti-indossano-orecchie-controllo-neuronale-per-drizzarle-o-rilassarle-come-felix\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/giapponesi-sempre-piu-simili-ai-gatti-indossano-orecchie-controllo-neuronale-per-drizzarle-o-rilassarle-come-felix\/"},"author":{"name":"Monica Genovese","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce"},"headline":"Giapponesi sempre pi\u00f9 simili ai gatti. Indossano orecchie a controllo neuronale per drizzarle o rilassarle come Felix","datePublished":"2014-03-03T05:54:58+00:00","dateModified":"2014-03-04T14:07:30+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/giapponesi-sempre-piu-simili-ai-gatti-indossano-orecchie-controllo-neuronale-per-drizzarle-o-rilassarle-come-felix\/"},"wordCount":299,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/giapponesi-sempre-piu-simili-ai-gatti-indossano-orecchie-controllo-neuronale-per-drizzarle-o-rilassarle-come-felix\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2014\/02\/12_necomimi.jpg","keywords":["Nekomini","Nekoshippo","Neurowear","orecchie gatto giapponesi"],"articleSection":["Quattro zampe"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/giapponesi-sempre-piu-simili-ai-gatti-indossano-orecchie-controllo-neuronale-per-drizzarle-o-rilassarle-come-felix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/giapponesi-sempre-piu-simili-ai-gatti-indossano-orecchie-controllo-neuronale-per-drizzarle-o-rilassarle-come-felix\/","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/giapponesi-sempre-piu-simili-ai-gatti-indossano-orecchie-controllo-neuronale-per-drizzarle-o-rilassarle-come-felix\/","name":"Giapponesi sempre pi\u00f9 simili ai gatti. Indossano orecchie a controllo neuronale per drizzarle o rilassarle come Felix - Quattro zampe e dintorni","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/giapponesi-sempre-piu-simili-ai-gatti-indossano-orecchie-controllo-neuronale-per-drizzarle-o-rilassarle-come-felix\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/giapponesi-sempre-piu-simili-ai-gatti-indossano-orecchie-controllo-neuronale-per-drizzarle-o-rilassarle-come-felix\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2014\/02\/12_necomimi.jpg","datePublished":"2014-03-03T05:54:58+00:00","dateModified":"2014-03-04T14:07:30+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce"},"description":"I giapponesi sono amanti dei gatti. Sono dei portafortuna. Li apprezzano, li coccolano e, in alcuni casi, li imitano. Come? Indossando delle belle","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/giapponesi-sempre-piu-simili-ai-gatti-indossano-orecchie-controllo-neuronale-per-drizzarle-o-rilassarle-come-felix\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/giapponesi-sempre-piu-simili-ai-gatti-indossano-orecchie-controllo-neuronale-per-drizzarle-o-rilassarle-come-felix\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/giapponesi-sempre-piu-simili-ai-gatti-indossano-orecchie-controllo-neuronale-per-drizzarle-o-rilassarle-come-felix\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2014\/02\/12_necomimi.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2014\/02\/12_necomimi.jpg","width":400,"height":250},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/giapponesi-sempre-piu-simili-ai-gatti-indossano-orecchie-controllo-neuronale-per-drizzarle-o-rilassarle-come-felix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/"},{"@type":"ListItem","position":2,"name":"Giapponesi sempre pi\u00f9 simili ai gatti. Indossano orecchie a controllo neuronale per drizzarle o rilassarle come Felix"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/","name":"Quattro zampe e dintorni","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce","name":"Monica Genovese","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","caption":"Monica Genovese"},"sameAs":["https:\/\/x.com\/Monica_Genovese"],"url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/author\/monica-genovese\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/1274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/comments?post=1274"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/1274\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media\/1275"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media?parent=1274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/categories?post=1274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/tags?post=1274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}