{"id":1187,"date":"2013-12-09T12:29:31","date_gmt":"2013-12-09T11:29:31","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/?p=1187"},"modified":"2013-12-09T15:30:25","modified_gmt":"2013-12-09T14:30:25","slug":"bistecca-di-cane-anche-europa-approvata-commestibilita-e-commercio","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/bistecca-di-cane-anche-europa-approvata-commestibilita-e-commercio\/","title":{"rendered":"Bistecca di cane anche in Europa. Approvata commestibilit\u00e0 e commercio ma \u00e8 una bufala"},"content":{"rendered":"<p><a href=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/12\/cina_cani.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-thumbnail wp-image-1188\" alt=\"cina_cani\" src=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/12\/cina_cani-150x150.jpg\" width=\"150\" height=\"150\" \/><\/a>Che direste se, nel vostro piatto al posto della solita carne di bovino, anatra o maiale, trovaste una bistecca di cane? Si, proprio cane, magari della stessa razza del vostro amatissimo Fido! In molti Paesi, soprattutto asiatici, questo animale che da anni ci fa compagnia in casa, viene mangiato e, addirittura alcune razze canine vengono allevate proprio per la macellazione. Gira in Rete da un po&#8217; l&#8217;inquietante informazione che il prossimo anno anche l&#8217;Europa diventer\u00e0 mangiatrice di cani, con l&#8217;entrata in vigore della <a href=\"http:\/\/oknotizie.virgilio.it\/go.php?us=20f58a6956f54f1f\">certificazione di commestibilit\u00e0 <\/a>richiesta da una societ\u00e0 di ristorazione di nome \u201cXinshipu Ltd\u201d per consentire \u00a0l\u2019importazione di carni congelate di cane d\u2019allevamento per consumatori cinesi e la commercializzazione legale nei supermarket gastronomici etnici. <a href=\"http:\/\/www.giornalettismo.com\/archives\/1256361\/la-bufala-dei-cani\/\">Tale certificazione non esiste<\/a>. Si tratta di una notizia bufala. Infondate, a quanto pare, anche le voci di un<a href=\"http:\/\/www.affaritaliani.it\/cronache\/carne-cane-commestibilit-commercio091213.html\"> blocco alle importazioni europee in Cina <\/a>di carni di cavallo e coniglio, sacri secondo la tradizione cinese e che, pertanto arrivano da altri Paesi, proprio per spingere i governi della vecchia Europa ad approvare l&#8217;introduzione di carni di cane per i cittadini cinesi che risiedono all&#8217;estero.<!--more-->C&#8217;\u00e8 di che esser sollevati, sebbene il problema della carne di cane e gatto &#8220;abusiva&#8221; nel piatto esista e gi\u00e0 da tempo. Si sprecano, infatti, notizie di ritrovamenti di macelli in nero che lavorano carni animali di importazioni illegali. Molti cani e gatti vengono introdotti, illegalmente in Europa per il consumo. Non necessariamente, il trascorrere del tempo vuol dire evoluzione umana, almeno dal punto di vista morale e civile.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Che direste se, nel vostro piatto al posto della solita carne di bovino, anatra o maiale, trovaste una bistecca di cane? Si, proprio cane, magari della stessa razza del vostro amatissimo Fido! In molti Paesi, soprattutto asiatici, questo animale che da anni ci fa compagnia in casa, viene mangiato e, addirittura alcune razze canine vengono &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/bistecca-di-cane-anche-europa-approvata-commestibilita-e-commercio\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Bistecca di cane anche in Europa. Approvata commestibilit\u00e0 e commercio ma \u00e8 una bufala&#8221;<\/span><\/a><\/p>\n","protected":false},"author":46,"featured_media":1188,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[958,955,957,956],"class_list":["post-1187","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-quattro-zampe","tag-cane-nel-piatto","tag-carne-di-cane","tag-commestibilita-carne-cane","tag-xinshipu-ltd"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bistecca di cane anche in Europa. Approvata commestibilit\u00e0 e commercio ma \u00e8 una bufala - Quattro zampe e dintorni<\/title>\n<meta name=\"description\" content=\"Che direste se, nel vostro piatto al posto della solita carne di bovino, anatra o maiale, trovaste una bistecca di cane? Si, proprio cane, magari della\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/bistecca-di-cane-anche-europa-approvata-commestibilita-e-commercio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bistecca di cane anche in Europa. Approvata commestibilit\u00e0 e commercio ma \u00e8 una bufala - Quattro zampe e dintorni\" \/>\n<meta property=\"og:description\" content=\"Che direste se, nel vostro piatto al posto della solita carne di bovino, anatra o maiale, trovaste una bistecca di cane? Si, proprio cane, magari della\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/bistecca-di-cane-anche-europa-approvata-commestibilita-e-commercio\/\" \/>\n<meta property=\"og:site_name\" content=\"Quattro zampe e dintorni\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2013-12-09T11:29:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-12-09T14:30:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/12\/cina_cani.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"354\" \/>\n\t<meta property=\"og:image:height\" content=\"280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Monica Genovese\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Monica Genovese\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/bistecca-di-cane-anche-europa-approvata-commestibilita-e-commercio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/bistecca-di-cane-anche-europa-approvata-commestibilita-e-commercio\\\/\"},\"author\":{\"name\":\"Monica Genovese\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\"},\"headline\":\"Bistecca di cane anche in Europa. Approvata commestibilit\u00e0 e commercio ma \u00e8 una bufala\",\"datePublished\":\"2013-12-09T11:29:31+00:00\",\"dateModified\":\"2013-12-09T14:30:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/bistecca-di-cane-anche-europa-approvata-commestibilita-e-commercio\\\/\"},\"wordCount\":271,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/bistecca-di-cane-anche-europa-approvata-commestibilita-e-commercio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2013\\\/12\\\/cina_cani.jpg\",\"keywords\":[\"cane nel piatto\",\"carne di cane\",\"commestibilit\u00e0 carne cane\",\"Xinshipu Ltd\"],\"articleSection\":[\"Quattro zampe\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/bistecca-di-cane-anche-europa-approvata-commestibilita-e-commercio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/bistecca-di-cane-anche-europa-approvata-commestibilita-e-commercio\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/bistecca-di-cane-anche-europa-approvata-commestibilita-e-commercio\\\/\",\"name\":\"Bistecca di cane anche in Europa. Approvata commestibilit\u00e0 e commercio ma \u00e8 una bufala - Quattro zampe e dintorni\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/bistecca-di-cane-anche-europa-approvata-commestibilita-e-commercio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/bistecca-di-cane-anche-europa-approvata-commestibilita-e-commercio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2013\\\/12\\\/cina_cani.jpg\",\"datePublished\":\"2013-12-09T11:29:31+00:00\",\"dateModified\":\"2013-12-09T14:30:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\"},\"description\":\"Che direste se, nel vostro piatto al posto della solita carne di bovino, anatra o maiale, trovaste una bistecca di cane? Si, proprio cane, magari della\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/bistecca-di-cane-anche-europa-approvata-commestibilita-e-commercio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/bistecca-di-cane-anche-europa-approvata-commestibilita-e-commercio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/bistecca-di-cane-anche-europa-approvata-commestibilita-e-commercio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2013\\\/12\\\/cina_cani.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2013\\\/12\\\/cina_cani.jpg\",\"width\":354,\"height\":280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/bistecca-di-cane-anche-europa-approvata-commestibilita-e-commercio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bistecca di cane anche in Europa. Approvata commestibilit\u00e0 e commercio ma \u00e8 una bufala\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\",\"name\":\"Quattro zampe e dintorni\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\",\"name\":\"Monica Genovese\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"caption\":\"Monica Genovese\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Monica_Genovese\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/author\\\/monica-genovese\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bistecca di cane anche in Europa. Approvata commestibilit\u00e0 e commercio ma \u00e8 una bufala - Quattro zampe e dintorni","description":"Che direste se, nel vostro piatto al posto della solita carne di bovino, anatra o maiale, trovaste una bistecca di cane? Si, proprio cane, magari della","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/bistecca-di-cane-anche-europa-approvata-commestibilita-e-commercio\/","og_locale":"it_IT","og_type":"article","og_title":"Bistecca di cane anche in Europa. Approvata commestibilit\u00e0 e commercio ma \u00e8 una bufala - Quattro zampe e dintorni","og_description":"Che direste se, nel vostro piatto al posto della solita carne di bovino, anatra o maiale, trovaste una bistecca di cane? Si, proprio cane, magari della","og_url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/bistecca-di-cane-anche-europa-approvata-commestibilita-e-commercio\/","og_site_name":"Quattro zampe e dintorni","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2013-12-09T11:29:31+00:00","article_modified_time":"2013-12-09T14:30:25+00:00","og_image":[{"width":354,"height":280,"url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/12\/cina_cani.jpg","type":"image\/jpeg"}],"author":"Monica Genovese","twitter_misc":{"Scritto da":"Monica Genovese","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/bistecca-di-cane-anche-europa-approvata-commestibilita-e-commercio\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/bistecca-di-cane-anche-europa-approvata-commestibilita-e-commercio\/"},"author":{"name":"Monica Genovese","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce"},"headline":"Bistecca di cane anche in Europa. Approvata commestibilit\u00e0 e commercio ma \u00e8 una bufala","datePublished":"2013-12-09T11:29:31+00:00","dateModified":"2013-12-09T14:30:25+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/bistecca-di-cane-anche-europa-approvata-commestibilita-e-commercio\/"},"wordCount":271,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/bistecca-di-cane-anche-europa-approvata-commestibilita-e-commercio\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/12\/cina_cani.jpg","keywords":["cane nel piatto","carne di cane","commestibilit\u00e0 carne cane","Xinshipu Ltd"],"articleSection":["Quattro zampe"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/bistecca-di-cane-anche-europa-approvata-commestibilita-e-commercio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/bistecca-di-cane-anche-europa-approvata-commestibilita-e-commercio\/","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/bistecca-di-cane-anche-europa-approvata-commestibilita-e-commercio\/","name":"Bistecca di cane anche in Europa. Approvata commestibilit\u00e0 e commercio ma \u00e8 una bufala - Quattro zampe e dintorni","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/bistecca-di-cane-anche-europa-approvata-commestibilita-e-commercio\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/bistecca-di-cane-anche-europa-approvata-commestibilita-e-commercio\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/12\/cina_cani.jpg","datePublished":"2013-12-09T11:29:31+00:00","dateModified":"2013-12-09T14:30:25+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce"},"description":"Che direste se, nel vostro piatto al posto della solita carne di bovino, anatra o maiale, trovaste una bistecca di cane? Si, proprio cane, magari della","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/bistecca-di-cane-anche-europa-approvata-commestibilita-e-commercio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/bistecca-di-cane-anche-europa-approvata-commestibilita-e-commercio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/bistecca-di-cane-anche-europa-approvata-commestibilita-e-commercio\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/12\/cina_cani.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/12\/cina_cani.jpg","width":354,"height":280},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/bistecca-di-cane-anche-europa-approvata-commestibilita-e-commercio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/"},{"@type":"ListItem","position":2,"name":"Bistecca di cane anche in Europa. Approvata commestibilit\u00e0 e commercio ma \u00e8 una bufala"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/","name":"Quattro zampe e dintorni","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce","name":"Monica Genovese","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","caption":"Monica Genovese"},"sameAs":["https:\/\/x.com\/Monica_Genovese"],"url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/author\/monica-genovese\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/1187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/comments?post=1187"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/1187\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media\/1188"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media?parent=1187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/categories?post=1187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/tags?post=1187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}