{"id":1178,"date":"2013-12-16T06:00:21","date_gmt":"2013-12-16T05:00:21","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/?p=1178"},"modified":"2013-12-06T17:49:51","modified_gmt":"2013-12-06T16:49:51","slug":"grigliate-vegan-style-ricette-per-non-mettere-gli-animali-nel-piatto","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/grigliate-vegan-style-ricette-per-non-mettere-gli-animali-nel-piatto\/","title":{"rendered":"&#8220;Grigliate vegan style&#8221;. Ricette cruelty-free per lasciare gli animali fuori dal piatto"},"content":{"rendered":"<p><a href=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/12\/Grigliate-vegan-style.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-thumbnail wp-image-1179\" alt=\"Grigliate vegan style\" src=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/12\/Grigliate-vegan-style-150x150.jpg\" width=\"150\" height=\"150\" \/><\/a>In questo spazio non parliamo solo di animali, ma di tutto ci\u00f2 che al mondo animale \u00e8 collegato, vegetarianismo compreso, visto che sempre pi\u00f9 persone scelgono di non mettere gli animali nel piatto. Presentiamo, dunque un libro speciale dal titolo significativo: &#8220;Grigliate vegan style &#8211; 125 ricette alla fiamma ed ecosostenibili&#8221; di <a href=\"http:\/\/www.sonda.it\/john-schlimm\/\">John Schlimm<\/a>, esperto di alimentazione sana e stili di vita sostenibili,\u00a0<span style=\"font-size: 13px\">pubblicato da<\/span><a style=\"font-size: 13px\" href=\"http:\/\/www.sonda.it\/\"> Sonda Editore<\/a><span style=\"font-size: 13px\"> con sede nell&#8217;alessandrino. Il libro, consigliato anche da <a href=\"http:\/\/vegnews.com\/\">VegNews<\/a>, vuole sfatare il mito che la cucina alla griglia sia prettamente a base di carne, mentre \u00e8 possibile preparare pietanze degne di un re usando solo verdure, ortaggi, frutta ma anche dolci, tofu, tempeh e seitan. Una guida, tipo ricettario, di oltre 200 pagine adatta ad ogni stagione, visto che alla griglia, al barbecue possiamo sostituire il forno o la bistecchiera. Questo libro etico, corredato da colorate foto, ottimo aiuto in cucina, propone moltissime ricette con informazioni alimentari e spiegazioni semplici, passo passo per ogni piatto ma anche per ogni alimento usato, anche per i meno appassionati di culinaria. Veggie burger, hot dog e salsicciotti vegani, brodi vegetali, zucchine al balsamico, marinata al sidro di mele, etc. Inoltre, \u00e8 un buon modo per provare, anche per gli amanti della carne, qualcosa di insolito e sano.<\/span><\/p>\n<p><!--more-->Poco comune, per\u00f2 sulla griglia si possono cucinare molti frutti. Gustose le ricette del kebab di frutta con zucchero di canna, cannella e menta e delle <strong>pesche grigliate con salsa di lamponi<\/strong>. Vi proponiamo quest&#8217;ultima nella versione per 5 persone (2 mezze pesche a testa):<\/p>\n<p>2 cucchiaini di zucchero; 1 cucchiaino di melassa; 2 cucchiai di succo fresco di limone; 1 tazza di lamponi freschi (se possibile); 5 pesche fresche di medie dimensioni non sbucciate, tagliate a met\u00e0 e denocciolate, olio vegetale (meglio se spray antiaderente per la piastra).<\/p>\n<p>In un piatto piano unire zucchero, melassa, succo di limone. Mescolare bene. Aggiungere met\u00e0 lamponi e schiacciare il tutto. Aggiungere le mezze pesche e girarle in modo che assorbano la purea. Farle marinare 30-60 minuti a temperatura ambiente con la parte interna rivolta verso il basso. Spennellare la griglia con l&#8217;olio antiaderente e scaldare il grill a fiamma medio-alta. Disporre le pesche sul grill con la parte interna rivolta verso la piastra. Conservare la marinata da parte. Girare le pesche dopo 2 minuti, poi grigliarle altre 6-8 minuti o finch\u00e9 non siano morbide spennellandole con la marinata. Togliere dal barbecue. Servire subito!<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In questo spazio non parliamo solo di animali, ma di tutto ci\u00f2 che al mondo animale \u00e8 collegato, vegetarianismo compreso, visto che sempre pi\u00f9 persone scelgono di non mettere gli animali nel piatto. Presentiamo, dunque un libro speciale dal titolo significativo: &#8220;Grigliate vegan style &#8211; 125 ricette alla fiamma ed ecosostenibili&#8221; di John Schlimm, esperto &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/grigliate-vegan-style-ricette-per-non-mettere-gli-animali-nel-piatto\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;&#8220;Grigliate vegan style&#8221;. Ricette cruelty-free per lasciare gli animali fuori dal piatto&#8221;<\/span><\/a><\/p>\n","protected":false},"author":46,"featured_media":1179,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[952,948,947,954,951,223,950,949,571,953,946],"class_list":["post-1178","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-quattro-zampe","tag-animali-fuori-paitto","tag-grigliate-vegan-style","tag-hot-dog","tag-john-schlimm","tag-seitan","tag-sonda-editore","tag-tempeh","tag-tofu","tag-vegani","tag-vegetariani-italia","tag-veggie-burger"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Grigliate vegan style&quot;. Ricette cruelty-free per lasciare gli animali fuori dal piatto - Quattro zampe e dintorni<\/title>\n<meta name=\"description\" content=\"In questo spazio non parliamo solo di animali, ma di tutto ci\u00f2 che al mondo animale \u00e8 collegato, vegetarianismo compreso, visto che sempre pi\u00f9 persone\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/grigliate-vegan-style-ricette-per-non-mettere-gli-animali-nel-piatto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Grigliate vegan style&quot;. Ricette cruelty-free per lasciare gli animali fuori dal piatto - Quattro zampe e dintorni\" \/>\n<meta property=\"og:description\" content=\"In questo spazio non parliamo solo di animali, ma di tutto ci\u00f2 che al mondo animale \u00e8 collegato, vegetarianismo compreso, visto che sempre pi\u00f9 persone\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/grigliate-vegan-style-ricette-per-non-mettere-gli-animali-nel-piatto\/\" \/>\n<meta property=\"og:site_name\" content=\"Quattro zampe e dintorni\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2013-12-16T05:00:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/12\/Grigliate-vegan-style.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"163\" \/>\n\t<meta property=\"og:image:height\" content=\"210\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Monica Genovese\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Monica Genovese\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/grigliate-vegan-style-ricette-per-non-mettere-gli-animali-nel-piatto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/grigliate-vegan-style-ricette-per-non-mettere-gli-animali-nel-piatto\\\/\"},\"author\":{\"name\":\"Monica Genovese\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\"},\"headline\":\"&#8220;Grigliate vegan style&#8221;. Ricette cruelty-free per lasciare gli animali fuori dal piatto\",\"datePublished\":\"2013-12-16T05:00:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/grigliate-vegan-style-ricette-per-non-mettere-gli-animali-nel-piatto\\\/\"},\"wordCount\":405,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/grigliate-vegan-style-ricette-per-non-mettere-gli-animali-nel-piatto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2013\\\/12\\\/Grigliate-vegan-style.jpg\",\"keywords\":[\"animali fuori paitto\",\"grigliate vegan style\",\"hot dog\",\"John Schlimm\",\"seitan\",\"Sonda editore\",\"tempeh\",\"tofu\",\"vegani\",\"vegetariani italia\",\"Veggie burger\"],\"articleSection\":[\"Quattro zampe\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/grigliate-vegan-style-ricette-per-non-mettere-gli-animali-nel-piatto\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/grigliate-vegan-style-ricette-per-non-mettere-gli-animali-nel-piatto\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/grigliate-vegan-style-ricette-per-non-mettere-gli-animali-nel-piatto\\\/\",\"name\":\"\\\"Grigliate vegan style\\\". Ricette cruelty-free per lasciare gli animali fuori dal piatto - Quattro zampe e dintorni\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/grigliate-vegan-style-ricette-per-non-mettere-gli-animali-nel-piatto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/grigliate-vegan-style-ricette-per-non-mettere-gli-animali-nel-piatto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2013\\\/12\\\/Grigliate-vegan-style.jpg\",\"datePublished\":\"2013-12-16T05:00:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\"},\"description\":\"In questo spazio non parliamo solo di animali, ma di tutto ci\u00f2 che al mondo animale \u00e8 collegato, vegetarianismo compreso, visto che sempre pi\u00f9 persone\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/grigliate-vegan-style-ricette-per-non-mettere-gli-animali-nel-piatto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/grigliate-vegan-style-ricette-per-non-mettere-gli-animali-nel-piatto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/grigliate-vegan-style-ricette-per-non-mettere-gli-animali-nel-piatto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2013\\\/12\\\/Grigliate-vegan-style.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2013\\\/12\\\/Grigliate-vegan-style.jpg\",\"width\":163,\"height\":210},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/grigliate-vegan-style-ricette-per-non-mettere-gli-animali-nel-piatto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Grigliate vegan style&#8221;. Ricette cruelty-free per lasciare gli animali fuori dal piatto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\",\"name\":\"Quattro zampe e dintorni\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\",\"name\":\"Monica Genovese\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"caption\":\"Monica Genovese\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Monica_Genovese\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/author\\\/monica-genovese\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Grigliate vegan style\". Ricette cruelty-free per lasciare gli animali fuori dal piatto - Quattro zampe e dintorni","description":"In questo spazio non parliamo solo di animali, ma di tutto ci\u00f2 che al mondo animale \u00e8 collegato, vegetarianismo compreso, visto che sempre pi\u00f9 persone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/grigliate-vegan-style-ricette-per-non-mettere-gli-animali-nel-piatto\/","og_locale":"it_IT","og_type":"article","og_title":"\"Grigliate vegan style\". Ricette cruelty-free per lasciare gli animali fuori dal piatto - Quattro zampe e dintorni","og_description":"In questo spazio non parliamo solo di animali, ma di tutto ci\u00f2 che al mondo animale \u00e8 collegato, vegetarianismo compreso, visto che sempre pi\u00f9 persone","og_url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/grigliate-vegan-style-ricette-per-non-mettere-gli-animali-nel-piatto\/","og_site_name":"Quattro zampe e dintorni","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2013-12-16T05:00:21+00:00","og_image":[{"width":163,"height":210,"url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/12\/Grigliate-vegan-style.jpg","type":"image\/jpeg"}],"author":"Monica Genovese","twitter_misc":{"Scritto da":"Monica Genovese","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/grigliate-vegan-style-ricette-per-non-mettere-gli-animali-nel-piatto\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/grigliate-vegan-style-ricette-per-non-mettere-gli-animali-nel-piatto\/"},"author":{"name":"Monica Genovese","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce"},"headline":"&#8220;Grigliate vegan style&#8221;. Ricette cruelty-free per lasciare gli animali fuori dal piatto","datePublished":"2013-12-16T05:00:21+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/grigliate-vegan-style-ricette-per-non-mettere-gli-animali-nel-piatto\/"},"wordCount":405,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/grigliate-vegan-style-ricette-per-non-mettere-gli-animali-nel-piatto\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/12\/Grigliate-vegan-style.jpg","keywords":["animali fuori paitto","grigliate vegan style","hot dog","John Schlimm","seitan","Sonda editore","tempeh","tofu","vegani","vegetariani italia","Veggie burger"],"articleSection":["Quattro zampe"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/grigliate-vegan-style-ricette-per-non-mettere-gli-animali-nel-piatto\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/grigliate-vegan-style-ricette-per-non-mettere-gli-animali-nel-piatto\/","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/grigliate-vegan-style-ricette-per-non-mettere-gli-animali-nel-piatto\/","name":"\"Grigliate vegan style\". Ricette cruelty-free per lasciare gli animali fuori dal piatto - Quattro zampe e dintorni","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/grigliate-vegan-style-ricette-per-non-mettere-gli-animali-nel-piatto\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/grigliate-vegan-style-ricette-per-non-mettere-gli-animali-nel-piatto\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/12\/Grigliate-vegan-style.jpg","datePublished":"2013-12-16T05:00:21+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce"},"description":"In questo spazio non parliamo solo di animali, ma di tutto ci\u00f2 che al mondo animale \u00e8 collegato, vegetarianismo compreso, visto che sempre pi\u00f9 persone","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/grigliate-vegan-style-ricette-per-non-mettere-gli-animali-nel-piatto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/grigliate-vegan-style-ricette-per-non-mettere-gli-animali-nel-piatto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/grigliate-vegan-style-ricette-per-non-mettere-gli-animali-nel-piatto\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/12\/Grigliate-vegan-style.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/12\/Grigliate-vegan-style.jpg","width":163,"height":210},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/grigliate-vegan-style-ricette-per-non-mettere-gli-animali-nel-piatto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/"},{"@type":"ListItem","position":2,"name":"&#8220;Grigliate vegan style&#8221;. Ricette cruelty-free per lasciare gli animali fuori dal piatto"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/","name":"Quattro zampe e dintorni","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce","name":"Monica Genovese","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","caption":"Monica Genovese"},"sameAs":["https:\/\/x.com\/Monica_Genovese"],"url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/author\/monica-genovese\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/1178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/comments?post=1178"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/1178\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media\/1179"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media?parent=1178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/categories?post=1178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/tags?post=1178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}