{"id":110,"date":"2012-01-02T07:19:36","date_gmt":"2012-01-02T07:19:36","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/?p=110"},"modified":"2011-12-27T13:21:25","modified_gmt":"2011-12-27T13:21:25","slug":"animali-da-guinness-e-record-di-abbandoni-canini-di-fine-anno","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/animali-da-guinness-e-record-di-abbandoni-canini-di-fine-anno\/","title":{"rendered":"Animali da guinness e record di abbandoni canini di fine anno"},"content":{"rendered":"<p><a href=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2011\/12\/vjyoni.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-114\" src=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2011\/12\/vjyoni-216x300.jpg\" alt=\"\" width=\"216\" height=\"300\" srcset=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2011\/12\/vjyoni-216x300.jpg 216w, https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2011\/12\/vjyoni.jpg 252w\" sizes=\"auto, (max-width: 216px) 85vw, 216px\" \/><\/a>Chi dice che le dimensioni non sono importanti? In questo caso, non solo lo sono, ma rappresentano un vero e proprio record per animali da giunness. Iniziamo dai pesci, quelli pi\u00f9 grandi appartengono alla famiglia degli squali, in particolare lo squalo balena pu\u00f2 raggiungere i 18 metri di lunghezza e pesare oltre 20mila kg. Non proprio una silouette leggera, ma si fa notare!<!--more-->All\u2019opposto, invece stanno i mammiferi pi\u00f9 piccoli, ovvero i kancil malesi. Misurano 25 centimetri di altezza e 47 di lunghezza per un peso di 2 kg. Sempre in tema mammiferi, il pi\u00f9 grande \u00e8 la balenottera azzurra che misura 33 metri di lunghezza per un peso di 130mila kg, come 20 elefanti.<\/p>\n<p>E Dumbo? Rammentate il piccolo elefantino della Disney dalle orecchie lunghe? Ebbene le orecchie pi\u00f9 grandi appartengono all\u2019elefante africano con una superficie di 4 metri quadrati circa ad orecchio e un diametro di quasi 2 metri.<\/p>\n<p>Se i bipedi poco apprezzano le corna, tra gli animali, invece c\u2019\u00e8 chi si vanta di averle molto lunghe! Il muflone di Marco Polo possiede corna, avvolte a spirale, di 190 centimetri di lunghezza. Sono permanenti e se subiscono danni non si rinnovano.<\/p>\n<p>E cani e gatti? Non sono cos\u00ec vanitosi da accaparrarsi qualche record? Figuriamoci, manco a dirlo\u2026 ecco che fanno capolino anche i nostri amici a 4 zampe. La gattina persiana di una coppia americana ha un suo record tutto personale. E\u2019 alta 7 centimetri e lunga 19. Il suo rifugio preferito? Le tasche degli abiti dei suoi proprietari.<\/p>\n<p><a href=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2011\/12\/fattest-cat-ever.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-thumbnail wp-image-115\" src=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2011\/12\/fattest-cat-ever-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>Un vero gigante \u00e8 invece un gatto bianco di una donna australiana. Peso: poco pi\u00f9 di 21 kg per un\u2019altezza di 83,8 e una lunghezza di 96,5 cm. Tra i felini matusalemme c\u2019\u00e8 Puss, un gatto vissuto fino alla veneranda et\u00e0 di 36 anni, contro la media di 15-20 anni, a seconda del sesso.<\/p>\n<p>La gatta pi\u00f9 prolifica \u00e8 una signora felina residente in Inghilterra dove ha dato alla luce 420 cuccioli in 17 anni. Il pi\u00f9 ghiotto, invece \u00e8 una femmina di nome Towser che, in Inghilterra ha catturato \u00a028.899 topi, tutti nella distilleria dove viveva. A lei, cacciatrice provetta \u00e8 stata anche dedicata una statua.<\/p>\n<p>Per parlare ancora di gatti, in Turchia, nella zona orientale, c\u2019\u00e8 una localit\u00e0, nei pressi del lago Van dove vivono pacificamente dei gatti di una razza molto particolare. Hanno il pelo bianco e gli occhi di diverso colore, uno azzurro e l\u2019altro verde. Inoltre, secondo un\u2019antica leggenda locale pare che sappiano nuotare.<\/p>\n<p>E i cani? Restano in disparte a farla fare da padrone ai Felix del mondo? Ma no! Ecco che arriva Giant George, un alano che vive in Arizona la cui altezza, da orecchie a coda, \u00e8 di 220 centimetri per 109 cm da spalla a zampa. Una sorta di cavallo che abbaia!<\/p>\n<p>Il cane pi\u00f9 vecchio del mondo, ormai morto, aveva l\u2019equivalente di 120 anni umani, circa. Ha avuto una lunga vita, interrotta all\u2019et\u00e0 di 26 anni e 9 mesi. Si chiamava Pusuke, un maschio di razza mista che viveva in Giappone con la sua padrona.<\/p>\n<p>Un altro record che riguarda i cani non ha per\u00f2 nulla di encomiabile o divertente, anzi. Secondo l\u2019Ansa, le segnalazioni di abbandoni di cani sulle strade italiane, ricevute dall\u2019Aidaa, associazione italiana difesa animali e ambiente, in questi giorni non fanno sorridere nessuno.<\/p>\n<p><a href=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2011\/12\/cagnolino31.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-117\" src=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2011\/12\/cagnolino31-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>Un Natale da record drammatico per i 4 zampe lasciati soli dai bipedi che, terminato il pasto luculliano natalizio, hanno pensato di disfarsi dell\u2019\u201dingombro\u201d canino!<\/p>\n<p>Secondo l\u2019associazione, nella sola giornata di Natale, le segnalazioni di abbandoni sono state 137 contro le 26 dello scorso anno. La maggior parte degli abbandoni sono stati segnalati in Lombardia (18) in particolare a Bergamo, Pavia e Milano. A seguire Emilia Romagna e Campania (15) e poi, nell&#8217;ordine, Sicilia, Lazio, Piemonte e Puglia.<\/p>\n<p><em>Lui, con il muso all\u2019ins\u00f9 e gli occhi sgranati dallo stupore, non capendo cosa succede, attende fiducioso in auto che il viaggio, con il suo padrone, finisca e si torni a casa, al riparo, al caldo, magari a giocare con i bambini della famiglia. Poi, per\u00f2 il suo padrone lo fa scendere dalla vettura, si guarda attorno che nessuno lo noti. Prende una catena, la stringe intorno al collo di Fido e lo incatena ad un qualsiasi palo o guardrail della strada. Poi, mette in moto e se ne va! da solo.<\/em><\/p>\n<p>Ecco la descrizione di una delle tante scene dell\u2019Italia \u201ccivile\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chi dice che le dimensioni non sono importanti? In questo caso, non solo lo sono, ma rappresentano un vero e proprio record per animali da giunness. Iniziamo dai pesci, quelli pi\u00f9 grandi appartengono alla famiglia degli squali, in particolare lo squalo balena pu\u00f2 raggiungere i 18 metri di lunghezza e pesare oltre 20mila kg. Non &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/animali-da-guinness-e-record-di-abbandoni-canini-di-fine-anno\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Animali da guinness e record di abbandoni canini di fine anno&#8221;<\/span><\/a><\/p>\n","protected":false},"author":46,"featured_media":117,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-110","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-quattro-zampe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Animali da guinness e record di abbandoni canini di fine anno - Quattro zampe e dintorni<\/title>\n<meta name=\"description\" content=\"Chi dice che le dimensioni non sono importanti? In questo caso, non solo lo sono, ma rappresentano un vero e proprio record per animali da giunness.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/animali-da-guinness-e-record-di-abbandoni-canini-di-fine-anno\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Animali da guinness e record di abbandoni canini di fine anno - Quattro zampe e dintorni\" \/>\n<meta property=\"og:description\" content=\"Chi dice che le dimensioni non sono importanti? In questo caso, non solo lo sono, ma rappresentano un vero e proprio record per animali da giunness.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/animali-da-guinness-e-record-di-abbandoni-canini-di-fine-anno\/\" \/>\n<meta property=\"og:site_name\" content=\"Quattro zampe e dintorni\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2012-01-02T07:19:36+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2011\/12\/cagnolino31.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Monica Genovese\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Monica Genovese\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/animali-da-guinness-e-record-di-abbandoni-canini-di-fine-anno\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/animali-da-guinness-e-record-di-abbandoni-canini-di-fine-anno\\\/\"},\"author\":{\"name\":\"Monica Genovese\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\"},\"headline\":\"Animali da guinness e record di abbandoni canini di fine anno\",\"datePublished\":\"2012-01-02T07:19:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/animali-da-guinness-e-record-di-abbandoni-canini-di-fine-anno\\\/\"},\"wordCount\":719,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/animali-da-guinness-e-record-di-abbandoni-canini-di-fine-anno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2011\\\/12\\\/cagnolino31.jpg\",\"articleSection\":[\"Quattro zampe\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/animali-da-guinness-e-record-di-abbandoni-canini-di-fine-anno\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/animali-da-guinness-e-record-di-abbandoni-canini-di-fine-anno\\\/\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/animali-da-guinness-e-record-di-abbandoni-canini-di-fine-anno\\\/\",\"name\":\"Animali da guinness e record di abbandoni canini di fine anno - Quattro zampe e dintorni\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/animali-da-guinness-e-record-di-abbandoni-canini-di-fine-anno\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/animali-da-guinness-e-record-di-abbandoni-canini-di-fine-anno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2011\\\/12\\\/cagnolino31.jpg\",\"datePublished\":\"2012-01-02T07:19:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\"},\"description\":\"Chi dice che le dimensioni non sono importanti? In questo caso, non solo lo sono, ma rappresentano un vero e proprio record per animali da giunness.\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/animali-da-guinness-e-record-di-abbandoni-canini-di-fine-anno\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/animali-da-guinness-e-record-di-abbandoni-canini-di-fine-anno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/animali-da-guinness-e-record-di-abbandoni-canini-di-fine-anno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2011\\\/12\\\/cagnolino31.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2011\\\/12\\\/cagnolino31.jpg\",\"width\":\"1024\",\"height\":\"768\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/animali-da-guinness-e-record-di-abbandoni-canini-di-fine-anno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Animali da guinness e record di abbandoni canini di fine anno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\",\"name\":\"Quattro zampe e dintorni\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\",\"name\":\"Monica Genovese\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"caption\":\"Monica Genovese\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Monica_Genovese\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/author\\\/monica-genovese\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Animali da guinness e record di abbandoni canini di fine anno - Quattro zampe e dintorni","description":"Chi dice che le dimensioni non sono importanti? In questo caso, non solo lo sono, ma rappresentano un vero e proprio record per animali da giunness.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/animali-da-guinness-e-record-di-abbandoni-canini-di-fine-anno\/","og_locale":"it_IT","og_type":"article","og_title":"Animali da guinness e record di abbandoni canini di fine anno - Quattro zampe e dintorni","og_description":"Chi dice che le dimensioni non sono importanti? In questo caso, non solo lo sono, ma rappresentano un vero e proprio record per animali da giunness.","og_url":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/animali-da-guinness-e-record-di-abbandoni-canini-di-fine-anno\/","og_site_name":"Quattro zampe e dintorni","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2012-01-02T07:19:36+00:00","og_image":[{"width":1024,"height":768,"url":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2011\/12\/cagnolino31.jpg","type":"image\/jpeg"}],"author":"Monica Genovese","twitter_misc":{"Scritto da":"Monica Genovese","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/animali-da-guinness-e-record-di-abbandoni-canini-di-fine-anno\/#article","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/animali-da-guinness-e-record-di-abbandoni-canini-di-fine-anno\/"},"author":{"name":"Monica Genovese","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce"},"headline":"Animali da guinness e record di abbandoni canini di fine anno","datePublished":"2012-01-02T07:19:36+00:00","mainEntityOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/animali-da-guinness-e-record-di-abbandoni-canini-di-fine-anno\/"},"wordCount":719,"commentCount":0,"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/animali-da-guinness-e-record-di-abbandoni-canini-di-fine-anno\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2011\/12\/cagnolino31.jpg","articleSection":["Quattro zampe"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/animali-da-guinness-e-record-di-abbandoni-canini-di-fine-anno\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/animali-da-guinness-e-record-di-abbandoni-canini-di-fine-anno\/","url":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/animali-da-guinness-e-record-di-abbandoni-canini-di-fine-anno\/","name":"Animali da guinness e record di abbandoni canini di fine anno - Quattro zampe e dintorni","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website"},"primaryImageOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/animali-da-guinness-e-record-di-abbandoni-canini-di-fine-anno\/#primaryimage"},"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/animali-da-guinness-e-record-di-abbandoni-canini-di-fine-anno\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2011\/12\/cagnolino31.jpg","datePublished":"2012-01-02T07:19:36+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce"},"description":"Chi dice che le dimensioni non sono importanti? In questo caso, non solo lo sono, ma rappresentano un vero e proprio record per animali da giunness.","breadcrumb":{"@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/animali-da-guinness-e-record-di-abbandoni-canini-di-fine-anno\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/animali-da-guinness-e-record-di-abbandoni-canini-di-fine-anno\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/animali-da-guinness-e-record-di-abbandoni-canini-di-fine-anno\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2011\/12\/cagnolino31.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2011\/12\/cagnolino31.jpg","width":"1024","height":"768"},{"@type":"BreadcrumbList","@id":"http:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/animali-da-guinness-e-record-di-abbandoni-canini-di-fine-anno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/"},{"@type":"ListItem","position":2,"name":"Animali da guinness e record di abbandoni canini di fine anno"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/","name":"Quattro zampe e dintorni","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce","name":"Monica Genovese","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","caption":"Monica Genovese"},"sameAs":["https:\/\/x.com\/Monica_Genovese"],"url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/author\/monica-genovese\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/comments?post=110"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/110\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media\/117"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media?parent=110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/categories?post=110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/tags?post=110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}