{"id":1076,"date":"2013-08-14T06:00:15","date_gmt":"2013-08-14T05:00:15","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/?p=1076"},"modified":"2013-07-17T17:06:56","modified_gmt":"2013-07-17T16:06:56","slug":"i-10-animali-piu-ricchi-del-mondo-e-ce-chi-la-chiama-vita-da-cani","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/i-10-animali-piu-ricchi-del-mondo-e-ce-chi-la-chiama-vita-da-cani\/","title":{"rendered":"I 10 animali pi\u00f9 ricchi del mondo e c&#8217;\u00e8 chi la chiama &#8220;vita da cani!!"},"content":{"rendered":"<p><a href=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/07\/cane-soldi.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-thumbnail wp-image-1077\" alt=\"cane soldi\" src=\"http:\/\/www.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/07\/cane-soldi-150x150.jpg\" width=\"150\" height=\"150\" \/><\/a>C&#8217;\u00e8 chi la chiama &#8220;vita da cani&#8221; per riferirsi a qualcuno la cui esistenza sia in difficolt\u00e0 eppure ci sono cani, ma non solo, ricchi, talmente ricchi che, da soli potrebbero rimettere in sesto il Pil di un Paese in crisi. Sono gli straricchi pelosi! E tale ricchezza nasce, il pi\u00f9 delle volte, da cospique eredit\u00e0 lasciate loro da padroni che, in vita, li hanno amati e viziati. Tanto per fare alcuni esempi il cane maltese Trouble \u00e8 titolare di 12 milioni di dollari. Insomma,\u00a0 giusto qualche spicciolo lasciatogli dalla sua bipede americana Leona Helmsley, neanche a dirlo milionaria. Secondo il magazine britannico,\u201cDaily Mail\u201d esiste una vera e propria &#8220;gara&#8221; tra animali per contendersi l&#8217;agognato (!) pomo d&#8217;oro. Il podio spetta a Gunther, un bel pastore tedesco che vanta 133 milioni di euro, unico erede di una contessa, anche lei tedesca, di nome Karlotta Liebenstein. Inoltre, a quanto pare\u00a0Gunther ha anche gusti costosi che, tra l&#8217;altro pu\u00f2 permettersi, visto che durante una delle aste per la vendita di tartufi piemontesi, ne ha acquistato personalmente (si fa per dire) uno a Torino per la modica cifa di 1.500 euro! Chiss\u00e0 poi se lo ha davvero mangiato lui. <!--more-->Il secondo posto di questa insolita classifica \u00e8 occupato da Kalu, un delizioso scimpanz\u00e8 che ha all&#8217;attivo 60milioni di euro donati da Patricia O\u2019Neil, figlia del conte di Kenmore e moglie di Franck O\u2019Neil, ex campione di nuoto australiano. Poi \u00e8 la volta di Trouble di cui abbiamo gi\u00e0 parlato. A seguire, una bella coppia, Tina e Kate, due collie che valgono 665mila euro, ricevuti dalla compianta Nora Hardwell, ricca signora morta un giorno prima di compiere 90 anni. Al quinto posto fa capolino Jasper, un incrocio da 221mila euro, met\u00e0 labrador e met\u00e0 doberman. Il 4 zampe deve la sua fortuna all\u2019ereditiera Diana Myburgh che lo ha adottato in un canile quando era ancora cucciolo e da allora non si \u00e8 pi\u00f9 separata da lui. Fino alla sua morte, almeno. Al sesto posto arriva un gatto il cui nome \u00e8 Tinker. Patrimonio stimato in 150mila euro. Al settimo ci sono Porgy, Pride, Joy e Ronald, tutto gatti che possiedono 26mila euro cadauno. Giusto per non litigare! Ma c&#8217;\u00e8 anche una tartaruga in questa lista. Si chiama Silvestone, ha oltre 50 anni e nel suo portafogli spiccano 24,6mila euro. Nono e decimo posto sono, rispettivamente di Top Cat, Matilda (15mila euro a testa) e Angus, mucca, e Larry, agnellino. A loro spettano 11,7mila euro cadauno. Che dire, a nessuno di questi animali mancheranno mai crocchette e acqua fresca!<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>C&#8217;\u00e8 chi la chiama &#8220;vita da cani&#8221; per riferirsi a qualcuno la cui esistenza sia in difficolt\u00e0 eppure ci sono cani, ma non solo, ricchi, talmente ricchi che, da soli potrebbero rimettere in sesto il Pil di un Paese in crisi. Sono gli straricchi pelosi! E tale ricchezza nasce, il pi\u00f9 delle volte, da cospique &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/i-10-animali-piu-ricchi-del-mondo-e-ce-chi-la-chiama-vita-da-cani\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;I 10 animali pi\u00f9 ricchi del mondo e c&#8217;\u00e8 chi la chiama &#8220;vita da cani!!&#8221;<\/span><\/a><\/p>\n","protected":false},"author":46,"featured_media":1077,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[871,870,873,872,876,874,875],"class_list":["post-1076","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-quattro-zampe","tag-animali-ricchi","tag-cani-richi","tag-daily-mail-patricia-oneil","tag-eredita-cane","tag-joy","tag-porgy","tag-pride"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I 10 animali pi\u00f9 ricchi del mondo e c&#039;\u00e8 chi la chiama &quot;vita da cani!! - Quattro zampe e dintorni<\/title>\n<meta name=\"description\" content=\"C&#039;\u00e8 chi la chiama &quot;vita da cani&quot; per riferirsi a qualcuno la cui esistenza sia in difficolt\u00e0 eppure ci sono cani, ma non solo, ricchi, talmente ricchi\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/i-10-animali-piu-ricchi-del-mondo-e-ce-chi-la-chiama-vita-da-cani\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I 10 animali pi\u00f9 ricchi del mondo e c&#039;\u00e8 chi la chiama &quot;vita da cani!! - Quattro zampe e dintorni\" \/>\n<meta property=\"og:description\" content=\"C&#039;\u00e8 chi la chiama &quot;vita da cani&quot; per riferirsi a qualcuno la cui esistenza sia in difficolt\u00e0 eppure ci sono cani, ma non solo, ricchi, talmente ricchi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/i-10-animali-piu-ricchi-del-mondo-e-ce-chi-la-chiama-vita-da-cani\/\" \/>\n<meta property=\"og:site_name\" content=\"Quattro zampe e dintorni\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2013-08-14T05:00:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/07\/cane-soldi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"411\" \/>\n\t<meta property=\"og:image:height\" content=\"255\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Monica Genovese\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Monica Genovese\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/i-10-animali-piu-ricchi-del-mondo-e-ce-chi-la-chiama-vita-da-cani\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/i-10-animali-piu-ricchi-del-mondo-e-ce-chi-la-chiama-vita-da-cani\\\/\"},\"author\":{\"name\":\"Monica Genovese\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\"},\"headline\":\"I 10 animali pi\u00f9 ricchi del mondo e c&#8217;\u00e8 chi la chiama &#8220;vita da cani!!\",\"datePublished\":\"2013-08-14T05:00:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/i-10-animali-piu-ricchi-del-mondo-e-ce-chi-la-chiama-vita-da-cani\\\/\"},\"wordCount\":437,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/i-10-animali-piu-ricchi-del-mondo-e-ce-chi-la-chiama-vita-da-cani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2013\\\/07\\\/cane-soldi.jpg\",\"keywords\":[\"animali ricchi\",\"cani richi\",\"daily mail Patricia O\u2019Neil\",\"eredit\u00e0 cane\",\"Joy\",\"Porgy\",\"Pride\"],\"articleSection\":[\"Quattro zampe\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/i-10-animali-piu-ricchi-del-mondo-e-ce-chi-la-chiama-vita-da-cani\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/i-10-animali-piu-ricchi-del-mondo-e-ce-chi-la-chiama-vita-da-cani\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/i-10-animali-piu-ricchi-del-mondo-e-ce-chi-la-chiama-vita-da-cani\\\/\",\"name\":\"I 10 animali pi\u00f9 ricchi del mondo e c'\u00e8 chi la chiama \\\"vita da cani!! - Quattro zampe e dintorni\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/i-10-animali-piu-ricchi-del-mondo-e-ce-chi-la-chiama-vita-da-cani\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/i-10-animali-piu-ricchi-del-mondo-e-ce-chi-la-chiama-vita-da-cani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2013\\\/07\\\/cane-soldi.jpg\",\"datePublished\":\"2013-08-14T05:00:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\"},\"description\":\"C'\u00e8 chi la chiama \\\"vita da cani\\\" per riferirsi a qualcuno la cui esistenza sia in difficolt\u00e0 eppure ci sono cani, ma non solo, ricchi, talmente ricchi\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/i-10-animali-piu-ricchi-del-mondo-e-ce-chi-la-chiama-vita-da-cani\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/i-10-animali-piu-ricchi-del-mondo-e-ce-chi-la-chiama-vita-da-cani\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/i-10-animali-piu-ricchi-del-mondo-e-ce-chi-la-chiama-vita-da-cani\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2013\\\/07\\\/cane-soldi.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/files\\\/2013\\\/07\\\/cane-soldi.jpg\",\"width\":411,\"height\":255},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/i-10-animali-piu-ricchi-del-mondo-e-ce-chi-la-chiama-vita-da-cani\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I 10 animali pi\u00f9 ricchi del mondo e c&#8217;\u00e8 chi la chiama &#8220;vita da cani!!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/\",\"name\":\"Quattro zampe e dintorni\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/#\\\/schema\\\/person\\\/1f141d61659bc85e6224aa454a674fce\",\"name\":\"Monica Genovese\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g\",\"caption\":\"Monica Genovese\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Monica_Genovese\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/quattrozampeedintorni\\\/author\\\/monica-genovese\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I 10 animali pi\u00f9 ricchi del mondo e c'\u00e8 chi la chiama \"vita da cani!! - Quattro zampe e dintorni","description":"C'\u00e8 chi la chiama \"vita da cani\" per riferirsi a qualcuno la cui esistenza sia in difficolt\u00e0 eppure ci sono cani, ma non solo, ricchi, talmente ricchi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/i-10-animali-piu-ricchi-del-mondo-e-ce-chi-la-chiama-vita-da-cani\/","og_locale":"it_IT","og_type":"article","og_title":"I 10 animali pi\u00f9 ricchi del mondo e c'\u00e8 chi la chiama \"vita da cani!! - Quattro zampe e dintorni","og_description":"C'\u00e8 chi la chiama \"vita da cani\" per riferirsi a qualcuno la cui esistenza sia in difficolt\u00e0 eppure ci sono cani, ma non solo, ricchi, talmente ricchi","og_url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/i-10-animali-piu-ricchi-del-mondo-e-ce-chi-la-chiama-vita-da-cani\/","og_site_name":"Quattro zampe e dintorni","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2013-08-14T05:00:15+00:00","og_image":[{"width":411,"height":255,"url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/07\/cane-soldi.jpg","type":"image\/jpeg"}],"author":"Monica Genovese","twitter_misc":{"Scritto da":"Monica Genovese","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/i-10-animali-piu-ricchi-del-mondo-e-ce-chi-la-chiama-vita-da-cani\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/i-10-animali-piu-ricchi-del-mondo-e-ce-chi-la-chiama-vita-da-cani\/"},"author":{"name":"Monica Genovese","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce"},"headline":"I 10 animali pi\u00f9 ricchi del mondo e c&#8217;\u00e8 chi la chiama &#8220;vita da cani!!","datePublished":"2013-08-14T05:00:15+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/i-10-animali-piu-ricchi-del-mondo-e-ce-chi-la-chiama-vita-da-cani\/"},"wordCount":437,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/i-10-animali-piu-ricchi-del-mondo-e-ce-chi-la-chiama-vita-da-cani\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/07\/cane-soldi.jpg","keywords":["animali ricchi","cani richi","daily mail Patricia O\u2019Neil","eredit\u00e0 cane","Joy","Porgy","Pride"],"articleSection":["Quattro zampe"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/i-10-animali-piu-ricchi-del-mondo-e-ce-chi-la-chiama-vita-da-cani\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/i-10-animali-piu-ricchi-del-mondo-e-ce-chi-la-chiama-vita-da-cani\/","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/i-10-animali-piu-ricchi-del-mondo-e-ce-chi-la-chiama-vita-da-cani\/","name":"I 10 animali pi\u00f9 ricchi del mondo e c'\u00e8 chi la chiama \"vita da cani!! - Quattro zampe e dintorni","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/i-10-animali-piu-ricchi-del-mondo-e-ce-chi-la-chiama-vita-da-cani\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/i-10-animali-piu-ricchi-del-mondo-e-ce-chi-la-chiama-vita-da-cani\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/07\/cane-soldi.jpg","datePublished":"2013-08-14T05:00:15+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce"},"description":"C'\u00e8 chi la chiama \"vita da cani\" per riferirsi a qualcuno la cui esistenza sia in difficolt\u00e0 eppure ci sono cani, ma non solo, ricchi, talmente ricchi","breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/i-10-animali-piu-ricchi-del-mondo-e-ce-chi-la-chiama-vita-da-cani\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/i-10-animali-piu-ricchi-del-mondo-e-ce-chi-la-chiama-vita-da-cani\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/i-10-animali-piu-ricchi-del-mondo-e-ce-chi-la-chiama-vita-da-cani\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/07\/cane-soldi.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/files\/2013\/07\/cane-soldi.jpg","width":411,"height":255},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/i-10-animali-piu-ricchi-del-mondo-e-ce-chi-la-chiama-vita-da-cani\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/"},{"@type":"ListItem","position":2,"name":"I 10 animali pi\u00f9 ricchi del mondo e c&#8217;\u00e8 chi la chiama &#8220;vita da cani!!"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#website","url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/","name":"Quattro zampe e dintorni","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/#\/schema\/person\/1f141d61659bc85e6224aa454a674fce","name":"Monica Genovese","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f761872600586f65aa3bdf1aa468da21a45fc1b4c03a7a41b5684ad9b3fb650?s=96&d=mm&r=g","caption":"Monica Genovese"},"sameAs":["https:\/\/x.com\/Monica_Genovese"],"url":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/author\/monica-genovese\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/1076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/comments?post=1076"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/posts\/1076\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media\/1077"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/media?parent=1076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/categories?post=1076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/quattrozampeedintorni\/wp-json\/wp\/v2\/tags?post=1076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}