{"id":93,"date":"2011-10-25T14:50:00","date_gmt":"2011-10-25T13:50:00","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/pionierisilenziosi\/?p=93"},"modified":"2011-10-25T14:50:00","modified_gmt":"2011-10-25T13:50:00","slug":"neuropsichiatria-infantile-in-mezzo-al-degrado-fra-disperati-alcolisti-e-prostitute","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/neuropsichiatria-infantile-in-mezzo-al-degrado-fra-disperati-alcolisti-e-prostitute\/","title":{"rendered":"Neuropsichiatria infantile in mezzo al degrado, fra disperati, alcolisti e prostitute"},"content":{"rendered":"<p style=\"text-align: justify\">Da un anno il servizio di neuropsichiatria infantile di San Salvario \u00e8 stato trasferito in una zona limite: via Nizza angolo via Berthollet. E le mamme dei bambini seguiti dall&#8217;Asl lanciano l&#8217;allarme. Non per il servizio terapeutico \u00a0in s\u00e9, che ritengono eccellente, ma per la &#8216;location&#8217; (diciamo cos\u00ec). Disperati, alcolisti, prostitute e persone che fanno i loro bisogni in strada: questo \u00e8 il quadro che i pazienti si trovano davanti quando entrano ed escono dalla struttura. A volte \u00e8 perfino capitato di trovarsi in mezzo a una rissa, con cocci di bottiglie presi in mano a mo&#8217; di arma. Insomma, un ambiente tutt&#8217;altro che accogliente, soprattutto per ragazzi che gi\u00e0 vivono situazioni di disagio e di fragilit\u00e0.<!--more--><\/p>\n<p style=\"text-align: justify\">La sede dovrebbe essere provvisoria, ma in realt\u00e0 \u00e8 una provvisoriet\u00e0 &#8220;all&#8217;italiana&#8221;, nel senso che prima di traslocare nella struttura dell&#8217;Asl 1 di via Petitti (dove attualmente sono in corso i lavori di ristrutturazione) potrebbero passare altri due anni. Un tempo inaccettabile, per ragazzi e genitori.<\/p>\n<p style=\"text-align: justify\">Non \u00e8 la prima volta che le mamme dei bambini seguiti dal Servizio fanno sentire la loro voce. Gi\u00e0 a giugno del 2010, allarmate dall&#8217;imminente trasferimento, avevano scritto lettere all&#8217;Asl, alla Regione e al Comune, ricevendo assicurazioni formali. Ma i mesi sono passati e a quanto pare la situazione non \u00e8 cambiata. Ieri, intervistate da <em>La Stampa<\/em>, hanno detto: &#8220;E&#8217; estremamente dannoso per i nostri figli vedere continuamente gente che beve, urla, orina per strada, ci molesta. Senza contare puzza e sporcizia, qui \u00e8 una latrina a cielo aperto&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da un anno il servizio di neuropsichiatria infantile di San Salvario \u00e8 stato trasferito in una zona limite: via Nizza angolo via Berthollet. E le mamme dei bambini seguiti dall&#8217;Asl lanciano l&#8217;allarme. Non per il servizio terapeutico \u00a0in s\u00e9, che ritengono eccellente, ma per la &#8216;location&#8217; (diciamo cos\u00ec). Disperati, alcolisti, prostitute e persone che fanno &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/neuropsichiatria-infantile-in-mezzo-al-degrado-fra-disperati-alcolisti-e-prostitute\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Neuropsichiatria infantile in mezzo al degrado, fra disperati, alcolisti e prostitute&#8221;<\/span><\/a><\/p>\n","protected":false},"author":38,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[112,115,113,114,116],"class_list":["post-93","post","type-post","status-publish","format-standard","hentry","category-pionieri-silenziosi","tag-asl","tag-degrado","tag-neuropsichiatria-infantile","tag-san-salvario","tag-via-nizza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Neuropsichiatria infantile in mezzo al degrado, fra disperati, alcolisti e prostitute - Pionieri silenziosi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/neuropsichiatria-infantile-in-mezzo-al-degrado-fra-disperati-alcolisti-e-prostitute\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neuropsichiatria infantile in mezzo al degrado, fra disperati, alcolisti e prostitute - Pionieri silenziosi\" \/>\n<meta property=\"og:description\" content=\"Da un anno il servizio di neuropsichiatria infantile di San Salvario \u00e8 stato trasferito in una zona limite: via Nizza angolo via Berthollet. E le mamme dei bambini seguiti dall&#8217;Asl lanciano l&#8217;allarme. Non per il servizio terapeutico \u00a0in s\u00e9, che ritengono eccellente, ma per la &#8216;location&#8217; (diciamo cos\u00ec). Disperati, alcolisti, prostitute e persone che fanno &hellip; Leggi tutto &quot;Neuropsichiatria infantile in mezzo al degrado, fra disperati, alcolisti e prostitute&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/neuropsichiatria-infantile-in-mezzo-al-degrado-fra-disperati-alcolisti-e-prostitute\/\" \/>\n<meta property=\"og:site_name\" content=\"Pionieri silenziosi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2011-10-25T13:50:00+00:00\" \/>\n<meta name=\"author\" content=\"Lorenzo Montanaro\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lorenzo Montanaro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/neuropsichiatria-infantile-in-mezzo-al-degrado-fra-disperati-alcolisti-e-prostitute\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/neuropsichiatria-infantile-in-mezzo-al-degrado-fra-disperati-alcolisti-e-prostitute\\\/\"},\"author\":{\"name\":\"Lorenzo Montanaro\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/#\\\/schema\\\/person\\\/1e4e6180afb10cca8c7da51aba1ac37d\"},\"headline\":\"Neuropsichiatria infantile in mezzo al degrado, fra disperati, alcolisti e prostitute\",\"datePublished\":\"2011-10-25T13:50:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/neuropsichiatria-infantile-in-mezzo-al-degrado-fra-disperati-alcolisti-e-prostitute\\\/\"},\"wordCount\":261,\"commentCount\":0,\"keywords\":[\"Asl\",\"degrado\",\"neuropsichiatria infantile\",\"San Salvario\",\"via Nizza\"],\"articleSection\":[\"Pionieri Silenziosi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/neuropsichiatria-infantile-in-mezzo-al-degrado-fra-disperati-alcolisti-e-prostitute\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/neuropsichiatria-infantile-in-mezzo-al-degrado-fra-disperati-alcolisti-e-prostitute\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/neuropsichiatria-infantile-in-mezzo-al-degrado-fra-disperati-alcolisti-e-prostitute\\\/\",\"name\":\"Neuropsichiatria infantile in mezzo al degrado, fra disperati, alcolisti e prostitute - Pionieri silenziosi\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/#website\"},\"datePublished\":\"2011-10-25T13:50:00+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/#\\\/schema\\\/person\\\/1e4e6180afb10cca8c7da51aba1ac37d\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/neuropsichiatria-infantile-in-mezzo-al-degrado-fra-disperati-alcolisti-e-prostitute\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/#website\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/\",\"name\":\"Pionieri silenziosi\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/#\\\/schema\\\/person\\\/1e4e6180afb10cca8c7da51aba1ac37d\",\"name\":\"Lorenzo Montanaro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4cb7183827096260c06fef52eb85a6a857832d5733bc002257d81b8b80561ff5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4cb7183827096260c06fef52eb85a6a857832d5733bc002257d81b8b80561ff5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4cb7183827096260c06fef52eb85a6a857832d5733bc002257d81b8b80561ff5?s=96&d=mm&r=g\",\"caption\":\"Lorenzo Montanaro\"},\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/author\\\/lorenzo-montanaro\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neuropsichiatria infantile in mezzo al degrado, fra disperati, alcolisti e prostitute - Pionieri silenziosi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/neuropsichiatria-infantile-in-mezzo-al-degrado-fra-disperati-alcolisti-e-prostitute\/","og_locale":"it_IT","og_type":"article","og_title":"Neuropsichiatria infantile in mezzo al degrado, fra disperati, alcolisti e prostitute - Pionieri silenziosi","og_description":"Da un anno il servizio di neuropsichiatria infantile di San Salvario \u00e8 stato trasferito in una zona limite: via Nizza angolo via Berthollet. E le mamme dei bambini seguiti dall&#8217;Asl lanciano l&#8217;allarme. Non per il servizio terapeutico \u00a0in s\u00e9, che ritengono eccellente, ma per la &#8216;location&#8217; (diciamo cos\u00ec). Disperati, alcolisti, prostitute e persone che fanno &hellip; Leggi tutto \"Neuropsichiatria infantile in mezzo al degrado, fra disperati, alcolisti e prostitute\"","og_url":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/neuropsichiatria-infantile-in-mezzo-al-degrado-fra-disperati-alcolisti-e-prostitute\/","og_site_name":"Pionieri silenziosi","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2011-10-25T13:50:00+00:00","author":"Lorenzo Montanaro","twitter_misc":{"Scritto da":"Lorenzo Montanaro","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/neuropsichiatria-infantile-in-mezzo-al-degrado-fra-disperati-alcolisti-e-prostitute\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/neuropsichiatria-infantile-in-mezzo-al-degrado-fra-disperati-alcolisti-e-prostitute\/"},"author":{"name":"Lorenzo Montanaro","@id":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/#\/schema\/person\/1e4e6180afb10cca8c7da51aba1ac37d"},"headline":"Neuropsichiatria infantile in mezzo al degrado, fra disperati, alcolisti e prostitute","datePublished":"2011-10-25T13:50:00+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/neuropsichiatria-infantile-in-mezzo-al-degrado-fra-disperati-alcolisti-e-prostitute\/"},"wordCount":261,"commentCount":0,"keywords":["Asl","degrado","neuropsichiatria infantile","San Salvario","via Nizza"],"articleSection":["Pionieri Silenziosi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/neuropsichiatria-infantile-in-mezzo-al-degrado-fra-disperati-alcolisti-e-prostitute\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/neuropsichiatria-infantile-in-mezzo-al-degrado-fra-disperati-alcolisti-e-prostitute\/","url":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/neuropsichiatria-infantile-in-mezzo-al-degrado-fra-disperati-alcolisti-e-prostitute\/","name":"Neuropsichiatria infantile in mezzo al degrado, fra disperati, alcolisti e prostitute - Pionieri silenziosi","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/#website"},"datePublished":"2011-10-25T13:50:00+00:00","author":{"@id":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/#\/schema\/person\/1e4e6180afb10cca8c7da51aba1ac37d"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/neuropsichiatria-infantile-in-mezzo-al-degrado-fra-disperati-alcolisti-e-prostitute\/"]}]},{"@type":"WebSite","@id":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/#website","url":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/","name":"Pionieri silenziosi","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/#\/schema\/person\/1e4e6180afb10cca8c7da51aba1ac37d","name":"Lorenzo Montanaro","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4cb7183827096260c06fef52eb85a6a857832d5733bc002257d81b8b80561ff5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4cb7183827096260c06fef52eb85a6a857832d5733bc002257d81b8b80561ff5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4cb7183827096260c06fef52eb85a6a857832d5733bc002257d81b8b80561ff5?s=96&d=mm&r=g","caption":"Lorenzo Montanaro"},"url":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/author\/lorenzo-montanaro\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/wp-json\/wp\/v2\/posts\/93","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/wp-json\/wp\/v2\/comments?post=93"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/wp-json\/wp\/v2\/posts\/93\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/wp-json\/wp\/v2\/media?parent=93"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/wp-json\/wp\/v2\/categories?post=93"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/wp-json\/wp\/v2\/tags?post=93"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}