{"id":87,"date":"2011-10-20T15:39:08","date_gmt":"2011-10-20T14:39:08","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/pionierisilenziosi\/?p=87"},"modified":"2011-10-20T15:39:08","modified_gmt":"2011-10-20T14:39:08","slug":"disabili-no-alla-legge-sulla-riforma-assistenziale-ieri-la-relazione-a-montecitorio","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/disabili-no-alla-legge-sulla-riforma-assistenziale-ieri-la-relazione-a-montecitorio\/","title":{"rendered":"Disabili: &#8220;No alla legge sulla Riforma Assistenziale&#8221;. Ieri la relazione a Montecitorio"},"content":{"rendered":"<p style=\"text-align: justify\">Il Disegno di Legge Delega sulla Riforma Assistenziale, attualmente in discussione alla Commissione Affari Sociali della Camera, incassa un altro risoluto no dal mondo dei disabili. Ieri la Fand (Federazione delle Associazioni Nazionali dei Disabili), un organismo di cui fanno parte alcune realt\u00e0 storiche come l&#8217;Unione Italiana Ciechi, l&#8217;Ente Nazionale Sordi e l&#8217;Associazione Mutilati e Invalidi Civili, ha presentato a Montecitorio una relazione che esprime totale disaccordo con la legge.<!--more--><\/p>\n<p style=\"text-align: justify\">I motivi? Niente di nuovo sotto il sole, purtroppo. Le ragioni del dissenso sono le stesse espresse nelle scorse settimane, ma forse cadute nel vuoto. A preoccupare i disabili \u00e8 soprattutto l&#8217;annuncio di tagli indiscriminati al sociale: &#8220;Il modello assistenziale \u2013 fa notare Giovanni Pagano, presidente Fand \u2013 deve essere svincolato dall&#8217;obiettivo del risparmio di spesa&#8221;. Come dire: i diritti dei cittadini non sono una voce di bilancio.<\/p>\n<p style=\"text-align: justify\">E naturalmente c&#8217;\u00e8 in ballo la <em>vexata quaestio <\/em>delle indennit\u00e0 di accompagnamento, che finora sono state erogate &#8220;a titolo della menomazione&#8221; (cio\u00e8 alle persone disabili in quanto tali, indipendentemente dalle loro condizioni economiche), ma che in futuro potrebbero essere vincolate al reddito o sostituite da un &#8220;fondo per l&#8217;indennit\u00e0 sussidiaria&#8221;, un&#8217;entit\u00e0 al momento ancora un po&#8217; nebulosa, di cui si fatica a immaginare il funzionamento.<\/p>\n<p style=\"text-align: justify\">Accanto alla relazione, \u00e8 stato presentato alla Commissione Parlamentare un altro testo, contenente alcune proposte di emendamenti alla legge. Le associazioni riunite nel Fand fanno blocco compatto: chiedono che i politici rimettano mano alla riforma, accogliendo almeno alcuni degli emendamenti proposti. In caso contrario i disabili sono pronti a una mobilitazione di piazza per far sentire la loro voce.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Disegno di Legge Delega sulla Riforma Assistenziale, attualmente in discussione alla Commissione Affari Sociali della Camera, incassa un altro risoluto no dal mondo dei disabili. Ieri la Fand (Federazione delle Associazioni Nazionali dei Disabili), un organismo di cui fanno parte alcune realt\u00e0 storiche come l&#8217;Unione Italiana Ciechi, l&#8217;Ente Nazionale Sordi e l&#8217;Associazione Mutilati e &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/disabili-no-alla-legge-sulla-riforma-assistenziale-ieri-la-relazione-a-montecitorio\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Disabili: &#8220;No alla legge sulla Riforma Assistenziale&#8221;. Ieri la relazione a Montecitorio&#8221;<\/span><\/a><\/p>\n","protected":false},"author":38,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[3,107,109,108],"class_list":["post-87","post","type-post","status-publish","format-standard","hentry","category-pionieri-silenziosi","tag-disabilita","tag-fand","tag-legge-delega-riforma-assistenziale","tag-montecitorio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Disabili: &quot;No alla legge sulla Riforma Assistenziale&quot;. Ieri la relazione a Montecitorio - Pionieri silenziosi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/disabili-no-alla-legge-sulla-riforma-assistenziale-ieri-la-relazione-a-montecitorio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Disabili: &quot;No alla legge sulla Riforma Assistenziale&quot;. Ieri la relazione a Montecitorio - Pionieri silenziosi\" \/>\n<meta property=\"og:description\" content=\"Il Disegno di Legge Delega sulla Riforma Assistenziale, attualmente in discussione alla Commissione Affari Sociali della Camera, incassa un altro risoluto no dal mondo dei disabili. Ieri la Fand (Federazione delle Associazioni Nazionali dei Disabili), un organismo di cui fanno parte alcune realt\u00e0 storiche come l&#8217;Unione Italiana Ciechi, l&#8217;Ente Nazionale Sordi e l&#8217;Associazione Mutilati e &hellip; Leggi tutto &quot;Disabili: &#8220;No alla legge sulla Riforma Assistenziale&#8221;. Ieri la relazione a Montecitorio&quot;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/disabili-no-alla-legge-sulla-riforma-assistenziale-ieri-la-relazione-a-montecitorio\/\" \/>\n<meta property=\"og:site_name\" content=\"Pionieri silenziosi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2011-10-20T14:39:08+00:00\" \/>\n<meta name=\"author\" content=\"Lorenzo Montanaro\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lorenzo Montanaro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/disabili-no-alla-legge-sulla-riforma-assistenziale-ieri-la-relazione-a-montecitorio\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/disabili-no-alla-legge-sulla-riforma-assistenziale-ieri-la-relazione-a-montecitorio\\\/\"},\"author\":{\"name\":\"Lorenzo Montanaro\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/#\\\/schema\\\/person\\\/1e4e6180afb10cca8c7da51aba1ac37d\"},\"headline\":\"Disabili: &#8220;No alla legge sulla Riforma Assistenziale&#8221;. Ieri la relazione a Montecitorio\",\"datePublished\":\"2011-10-20T14:39:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/disabili-no-alla-legge-sulla-riforma-assistenziale-ieri-la-relazione-a-montecitorio\\\/\"},\"wordCount\":277,\"commentCount\":0,\"keywords\":[\"disabilit\u00e0\",\"Fand\",\"Legge Delega Riforma assistenziale\",\"Montecitorio\"],\"articleSection\":[\"Pionieri Silenziosi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/disabili-no-alla-legge-sulla-riforma-assistenziale-ieri-la-relazione-a-montecitorio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/disabili-no-alla-legge-sulla-riforma-assistenziale-ieri-la-relazione-a-montecitorio\\\/\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/disabili-no-alla-legge-sulla-riforma-assistenziale-ieri-la-relazione-a-montecitorio\\\/\",\"name\":\"Disabili: \\\"No alla legge sulla Riforma Assistenziale\\\". Ieri la relazione a Montecitorio - Pionieri silenziosi\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/#website\"},\"datePublished\":\"2011-10-20T14:39:08+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/#\\\/schema\\\/person\\\/1e4e6180afb10cca8c7da51aba1ac37d\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/disabili-no-alla-legge-sulla-riforma-assistenziale-ieri-la-relazione-a-montecitorio\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/#website\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/\",\"name\":\"Pionieri silenziosi\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/#\\\/schema\\\/person\\\/1e4e6180afb10cca8c7da51aba1ac37d\",\"name\":\"Lorenzo Montanaro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4cb7183827096260c06fef52eb85a6a857832d5733bc002257d81b8b80561ff5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4cb7183827096260c06fef52eb85a6a857832d5733bc002257d81b8b80561ff5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4cb7183827096260c06fef52eb85a6a857832d5733bc002257d81b8b80561ff5?s=96&d=mm&r=g\",\"caption\":\"Lorenzo Montanaro\"},\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/author\\\/lorenzo-montanaro\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Disabili: \"No alla legge sulla Riforma Assistenziale\". Ieri la relazione a Montecitorio - Pionieri silenziosi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/disabili-no-alla-legge-sulla-riforma-assistenziale-ieri-la-relazione-a-montecitorio\/","og_locale":"it_IT","og_type":"article","og_title":"Disabili: \"No alla legge sulla Riforma Assistenziale\". Ieri la relazione a Montecitorio - Pionieri silenziosi","og_description":"Il Disegno di Legge Delega sulla Riforma Assistenziale, attualmente in discussione alla Commissione Affari Sociali della Camera, incassa un altro risoluto no dal mondo dei disabili. Ieri la Fand (Federazione delle Associazioni Nazionali dei Disabili), un organismo di cui fanno parte alcune realt\u00e0 storiche come l&#8217;Unione Italiana Ciechi, l&#8217;Ente Nazionale Sordi e l&#8217;Associazione Mutilati e &hellip; Leggi tutto \"Disabili: &#8220;No alla legge sulla Riforma Assistenziale&#8221;. Ieri la relazione a Montecitorio\"","og_url":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/disabili-no-alla-legge-sulla-riforma-assistenziale-ieri-la-relazione-a-montecitorio\/","og_site_name":"Pionieri silenziosi","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2011-10-20T14:39:08+00:00","author":"Lorenzo Montanaro","twitter_misc":{"Scritto da":"Lorenzo Montanaro","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/disabili-no-alla-legge-sulla-riforma-assistenziale-ieri-la-relazione-a-montecitorio\/#article","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/disabili-no-alla-legge-sulla-riforma-assistenziale-ieri-la-relazione-a-montecitorio\/"},"author":{"name":"Lorenzo Montanaro","@id":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/#\/schema\/person\/1e4e6180afb10cca8c7da51aba1ac37d"},"headline":"Disabili: &#8220;No alla legge sulla Riforma Assistenziale&#8221;. Ieri la relazione a Montecitorio","datePublished":"2011-10-20T14:39:08+00:00","mainEntityOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/disabili-no-alla-legge-sulla-riforma-assistenziale-ieri-la-relazione-a-montecitorio\/"},"wordCount":277,"commentCount":0,"keywords":["disabilit\u00e0","Fand","Legge Delega Riforma assistenziale","Montecitorio"],"articleSection":["Pionieri Silenziosi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/disabili-no-alla-legge-sulla-riforma-assistenziale-ieri-la-relazione-a-montecitorio\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/disabili-no-alla-legge-sulla-riforma-assistenziale-ieri-la-relazione-a-montecitorio\/","url":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/disabili-no-alla-legge-sulla-riforma-assistenziale-ieri-la-relazione-a-montecitorio\/","name":"Disabili: \"No alla legge sulla Riforma Assistenziale\". Ieri la relazione a Montecitorio - Pionieri silenziosi","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/#website"},"datePublished":"2011-10-20T14:39:08+00:00","author":{"@id":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/#\/schema\/person\/1e4e6180afb10cca8c7da51aba1ac37d"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/disabili-no-alla-legge-sulla-riforma-assistenziale-ieri-la-relazione-a-montecitorio\/"]}]},{"@type":"WebSite","@id":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/#website","url":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/","name":"Pionieri silenziosi","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/#\/schema\/person\/1e4e6180afb10cca8c7da51aba1ac37d","name":"Lorenzo Montanaro","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4cb7183827096260c06fef52eb85a6a857832d5733bc002257d81b8b80561ff5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4cb7183827096260c06fef52eb85a6a857832d5733bc002257d81b8b80561ff5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4cb7183827096260c06fef52eb85a6a857832d5733bc002257d81b8b80561ff5?s=96&d=mm&r=g","caption":"Lorenzo Montanaro"},"url":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/author\/lorenzo-montanaro\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/wp-json\/wp\/v2\/posts\/87","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/wp-json\/wp\/v2\/comments?post=87"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/wp-json\/wp\/v2\/posts\/87\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/wp-json\/wp\/v2\/media?parent=87"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/wp-json\/wp\/v2\/categories?post=87"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/wp-json\/wp\/v2\/tags?post=87"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}