{"id":237,"date":"2012-04-03T09:36:36","date_gmt":"2012-04-03T08:36:36","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/pionierisilenziosi\/?p=237"},"modified":"2012-04-03T09:36:36","modified_gmt":"2012-04-03T08:36:36","slug":"una-luce-blu-per-la-giornata-mondiale-dellautismo","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/una-luce-blu-per-la-giornata-mondiale-dellautismo\/","title":{"rendered":"Una luce blu per la giornata mondiale dell&#8217;autismo"},"content":{"rendered":"<p style=\"text-align: justify\"><a href=\"http:\/\/www.quotidianopiemontese.it\/pionierisilenziosi\/files\/2012\/04\/Terrazza-sul-Po-def.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-thumbnail wp-image-239\" src=\"http:\/\/www.quotidianopiemontese.it\/pionierisilenziosi\/files\/2012\/04\/Terrazza-sul-Po-def-150x120.jpg\" alt=\"\" width=\"150\" height=\"120\" \/><\/a>Una luce blu accesa nella sera torinese: un messaggio tenue e forte insieme, un ponte lanciato verso la citt\u00e0 e il mondo. Luned\u00ec 2 aprile, in occasione della giornata mondiale dell&#8217;autismo promossa dalle nazioni unite, la Terrazza sul Po, edificio di Corso Moncalieri dove hanno sede il Centro del Protagonismo Giovanile e gli Amici del Fiume, si \u00e8 illuminato di blu. L&#8217;iniziativa \u00e8 stata voluta dall&#8217;Ama (Associazione Missione Autismo) e si \u00e8 inserita in un progetto ben pi\u00f9 ampio. Qualcosa di simile \u00e8 accaduto in varie citt\u00e0 del pianeta, dove palazzi e luoghi simbolo si sono accesi di blu, per richiamare l&#8217;attenzione su una patologia psichica che coinvolge migliaia di famiglie. Secondo una stima dell&#8217;Istituto Superiore di Sanit\u00e0, nel nostro Paese l&#8217;autismo colpisce una persona su 150.<!--more--><\/p>\n<p style=\"text-align: justify\">Al di l\u00e0 di qualche rappresentazione cinematografica (a volte un po&#8217; romanzata e semplicistica) la sindrome di Asperger \u00e8 una patologia ancora poco conosciuta. E spesso, quando viene diagnosticata, le famiglie si scoprono sole e fragili davanti a una realt\u00e0 difficilissima da affrontare. Da qui la missione dell&#8217;Ama, associazione torinese giovane, fondata nel 2009 con l&#8217;obiettivo di creare una rete e fornire alle famiglie con persone autistiche sostegno medico, formazione e strumenti adeguati. Per capire lo spirito dell&#8217;associazione basta dare un&#8217;occhiata alla locandina con cui si presenta. In primo piano una catena spezzata e la scritta: &#8220;L&#8217;autismo \u00e8 trattabile&#8221;.<\/p>\n<p style=\"text-align: justify\">Info <a href=\"http:\/\/amaautismo.altervista.org\/\" target=\"_blank\">http:\/\/amaautismo.altervista.org\/<\/a><\/p>\n<p style=\"text-align: justify\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una luce blu accesa nella sera torinese: un messaggio tenue e forte insieme, un ponte lanciato verso la citt\u00e0 e il mondo. Luned\u00ec 2 aprile, in occasione della giornata mondiale dell&#8217;autismo promossa dalle nazioni unite, la Terrazza sul Po, edificio di Corso Moncalieri dove hanno sede il Centro del Protagonismo Giovanile e gli Amici del &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/una-luce-blu-per-la-giornata-mondiale-dellautismo\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Una luce blu per la giornata mondiale dell&#8217;autismo&#8221;<\/span><\/a><\/p>\n","protected":false},"author":38,"featured_media":239,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[230,227,229,228,231],"class_list":["post-237","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pionieri-silenziosi","tag-associazione-missione-autismo","tag-autismo","tag-giornata-mondiale-dellautismo","tag-sindrome-di-asperger","tag-terrazza-sul-po"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Una luce blu per la giornata mondiale dell&#039;autismo - Pionieri silenziosi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/una-luce-blu-per-la-giornata-mondiale-dellautismo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una luce blu per la giornata mondiale dell&#039;autismo - Pionieri silenziosi\" \/>\n<meta property=\"og:description\" content=\"Una luce blu accesa nella sera torinese: un messaggio tenue e forte insieme, un ponte lanciato verso la citt\u00e0 e il mondo. Luned\u00ec 2 aprile, in occasione della giornata mondiale dell&#8217;autismo promossa dalle nazioni unite, la Terrazza sul Po, edificio di Corso Moncalieri dove hanno sede il Centro del Protagonismo Giovanile e gli Amici del &hellip; Leggi tutto &quot;Una luce blu per la giornata mondiale dell&#8217;autismo&quot;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/una-luce-blu-per-la-giornata-mondiale-dellautismo\/\" \/>\n<meta property=\"og:site_name\" content=\"Pionieri silenziosi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2012-04-03T08:36:36+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/files\/2012\/04\/Terrazza-sul-Po-def.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"180\" \/>\n\t<meta property=\"og:image:height\" content=\"120\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lorenzo Montanaro\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lorenzo Montanaro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/una-luce-blu-per-la-giornata-mondiale-dellautismo\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/una-luce-blu-per-la-giornata-mondiale-dellautismo\\\/\"},\"author\":{\"name\":\"Lorenzo Montanaro\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/#\\\/schema\\\/person\\\/1e4e6180afb10cca8c7da51aba1ac37d\"},\"headline\":\"Una luce blu per la giornata mondiale dell&#8217;autismo\",\"datePublished\":\"2012-04-03T08:36:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/una-luce-blu-per-la-giornata-mondiale-dellautismo\\\/\"},\"wordCount\":242,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/una-luce-blu-per-la-giornata-mondiale-dellautismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/files\\\/2012\\\/04\\\/Terrazza-sul-Po-def.jpg\",\"keywords\":[\"associazione missione autismo\",\"autismo\",\"giornata mondiale dell'autismo\",\"sindrome di Asperger\",\"terrazza sul Po\"],\"articleSection\":[\"Pionieri Silenziosi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/una-luce-blu-per-la-giornata-mondiale-dellautismo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/una-luce-blu-per-la-giornata-mondiale-dellautismo\\\/\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/una-luce-blu-per-la-giornata-mondiale-dellautismo\\\/\",\"name\":\"Una luce blu per la giornata mondiale dell'autismo - Pionieri silenziosi\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/una-luce-blu-per-la-giornata-mondiale-dellautismo\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/una-luce-blu-per-la-giornata-mondiale-dellautismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/files\\\/2012\\\/04\\\/Terrazza-sul-Po-def.jpg\",\"datePublished\":\"2012-04-03T08:36:36+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/#\\\/schema\\\/person\\\/1e4e6180afb10cca8c7da51aba1ac37d\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/una-luce-blu-per-la-giornata-mondiale-dellautismo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/una-luce-blu-per-la-giornata-mondiale-dellautismo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/files\\\/2012\\\/04\\\/Terrazza-sul-Po-def.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/files\\\/2012\\\/04\\\/Terrazza-sul-Po-def.jpg\",\"width\":\"180\",\"height\":\"120\"},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/#website\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/\",\"name\":\"Pionieri silenziosi\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/#\\\/schema\\\/person\\\/1e4e6180afb10cca8c7da51aba1ac37d\",\"name\":\"Lorenzo Montanaro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4cb7183827096260c06fef52eb85a6a857832d5733bc002257d81b8b80561ff5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4cb7183827096260c06fef52eb85a6a857832d5733bc002257d81b8b80561ff5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4cb7183827096260c06fef52eb85a6a857832d5733bc002257d81b8b80561ff5?s=96&d=mm&r=g\",\"caption\":\"Lorenzo Montanaro\"},\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/author\\\/lorenzo-montanaro\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una luce blu per la giornata mondiale dell'autismo - Pionieri silenziosi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/una-luce-blu-per-la-giornata-mondiale-dellautismo\/","og_locale":"it_IT","og_type":"article","og_title":"Una luce blu per la giornata mondiale dell'autismo - Pionieri silenziosi","og_description":"Una luce blu accesa nella sera torinese: un messaggio tenue e forte insieme, un ponte lanciato verso la citt\u00e0 e il mondo. Luned\u00ec 2 aprile, in occasione della giornata mondiale dell&#8217;autismo promossa dalle nazioni unite, la Terrazza sul Po, edificio di Corso Moncalieri dove hanno sede il Centro del Protagonismo Giovanile e gli Amici del &hellip; Leggi tutto \"Una luce blu per la giornata mondiale dell&#8217;autismo\"","og_url":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/una-luce-blu-per-la-giornata-mondiale-dellautismo\/","og_site_name":"Pionieri silenziosi","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2012-04-03T08:36:36+00:00","og_image":[{"width":180,"height":120,"url":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/files\/2012\/04\/Terrazza-sul-Po-def.jpg","type":"image\/jpeg"}],"author":"Lorenzo Montanaro","twitter_misc":{"Scritto da":"Lorenzo Montanaro","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/una-luce-blu-per-la-giornata-mondiale-dellautismo\/#article","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/una-luce-blu-per-la-giornata-mondiale-dellautismo\/"},"author":{"name":"Lorenzo Montanaro","@id":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/#\/schema\/person\/1e4e6180afb10cca8c7da51aba1ac37d"},"headline":"Una luce blu per la giornata mondiale dell&#8217;autismo","datePublished":"2012-04-03T08:36:36+00:00","mainEntityOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/una-luce-blu-per-la-giornata-mondiale-dellautismo\/"},"wordCount":242,"commentCount":0,"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/una-luce-blu-per-la-giornata-mondiale-dellautismo\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/files\/2012\/04\/Terrazza-sul-Po-def.jpg","keywords":["associazione missione autismo","autismo","giornata mondiale dell'autismo","sindrome di Asperger","terrazza sul Po"],"articleSection":["Pionieri Silenziosi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/una-luce-blu-per-la-giornata-mondiale-dellautismo\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/una-luce-blu-per-la-giornata-mondiale-dellautismo\/","url":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/una-luce-blu-per-la-giornata-mondiale-dellautismo\/","name":"Una luce blu per la giornata mondiale dell'autismo - Pionieri silenziosi","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/#website"},"primaryImageOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/una-luce-blu-per-la-giornata-mondiale-dellautismo\/#primaryimage"},"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/una-luce-blu-per-la-giornata-mondiale-dellautismo\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/files\/2012\/04\/Terrazza-sul-Po-def.jpg","datePublished":"2012-04-03T08:36:36+00:00","author":{"@id":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/#\/schema\/person\/1e4e6180afb10cca8c7da51aba1ac37d"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/una-luce-blu-per-la-giornata-mondiale-dellautismo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/una-luce-blu-per-la-giornata-mondiale-dellautismo\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/files\/2012\/04\/Terrazza-sul-Po-def.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/files\/2012\/04\/Terrazza-sul-Po-def.jpg","width":"180","height":"120"},{"@type":"WebSite","@id":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/#website","url":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/","name":"Pionieri silenziosi","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/#\/schema\/person\/1e4e6180afb10cca8c7da51aba1ac37d","name":"Lorenzo Montanaro","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4cb7183827096260c06fef52eb85a6a857832d5733bc002257d81b8b80561ff5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4cb7183827096260c06fef52eb85a6a857832d5733bc002257d81b8b80561ff5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4cb7183827096260c06fef52eb85a6a857832d5733bc002257d81b8b80561ff5?s=96&d=mm&r=g","caption":"Lorenzo Montanaro"},"url":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/author\/lorenzo-montanaro\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/wp-json\/wp\/v2\/posts\/237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/wp-json\/wp\/v2\/comments?post=237"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/wp-json\/wp\/v2\/posts\/237\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/wp-json\/wp\/v2\/media\/239"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/wp-json\/wp\/v2\/media?parent=237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/wp-json\/wp\/v2\/categories?post=237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/wp-json\/wp\/v2\/tags?post=237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}