{"id":140,"date":"2011-12-22T17:53:48","date_gmt":"2011-12-22T16:53:48","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/pionierisilenziosi\/?p=140"},"modified":"2011-12-22T17:53:48","modified_gmt":"2011-12-22T16:53:48","slug":"pensioni-di-indennita-tempi-dattesa-infiniti-irregolarita-e-abusi-dura-denuncia-di-cittadinanzattiva-contro-linps","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/pensioni-di-indennita-tempi-dattesa-infiniti-irregolarita-e-abusi-dura-denuncia-di-cittadinanzattiva-contro-linps\/","title":{"rendered":"Pensioni di indennit\u00e0: tempi d&#8217;attesa infiniti, irregolarit\u00e0 e abusi. Dura denuncia di Cittadinanzattiva contro l&#8217;Inps"},"content":{"rendered":"<p style=\"text-align: justify\">&#8220;Totale disprezzo delle norme, inefficienza, abuso di potere. All&#8217;associazione <a href=\"http:\/\/www.cittadinanzattiva.it\/\">Cittadinanzattiva<\/a> i mezzi termini e i toni accomodanti proprio non si addicono. Riguardo al delicato tema delle pensioni di invalidit\u00e0, gi\u00e0 oggetto di infinite diatribe nei mesi scorsi, l&#8217;associazione prende una posizione dura nei confronti dell&#8217;Inps, scagliandosi contro i tempi lunghissimi di attesa, l&#8217;eccessiva burocrazia e la scorrettezza di certe procedure. Tutti ostacoli che rischiano di aggravare le condizioni di \u201cestremo disagio in cui versano tutti quei cittadini che, del tutto legittimamente, aspirano al riconoscimento delle indennit\u00e0 economiche correlate alle minorazioni civili\u201d.<!--more--><\/p>\n<p style=\"text-align: justify\">&#8220;Dopo la visita della commissione Asl integrata con un medico dell\u2019Inps \u2013 afferma l&#8217;associazione &#8211; gli interessati sono obbligati ad ulteriori accertamenti, in contrasto con gli obiettivi di semplificazione e di rispetto della dignit\u00e0 della persona; sono costretti ad attendere a lungo i verbali degli accertamenti sanitari e a fare i conti con procedure di pagamento bloccate da tempo&#8221;. Non solo. La denuncia prosegue affermando che le azioni intraprese dall&#8217;Inps \u201criducono arbitrariamente i requisiti previsti dalla legge per l\u2019assegnazione delle indennit\u00e0 e appaiono strumentalizzate per il raggiungimento di un obiettivo non dichiarato, ovvero il massimo contenimento possibile della spesa assistenziale\u201d.<\/p>\n<p style=\"text-align: justify\">Accuse pesanti, che si concludono con un appello rivolto allo Stato: sarebbe ora di intraprendere \u201cazioni ad hoc anche nei confronti dei propri funzionari che violano le norme e non soltanto controlli, in molti casi vessatori, nei confronti dei cittadini&#8221;. Insomma, siamo all&#8217;ennesima puntata della saga &#8216;Inps contro associazioni di categoria&#8217;, un contenzioso in cui, ovviamente, non ha nessun senso schierarsi, come allo stadio, per una fazione o per l&#8217;altra. Cercando di non generalizzare, ci permettiamo solo un piccolo commento.<\/p>\n<p style=\"text-align: justify\">\u00a0La denuncia di Cittadinanzattiva sembra il condensato di mille denunce individuali, quelle che certamente chiunque abbia fatto un giro nei corridoi Inps avr\u00e0 potuto sentire: denunce di persone esasperate, denunce di disabili gravi (o di loro familiari) che non ne possono pi\u00f9 di rimbalzare da un ufficio all&#8217;altro, da una commissione all&#8217;altra, sempre all&#8217;inseguimento dell&#8217;ennesimo timbro, dell&#8217;ultimo verbale. Denunce di persone che probabilmente non hanno nessuna ragione per mentire o per barare, ma semplicemente vivono un disagio cui sarebbe il momento di dare una risposta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Totale disprezzo delle norme, inefficienza, abuso di potere. All&#8217;associazione Cittadinanzattiva i mezzi termini e i toni accomodanti proprio non si addicono. Riguardo al delicato tema delle pensioni di invalidit\u00e0, gi\u00e0 oggetto di infinite diatribe nei mesi scorsi, l&#8217;associazione prende una posizione dura nei confronti dell&#8217;Inps, scagliandosi contro i tempi lunghissimi di attesa, l&#8217;eccessiva burocrazia e &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/pensioni-di-indennita-tempi-dattesa-infiniti-irregolarita-e-abusi-dura-denuncia-di-cittadinanzattiva-contro-linps\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Pensioni di indennit\u00e0: tempi d&#8217;attesa infiniti, irregolarit\u00e0 e abusi. Dura denuncia di Cittadinanzattiva contro l&#8217;Inps&#8221;<\/span><\/a><\/p>\n","protected":false},"author":38,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[150,4,148,86,149],"class_list":["post-140","post","type-post","status-publish","format-standard","hentry","category-pionieri-silenziosi","tag-cittadinanzattiva","tag-disabili","tag-indennita","tag-inps","tag-invalidi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pensioni di indennit\u00e0: tempi d&#039;attesa infiniti, irregolarit\u00e0 e abusi. Dura denuncia di Cittadinanzattiva contro l&#039;Inps - Pionieri silenziosi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/pensioni-di-indennita-tempi-dattesa-infiniti-irregolarita-e-abusi-dura-denuncia-di-cittadinanzattiva-contro-linps\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pensioni di indennit\u00e0: tempi d&#039;attesa infiniti, irregolarit\u00e0 e abusi. Dura denuncia di Cittadinanzattiva contro l&#039;Inps - Pionieri silenziosi\" \/>\n<meta property=\"og:description\" content=\"&#8220;Totale disprezzo delle norme, inefficienza, abuso di potere. All&#8217;associazione Cittadinanzattiva i mezzi termini e i toni accomodanti proprio non si addicono. Riguardo al delicato tema delle pensioni di invalidit\u00e0, gi\u00e0 oggetto di infinite diatribe nei mesi scorsi, l&#8217;associazione prende una posizione dura nei confronti dell&#8217;Inps, scagliandosi contro i tempi lunghissimi di attesa, l&#8217;eccessiva burocrazia e &hellip; Leggi tutto &quot;Pensioni di indennit\u00e0: tempi d&#8217;attesa infiniti, irregolarit\u00e0 e abusi. Dura denuncia di Cittadinanzattiva contro l&#8217;Inps&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/pensioni-di-indennita-tempi-dattesa-infiniti-irregolarita-e-abusi-dura-denuncia-di-cittadinanzattiva-contro-linps\/\" \/>\n<meta property=\"og:site_name\" content=\"Pionieri silenziosi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2011-12-22T16:53:48+00:00\" \/>\n<meta name=\"author\" content=\"Lorenzo Montanaro\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lorenzo Montanaro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/pensioni-di-indennita-tempi-dattesa-infiniti-irregolarita-e-abusi-dura-denuncia-di-cittadinanzattiva-contro-linps\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/pensioni-di-indennita-tempi-dattesa-infiniti-irregolarita-e-abusi-dura-denuncia-di-cittadinanzattiva-contro-linps\\\/\"},\"author\":{\"name\":\"Lorenzo Montanaro\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/#\\\/schema\\\/person\\\/1e4e6180afb10cca8c7da51aba1ac37d\"},\"headline\":\"Pensioni di indennit\u00e0: tempi d&#8217;attesa infiniti, irregolarit\u00e0 e abusi. Dura denuncia di Cittadinanzattiva contro l&#8217;Inps\",\"datePublished\":\"2011-12-22T16:53:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/pensioni-di-indennita-tempi-dattesa-infiniti-irregolarita-e-abusi-dura-denuncia-di-cittadinanzattiva-contro-linps\\\/\"},\"wordCount\":387,\"commentCount\":0,\"keywords\":[\"Cittadinanzattiva\",\"disabili\",\"indennit\u00e0\",\"Inps\",\"invalidi\"],\"articleSection\":[\"Pionieri Silenziosi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/pensioni-di-indennita-tempi-dattesa-infiniti-irregolarita-e-abusi-dura-denuncia-di-cittadinanzattiva-contro-linps\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/pensioni-di-indennita-tempi-dattesa-infiniti-irregolarita-e-abusi-dura-denuncia-di-cittadinanzattiva-contro-linps\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/pensioni-di-indennita-tempi-dattesa-infiniti-irregolarita-e-abusi-dura-denuncia-di-cittadinanzattiva-contro-linps\\\/\",\"name\":\"Pensioni di indennit\u00e0: tempi d'attesa infiniti, irregolarit\u00e0 e abusi. Dura denuncia di Cittadinanzattiva contro l'Inps - Pionieri silenziosi\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/#website\"},\"datePublished\":\"2011-12-22T16:53:48+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/#\\\/schema\\\/person\\\/1e4e6180afb10cca8c7da51aba1ac37d\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/pensioni-di-indennita-tempi-dattesa-infiniti-irregolarita-e-abusi-dura-denuncia-di-cittadinanzattiva-contro-linps\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/#website\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/\",\"name\":\"Pionieri silenziosi\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/#\\\/schema\\\/person\\\/1e4e6180afb10cca8c7da51aba1ac37d\",\"name\":\"Lorenzo Montanaro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4cb7183827096260c06fef52eb85a6a857832d5733bc002257d81b8b80561ff5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4cb7183827096260c06fef52eb85a6a857832d5733bc002257d81b8b80561ff5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4cb7183827096260c06fef52eb85a6a857832d5733bc002257d81b8b80561ff5?s=96&d=mm&r=g\",\"caption\":\"Lorenzo Montanaro\"},\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/pionierisilenziosi\\\/author\\\/lorenzo-montanaro\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pensioni di indennit\u00e0: tempi d'attesa infiniti, irregolarit\u00e0 e abusi. Dura denuncia di Cittadinanzattiva contro l'Inps - Pionieri silenziosi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/pensioni-di-indennita-tempi-dattesa-infiniti-irregolarita-e-abusi-dura-denuncia-di-cittadinanzattiva-contro-linps\/","og_locale":"it_IT","og_type":"article","og_title":"Pensioni di indennit\u00e0: tempi d'attesa infiniti, irregolarit\u00e0 e abusi. Dura denuncia di Cittadinanzattiva contro l'Inps - Pionieri silenziosi","og_description":"&#8220;Totale disprezzo delle norme, inefficienza, abuso di potere. All&#8217;associazione Cittadinanzattiva i mezzi termini e i toni accomodanti proprio non si addicono. Riguardo al delicato tema delle pensioni di invalidit\u00e0, gi\u00e0 oggetto di infinite diatribe nei mesi scorsi, l&#8217;associazione prende una posizione dura nei confronti dell&#8217;Inps, scagliandosi contro i tempi lunghissimi di attesa, l&#8217;eccessiva burocrazia e &hellip; Leggi tutto \"Pensioni di indennit\u00e0: tempi d&#8217;attesa infiniti, irregolarit\u00e0 e abusi. Dura denuncia di Cittadinanzattiva contro l&#8217;Inps\"","og_url":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/pensioni-di-indennita-tempi-dattesa-infiniti-irregolarita-e-abusi-dura-denuncia-di-cittadinanzattiva-contro-linps\/","og_site_name":"Pionieri silenziosi","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2011-12-22T16:53:48+00:00","author":"Lorenzo Montanaro","twitter_misc":{"Scritto da":"Lorenzo Montanaro","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/pensioni-di-indennita-tempi-dattesa-infiniti-irregolarita-e-abusi-dura-denuncia-di-cittadinanzattiva-contro-linps\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/pensioni-di-indennita-tempi-dattesa-infiniti-irregolarita-e-abusi-dura-denuncia-di-cittadinanzattiva-contro-linps\/"},"author":{"name":"Lorenzo Montanaro","@id":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/#\/schema\/person\/1e4e6180afb10cca8c7da51aba1ac37d"},"headline":"Pensioni di indennit\u00e0: tempi d&#8217;attesa infiniti, irregolarit\u00e0 e abusi. Dura denuncia di Cittadinanzattiva contro l&#8217;Inps","datePublished":"2011-12-22T16:53:48+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/pensioni-di-indennita-tempi-dattesa-infiniti-irregolarita-e-abusi-dura-denuncia-di-cittadinanzattiva-contro-linps\/"},"wordCount":387,"commentCount":0,"keywords":["Cittadinanzattiva","disabili","indennit\u00e0","Inps","invalidi"],"articleSection":["Pionieri Silenziosi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/pensioni-di-indennita-tempi-dattesa-infiniti-irregolarita-e-abusi-dura-denuncia-di-cittadinanzattiva-contro-linps\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/pensioni-di-indennita-tempi-dattesa-infiniti-irregolarita-e-abusi-dura-denuncia-di-cittadinanzattiva-contro-linps\/","url":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/pensioni-di-indennita-tempi-dattesa-infiniti-irregolarita-e-abusi-dura-denuncia-di-cittadinanzattiva-contro-linps\/","name":"Pensioni di indennit\u00e0: tempi d'attesa infiniti, irregolarit\u00e0 e abusi. Dura denuncia di Cittadinanzattiva contro l'Inps - Pionieri silenziosi","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/#website"},"datePublished":"2011-12-22T16:53:48+00:00","author":{"@id":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/#\/schema\/person\/1e4e6180afb10cca8c7da51aba1ac37d"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/pensioni-di-indennita-tempi-dattesa-infiniti-irregolarita-e-abusi-dura-denuncia-di-cittadinanzattiva-contro-linps\/"]}]},{"@type":"WebSite","@id":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/#website","url":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/","name":"Pionieri silenziosi","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"http:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/#\/schema\/person\/1e4e6180afb10cca8c7da51aba1ac37d","name":"Lorenzo Montanaro","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4cb7183827096260c06fef52eb85a6a857832d5733bc002257d81b8b80561ff5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4cb7183827096260c06fef52eb85a6a857832d5733bc002257d81b8b80561ff5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4cb7183827096260c06fef52eb85a6a857832d5733bc002257d81b8b80561ff5?s=96&d=mm&r=g","caption":"Lorenzo Montanaro"},"url":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/author\/lorenzo-montanaro\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/wp-json\/wp\/v2\/posts\/140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/wp-json\/wp\/v2\/comments?post=140"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/wp-json\/wp\/v2\/posts\/140\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/wp-json\/wp\/v2\/media?parent=140"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/wp-json\/wp\/v2\/categories?post=140"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/pionierisilenziosi\/wp-json\/wp\/v2\/tags?post=140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}