{"id":60,"date":"2016-12-29T10:57:13","date_gmt":"2016-12-29T09:57:13","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/offerte-lavoro-piemonte\/?p=60"},"modified":"2016-12-29T10:57:48","modified_gmt":"2016-12-29T09:57:48","slug":"il-comune-di-torino-cerca-giovani-tra-i-18-e-i-29-anni-per-il-progetto-giovani-per-lintegrazione","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-comune-di-torino-cerca-giovani-tra-i-18-e-i-29-anni-per-il-progetto-giovani-per-lintegrazione\/","title":{"rendered":"Il comune di Torino cerca giovani tra i 18 e i 29 anni per il progetto &#8220;Giovani per l&#8217;integrazione"},"content":{"rendered":"<p>Il comune di Torino cerca giovani tra i 18 e i 29 anni per il progetto &#8220;Giovani per l&#8217;integrazione. Le candidature devono essere inviate entro il 27 gennaio. Il progetto \u201cGiovani per l\u2019Integrazione\u201d si propone di facilitare il dialogo<!--more--> tra cittadine\/i e istituzioni, a partire dagli uffici che ricevono il pubblico, fino a sperimentare nuove modalit\u00e0 di<br \/>\nprima informazione sui servizi offerti dalla citt\u00e0 a chi proviene da Paesi terzi.<\/p>\n<p>Il progetto, ideato e coordinato dalla Citt\u00e0 di Torino e sostenuto dalla Compagnia di San Paolo, ha l\u2019intento di valorizzare il ruolo dei gio vani torinesi attraverso un\u2019attivit\u00e0 di informazione e comunicazione con l\u2019utenza, soprattutto di origine straniera, e in sinergia con gli operatori degli uffici pubblici, al fine di superare i problemi di comprensione della modulistica e delle procedure.<\/p>\n<p>Ecco il bando completo<\/p>\n<p><iframe loading=\"lazy\" style=\"border: 1px solid #CCC; border-width: 1px; margin-bottom: 5px; max-width: 100%;\" src=\"\/\/www.slideshare.net\/slideshow\/embed_code\/key\/46VJEbiXx9slxA\" width=\"668\" height=\"714\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"> <\/iframe><\/p>\n<div style=\"margin-bottom: 5px;\"><strong> <a title=\"Bando &quot;Giovani per l'integrazione&quot; a Torino\" href=\"\/\/www.slideshare.net\/quotidianopiemontese\/bando-giovani-per-lintegrazione-a-torino\" target=\"_blank\">Bando &#8220;Giovani per l&#8217;integrazione&#8221; a Torino<\/a> <\/strong> from <strong><a href=\"\/\/www.slideshare.net\/quotidianopiemontese\" target=\"_blank\">Quotidiano Piemontese<\/a><\/strong><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Il comune di Torino cerca giovani tra i 18 e i 29 anni per il progetto &#8220;Giovani per l&#8217;integrazione. Le candidature devono essere inviate entro il 27 gennaio. Il progetto \u201cGiovani per l\u2019Integrazione\u201d si propone di facilitare il dialogo<\/p>\n","protected":false},"author":1,"featured_media":61,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[11],"class_list":["post-60","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-offerte-lavoro","tag-comune-di-torino"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il comune di Torino cerca giovani tra i 18 e i 29 anni per il progetto &quot;Giovani per l&#039;integrazione - Offerte di Lavoro in Piemonte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-comune-di-torino-cerca-giovani-tra-i-18-e-i-29-anni-per-il-progetto-giovani-per-lintegrazione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il comune di Torino cerca giovani tra i 18 e i 29 anni per il progetto &quot;Giovani per l&#039;integrazione - Offerte di Lavoro in Piemonte\" \/>\n<meta property=\"og:description\" content=\"Il comune di Torino cerca giovani tra i 18 e i 29 anni per il progetto &#8220;Giovani per l&#8217;integrazione. Le candidature devono essere inviate entro il 27 gennaio. Il progetto \u201cGiovani per l\u2019Integrazione\u201d si propone di facilitare il dialogo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-comune-di-torino-cerca-giovani-tra-i-18-e-i-29-anni-per-il-progetto-giovani-per-lintegrazione\/\" \/>\n<meta property=\"og:site_name\" content=\"Offerte di Lavoro in Piemonte\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese\" \/>\n<meta property=\"article:published_time\" content=\"2016-12-29T09:57:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-12-29T09:57:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2016\/12\/bando-giovani-integrazione.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"917\" \/>\n\t<meta property=\"og:image:height\" content=\"560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@quotidianopiem\" \/>\n<meta name=\"twitter:site\" content=\"@quotidianopiem\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-comune-di-torino-cerca-giovani-tra-i-18-e-i-29-anni-per-il-progetto-giovani-per-lintegrazione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-comune-di-torino-cerca-giovani-tra-i-18-e-i-29-anni-per-il-progetto-giovani-per-lintegrazione\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"headline\":\"Il comune di Torino cerca giovani tra i 18 e i 29 anni per il progetto &#8220;Giovani per l&#8217;integrazione\",\"datePublished\":\"2016-12-29T09:57:13+00:00\",\"dateModified\":\"2016-12-29T09:57:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-comune-di-torino-cerca-giovani-tra-i-18-e-i-29-anni-per-il-progetto-giovani-per-lintegrazione\\\/\"},\"wordCount\":165,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-comune-di-torino-cerca-giovani-tra-i-18-e-i-29-anni-per-il-progetto-giovani-per-lintegrazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/files\\\/2016\\\/12\\\/bando-giovani-integrazione.jpg\",\"keywords\":[\"comune di torino\"],\"articleSection\":[\"Offerte Lavoro\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-comune-di-torino-cerca-giovani-tra-i-18-e-i-29-anni-per-il-progetto-giovani-per-lintegrazione\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-comune-di-torino-cerca-giovani-tra-i-18-e-i-29-anni-per-il-progetto-giovani-per-lintegrazione\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-comune-di-torino-cerca-giovani-tra-i-18-e-i-29-anni-per-il-progetto-giovani-per-lintegrazione\\\/\",\"name\":\"Il comune di Torino cerca giovani tra i 18 e i 29 anni per il progetto \\\"Giovani per l'integrazione - Offerte di Lavoro in Piemonte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-comune-di-torino-cerca-giovani-tra-i-18-e-i-29-anni-per-il-progetto-giovani-per-lintegrazione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-comune-di-torino-cerca-giovani-tra-i-18-e-i-29-anni-per-il-progetto-giovani-per-lintegrazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/files\\\/2016\\\/12\\\/bando-giovani-integrazione.jpg\",\"datePublished\":\"2016-12-29T09:57:13+00:00\",\"dateModified\":\"2016-12-29T09:57:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-comune-di-torino-cerca-giovani-tra-i-18-e-i-29-anni-per-il-progetto-giovani-per-lintegrazione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-comune-di-torino-cerca-giovani-tra-i-18-e-i-29-anni-per-il-progetto-giovani-per-lintegrazione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-comune-di-torino-cerca-giovani-tra-i-18-e-i-29-anni-per-il-progetto-giovani-per-lintegrazione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/files\\\/2016\\\/12\\\/bando-giovani-integrazione.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/files\\\/2016\\\/12\\\/bando-giovani-integrazione.jpg\",\"width\":917,\"height\":560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/il-comune-di-torino-cerca-giovani-tra-i-18-e-i-29-anni-per-il-progetto-giovani-per-lintegrazione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il comune di Torino cerca giovani tra i 18 e i 29 anni per il progetto &#8220;Giovani per l&#8217;integrazione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/\",\"name\":\"Offerte di Lavoro in Piemonte\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte\",\"sameAs\":[\"http:\\\/\\\/www.quotidianopiemontese.it\\\/\",\"https:\\\/\\\/www.facebook.com\\\/quotidianopiemontese\",\"https:\\\/\\\/x.com\\\/quotidianopiem\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/offerte-lavoro-piemonte\\\/author\\\/administrator\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il comune di Torino cerca giovani tra i 18 e i 29 anni per il progetto \"Giovani per l'integrazione - Offerte di Lavoro in Piemonte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-comune-di-torino-cerca-giovani-tra-i-18-e-i-29-anni-per-il-progetto-giovani-per-lintegrazione\/","og_locale":"it_IT","og_type":"article","og_title":"Il comune di Torino cerca giovani tra i 18 e i 29 anni per il progetto \"Giovani per l'integrazione - Offerte di Lavoro in Piemonte","og_description":"Il comune di Torino cerca giovani tra i 18 e i 29 anni per il progetto &#8220;Giovani per l&#8217;integrazione. Le candidature devono essere inviate entro il 27 gennaio. Il progetto \u201cGiovani per l\u2019Integrazione\u201d si propone di facilitare il dialogo","og_url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-comune-di-torino-cerca-giovani-tra-i-18-e-i-29-anni-per-il-progetto-giovani-per-lintegrazione\/","og_site_name":"Offerte di Lavoro in Piemonte","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese","article_author":"https:\/\/www.facebook.com\/quotidianopiemontese","article_published_time":"2016-12-29T09:57:13+00:00","article_modified_time":"2016-12-29T09:57:48+00:00","og_image":[{"width":917,"height":560,"url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2016\/12\/bando-giovani-integrazione.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@quotidianopiem","twitter_site":"@quotidianopiem","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-comune-di-torino-cerca-giovani-tra-i-18-e-i-29-anni-per-il-progetto-giovani-per-lintegrazione\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-comune-di-torino-cerca-giovani-tra-i-18-e-i-29-anni-per-il-progetto-giovani-per-lintegrazione\/"},"author":{"name":"Redazione","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"headline":"Il comune di Torino cerca giovani tra i 18 e i 29 anni per il progetto &#8220;Giovani per l&#8217;integrazione","datePublished":"2016-12-29T09:57:13+00:00","dateModified":"2016-12-29T09:57:48+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-comune-di-torino-cerca-giovani-tra-i-18-e-i-29-anni-per-il-progetto-giovani-per-lintegrazione\/"},"wordCount":165,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-comune-di-torino-cerca-giovani-tra-i-18-e-i-29-anni-per-il-progetto-giovani-per-lintegrazione\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2016\/12\/bando-giovani-integrazione.jpg","keywords":["comune di torino"],"articleSection":["Offerte Lavoro"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-comune-di-torino-cerca-giovani-tra-i-18-e-i-29-anni-per-il-progetto-giovani-per-lintegrazione\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-comune-di-torino-cerca-giovani-tra-i-18-e-i-29-anni-per-il-progetto-giovani-per-lintegrazione\/","url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-comune-di-torino-cerca-giovani-tra-i-18-e-i-29-anni-per-il-progetto-giovani-per-lintegrazione\/","name":"Il comune di Torino cerca giovani tra i 18 e i 29 anni per il progetto \"Giovani per l'integrazione - Offerte di Lavoro in Piemonte","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-comune-di-torino-cerca-giovani-tra-i-18-e-i-29-anni-per-il-progetto-giovani-per-lintegrazione\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-comune-di-torino-cerca-giovani-tra-i-18-e-i-29-anni-per-il-progetto-giovani-per-lintegrazione\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2016\/12\/bando-giovani-integrazione.jpg","datePublished":"2016-12-29T09:57:13+00:00","dateModified":"2016-12-29T09:57:48+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-comune-di-torino-cerca-giovani-tra-i-18-e-i-29-anni-per-il-progetto-giovani-per-lintegrazione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-comune-di-torino-cerca-giovani-tra-i-18-e-i-29-anni-per-il-progetto-giovani-per-lintegrazione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-comune-di-torino-cerca-giovani-tra-i-18-e-i-29-anni-per-il-progetto-giovani-per-lintegrazione\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2016\/12\/bando-giovani-integrazione.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/files\/2016\/12\/bando-giovani-integrazione.jpg","width":917,"height":560},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/il-comune-di-torino-cerca-giovani-tra-i-18-e-i-29-anni-per-il-progetto-giovani-per-lintegrazione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/"},{"@type":"ListItem","position":2,"name":"Il comune di Torino cerca giovani tra i 18 e i 29 anni per il progetto &#8220;Giovani per l&#8217;integrazione"}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/#website","url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/","name":"Offerte di Lavoro in Piemonte","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","caption":"Redazione"},"description":"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte","sameAs":["http:\/\/www.quotidianopiemontese.it\/","https:\/\/www.facebook.com\/quotidianopiemontese","https:\/\/x.com\/quotidianopiem"],"url":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/author\/administrator\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/posts\/60","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/comments?post=60"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/posts\/60\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/media\/61"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/media?parent=60"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/categories?post=60"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/offerte-lavoro-piemonte\/wp-json\/wp\/v2\/tags?post=60"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}